{"id":1444853,"date":"2024-02-03T14:33:33","date_gmt":"2024-02-03T22:33:33","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444853"},"modified":"2024-02-03T14:33:33","modified_gmt":"2024-02-03T22:33:33","slug":"como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/","title":{"rendered":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.<\/p>\n<p>Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un segundo mandato. De ganar, como lo indican encuestas como la de Cid Gallup o la del Instituto de Opini\u00f3n P\u00fablica, de la Universidad Centroamericana, se convertir\u00e1 en el primero en repetir el cargo en la historia reciente de El Salvador, a pesar de que algunos sectores acad\u00e9micos y de juristas consideran que la Constituci\u00f3n proh\u00edbe la reelecci\u00f3n inmediata.<\/p>\n<p>Lo que est\u00e1 en juego con las elecciones en El Salvador<\/p>\n<p>Te decimos c\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador. Los documentos, el horario de votaci\u00f3n y c\u00f3mo se ve la boleta.<\/p>\n<p>\u00bfC\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador?<\/p>\n<p>Para ejercer tu voto en las elecciones que definir\u00e1n el rumbo que tomar\u00e1 el pa\u00eds los pr\u00f3ximos a\u00f1os tendr\u00e1s que acudir a un centro de votaci\u00f3n.<\/p>\n<p>Puedes consultar la direcci\u00f3n de tu centro de votaci\u00f3n a trav\u00e9s de la p\u00e1gina oficial del Tribunal Supremo Electoral (TSE). Deber\u00e1s ingresar tu n\u00famero de Documento \u00danico de Identidad (DUI) aqu\u00ed.<\/p>\n<p>Una vez que tengas esta informaci\u00f3n, acude el 4 de febrero a la direcci\u00f3n correspondiente.<\/p>\n<p>Si vives en el extranjero podr\u00e1s votar a trav\u00e9s de internet a partir del 6 de enero y hasta el 4 de febrero, bajo la modalidad de voto remoto por internet. Sigue estos pasos:<\/p>\n<p>Ingresar al sitio web oficial del TSE, aqu\u00ed.\u00a0<br \/>\nPara acceder al sistema y emitir tu voto, deber\u00e1s contar con un dispositivo con c\u00e1mara y con conexi\u00f3n a internet.<br \/>\nIngresa tu n\u00famero DUI y el n\u00famero de folio. Este \u00faltimo es un n\u00famero \u00fanico que se asigna a cada ciudadano como parte de su identificaci\u00f3n y puedes encontrarlo en la parte lateral de tu documento de identidad. Para ubicarlo, ten en cuenta que siempre comienza con una letra seguida de n\u00fameros.<br \/>\nEl sistema solicitar\u00e1 tomar una foto al rev\u00e9s y al derecho del documento de identidad.<br \/>\nLa plataforma abrir\u00e1 la c\u00e1mara del dispositivo para hacer una foto del votante.<br \/>\nEl sistema mostrar\u00e1 a los candidatos para presidente y vicepresidente y diputados a la Asamblea Legislativa. Emitir el voto. El sistema pedir\u00e1 confirmar la votaci\u00f3n.<br \/>\nEl sistema mostrar\u00e1 un comprobante de emisi\u00f3n del voto que podr\u00e1 ser descargado.<br \/>\n\u00a0Toma en cuenta que si la direcci\u00f3n en tu DUI es de El Salvador, deber\u00e1s asistir a un centro de votaci\u00f3n el 4 de febrero en las sedes que se habilitar\u00e1n en el exterior. Puedes consultarlas aqu\u00ed.<\/p>\n<p>Documentos, boleta y horarios<\/p>\n<p>M\u00e1s de 6 millones de salvadore\u00f1os conforman el padr\u00f3n electoral para las elecciones generales del 4 de febrero en El Salvador, de acuerdo con el TSE. Para poder emitir su voto, todos los salvadore\u00f1os mayores de 18 a\u00f1os tendr\u00e1n que contar con su DUI. Si vives en el extranjero puedes hacerlo con tu pasaporte tambi\u00e9n.<\/p>\n<p>El TSE public\u00f3 recientemente los dise\u00f1os de las papeletas de votaci\u00f3n para la presidencia de la Rep\u00fablica y para Asamblea Legislativa de cada departamento.<\/p>\n<p>En la papeleta de votaci\u00f3n para la presidencia aparecen los 6 candidatos que este a\u00f1o se disputan el cargo en el pa\u00eds centroamericano.<\/p>\n<p>Cr\u00e9dito: TSE<\/p>\n<p>Aqui puedes consultar las papeletas para la Asamblea Legislativa.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa. Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un segundo mandato. De ganar, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444853","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa. Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un segundo mandato. De ganar, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-03T22:33:33+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta\",\"datePublished\":\"2024-02-03T22:33:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/\"},\"wordCount\":647,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/\",\"url\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/\",\"name\":\"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-03T22:33:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa. Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un segundo mandato. De ganar, [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/","og_site_name":"Noticias","article_published_time":"2024-02-03T22:33:33+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","datePublished":"2024-02-03T22:33:33+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/"},"wordCount":647,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/","url":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/","name":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-03T22:33:33+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-centro\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","url":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/03\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-03T22:33:33Z","datePublished":"2024-02-03T22:33:33Z","dateModified":"2024-02-03T22:33:33Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo y d\\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/03\\\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/03\\\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-03T22:33:33Z\",\"datePublished\":\"2024-02-03T22:33:33Z\",\"dateModified\":\"2024-02-03T22:33:33Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444814,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/02\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta\/","url_meta":{"origin":1444853,"position":0},"title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","author":"","date":"febrero 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445004,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/06\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-3\/","url_meta":{"origin":1444853,"position":1},"title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445006,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/06\/como-y-donde-votar-en-las-elecciones-presidenciales-de-el-salvador-horarios-documentos-boleta-4\/","url_meta":{"origin":1444853,"position":2},"title":"C\u00f3mo y d\u00f3nde votar en las elecciones presidenciales de El Salvador: horarios, documentos, boleta","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pr\u00f3ximo 4 de febrero m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.Nayib Bukele, actual presidente \u2014con permiso de la Asamblea Legislativa para la campa\u00f1a electoral\u2014 busca reelegirse para un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444331,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/23\/lo-que-esta-en-juego-con-las-elecciones-en-el-salvador\/","url_meta":{"origin":1444853,"position":3},"title":"Lo que est\u00e1 en juego con las elecciones en El Salvador","author":"","date":"enero 23, 2024","format":false,"excerpt":"(CNN) -- El pr\u00f3ximo 4 de febrero poco m\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados a las urnas para elegir al pr\u00f3ximo presidente, vicepresidente y 60 diputados que integrar\u00e1n la Asamblea Legislativa.Nayib Bukele, actual presidente -con permiso de la Asamblea Legislativa para la campa\u00f1a electoral- busca un segundo mandato\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444470,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/26\/cuando-son-las-elecciones-de-el-salvador-2024-y-que-se-votara\/","url_meta":{"origin":1444853,"position":4},"title":"\u00bfCu\u00e1ndo son las elecciones de El Salvador 2024 y que se votar\u00e1?","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- M\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados para votar en las pr\u00f3ximas elecciones nacionales de febrero.Se van a votar m\u00faltiples cargos, pero el que m\u00e1s llama la atenci\u00f3n es el de presidente, ya que el actual mandatario Nayib Bukele busca un segundo mandato de cinco a\u00f1os.Si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457920,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/01\/27\/donde-como-votar-elecciones-ecuador-2025-documentos-horarios-requisitos-orix\/","url_meta":{"origin":1444853,"position":5},"title":"D\u00f3nde y c\u00f3mo votar en las elecciones de Ecuador en 2025: documentos, horarios y requisitos","author":"","date":"enero 27, 2025","format":false,"excerpt":"Ecuador se prepara para unas nuevas elecciones en medio de un clima pol\u00edtico y social tenso, marcado por la inseguridad, reactivaci\u00f3n econ\u00f3mica y la crisis energ\u00e9tica, temas que se discutieron en el primer \u201cdebate obligatorio\u201d organizado por el Consejo Nacional Electoral (CNE).En este contexto, los ecuatorianos deber\u00e1n acudir a las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1444853"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444853\/revisions"}],"predecessor-version":[{"id":1444870,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444853\/revisions\/1444870"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1444853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1444853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1444853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}