{"id":1444886,"date":"2024-02-04T06:33:37","date_gmt":"2024-02-04T14:33:37","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444886"},"modified":"2024-02-04T06:33:37","modified_gmt":"2024-02-04T14:33:37","slug":"los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/","title":{"rendered":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0 Los diagn\u00f3sticos de c\u00e1ncer en todo el mundo alcanzar\u00e1n los 35 millones en 2050, seg\u00fan nuevas estimaciones de la Organizaci\u00f3n Mundial de la Salud, un aumento del 77 % con respecto a los 20 millones de casos diagnosticados en 2022.<\/p>\n<p>Los datos, publicados este viernes por la Agencia Internacional para la Investigaci\u00f3n del C\u00e1ncer de la OMS, cubren 185 pa\u00edses y 36 formas de la enfermedad. Los investigadores descubrieron que el c\u00e1ncer de pulm\u00f3n era la forma m\u00e1s com\u00fan en todo el mundo en 2022 (responsable de 2,5 millones de casos, el 12,4% del total), seguido del c\u00e1ncer de mama, colorrectal, pr\u00f3stata y est\u00f3mago en las mujeres. El c\u00e1ncer de pulm\u00f3n tambi\u00e9n fue responsable de la mayor\u00eda de las muertes por c\u00e1ncer: 1,8 millones, o casi el 19% del total.<\/p>\n<p>La agencia tambi\u00e9n cita desigualdades en la carga del c\u00e1ncer en las naciones desarrolladas. Por ejemplo, en pa\u00edses con un \u00edndice de desarrollo humano muy alto (una medida de los logros en salud, educaci\u00f3n y nivel de vida), 1 de cada 12 mujeres ser\u00e1 diagnosticada con c\u00e1ncer de mama y 1 de cada 71 morir\u00e1 a causa de \u00e9l. En los pa\u00edses con un IDH bajo, solo 1 de cada 27 mujeres ser\u00e1 diagnosticada con c\u00e1ncer de mama, pero 1 de cada 48 morir\u00e1 a causa de \u00e9l, en gran parte debido a un diagn\u00f3stico tard\u00edo y a la falta de acceso a los tratamientos.<\/p>\n<p>Tambi\u00e9n se observaron desigualdades en los servicios oncol\u00f3gicos, como la radiaci\u00f3n y los trasplantes de c\u00e9lulas madre.<\/p>\n<p>&#171;La nueva encuesta mundial de la OMS arroja luz sobre las principales desigualdades y la falta de protecci\u00f3n financiera contra el c\u00e1ncer en todo el mundo, donde las poblaciones, especialmente en los pa\u00edses de ingresos m\u00e1s bajos, no pueden acceder a los cuidados b\u00e1sicos del c\u00e1ncer&#187;, dijo el Dr. Bente Mikkelsen, director del Departamento de Salud de la OMS. Enfermedades No Transmisibles, dijo en un comunicado de prensa. \u201cLa OMS, incluso a trav\u00e9s de sus iniciativas contra el c\u00e1ncer, est\u00e1 trabajando intensamente con m\u00e1s de 75 gobiernos para desarrollar, financiar e implementar pol\u00edticas que promuevan la atenci\u00f3n del c\u00e1ncer para todos. Para ampliar este trabajo, se necesitan con urgencia importantes inversiones para abordar las desigualdades globales en los resultados del c\u00e1ncer\u201d.<\/p>\n<p>Los investigadores se\u00f1alan que varios factores impulsan los aumentos esperados en las tasas de c\u00e1ncer, como la obesidad, el consumo de tabaco y el consumo de alcohol, as\u00ed como factores ambientales como la contaminaci\u00f3n del aire.<\/p>\n<p>En Estados Unidos, el n\u00famero de personas que mueren de c\u00e1ncer contin\u00faa disminuyendo mientras que las tasas de incidencia de ciertas formas de la enfermedad aumentan, seg\u00fan un informe publicado el mes pasado por la Sociedad Estadounidense del C\u00e1ncer.<\/p>\n<p>De 1991 a 2021, las muertes por c\u00e1ncer en EE. UU. cayeron un 33 %, en gran parte debido a la ca\u00edda del consumo de tabaco, la detecci\u00f3n m\u00e1s temprana y mejoras importantes en los tratamientos. Sin embargo, las disparidades raciales persisten y las personas de color enfrentan mayores riesgos.<\/p>\n<p>Los pacientes con c\u00e1ncer tambi\u00e9n son cada vez m\u00e1s j\u00f3venes, se\u00f1al\u00f3 el informe de la Sociedad Estadounidense del C\u00e1ncer. La proporci\u00f3n de diagn\u00f3sticos de c\u00e1ncer colorrectal en adultos menores de 55 a\u00f1os, por ejemplo, aument\u00f3 del 11% en 1995 al 20% en 2019, seg\u00fan investigaciones anteriores.<\/p>\n<p>El presidente Joe Biden ha hecho de la lucha contra el c\u00e1ncer una parte importante de su administraci\u00f3n, con su esfuerzo Cancer Moonshot destinado a reducir a la mitad las muertes por c\u00e1ncer en Estados Unidos en 25 a\u00f1os. Agencias como la NASA y la Agencia de Protecci\u00f3n Ambiental se han comprometido a unirse al esfuerzo junto con el Departamento de Salud y Servicios Humanos y el Departamento de Asuntos de Veteranos.<\/p>\n<p>\u201cA pesar de los avances que se han logrado en la detecci\u00f3n temprana del c\u00e1ncer y en el tratamiento y atenci\u00f3n de los pacientes con c\u00e1ncer, existen disparidades significativas en los resultados del tratamiento del c\u00e1ncer no solo entre las regiones de altos y bajos ingresos del mundo, sino tambi\u00e9n dentro de los pa\u00edses. El lugar donde vive alguien no debe determinar si vive o no. Existen herramientas para permitir a los gobiernos priorizar la atenci\u00f3n del c\u00e1ncer y garantizar que todos tengan acceso a servicios asequibles y de calidad. Esto no es s\u00f3lo una cuesti\u00f3n de recursos sino una cuesti\u00f3n de voluntad pol\u00edtica\u201d, dijo el Dr. Cary Adams, director de la Uni\u00f3n para el Control Internacional del C\u00e1ncer, en el comunicado de prensa de este viernes de la Agencia Internacional para la Investigaci\u00f3n del C\u00e1ncer.<\/p>\n<p>Jacqueline Howard de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0 Los diagn\u00f3sticos de c\u00e1ncer en todo el mundo alcanzar\u00e1n los 35 millones en 2050, seg\u00fan nuevas estimaciones de la Organizaci\u00f3n Mundial de la Salud, un aumento del 77 % con respecto a los 20 millones de casos diagnosticados en 2022. Los datos, publicados este viernes por la Agencia Internacional para la Investigaci\u00f3n del [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444886","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0 Los diagn\u00f3sticos de c\u00e1ncer en todo el mundo alcanzar\u00e1n los 35 millones en 2050, seg\u00fan nuevas estimaciones de la Organizaci\u00f3n Mundial de la Salud, un aumento del 77 % con respecto a los 20 millones de casos diagnosticados en 2022. Los datos, publicados este viernes por la Agencia Internacional para la Investigaci\u00f3n del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-04T14:33:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS\",\"datePublished\":\"2024-02-04T14:33:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/\"},\"wordCount\":854,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/\",\"name\":\"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-04T14:33:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/","og_locale":"es_ES","og_type":"article","og_title":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS - Noticias","og_description":"(CNN) &#8212;\u00a0 Los diagn\u00f3sticos de c\u00e1ncer en todo el mundo alcanzar\u00e1n los 35 millones en 2050, seg\u00fan nuevas estimaciones de la Organizaci\u00f3n Mundial de la Salud, un aumento del 77 % con respecto a los 20 millones de casos diagnosticados en 2022. Los datos, publicados este viernes por la Agencia Internacional para la Investigaci\u00f3n del [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/","og_site_name":"Noticias","article_published_time":"2024-02-04T14:33:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/"},"author":{"name":"","@id":""},"headline":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS","datePublished":"2024-02-04T14:33:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/"},"wordCount":854,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/","name":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-04T14:33:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS","url":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-04T14:33:37Z","datePublished":"2024-02-04T14:33:37Z","dateModified":"2024-02-04T14:33:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los casos mundiales de c\\u00e1ncer aumentar\\u00e1n un 77% para 2050, seg\\u00fan estimaciones de un informe de la OMS\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/04\\\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/04\\\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-04T14:33:37Z\",\"datePublished\":\"2024-02-04T14:33:37Z\",\"dateModified\":\"2024-02-04T14:33:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444888,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms-2\/","url_meta":{"origin":1444886,"position":0},"title":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN) --\u00a0 Los diagn\u00f3sticos de c\u00e1ncer en todo el mundo alcanzar\u00e1n los 35 millones en 2050, seg\u00fan nuevas estimaciones de la Organizaci\u00f3n Mundial de la Salud, un aumento del 77 % con respecto a los 20 millones de casos diagnosticados en 2022.Los datos, publicados este viernes por la Agencia Internacional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444901,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/los-casos-mundiales-de-cancer-aumentaran-un-77-para-2050-segun-estimaciones-de-un-informe-de-la-oms-3\/","url_meta":{"origin":1444886,"position":1},"title":"Los casos mundiales de c\u00e1ncer aumentar\u00e1n un 77% para 2050, seg\u00fan estimaciones de un informe de la OMS","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN) --\u00a0 Los diagn\u00f3sticos de c\u00e1ncer en todo el mundo alcanzar\u00e1n los 35 millones en 2050, seg\u00fan nuevas estimaciones de la Organizaci\u00f3n Mundial de la Salud, un aumento del 77 % con respecto a los 20 millones de casos diagnosticados en 2022.Los datos, publicados este viernes por la Agencia Internacional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447730,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/04\/casos-cancer-envejece-poblacion-trax\/","url_meta":{"origin":1444886,"position":2},"title":"Los casos de c\u00e1ncer aumentar\u00e1n a medida que el mundo envejece, lo que afectar\u00e1 a algunos pa\u00edses como &#171;un maremoto&#187;","author":"","date":"abril 4, 2024","format":false,"excerpt":"(CNN) -- Cada a\u00f1o, decenas de millones de personas en todo el mundo son diagnosticadas de c\u00e1ncer y millones mueren a causa de esta enfermedad. Ahora, un informe de la Sociedad Estadounidense contra el C\u00e1ncer prev\u00e9 que, para 2050, el n\u00famero de personas con c\u00e1ncer podr\u00eda aumentar un 77%.El informe,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444903,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/04\/dia-mundial-contra-el-cancer-2024-estos-son-los-5-tipos-de-cancer-mas-mortales-en-el-mundo\/","url_meta":{"origin":1444886,"position":3},"title":"D\u00eda Mundial contra el C\u00e1ncer 2024: estos son los 5 tipos de c\u00e1ncer m\u00e1s mortales en el mundo","author":"","date":"febrero 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Cada 4 de febrero se conmemora el D\u00eda Mundial contra el C\u00e1ncer.\u00bfCu\u00e1les son los cinco tipos de c\u00e1ncer m\u00e1s mortales en el mundo? Aqu\u00ed algunas de sus caracter\u00edsticas y s\u00edntomas, seg\u00fan la Organizaci\u00f3n Mundial de la Salud (OMS).1. C\u00e1ncer de pulm\u00f3nSeg\u00fan la OMS, 1,8 millones de personas murieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444465,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/26\/estos-son-los-examenes-para-la-deteccion-temprana-del-cancer\/","url_meta":{"origin":1444886,"position":4},"title":"Estos son los ex\u00e1menes para la detecci\u00f3n temprana del c\u00e1ncer","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La detecci\u00f3n temprana del c\u00e1ncer es un factor crucial para salvar vidas y reducir los costos del tratamiento de esa enfermedad, seg\u00fan las autoridades en salud. Conocer c\u00f3mo se logra esa detecci\u00f3n se vuelve fundamental ahora que la incidencia del c\u00e1ncer ha pasado cada vez m\u00e1s a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444471,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/26\/estos-son-los-examenes-para-la-deteccion-temprana-del-cancer-2\/","url_meta":{"origin":1444886,"position":5},"title":"Estos son los ex\u00e1menes para la detecci\u00f3n temprana del c\u00e1ncer","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La detecci\u00f3n temprana del c\u00e1ncer es un factor crucial para salvar vidas y reducir los costos del tratamiento de esa enfermedad, seg\u00fan las autoridades en salud. Conocer c\u00f3mo se logra esa detecci\u00f3n se vuelve fundamental ahora que la incidencia del c\u00e1ncer ha pasado cada vez m\u00e1s a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1444886"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444886\/revisions"}],"predecessor-version":[{"id":1444902,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444886\/revisions\/1444902"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1444886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1444886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1444886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}