{"id":1444999,"date":"2024-02-06T13:33:27","date_gmt":"2024-02-06T21:33:27","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1444999"},"modified":"2024-02-06T13:33:27","modified_gmt":"2024-02-06T21:33:27","slug":"muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/","title":{"rendered":"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago"},"content":{"rendered":"<p>(CNN) &#8212; El cantante de country Toby Keith falleci\u00f3 el lunes a los 62 a\u00f1os tras una batalla contra el c\u00e1ncer de est\u00f3mago.<\/p>\n<p>&#171;Toby Keith falleci\u00f3 en paz anoche, 5 de febrero, rodeado de su familia. Luch\u00f3 con gracia y coraje. Por favor, respeten la privacidad de su familia en este momento&#187;, dice un comunicado publicado en la p\u00e1gina web y en las redes sociales de Keith.<\/p>\n<p>Elaine Schock, publicista de Keith desde 2003, confirm\u00f3 su muerte a CNN.<\/p>\n<p>Le sobreviven su mujer, Tricia, y sus tres hijos, Shelley, Krystal y Stelen, seg\u00fan inform\u00f3 su publicista a CNN. Tambi\u00e9n su madre y dos hermanos.<\/p>\n<p>Keith revel\u00f3 su diagn\u00f3stico de c\u00e1ncer de est\u00f3mago en 2022.<\/p>\n<p>El cantante actu\u00f3 en los People&#8217;s Choice Country Awards 2023 en septiembre y recibi\u00f3 el premio Country Icon.<\/p>\n<p>Public\u00f3 su \u00e1lbum de debut en 1993 y es conocido por \u00e9xitos como &#171;Red Solo Cup&#187; y &#171;I Wanna Talk About Me&#187;. Su canci\u00f3n de 2002 &#171;Courtesy of the Red, White and Blue (The Angry American)&#187;, lanzada tras los atentados del 11S, le convirti\u00f3 en un nombre muy conocido.<\/p>\n<p>Keith dio cientos de conciertos para miembros de las fuerzas armadas estadounidenses en el extranjero, incluido en Afganist\u00e1n e Iraq, as\u00ed como en actos para los presidentes Donald Trump, Barack Obama y George W. Bush.<\/p>\n<p>A veces regalaba sillas de ruedas a veteranos heridos en sus conciertos.<\/p>\n<p>Keith, que se considera dem\u00f3crata de tercera generaci\u00f3n, declar\u00f3 a CNN en 2010 que su apoyo a los miembros de las fuerzas armadas no ten\u00eda nada que ver con la pol\u00edtica.<\/p>\n<p>&#171;No hay nada pol\u00edtico en apoyar a las tropas&#187;, dijo.<\/p>\n<p>En 2021, el entonces presidente Donald Trump concedi\u00f3 a Keith la Medalla Nacional de las Artes, que la Fundaci\u00f3n Nacional de las Artes describe como &#171;el m\u00e1s alto galard\u00f3n otorgado a artistas y mecenas de las artes por parte del gobierno de Estados Unidos.&#187;<\/p>\n<p>Marianne Garvey, Raja Razek, Amanda Jackson y Susannah Cullinane de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El cantante de country Toby Keith falleci\u00f3 el lunes a los 62 a\u00f1os tras una batalla contra el c\u00e1ncer de est\u00f3mago. &#171;Toby Keith falleci\u00f3 en paz anoche, 5 de febrero, rodeado de su familia. Luch\u00f3 con gracia y coraje. Por favor, respeten la privacidad de su familia en este momento&#187;, dice un comunicado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1444999","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El cantante de country Toby Keith falleci\u00f3 el lunes a los 62 a\u00f1os tras una batalla contra el c\u00e1ncer de est\u00f3mago. &#171;Toby Keith falleci\u00f3 en paz anoche, 5 de febrero, rodeado de su familia. Luch\u00f3 con gracia y coraje. Por favor, respeten la privacidad de su familia en este momento&#187;, dice un comunicado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-06T21:33:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago\",\"datePublished\":\"2024-02-06T21:33:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/\"},\"wordCount\":369,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/\",\"name\":\"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-06T21:33:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/","og_locale":"es_ES","og_type":"article","og_title":"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago - Noticias","og_description":"(CNN) &#8212; El cantante de country Toby Keith falleci\u00f3 el lunes a los 62 a\u00f1os tras una batalla contra el c\u00e1ncer de est\u00f3mago. &#171;Toby Keith falleci\u00f3 en paz anoche, 5 de febrero, rodeado de su familia. Luch\u00f3 con gracia y coraje. Por favor, respeten la privacidad de su familia en este momento&#187;, dice un comunicado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/","og_site_name":"Noticias","article_published_time":"2024-02-06T21:33:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/"},"author":{"name":"","@id":""},"headline":"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago","datePublished":"2024-02-06T21:33:27+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/"},"wordCount":369,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/","url":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/","name":"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-06T21:33:27+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago","url":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-06T21:33:27Z","datePublished":"2024-02-06T21:33:27Z","dateModified":"2024-02-06T21:33:27Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Muere el cantante de country Toby Keith tras luchar contra un c\\u00e1ncer de est\\u00f3mago\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/06\\\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/02\\\/06\\\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago-2\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-06T21:33:27Z\",\"datePublished\":\"2024-02-06T21:33:27Z\",\"dateModified\":\"2024-02-06T21:33:27Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444997,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/06\/muere-el-cantante-de-country-toby-keith-tras-luchar-contra-un-cancer-de-estomago\/","url_meta":{"origin":1444999,"position":0},"title":"Muere el cantante de country Toby Keith tras luchar contra un c\u00e1ncer de est\u00f3mago","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN) -- El cantante de country Toby Keith falleci\u00f3 el lunes a los 62 a\u00f1os tras una batalla contra el c\u00e1ncer de est\u00f3mago.\"Toby Keith falleci\u00f3 en paz anoche, 5 de febrero, rodeado de su familia. Luch\u00f3 con gracia y coraje. Por favor, respeten la privacidad de su familia en este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458039,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/01\/30\/muere-78-anios-cantante-britanica-marianne-faithfull-efe\/","url_meta":{"origin":1444999,"position":1},"title":"Muere a los 78 a\u00f1os la cantante brit\u00e1nica Marianne Faithfull","author":"","date":"enero 30, 2025","format":false,"excerpt":"La cantante brit\u00e1nica Marianne Faithfull falleci\u00f3 este jueves a los 78 a\u00f1os, seg\u00fan inform\u00f3 un portavoz de la artista.\u201cCon profunda tristeza anunciamos la muerte de la cantautora y actriz Marianne Faithfull\u201d, anunciaron en un comunicado.Entre los \u00e9xitos de la carrera de Faithfull se encuentra el tema \u201cAs Tears Go By\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465226,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/07\/brandon-blackstock-kelly-clarkson-muere-batalla-cancer-trax\/","url_meta":{"origin":1444999,"position":2},"title":"Brandon Blackstock, exesposo de Kelly Clarkson, muere a los 48 a\u00f1os tras una batalla contra el c\u00e1ncer","author":"","date":"agosto 7, 2025","format":false,"excerpt":"Brandon Blackstock, representante de talentos y exesposo de la cantante Kelly Clarkson, muri\u00f3 tras una batalla contra el c\u00e1ncer. Ten\u00eda 48 a\u00f1os.\u201cCon gran tristeza compartimos la noticia del fallecimiento de Brandon Blackstock\u201d, dijo a CNN un representante de la familia Blackstock en un comunicado este jueves. \u201cBrandon luch\u00f3 valientemente contra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467052,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/10\/02\/keith-urban-cambia-cancion-nicole-kidman-trax\/","url_meta":{"origin":1444999,"position":3},"title":"Keith Urban cambia la letra de una canci\u00f3n inspirada en Nicole Kidman","author":"","date":"octubre 2, 2025","format":false,"excerpt":"Keith Urban est\u00e1 cantando una melod\u00eda diferente estos d\u00edas.En un video reciente compartido con la prometedora cantante de m\u00fasica country Maggie Baugh, ella interpreta junto a Urban su canci\u00f3n \u201cThe Fighter\u201d.En la versi\u00f3n original, que cuenta con la participaci\u00f3n de la estrella del country Carrie Underwood, Urban canta: \u201cWhen they\u2019re\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448272,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/19\/encontrar-marido-chico-londres-aplicacion-citas-trax\/","url_meta":{"origin":1444999,"position":4},"title":"Se propuso encontrar marido en un a\u00f1o. Luego conect\u00f3 con un chico del otro lado del mundo a trav\u00e9s de una aplicaci\u00f3n de citas","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN) -- Samantha Hannah viajaba por Australia y Nueva Zelandia, empap\u00e1ndose de nuevos lugares y experiencias, al tiempo que reflexionaba sobre su pasado y se planteaba c\u00f3mo hab\u00eda sido su vida hasta el momento.Era finales de 2017. Samantha, de Perth, Escocia, ten\u00eda 31 a\u00f1os. Su hermano hab\u00eda fallecido inesperadamente un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471463,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/19\/eric-dane-actor-muere-trax\/","url_meta":{"origin":1444999,"position":5},"title":"Eric Dane, actor de &#171;Grey\u2019s Anatomy&#187; y &#171;Euphoria&#187;, muere a los 53 a\u00f1os","author":"","date":"febrero 19, 2026","format":false,"excerpt":"Eric Dane, el actor que cautiv\u00f3 a la audiencia en horario estelar con \u201cGrey\u2019s Anatomy\u201d en el apogeo de la popularidad del programa, falleci\u00f3, seg\u00fan inform\u00f3 su publicista. Ten\u00eda 53 a\u00f1os.\u201cCon gran pesar, compartimos que Eric Dane falleci\u00f3 este jueves por la tarde tras una valiente batalla contra la esclerosis\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1444999"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444999\/revisions"}],"predecessor-version":[{"id":1445015,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1444999\/revisions\/1445015"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1444999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1444999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1444999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}