{"id":1447551,"date":"2024-03-30T01:03:39","date_gmt":"2024-03-30T08:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/"},"modified":"2024-03-30T01:03:39","modified_gmt":"2024-03-30T08:03:39","slug":"hawai-otan-eeuu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/30\/hawai-otan-eeuu-trax\/","title":{"rendered":"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar"},"content":{"rendered":"<p>(CNN) &#8212; Suecia se convirti\u00f3 en el miembro m\u00e1s nuevo de la OTAN este mes, uni\u00e9ndose a 31 naciones de la alianza de seguridad que incluye a Estados Unidos. Bueno, a 49 de los 50 estados de Estados Unidos.<\/p>\n<p>Por un capricho de la geograf\u00eda y la historia, Hawai no est\u00e1 t\u00e9cnicamente cubierto por el pacto de la OTAN.<\/p>\n<p>Si una potencia extranjera atacara Hawai -por ejemplo, la base de la Marina estadounidense en Pearl Harbor o el cuartel general del Mando Indo-Pac\u00edfico al noroeste de Honolulu-, los miembros de la Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte no estar\u00edan obligados a acudir en defensa del estado.<\/p>\n<p>&#171;Es lo m\u00e1s extra\u00f1o&#187;, afirma David Santoro, presidente del think tank Pacific Forum de Honolulu, quien a\u00f1ade que ni siquiera la mayor\u00eda de los habitantes de Hawai saben que su estado est\u00e1 t\u00e9cnicamente a la deriva de la alianza.<\/p>\n<p>&#171;La gente tiende a asumir que Hawai forma parte de Estados Unidos y que, por tanto, est\u00e1 cubierto por la OTAN&#187;, afirma.<\/p>\n<p>Pero, admite, la pista est\u00e1 en el nombre de la alianza: Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte.<\/p>\n<p>Hawai est\u00e1, por supuesto, en el Pac\u00edfico, y a diferencia de California, Colorado o Alaska, el 50\u00ba estado no forma parte del territorio continental de EE.UU. que llega hasta el oc\u00e9ano Atl\u00e1ntico Norte por sus costas orientales.<\/p>\n<p>&#171;El argumento para no incluir a Hawai es simplemente que no forma parte de Norteam\u00e9rica&#187;, afirma Santoro.<\/p>\n<p>La excepci\u00f3n est\u00e1 recogida en el Tratado de Washington, el documento que estableci\u00f3 la OTAN en 1949, una d\u00e9cada antes de que Hawai se convirtiera en estado.<\/p>\n<p>Aunque el Art\u00edculo 5 del tratado prev\u00e9 la autodefensa colectiva en caso de ataque militar a cualquier estado miembro, el Art\u00edculo 6 limita el alcance geogr\u00e1fico de la misma.<\/p>\n<p>Marineros a bordo del USS Decatur rinden honores al pasar por el USS Arizona Memorial y el acorazado hundido USS Arizona durante la 82\u00aa ceremonia del D\u00eda del Recuerdo de Pearl Harbor el jueves 7 de diciembre de 2023, en Pearl Harbor, Hawai. (Cr\u00e9dito: Mengshin Lin\/AP)<\/p>\n<p>&#171;Se considera que un ataque armado contra una o m\u00e1s de las partes incluye un ataque armado contra el territorio de cualquiera de las partes en Europa o Norteam\u00e9rica&#187;, dice el Art\u00edculo 6. Tambi\u00e9n dice que cualquier territorio insular debe estar en el Atl\u00e1ntico Norte, al norte del Tr\u00f3pico de C\u00e1ncer.<\/p>\n<p>Un portavoz del Departamento de Estado de EE.UU. confirm\u00f3 que Hawai no est\u00e1 cubierto por el Art\u00edculo 5, pero dijo que el Art\u00edculo 4, que dice que los miembros consultar\u00e1n cuando &#171;la integridad territorial, la independencia pol\u00edtica o la seguridad&#187; de cualquier miembro se vea amenazada, deber\u00eda cubrir cualquier situaci\u00f3n que pudiera afectar al estado 50.<\/p>\n<p>El portavoz tambi\u00e9n afirm\u00f3 que cualquier modificaci\u00f3n del tratado para incluir a Hawai tendr\u00eda pocas probabilidades de obtener consenso porque otros miembros tienen territorios fuera de los l\u00edmites establecidos en el Art\u00edculo 5.<\/p>\n<p>Por ejemplo, la OTAN no se uni\u00f3 al Reino Unido en la guerra de 1982 contra Argentina, despu\u00e9s de que las tropas argentinas invadieran las islas Malvinas, un territorio brit\u00e1nico disputado en el Atl\u00e1ntico Sur.<\/p>\n<p>La OTAN no ha respondido a la solicitud de comentarios de CNN.<\/p>\n<p>Hawai, Guam, Taiw\u00e1n y Corea del Norte<\/p>\n<p>Algunos expertos afirman que los tiempos han cambiado en las d\u00e9cadas transcurridas desde la firma del Tratado de Washington, y sostienen que la situaci\u00f3n pol\u00edtica actual en el Indo-Pac\u00edfico podr\u00eda exigir un replanteamiento.<\/p>\n<p>Y es que las bases militares estadounidenses en Hawai podr\u00edan desempe\u00f1ar un papel vital tanto para contrarrestar una agresi\u00f3n norcoreana como para apoyar cualquier posible defensa de Taiw\u00e1n.<br \/>\nEl gobernante Partido Comunista de China reclama la isla democr\u00e1tica aut\u00f3noma como su territorio a pesar de no haberla controlado nunca. El l\u00edder chino, Xi Jinping, ha hecho de la &#171;reunificaci\u00f3n&#187; con Taiw\u00e1n una parte clave de su objetivo general de &#171;rejuvenecer&#187; la naci\u00f3n para 2049.<\/p>\n<p>Aunque los dirigentes chinos han dicho que esperan hacerse con el control de la isla por medios pac\u00edficos, no han descartado hacerlo por la fuerza, y en los \u00faltimos a\u00f1os han intensificado la intimidaci\u00f3n militar a la isla.<\/p>\n<p>AN\u00c1LISIS | Los peligrosos paralelismos entre las ambiciones de Putin en Ucrania y las reclamaciones de Xi sobre Taiw\u00e1n<\/p>\n<p>La Ley de Relaciones con Taiw\u00e1n obliga a Washington a proporcionar armamento para la defensa de la isla, y el presidente Joe Biden ha sugerido que utilizar\u00eda personal militar estadounidense para defenderla en caso de invasi\u00f3n china (aunque funcionarios de la Casa Blanca han dicho que la pol\u00edtica estadounidense de dejar esa cuesti\u00f3n en ambig\u00fcedad no ha cambiado).<\/p>\n<p>John Hemmings, director del Programa de Pol\u00edtica Exterior y de Seguridad Indo-Pac\u00edfica del Foro del Pac\u00edfico, afirma que la exclusi\u00f3n de Hawai de la OTAN elimina &#171;un elemento de disuasi\u00f3n&#187; ante la posibilidad de un ataque chino contra Hawai en apoyo de una posible campa\u00f1a contra Taiw\u00e1n.<\/p>\n<p>Vista de una fila de acorazados durante el ataque japon\u00e9s a Pearl Harbor, Hawai, el 7 de diciembre de 1941. (Cr\u00e9dito: US Navy\/Archivos Interinos\/Getty Images)<\/p>\n<p>Dejar fuera a Hawai permite a Beijing saber que los miembros europeos de la OTAN tienen potencialmente una especie de &#171;cl\u00e1usula de escape&#187; a la hora de defender el territorio estadounidense en esa hipot\u00e9tica situaci\u00f3n, afirma.<\/p>\n<p>&#171;\u00bfPor qu\u00e9 no pondr\u00edamos ese elemento de disuasi\u00f3n a nuestra disposici\u00f3n?&#187;, dice Hemmings. &#171;\u00bfPor qu\u00e9 dejar\u00edamos eso fuera de la mesa si realmente detendr\u00eda (a China) de una invasi\u00f3n de Taiw\u00e1n?&#187;.<\/p>\n<p>La importancia estrat\u00e9gica de Hawai tambi\u00e9n tiene un profundo significado hist\u00f3rico para Estados Unidos. &#171;Aqu\u00ed ocurri\u00f3 lo de Pearl Harbor. Aqu\u00ed es donde se produjo el ataque que nos llev\u00f3 a la Segunda Guerra Mundial, y \u2014por cierto\u2014 esto es lo que tambi\u00e9n nos llev\u00f3 a ayudar a liberar a Francia&#187;, afirma.<\/p>\n<p>&#171;Para los estadounidenses existe un v\u00ednculo directo entre este estado y nuestra participaci\u00f3n en la Segunda Guerra Mundial y, en \u00faltima instancia, nuestra ayuda para contribuir a la victoria sobre el Eje (la alianza de la Alemania nazi, Jap\u00f3n e Italia)&#187;.<\/p>\n<p>Hemmings tambi\u00e9n argumenta a favor de que Guam, el territorio insular estadounidense del Pac\u00edfico situado a unas 3.000 millas al oeste de Hawai, se incluya en el paraguas de la OTAN.<\/p>\n<p>La isla alberga la Base A\u00e9rea Andersen, desde la que EE.UU. puede lanzar sus bombarderos B-1, B-2 y B-52 a trav\u00e9s del Indo-Pac\u00edfico.<\/p>\n<p>Hemmings compara la exclusi\u00f3n de Guam de la OTAN con la forma en que EE.UU. dej\u00f3 la pen\u00ednsula de Corea fuera de una l\u00ednea que traz\u00f3 a trav\u00e9s del Pac\u00edfico para disuadir a la Uni\u00f3n Sovi\u00e9tica y China de extender el comunismo en enero de 1950. Cinco meses despu\u00e9s de que se trazara la llamada L\u00ednea Acheson comenz\u00f3 la guerra de Corea.<\/p>\n<p>&#171;El adversario se siente envalentonado para llevar a cabo un conflicto militar y acabas teniendo una guerra de todos modos&#187;, afirma Hemmings.<\/p>\n<p>Santoro, del Foro del Pac\u00edfico, tambi\u00e9n menciona que Guam deber\u00eda incluirse bajo el paraguas de la OTAN. &#171;Desde el punto de vista estrat\u00e9gico, Guam es mucho m\u00e1s importante que Hawai&#187;, afirma.<\/p>\n<p>&#171;Coalici\u00f3n de la voluntad&#187;<\/p>\n<p>Otros analistas sostienen que si ese hipot\u00e9tico ataque tuviera lugar en Hawai o Guam, los profundos y duraderos lazos que unen a Estados Unidos y a sus aliados democr\u00e1ticos ser\u00edan sustancialmente m\u00e1s significativos en la toma de decisiones de los pa\u00edses que un tecnicismo en el tratado de la OTAN.<\/p>\n<p>En caso de ataque, &#171;yo esperar\u00eda (&#8230;) que Estados Unidos intentara formar una coalici\u00f3n de la voluntad en la que participaran principalmente \u2014pero no exclusivamente\u2014 los aliados regionales&#187;, afirma Luis Simon, director del Centro de Investigaci\u00f3n sobre Seguridad, Diplomacia y Estrategia de la Escuela de Gobierno de Bruselas (B\u00e9lgica).<\/p>\n<p>Simon cita la en\u00e9rgica e inmediata respuesta de la Alianza tras los atentados del 11S, la \u00fanica vez en sus 74 a\u00f1os de historia que la OTAN ha activado el mecanismo de autodefensa colectiva previsto en el Art\u00edculo 5.<\/p>\n<p>Bombarderos B-52H Stratofortress de la Fuerza A\u00e9rea de EE.UU. carretean para despegar en la Base Andersen de la Fuerza A\u00e9rea, en Guam, el 14 de febrero de 2024. (Cr\u00e9dito: sargento mayor Amy Picard\/Fuerza A\u00e9rea de EE.UU.)<\/p>\n<p>&#171;Pero Washington opt\u00f3 en realidad por canalizar su respuesta a trav\u00e9s de una coalici\u00f3n de la voluntad, y no a trav\u00e9s del mando de la OTAN&#187;, afirma. &#171;Sospecho que ver\u00edamos una reacci\u00f3n similar en el caso de un ataque a Guam o Hawai, con EE.UU. queriendo mantener el control militar total sobre (la respuesta) y la flexibilidad diplom\u00e1tica&#187;.<\/p>\n<p>Simon tambi\u00e9n afirma que no ve ninguna diferencia real entre los miembros de la OTAN y su compromiso con Estados Unidos y la alianza.<\/p>\n<p>La OTAN es uno de los cimientos de la comunidad democr\u00e1tica transatl\u00e1ntica. Estados Unidos y otros miembros de la OTAN han pregonado una unidad sin precedentes entre la alianza ante la invasi\u00f3n no provocada de Ucrania por parte de Rusia. Y la OTAN tambi\u00e9n ha endurecido su ret\u00f3rica compartida sobre China en los \u00faltimos a\u00f1os, prometiendo abordar lo que describen como los &#171;desaf\u00edos sist\u00e9micos&#187; que plantea Beijing.<\/p>\n<p>&#171;Personalmente, tengo pocas dudas de que estar\u00edan dispuestos a proporcionar diferentes formas de asistencia en caso de un ataque contra territorio soberano estadounidense, incluso individualmente y a trav\u00e9s de instancias multilaterales como la Uni\u00f3n Europea o la OTAN&#187;, afirma.<\/p>\n<p>Jennifer Hansler de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Suecia se convirti\u00f3 en el miembro m\u00e1s nuevo de la OTAN este mes, uni\u00e9ndose a 31 naciones de la alianza de seguridad que incluye a Estados Unidos. Bueno, a 49 de los 50 estados de Estados Unidos. Por un capricho de la geograf\u00eda y la historia, Hawai no est\u00e1 t\u00e9cnicamente cubierto por el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1447551","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Suecia se convirti\u00f3 en el miembro m\u00e1s nuevo de la OTAN este mes, uni\u00e9ndose a 31 naciones de la alianza de seguridad que incluye a Estados Unidos. Bueno, a 49 de los 50 estados de Estados Unidos. Por un capricho de la geograf\u00eda y la historia, Hawai no est\u00e1 t\u00e9cnicamente cubierto por el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-30T08:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar\",\"datePublished\":\"2024-03-30T08:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/\"},\"wordCount\":1708,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/\",\"name\":\"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-30T08:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar - Noticias","og_description":"(CNN) &#8212; Suecia se convirti\u00f3 en el miembro m\u00e1s nuevo de la OTAN este mes, uni\u00e9ndose a 31 naciones de la alianza de seguridad que incluye a Estados Unidos. Bueno, a 49 de los 50 estados de Estados Unidos. Por un capricho de la geograf\u00eda y la historia, Hawai no est\u00e1 t\u00e9cnicamente cubierto por el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-30T08:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/"},"author":{"name":"","@id":""},"headline":"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar","datePublished":"2024-03-30T08:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/"},"wordCount":1708,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/","name":"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-30T08:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/30\/hawai-otan-eeuu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/30\/hawai-otan-eeuu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Este estado de EE.UU. no est\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar","url":"http:\/\/noticiasya.com\/el-valle\/2024\/03\/30\/hawai-otan-eeuu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/03\/30\/hawai-otan-eeuu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-30T08:03:39Z","datePublished":"2024-03-30T08:03:39Z","dateModified":"2024-03-30T08:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Este estado de EE.UU. no est\\u00e1 cubierto por el tratado de la OTAN. Algunos expertos dicen que eso tiene que cambiar\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/03\\\/30\\\/hawai-otan-eeuu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/03\\\/30\\\/hawai-otan-eeuu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-30T08:03:39Z\",\"datePublished\":\"2024-03-30T08:03:39Z\",\"dateModified\":\"2024-03-30T08:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456916,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/24\/kilauea-volcan-erupcion-hawai-23-diciembre-trax\/","url_meta":{"origin":1447551,"position":0},"title":"El volc\u00e1n Kilauea entra en erupci\u00f3n en la isla de Hawai y atrae a multitudes por las fiestas","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"Uno de los volcanes m\u00e1s activos del mundo entr\u00f3 en erupci\u00f3n este lunes despu\u00e9s de tres meses de interrupci\u00f3n, arrojando lava de color naranja brillante a una altura de hasta 90 metros, seg\u00fan el Servicio Geol\u00f3gico de Estados Unidos (USGS, por sus siglas en ingl\u00e9s).El volc\u00e1n Kilauea, situado en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470317,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/01\/21\/analisis-trump-groenlandia-esto-dice-constitucion-trax\/","url_meta":{"origin":1447551,"position":1},"title":"Trump afirma que &#171;adquirir\u00e1&#187; Groenlandia. Esto es lo que dice la Constituci\u00f3n","author":"","date":"enero 21, 2026","format":false,"excerpt":"El presidente Donald Trump ha dejado muy claro su deseo de \u201cadquirir\u201d Groenlandia de parte de Dinamarca, sin importar el da\u00f1o que ello suponga para la OTAN o para la alianza de Estados Unidos con Europa.Pero la Casa Blanca no ha explicado todav\u00eda c\u00f3mo se llevar\u00eda a cabo la adquisici\u00f3n.Si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472992,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/09\/hawai-amenaza-inundaciones-kona-trax\/","url_meta":{"origin":1447551,"position":2},"title":"Aumenta la amenaza de inundaciones en Hawai, semanas despu\u00e9s de las peores en 20 a\u00f1os","author":"","date":"abril 9, 2026","format":false,"excerpt":"Una potente tormenta de varios d\u00edas alcanzar\u00e1 su punto \u00e1lgido entre el jueves y el viernes, azotando a Hawai con intensas lluvias y reavivando una grave amenaza de inundaciones, mientras el estado a\u00fan se recupera de las devastadoras inundaciones ocurridas en marzo.Algunos lugares podr\u00edan registrar el equivalente a varios meses\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466259,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/08\/emergencia-hawai-huracan-kiko-evacuaciones-orix\/","url_meta":{"origin":1447551,"position":3},"title":"Qu\u00e9 implica la declaraci\u00f3n de emergencia vigente en Hawai por el hurac\u00e1n Kiko","author":"","date":"septiembre 8, 2025","format":false,"excerpt":"El centro del hurac\u00e1n Kiko est\u00e1 este lunes a unos 950 km de Honolulu, Hawai, un estado donde el 5 de septiembre se declar\u00f3 la emergencia \u201cdebido a las posibles inclemencias del tiempo\u201d ocasionadas por el cicl\u00f3n.La proclamaci\u00f3n del estado de emergencia firmada por la gobernadora interina Sylvia Luke implica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452104,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/23\/tormenta-tropical-hone-pacifico-hawai-trax\/","url_meta":{"origin":1447551,"position":4},"title":"La tormenta tropical Hone podr\u00eda llegar a Hawai este fin de semana y amenaza con inundaciones e incendios","author":"","date":"agosto 23, 2024","format":false,"excerpt":"(CNN) -- Puede que la temporada de huracanes en el Atl\u00e1ntico est\u00e9 tranquila por ahora, pero en el Pac\u00edfico, la tormenta tropical Hone amenaza con dar un duro golpe a Hawai este fin de semana.Se activ\u00f3 una alerta de tormenta tropical para la isla Grande de Hawai, ya que podr\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452134,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/24\/estado-de-emergencia-en-hawai-llegada-de-la-tormenta-tropical-hone-trax\/","url_meta":{"origin":1447551,"position":5},"title":"Declaran el estado de emergencia en Hawai ante la llegada de la tormenta tropical Hone","author":"","date":"agosto 24, 2024","format":false,"excerpt":"(CNN) -- El gobernador de Hawai, el dem\u00f3crata Josh Green, declar\u00f3 este s\u00e1bado el estado de emergencia debido a la amenaza de la tormenta tropical Hone y al elevado peligro de incendios en el estado.El per\u00edodo de socorro de emergencia comienza inmediatamente y se espera que contin\u00fae hasta este lunes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1447551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1447551"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1447551\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1447551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1447551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1447551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}