{"id":1447567,"date":"2024-03-31T01:03:40","date_gmt":"2024-03-31T08:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/"},"modified":"2024-03-31T01:03:40","modified_gmt":"2024-03-31T08:03:40","slug":"dia-internacional-de-la-visibilidad-transgenero-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/","title":{"rendered":"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber"},"content":{"rendered":"<p>(CNN) &#8212; Hoy, las personas transg\u00e9nero y no binarias de todo el mundo conmemoran el D\u00eda Internacional de la Visibilidad Transg\u00e9nero.<\/p>\n<p>Esto es lo que debes saber.<\/p>\n<p>\u00bfC\u00f3mo comenz\u00f3?<\/p>\n<p>El D\u00eda de la Visibilidad Transg\u00e9nero fue fundado en 2009 por Rachel Crandall, una activista transg\u00e9nero con sede en Michigan y directora ejecutiva de Transgender Michigan. Comenz\u00f3 como un d\u00eda de concientizaci\u00f3n para celebrar los \u00e9xitos de las personas transg\u00e9nero y de g\u00e9nero no conforme y es un d\u00eda importante para la comunidad LGBTQ.<\/p>\n<p>Mientras que el D\u00eda del Recuerdo Transg\u00e9nero se lleva a cabo todos los a\u00f1os el 20 de noviembre para conmemorar a las personas transg\u00e9nero que han perdido la vida como resultado de la violencia contra las personas transg\u00e9nero, el D\u00eda de la Visibilidad Transg\u00e9nero es un d\u00eda dedicado a honrar y empoderar las vidas de las personas transg\u00e9nero y personas no binarias.<\/p>\n<p>El d\u00eda se celebra anualmente el 31 de marzo.<\/p>\n<p>La importancia de la representaci\u00f3n transg\u00e9nero<\/p>\n<p>Este d\u00eda ilustra la importancia de la representaci\u00f3n transg\u00e9nero en todo el mundo, especialmente porque las personas transg\u00e9nero y de g\u00e9nero no conforme enfrentan riesgos todos los d\u00edas.<\/p>\n<p>Seg\u00fan una encuesta de Gallup de 2021, el 11,3% de los adultos LGBT se identifican como transg\u00e9nero; sin embargo, en lo que respecta a la representaci\u00f3n en los medios, solo hay 29 personajes transg\u00e9nero en las transmisiones originales en horario estelar, por cable y en streaming, seg\u00fan la organizaci\u00f3n de defensa de los medios GLAAD.<\/p>\n<p>Por qu\u00e9 es importante: encuestas recientes muestran que una cuarta parte de las personas en EE.UU. dicen que conocen personalmente a alguien que es transg\u00e9nero, lo que significa que la mayor\u00eda de los estadounidenses aprenden sobre la comunidad transg\u00e9nero a partir de lo que ven en los medios de entretenimiento. Debido a esto, dice GLAAD, es imperativo que los medios de entretenimiento hagan un buen trabajo cuando abordan historias transg\u00e9nero.<\/p>\n<p>C\u00f3mo ser un buen aliado<\/p>\n<p>Aqu\u00ed hay algunas maneras de apoyar a la comunidad transg\u00e9nero hoy:<\/p>\n<p>Busca historias de creadores transg\u00e9nero. Busca historias y medios aut\u00e9nticos que hayan sido creados por la comunidad transg\u00e9nero, como el Centro de Cine Transg\u00e9nero, una organizaci\u00f3n sin fines de lucro que apoya a los cineastas transg\u00e9nero y sus proyectos.<\/p>\n<p>Llama a tu centro LGBTQ local. Ve qu\u00e9 tipo de ayuda necesitan, ya sea como voluntario u ofreciendo un servicio en el que seas bueno.<\/p>\n<p>Ed\u00facate t\u00fa mismo. Los aliados pueden comenzar aprendiendo la terminolog\u00eda b\u00e1sica que rodea a la comunidad transg\u00e9nero. Por ejemplo, las personas a menudo confunden orientaci\u00f3n sexual e identidad de g\u00e9nero. Hay muchos lugares en l\u00ednea que comparten consejos sobre c\u00f3mo ser un buen aliado.<\/p>\n<p>Muchas personas transg\u00e9nero est\u00e1n felices de hablar sobre su experiencia, pero los aliados no siempre deben asumir que ese es el caso. Hay tantos recursos disponibles para ayudarte si deseas obtener m\u00e1s informaci\u00f3n sobre la comunidad y c\u00f3mo brindar apoyo.<\/p>\n<p>Este art\u00edculo fue publicado originalmente en 2022.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Hoy, las personas transg\u00e9nero y no binarias de todo el mundo conmemoran el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber. \u00bfC\u00f3mo comenz\u00f3? El D\u00eda de la Visibilidad Transg\u00e9nero fue fundado en 2009 por Rachel Crandall, una activista transg\u00e9nero con sede en Michigan y directora ejecutiva de Transgender Michigan. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1447567","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Hoy, las personas transg\u00e9nero y no binarias de todo el mundo conmemoran el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber. \u00bfC\u00f3mo comenz\u00f3? El D\u00eda de la Visibilidad Transg\u00e9nero fue fundado en 2009 por Rachel Crandall, una activista transg\u00e9nero con sede en Michigan y directora ejecutiva de Transgender Michigan. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-31T08:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber\",\"datePublished\":\"2024-03-31T08:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/\"},\"wordCount\":573,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/\",\"name\":\"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-31T08:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber - Noticias","og_description":"(CNN) &#8212; Hoy, las personas transg\u00e9nero y no binarias de todo el mundo conmemoran el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber. \u00bfC\u00f3mo comenz\u00f3? El D\u00eda de la Visibilidad Transg\u00e9nero fue fundado en 2009 por Rachel Crandall, una activista transg\u00e9nero con sede en Michigan y directora ejecutiva de Transgender Michigan. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-31T08:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/"},"author":{"name":"","@id":""},"headline":"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber","datePublished":"2024-03-31T08:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/"},"wordCount":573,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/","name":"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-31T08:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hoy es el D\u00eda Internacional de la Visibilidad Transg\u00e9nero. Esto es lo que debes saber","url":"http:\/\/noticiasya.com\/el-valle\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/03\/31\/dia-internacional-de-la-visibilidad-transgenero-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-31T08:03:40Z","datePublished":"2024-03-31T08:03:40Z","dateModified":"2024-03-31T08:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hoy es el D\\u00eda Internacional de la Visibilidad Transg\\u00e9nero. Esto es lo que debes saber\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/03\\\/31\\\/dia-internacional-de-la-visibilidad-transgenero-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/03\\\/31\\\/dia-internacional-de-la-visibilidad-transgenero-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-31T08:03:40Z\",\"datePublished\":\"2024-03-31T08:03:40Z\",\"dateModified\":\"2024-03-31T08:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1446246,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/03\/fiscal-nueva-york-decreto-prohibicion-atletas-transgenero-trax\/","url_meta":{"origin":1447567,"position":0},"title":"Fiscal general de Nueva York pide al condado de Nassau anular decreto sobre prohibici\u00f3n a atletas transg\u00e9nero","author":"","date":"marzo 3, 2024","format":false,"excerpt":"(CNN) -- La fiscal general de Nueva York, Letitia James, exigi\u00f3 al ejecutivo del condado de Nassau, Bruce Blakeman, que anulara la prohibici\u00f3n impuesta a atletas transg\u00e9nero de competir en deportes en categor\u00edas de mujeres y ni\u00f1as, al afirmar que era un \"decreto discriminatorio y transf\u00f3bico\", seg\u00fan un comunicado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446423,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/fiscal-nueva-york-decreto-prohibicion-atletas-transgenero-trax-2\/","url_meta":{"origin":1447567,"position":1},"title":"Fiscal general de Nueva York pide al condado de Nassau anular decreto sobre prohibici\u00f3n a atletas transg\u00e9nero","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- La fiscal general de Nueva York, Letitia James, exigi\u00f3 al ejecutivo del condado de Nassau, Bruce Blakeman, que anulara la prohibici\u00f3n impuesta a atletas transg\u00e9nero de competir en deportes en categor\u00edas de mujeres y ni\u00f1as, al afirmar que era un \"decreto discriminatorio y transf\u00f3bico\", seg\u00fan un comunicado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464712,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/07\/21\/administracion-trump-ataque-comunidad-transgenero-trax\/","url_meta":{"origin":1447567,"position":2},"title":"Gobierno de Trump est\u00e1 usando todos los recursos disponibles para cargar contra la comunidad transg\u00e9nero","author":"","date":"julio 21, 2025","format":false,"excerpt":"Desde el primer d\u00eda de su segundo mandato, el presidente Donald Trump ha utilizado un enfoque integral utilizando todos los recursos del Gobierno no solo para limitar los derechos de la comunidad transg\u00e9nero sino incluso para negar su existencia.Las personas trans representan menos del 0,6 % de la poblaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458765,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/14\/comunidad-lgbtq-trans-queer-eliminados-monumento-stonewall-trax\/","url_meta":{"origin":1447567,"position":3},"title":"La comunidad LGBTQ se moviliza despu\u00e9s de que &#8216;trans&#8217; y &#8216;queer&#8217; fueran eliminados del sitio web del Monumento de Stonewall","author":"","date":"febrero 14, 2025","format":false,"excerpt":"Despu\u00e9s de que las palabras \u201ctransg\u00e9nero\u201d y \u201cqueer\u201d fueran eliminadas del sitio web del Servicio de Parques Nacionales para el Monumento Nacional de Stonewall, un hito del movimiento del orgullo LGBTQ en la ciudad de Nueva York, los manifestantes llenaron el cercano Christopher Park este viernes con un mensaje simple:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458255,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/04\/juez-lamberth-trump-transgenero-prison-decreto-trax\/","url_meta":{"origin":1447567,"position":4},"title":"Un juez impide que el sistema penitenciario federal traslade a tres mujeres transg\u00e9nero a prisiones de hombres","author":"","date":"febrero 4, 2025","format":false,"excerpt":"Un juez federal impedi\u00f3 que la administraci\u00f3n Trump aplique su pol\u00edtica penitenciaria antitrans contra tres mujeres transg\u00e9nero actualmente alojadas en instalaciones para mujeres en prisiones federales.El fallo de este martes del juez de distrito estadounidense Royce Lamberth representa otro rev\u00e9s legal para un decreto controvertido emitido por el presidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456237,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/03\/derechos-personas-transgenero-corte-suprema-estados-unidos-trax\/","url_meta":{"origin":1447567,"position":5},"title":"Los derechos de las personas transg\u00e9nero est\u00e1n al centro de la discusi\u00f3n en la Corte Suprema de Estados Unidos","author":"","date":"diciembre 3, 2024","format":false,"excerpt":"Washington (CNN) --\u00a0La Corte Suprema abordar\u00e1 el mi\u00e9rcoles el tema, pol\u00edticamente tenso, de los derechos de las personas transg\u00e9nero cuando escuche la impugnaci\u00f3n a la prohibici\u00f3n de Tennessee de que los menores reciban tratamiento de afirmaci\u00f3n de g\u00e9nero, en el caso de mayor repercusi\u00f3n del oto\u00f1o.Los abogados del Gobierno de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1447567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1447567"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1447567\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1447567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1447567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1447567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}