{"id":1448043,"date":"2024-04-12T18:03:42","date_gmt":"2024-04-13T01:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/"},"modified":"2024-04-12T18:03:42","modified_gmt":"2024-04-13T01:03:42","slug":"conocieron-hotel-plaza-nueva-york-1970-amor-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/","title":{"rendered":"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0En 1969, Stefano Ripamonti ten\u00eda una buena vida. Ten\u00eda veintitantos a\u00f1os y un glamuroso trabajo en una firma italiana de zapatos de alta costura. Se acababa de casar con su novia de la infancia y los reci\u00e9n casados se estaban instalando en un departamento cerca de las murallas del Vaticano, en Roma, Italia.<\/p>\n<p>Aunque su nuevo hogar ten\u00eda un gran potencial, la pareja quer\u00eda renovar el espacio a su gusto, as\u00ed que contrataron a un arquitecto y dise\u00f1ador de interiores. Este arquitecto pas\u00f3 mucho tiempo en el departamento con la mujer de Stefano, remodelando espacios, sugiriendo colores de pintura y ofreciendo ideas de interiorismo.<br \/>\nMientras tanto, Stefano viajaba a menudo por motivos de trabajo.<\/p>\n<p>Un d\u00eda, Stefano regres\u00f3 de un viaje a Accra, Ghana, y se encontr\u00f3 a su mujer llorando en el departamento a medio decorar.<\/p>\n<p>&#171;Al parecer, durante mi ausencia, ella y el arquitecto se hab\u00edan enamorado&#187;, cuenta Stefano hoy a CNN Travel.<br \/>\n&#171;Y as\u00ed como as\u00ed, ella estaba fuera de mi vida, dej\u00e1ndome devastado&#187;.<\/p>\n<p>Un viaje a Nueva York<\/p>\n<p>Con el coraz\u00f3n destrozado, Stefano se sumergi\u00f3 en el trabajo, y posteriormente le ofrecieron un nuevo empleo en otra empresa italiana de calzado.<\/p>\n<p>El nuevo puesto no solo le pagaba &#171;casi el doble&#187;, sino que adem\u00e1s le ofrec\u00eda la oportunidad de visitar Estados Unidos por primera vez, para asistir a una convenci\u00f3n de calzado en Nueva York.<\/p>\n<p>Stefano estaba fascinado con Estados Unidos desde el d\u00eda en que los tanques estadounidenses entraron en Roma para liberar la ciudad de los nazis. El joven Stefano y sus padres se hab\u00edan unido a la multitud que vitoreaba en las calles, y entonces un soldado estadounidense baj\u00f3 de uno de los tanques Sherman para regalarle a Stefano, de dos a\u00f1os, una cajita de hojalata con chocolate. En la parte delantera de la lata estaba escrito: &#171;Fabricado por Curtiss Candy Co. Chicago&#187;.<\/p>\n<p>Se conocieron en un tren nocturno en Europa. Ahora llevan casi 30 a\u00f1os casados<\/p>\n<p>En los a\u00f1os siguientes, Stefano guard\u00f3 como un tesoro esta caja de bombones y so\u00f1\u00f3 despierto con Chicago, cuna de deliciosos dulces que no solo sab\u00edan bien, sino que representaban la libertad.<br \/>\n&#171;Todav\u00eda conservo esa caja&#187;, dice Stefano.<\/p>\n<p>Todo esto significaba que, para Stefano, nada pod\u00eda empa\u00f1ar la emoci\u00f3n de su primer viaje a EE.UU., ni siquiera la angustia de un matrimonio roto.<\/p>\n<p>Al d\u00eda siguiente de su llegada a Estados Unidos, en febrero de 1970, Stefano se visti\u00f3 con su mejor traje y entr\u00f3 en el vest\u00edbulo del Hotel Plaza de Nueva York. Esperaba conocer a algunos compradores de grandes almacenes y empaparse del ambiente de una verdadera instituci\u00f3n en Estados Unidos.<\/p>\n<p>Stefano recuerda que se acomod\u00f3 &#171;en un largo banco tapizado&#187; en el vest\u00edbulo de m\u00e1rmol del hotel.<\/p>\n<p>All\u00ed sentado, observando a la gente y admirando la grandeza del lugar, Stefano se percat\u00f3 poco a poco de la presencia de la joven sentada a su lado, que le\u00eda un ejemplar de The New York Times.<\/p>\n<p>Cuando Stefano la mir\u00f3, le vino a la mente una palabra: &#171;radiante&#187;.<\/p>\n<p>Quer\u00eda decir algo, presentarse, pero no se le ocurr\u00eda nada que decir que no pareciera &#171;est\u00fapido&#187;.<\/p>\n<p>Stefano no quer\u00eda molestarla, y se supon\u00eda que estaba haciendo contactos. Al final, pensando que los ascensores eran probablemente el mejor lugar para encontrar compradores potenciales, Stefano decidi\u00f3 salir del vest\u00edbulo. Estaba a punto de levantarse cuando la mujer baj\u00f3 el peri\u00f3dico y le sonri\u00f3.<\/p>\n<p>&#171;Disculpe, \u00bfqu\u00e9 hora es?&#187;, le pregunt\u00f3.<\/p>\n<p>Sorprendido, Stefano mir\u00f3 su reloj y se dio cuenta de que a\u00fan no lo hab\u00eda ajustado a la hora est\u00e1ndar del Este.<\/p>\n<p>&#171;A ver, tengo la hora italiana en mi reloj&#187;, dijo Stefano.<br \/>\n&#171;Ah, \u00bferes de Italia?&#187;, pregunt\u00f3 la mujer. &#171;Estuve all\u00ed el verano pasado con mi hermana&#187;.<\/p>\n<p>La mujer apart\u00f3 el peri\u00f3dico. Le tendi\u00f3 la mano a Stefano para que se la estrechara, sin dejar de sonre\u00edr.<br \/>\n&#171;Soy Sally&#187;, dijo. &#171;Sally Wilton&#187;.<\/p>\n<p>Sally Wilton era una joven de 22 a\u00f1os reci\u00e9n graduada que trabajaba en Washington. Aquel fin de semana de febrero de 1970 hab\u00eda decidido visitar Nueva York en un viaje espont\u00e1neo.<\/p>\n<p>&#171;Decid\u00ed ir a Nueva York por mi cuenta: quer\u00eda ver una obra de teatro&#187;, cuenta Sally a CNN Travel.<\/p>\n<p>Sin que Stefano lo supiera, Sally se fij\u00f3 en \u00e9l en cuanto se sent\u00f3 en el banco del vest\u00edbulo. De hecho, todo el tiempo que \u00e9l hab\u00eda estado buscando una oportunidad para presentarse, ella hab\u00eda estado haciendo lo mismo.<\/p>\n<p>&#171;Iba vestido impecablemente, con una chaqueta de pana. Recuerdo que era de un color dorado oscuro&#187;, recuerda Sally. &#171;Parec\u00eda tan italiano y tan bien confeccionado. Yo estaba acostumbrada a los chicos estadounidenses que llevaban sudaderas y pantalones de mezclilla&#187;.<\/p>\n<p>Durante sus a\u00f1os universitarios, Sally hab\u00eda pasado un a\u00f1o estudiando en el extranjero, en Leeds, Inglaterra. Esta experiencia le hab\u00eda abierto la mente a los viajes y le encantaba conocer gente de diferentes pa\u00edses y culturas.<\/p>\n<p>Sally se lo cont\u00f3 a Stefano mientras beb\u00edan un caf\u00e9 en el Palm Court, el gran sal\u00f3n de t\u00e9 del Hotel Plaza. Y mencion\u00f3, de pasada, que hab\u00eda nacido y crecido en Chicago.<\/p>\n<p>Stefano no se lo pod\u00eda creer. La ciudad hab\u00eda adquirido proporciones casi m\u00edticas en su mente. Estar sentado frente a una mujer de Chicago era una experiencia irreal.<\/p>\n<p>Entonces, Sally mencion\u00f3 casualmente que su padre trabajaba en el negocio de los dulces.<\/p>\n<p>Aunque el padre de Sally no trabajaba para Curtiss Candy (eso habr\u00eda sido demasiado extra\u00f1o), a Stefano aquella conexi\u00f3n le segu\u00eda pareciendo una enorme coincidencia. Parec\u00eda que era obra del destino.<\/p>\n<p>El caf\u00e9 se convirti\u00f3 en comida, y \u00e9sta en una tarde en la que Sally y Stefano se dedicaron a explorar Nueva York juntos. Se dieron cuenta de que compart\u00edan el amor por el arte, y se sumergieron en el Guggenheim y luego en el Museo de Arte Moderno.<\/p>\n<p>Durante todo ese tiempo, no dejaron de mirarse el uno al otro.<\/p>\n<p>&#171;Sally ten\u00eda un aspecto radiante y estadounidense, con esa sonrisa tan bonita&#187;, recuerda Stefano. &#171;Era guapa, muy atractiva. Pero tambi\u00e9n era extremadamente simp\u00e1tica, chispeante, burbujeante&#187;.<\/p>\n<p>&#171;Stefano era un tipo muy guapo y algo erudito&#187;, dice Sally. &#171;Fue encantador para m\u00ed&#187;.<\/p>\n<p>Despu\u00e9s de esa sola tarde, Stefano sinti\u00f3 que &#171;encajaban enseguida&#187;.<\/p>\n<p>&#171;Aunque nuestras culturas fueran tan diferentes, las dos chocaban de forma positiva&#187;, dice.<\/p>\n<p>Stefano segu\u00eda casado, aunque separado. Y Sally ten\u00eda novio en Washington D.C. Pero a pesar de esos otros lazos, toda esa tarde hubo algo entre ellos que era &#171;dif\u00edcil de identificar&#187;, como lo recuerda Stefano, pero que se sent\u00eda especial.<\/p>\n<p>A rega\u00f1adientes, Sally y Stefano se despidieron al final del d\u00eda.<\/p>\n<p>&#171;Yo ten\u00eda que volver a mi trabajo y \u00e9l ten\u00eda que irse de Nueva York&#187;, recuerda Sally. &#171;Pero me dijo: &#8216;Si puedes volver la semana que viene, me las arreglar\u00e9 para quedarme toda la semana y esperarte&#8217;. As\u00ed que lo hice. Volv\u00ed. Trabaj\u00e9 toda la semana. Luego vol\u00e9 de vuelta el fin de semana siguiente&#187;.<\/p>\n<p>Casi 1 de cada 4 personas en el mundo se siente sola, seg\u00fan una nueva encuesta<\/p>\n<p>El mejor fin de semana de nuestra vida<\/p>\n<p>El fin de semana siguiente fue un torbellino. Sally y Stefano alquilaron un helic\u00f3ptero para recorrer la ciudad. Fueron a bailar al deslumbrante Rainbow Room, en la planta 65 del 30 Rockefeller Plaza, en el Rockefeller Center. Bebieron c\u00f3cteles en el Russian Tea Room. Se maravillaron de haberse cruzado en la vida del otro.<br \/>\n&#171;Fue el mejor fin de semana de nuestra vida&#187;, dice Stefano. &#171;Est\u00e1bamos enamorados&#187;.<\/p>\n<p>El domingo por la noche, Stefano tuvo que volver a Italia y Sally a Washington. Pero esta distancia, en realidad, cualquier otra complicaci\u00f3n, parec\u00eda irrelevante.<\/p>\n<p>&#171;Fue una gran chispa lo que sentimos, as\u00ed que todo cambi\u00f3&#187;, dice Sally.<\/p>\n<p>En Trader Vic&#8217;s, un Tiki Bar del Hotel Plaza que cerr\u00f3 hace poco, Stefano escribi\u00f3 una promesa para Sally en el dorso de un posavasos: &#171;Se sono rose, fioriranno&#187;, una frase italiana que significa &#171;si son rosas, florecer\u00e1n&#187;.<\/p>\n<p>Stefano escribi\u00f3 esta frase en italiano en un posavasos de un bar de Nueva York tras conocer a Sally. Cr\u00e9dito: Stefano Ripamonti y Sally Ripamonti<\/p>\n<p>Para Stefano, las palabras resonaban: si \u00e9l y Sally estaban destinados a estar juntos, lo estar\u00edan. Debajo garabate\u00f3 el lugar, &#171;Nueva York&#187;, y la fecha: 6 de febrero de 1970.<\/p>\n<p>Cuando se despidieron, Sally prometi\u00f3 ir a Roma en cuanto pudiera. Una semana despu\u00e9s, el d\u00eda de San Valent\u00edn, lleg\u00f3 un telegrama para Stefano:<\/p>\n<p>&#171;Mi dulce amigo stop Te env\u00edo un beso de San Valent\u00edn stop Llegar a Roma en una o dos semanas como m\u00e1ximo stop Los detalles seguir\u00e1n pronto&#187;.<\/p>\n<p>Cruzando el mundo<\/p>\n<p>Este es el telegrama que Sally envi\u00f3 a Stefano antes de llegar a Roma. Cr\u00e9dito: Stefano Ripamonti y Sally Ripamonti<\/p>\n<p>La ma\u00f1ana en que Sally lleg\u00f3 a Roma coincidi\u00f3 con el d\u00eda en que Stefano estaba en el juzgado ultimando la separaci\u00f3n de su mujer. En Italia no exist\u00eda el divorcio hasta 1970, pero ese d\u00eda marcaba el final de la relaci\u00f3n de Stefano y el comienzo de una nueva etapa.<\/p>\n<p>Despu\u00e9s de la audiencia, Sally y Stefano se reunieron en la puerta del departamento de Stefano. Se abrazaron en medio de la calle, Stefano levant\u00f3 a Sally en el aire y los dos giraron juntos.<\/p>\n<p>&#171;Est\u00e1bamos muy emocionados&#187;, recuerda Stefano. &#171;Nos abrazamos y besamos durante un rato en medio de la calle&#187;.<br \/>\nDespu\u00e9s, Stefano le ense\u00f1\u00f3 a Sally su departamento de Roma por primera vez.<\/p>\n<p>&#171;El decorador del que se hab\u00eda enamorado la mujer hizo un trabajo precioso&#187;, dice Sally. &#171;El departamento era precioso&#187;.<\/p>\n<p>El departamento estaba situado encima de un peque\u00f1o bar, y Stefano y Sally llegaron a un acuerdo con el propietario.<\/p>\n<p>&#171;Todas las ma\u00f1anas nos sub\u00edan a la habitaci\u00f3n una bandeja con capuchino, fruta fresca y jugos de naranja&#187;, dice Stefano.<\/p>\n<p>&#171;Lo pon\u00eda directamente sobre la cama, todas las ma\u00f1anas&#187;, recuerda Sally. &#171;Era muy rom\u00e1ntico&#187;.<\/p>\n<p>Para Sally, no se trataba de un viaje r\u00e1pido a Roma. Planeaba quedarse indefinidamente. Dej\u00f3 su trabajo en Washington y llam\u00f3 a sus padres para decirles que hab\u00eda conocido al amor de su vida.<\/p>\n<p>&#171;Por desgracia, las circunstancias de nuestro encuentro sonaron mucho menos rom\u00e1nticas cuando la familia las recibi\u00f3 por tel\u00e9fono de su hija en Italia&#187;, dice Stefano.<\/p>\n<p>A los padres de Sally les preocupaba que Stefano siguiera casado y les alarmaba que Sally hubiera hecho las maletas y se hubiera mudado a Roma tras dos breves encuentros. Decidieron volar desde Chicago, no solo sus padres, sino tambi\u00e9n sus hermanas, para ver c\u00f3mo estaba Sally y ver d\u00f3nde viv\u00eda Stefano.<\/p>\n<p>Stefano comprendi\u00f3 que en esta visita hab\u00eda mucho en juego. Decidi\u00f3, como dice hoy, que &#171;ten\u00eda que hacer algo muy impresionante para esta gente para derribar cualquier sospecha sobre la integridad de mi car\u00e1cter&#187;.<\/p>\n<p>El padre de Stefano trabajaba para la polic\u00eda metropolitana de Roma, dirigiendo la unidad de veh\u00edculos motorizados. Stefano empez\u00f3 a preguntarse si su padre podr\u00eda organizar una escolta policial personal para la familia de Sally a su llegada al aeropuerto romano de Fiumicino.<\/p>\n<p>&#171;Mi padre, como era de esperar, respondi\u00f3 con un rotundo no&#187;, dice Stefano. &#171;Pero dio la casualidad de que yo conoc\u00eda personalmente a media docena de polic\u00edas motoristas, ya que hab\u00eda crecido con ellos desde que ten\u00eda 12 a\u00f1os. Habl\u00e9 con los dos m\u00e1s cercanos y les expliqu\u00e9 la situaci\u00f3n&#187;.<\/p>\n<p>Los dos polic\u00edas aceptaron el plan de Stefano, m\u00e1s o menos.<\/p>\n<p>&#171;Dijeron que &#8216;casualmente&#8217; estar\u00edan en el lugar y que lo har\u00edan&#187;, recuerda Stefano. &#171;Nadie se enterar\u00eda&#187;.<\/p>\n<p>As\u00ed que al aterrizar en Italia, la familia de Sally atraves\u00f3 el tr\u00e1fico romano, los sem\u00e1foros en rojo y las calles m\u00e1s transitadas, en una limusina alquilada, flanqueada por dos polic\u00edas en moto.<\/p>\n<p>El plan de Stefano funcion\u00f3: el padre de Sally qued\u00f3 impresionado.<\/p>\n<p>&#171;Cuando llegamos al hotel salt\u00f3 de la limusina y me abraz\u00f3 diciendo que era la experiencia m\u00e1s emocionante que recordaba&#187;, cuenta Stefano.<\/p>\n<p>Este momento, unido al hecho evidente de la felicidad de Sally, bast\u00f3 para disipar las preocupaciones de su familia.<\/p>\n<p>&#171;Y luego, por supuesto, conocieron a los padres de Stefano, que eran maravillosos, y a su hermano y su hermana&#187;, dice Sally. &#171;Fue un fin de semana estupendo y todos volvieron a casa felices&#187;.<\/p>\n<p>Por poco no se conocen en 1971, pero ahora llevan m\u00e1s de 50 a\u00f1os juntos<\/p>\n<p>Una vida en Roma<\/p>\n<p>Sally y Stefano disfrutaban saliendo y socializando. Cr\u00e9dito: Stefano Ripamonti y Sally Ripamonti<\/p>\n<p>Con la familia de Sally de vuelta en Estados Unidos, Sally y Stefano empezaron a hacer su vida en Roma. Sally se adapt\u00f3 a las cenas nocturnas italianas e intent\u00f3 aprender el idioma: quer\u00eda aprender italiano lo antes posible. Se sent\u00eda frustrada cuando no pod\u00eda participar plenamente en las conversaciones con los amigos de Stefano.<\/p>\n<p>&#171;La guerra de Vietnam estaba todav\u00eda en curso, y yo ten\u00eda opiniones muy firmes al respecto&#187;, recuerda Sally. &#171;Todos empez\u00e1bamos a hablar, pero yo no ten\u00eda las palabras porque mi italiano todav\u00eda estaba muy roto&#187;.<\/p>\n<p>Mientras tanto, Sally y Stefano cenaban en los mejores restaurantes de Roma la mayor\u00eda de las noches, intercaladas con cenas en casa de los padres de Stefano. Ni Sally ni Stefano sab\u00edan cocinar.<\/p>\n<p>Uno de sus restaurantes favoritos estaba en la Piazza del Popolo y tambi\u00e9n lo frecuentaba el actor Marcello Mastroianni.<\/p>\n<p>&#171;Se sentaba all\u00ed con gafas de sol y era muy emocionante&#187;, recuerda Sally. &#171;Era mi actor italiano favorito&#187;.<\/p>\n<p>Sally se enamor\u00f3 r\u00e1pidamente de la vida en Roma.<\/p>\n<p>&#171;Recorrimos todas las ruinas romanas. Fuimos a pasear por el Coliseo, y Stefano era el mejor gu\u00eda tur\u00edstico&#187;, dice Sally. &#171;En realidad no ten\u00edamos responsabilidades, aunque \u00e9l ten\u00eda su trabajo&#187;.<\/p>\n<p>Para entonces, Stefano se hab\u00eda alejado del mundo de la moda y se dedicaba al cine. Hab\u00eda creado una empresa con un viejo amigo, con el objetivo de ayudar a distribuir y promocionar pel\u00edculas estadounidenses en el mercado italiano.<\/p>\n<p>&#171;Montamos una peque\u00f1a empresa en una bonita oficina y ten\u00edamos como clientes a 20th Century Fox, United Artists y Walt Disney&#187;, cuenta Stefano. &#171;As\u00ed que lanzamos todas sus pel\u00edculas&#187;.<\/p>\n<p>Stefano y su socio organizaban ruedas de prensa y transportaban a actores estadounidenses por toda Italia. La vida de Stefano y Sally pronto incluy\u00f3 codearse con famosos de forma habitual: en c\u00f3cteles, estrenos, ense\u00f1ando Roma a los actores.<\/p>\n<p>&#171;Era emocionante&#187;, dice Stefano. &#171;Emocionante y glamuroso&#187;.<\/p>\n<p>Tambi\u00e9n hubo novedades en la vida personal de Sally y Stefano. Se casaron, en una peque\u00f1a ceremonia por la iglesia, con unos 25 amigos y familiares. Sally adopt\u00f3 el apellido de Stefano, convirti\u00e9ndose en Sally Ripamonti.<\/p>\n<p>&#171;Despu\u00e9s comimos en la Domus Aurea, que daba al Coliseo&#187;, dice Sally, que califica las celebraciones de &#171;muy entra\u00f1ables e \u00edntimas&#187;.<\/p>\n<p>Sally y Stefano tambi\u00e9n dieron la bienvenida a su primer hijo, un var\u00f3n.<\/p>\n<p>A Sally le hac\u00eda ilusi\u00f3n criar a su hijo en Italia. Italia, al menos la Italia de Sally, le parec\u00eda &#171;m\u00e1s abierta y mucho m\u00e1s libre&#187; que Estados Unidos. Sally y Stefano ten\u00edan un amplio grupo de amigos de mentalidad abierta y pensamiento liberal. Muchos de ellos eran homosexuales, y a Sally le parec\u00eda que hab\u00eda m\u00e1s aceptaci\u00f3n de la homosexualidad que en los Estados Unidos de principios de los setenta.<\/p>\n<p>Nuevas oportunidades<\/p>\n<p>Aqu\u00ed est\u00e1n Sally y Stefano en 1979 en Los \u00c1ngeles, California. Cr\u00e9dito: Stefano Ripamonti y Sally Ripamonti<\/p>\n<p>Sally y Stefano vivieron cinco a\u00f1os en Italia y tuvieron otro hijo antes de que una oportunidad laboral llevara a la joven familia a Estados Unidos.<\/p>\n<p>En 1975, Stefano tom\u00f3 el tim\u00f3n empresarial de Halston, la vanguardista casa de dise\u00f1o de moda estadounidense cuyos dise\u00f1os asaltaban el mundo de la moda en los a\u00f1os setenta.<\/p>\n<p>&#171;Podr\u00eda decirse que Halston sigue siendo considerado el mejor dise\u00f1ador de la historia de la alta costura estadounidense&#187;, afirma Stefano. &#171;Esa asociaci\u00f3n con \u00e9l cambi\u00f3 nuestra vida y me lanz\u00f3 a una trayectoria profesional cada vez m\u00e1s interesante, desafiante y exitosa&#187;.<\/p>\n<p>En Chicago, la pareja estableci\u00f3 una &#171;vida social bastante glamurosa&#187;, que rivalizaba con la que hab\u00edan disfrutado en Roma. Se relacionaban con los grandes artistas, actores, m\u00fasicos y dise\u00f1adores de moda de los a\u00f1os setenta.<\/p>\n<p>Sally y Stefano en Las Vegas en 1980. Cr\u00e9dito: Stefano Ripamonti y Sally Ripamonti<\/p>\n<p>Mientras tanto, Sally y Stefano tuvieron dos hijos m\u00e1s, y Sally compagin\u00f3 la vida familiar con su pasi\u00f3n por la pintura.<\/p>\n<p>Trasladarse a Estados Unidos fue interesante porque la pareja vio &#171;cambiar las tornas&#187; en muchos sentidos. Cuando lleg\u00f3 a Italia, Sally &#171;no ten\u00eda ni idea&#187; de c\u00f3mo funcionaba todo, desde las facturas hasta las tiendas de comestibles, as\u00ed que Stefano tom\u00f3 las riendas. En Estados Unidos, Sally estaba familiarizada con el sistema y el estilo de vida estadounidenses. Empez\u00f3 a gestionar los asuntos familiares.<\/p>\n<p>Tambi\u00e9n hubo otros ajustes.<\/p>\n<p>&#171;A la hora de hacer amigos, en Italia yo era la estrella, &#8216;l&#8217;Americana&#8217;. De repente, era una estadounidense m\u00e1s&#187;, dice Sally riendo. &#171;Y \u00e9l era el &#8216;Italiano&#8217;, todo el mundo quer\u00eda conocer a Stefano&#187;.<\/p>\n<p>Aunque a Sally le gustaba estar m\u00e1s cerca de sus padres y hermanas, descubri\u00f3 que &#171;extra\u00f1aba muchas cosas de Italia&#187;. Ella y Stefano la visitaban siempre que pod\u00edan.<\/p>\n<p>&#171;Fuimos y vinimos un mill\u00f3n de veces con los ni\u00f1os&#187;, dice Sally. &#171;Siempre se reun\u00edan con los abuelos de ambos sitios&#187;.<\/p>\n<p>Sally y Stefano educaron a sus hijos con un sentido de la apertura y les inculcaron la sed de viajar. Uno de sus hijos vive ahora en Tailandia, mientras que otro se enamor\u00f3 de su futura esposa durante una temporada en Jap\u00f3n. Ahora est\u00e1n casados y cr\u00edan a ni\u00f1os de ascendencia japonesa, estadounidense e italiana.<\/p>\n<p>&#171;Est\u00e1n acostumbrados a esta idea bicultural&#187;, dice Sally de sus hijos. &#171;Son muy abiertos. Nuestros hijos tienen una visi\u00f3n amplia&#187;.<\/p>\n<p>La vida como una &#171;m\u00e1quina de pinball&#187;<\/p>\n<p>Sally y Stefano viven actualmente en San Francisco, California, y tienen planes apasionantes por delante. Cr\u00e9dito: Stefano Ripamonti y Sally Ripamonti<\/p>\n<p>En la actualidad, Sally, que ya cumpli\u00f3 los setenta, y Stefano, que ronda los ochenta, viven en San Francisco, California, en un departamento con vistas a la bah\u00eda.<\/p>\n<p>En las \u00faltimas d\u00e9cadas, la pareja ha vivido por todo Estados Unidos, desde Nueva York a Arizona, pasando por Las Vegas, donde Stefano trabajaba en el sector de la hosteler\u00eda.<\/p>\n<p>Stefano se jubil\u00f3 en 2022, mientras que Sally sigue pintando. La vida de la pareja gira en torno a los viajes, el tiempo con la familia &#8212; incluidos sus cuatro nietos&#8211;, disfrutar de sus aficiones y pasar tiempo de calidad juntos.<\/p>\n<p>Stefano dice que cuando mira atr\u00e1s en su vida, se encuentra pensando en una &#171;m\u00e1quina de pinball&#187;. La vida es azarosa, dice, nunca se sabe lo que puede pasar.<\/p>\n<p>&#171;La vida, especialmente la m\u00eda y la de Sally, la nuestra, ha estado absolutamente llena de cosas inesperadas&#187;, dice.<br \/>\n&#171;Pero la vida est\u00e1 hecha as\u00ed. Las oportunidades se abren, y si eres creativo, curioso, las coges y ves ad\u00f3nde van&#187;.<\/p>\n<p>Cuando Sally y Stefano recuerdan el momento en que se conocieron, en el vest\u00edbulo del Hotel Plaza en 1970, siguen impresionados por lo fortuito de su encuentro: la idea de que si Stefano se hubiera &#171;levantado de aquel banco del Plaza un segundo antes&#187; la vida ser\u00eda diferente, &#171;nada de esta historia habr\u00eda ocurrido&#187;, como dice Stefano.<\/p>\n<p>Pero su emoci\u00f3n abrumadora es un sentimiento de gratitud, est\u00e1n contentos de haber &#171;dado un gran salto&#187;, como describe Sally, embarc\u00e1ndose en una vida juntos.<\/p>\n<p>Sally y Stefano piensan volver a Italia este mismo a\u00f1o.<\/p>\n<p>&#171;A nuestra edad la gente dice: &#8216;\u00bfEst\u00e1n locos? Est\u00e1n empezando una nueva vida&#187;, dice Sally. &#171;Nosotros decimos: &#8216;S\u00ed, estamos locos'&#187;.<\/p>\n<p>&#171;Es la m\u00e1quina de pinball&#187;, explica Stefano.<\/p>\n<p>&#171;La vida es una aventura&#187;, dice Sally. &#171;Tienes que estar dispuesto a mantenerte siempre abierto a sus retos y recompensas. No pasa gran cosa si te quedas en casa&#187;.<\/p>\n<p>&#171;Los dos ten\u00edamos un sexto sentido de que \u00e9ramos el uno para el otro&#187;, dice Stefano. &#171;Y volver\u00edamos a hacerlo&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0En 1969, Stefano Ripamonti ten\u00eda una buena vida. Ten\u00eda veintitantos a\u00f1os y un glamuroso trabajo en una firma italiana de zapatos de alta costura. Se acababa de casar con su novia de la infancia y los reci\u00e9n casados se estaban instalando en un departamento cerca de las murallas del Vaticano, en Roma, Italia. Aunque [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448043","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0En 1969, Stefano Ripamonti ten\u00eda una buena vida. Ten\u00eda veintitantos a\u00f1os y un glamuroso trabajo en una firma italiana de zapatos de alta costura. Se acababa de casar con su novia de la infancia y los reci\u00e9n casados se estaban instalando en un departamento cerca de las murallas del Vaticano, en Roma, Italia. Aunque [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-13T01:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s\",\"datePublished\":\"2024-04-13T01:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/\"},\"wordCount\":3535,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/\",\"name\":\"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-13T01:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s - Noticias","og_description":"(CNN) &#8212;\u00a0En 1969, Stefano Ripamonti ten\u00eda una buena vida. Ten\u00eda veintitantos a\u00f1os y un glamuroso trabajo en una firma italiana de zapatos de alta costura. Se acababa de casar con su novia de la infancia y los reci\u00e9n casados se estaban instalando en un departamento cerca de las murallas del Vaticano, en Roma, Italia. Aunque [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-13T01:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/"},"author":{"name":"","@id":""},"headline":"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s","datePublished":"2024-04-13T01:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/"},"wordCount":3535,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/","name":"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-13T01:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\u00f3 despu\u00e9s","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/12\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-13T01:03:42Z","datePublished":"2024-04-13T01:03:42Z","dateModified":"2024-04-13T01:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se conocieron en el Hotel Plaza de Nueva York en 1970. Esto es lo que pas\\u00f3 despu\\u00e9s\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/12\\\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/12\\\/conocieron-hotel-plaza-nueva-york-1970-amor-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-13T01:03:42Z\",\"datePublished\":\"2024-04-13T01:03:42Z\",\"dateModified\":\"2024-04-13T01:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458777,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/15\/salvador-di-stefano-si-el-pais-tiene-superavit-fiscal-y-no-emite-no-vamos-a-tener-inflacion\/","url_meta":{"origin":1448043,"position":0},"title":"Salvador Di Stefano: &#171;Si el pa\u00eds tiene super\u00e1vit fiscal y no emite, no vamos a tener inflaci\u00f3n&#187;","author":"","date":"febrero 15, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Salvador Di Stefano, analista econ\u00f3mico, habl\u00f3 este s\u00e1bado con Guillermo Panizza en Aire de Ma\u00f1ana sobre el rumbo de la econom\u00eda argentina y la pol\u00e9mica generada por el tuit del presidente Javier Milei sobre una criptomoneda.En cuanto a la inflaci\u00f3n, Di Stefano explic\u00f3 que \u201clos a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450672,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/24\/julian-assange-acuerdo-gobierno-biden-evitar-carcel-estados-unidos-trax\/","url_meta":{"origin":1448043,"position":1},"title":"Julian Assange logra un acuerdo con el Gobierno de Biden que le permitir\u00eda evitar la c\u00e1rcel en EE.UU.","author":"","date":"junio 24, 2024","format":false,"excerpt":"(CNN) --\u00a0El fundador de WikiLeaks, Julian Assange, acept\u00f3 declararse culpable de un delito grave relacionado con su presunta participaci\u00f3n en una de las mayores filtraciones de material clasificado del Gobierno estadounidense, como parte de un acuerdo con el Departamento de Justicia que le permitir\u00eda evitar la c\u00e1rcel en Estados Unidos,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466891,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/27\/departamento-estado-ee-uu-revocara-visa-petro-trax\/","url_meta":{"origin":1448043,"position":2},"title":"EE.UU. revoca visa a Petro por llamar a soldados estadounidenses a desobedecer a Trump","author":"","date":"septiembre 27, 2025","format":false,"excerpt":"Estados Unidos anunci\u00f3 este viernes que tiene intenciones de cancelar la visa del presidente de Colombia, Gustavo Petro, despu\u00e9s de que el mandatario sudamericano llamara p\u00fablicamente a los soldados estadounidenses a desobedecer a Donald Trump, tensando a\u00fan m\u00e1s las relaciones entre Washington y Bogot\u00e1.Petro, quien anteriormente se ha enfrentado con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447039,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/16\/oficialismo-venezuela-nombra-nicolas-maduro-candidato-presidencial-orix\/","url_meta":{"origin":1448043,"position":3},"title":"El oficialismo en Venezuela nombra a Nicol\u00e1s Maduro como su candidato presidencial","author":"","date":"marzo 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Partido Socialista Unido de Venezuela (PSUV) confirm\u00f3 este s\u00e1bado que el presidente Nicol\u00e1s Maduro ser\u00e1 el candidato presidencial del oficialismo para los comicios de este a\u00f1o.Maduro, quien acept\u00f3 la candidatura en una asamblea del partido celebrada en Caracas, buscar\u00e1 su segunda reelecci\u00f3n en los comicios que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463980,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/26\/cristiano-ronaldo-2027-al-nassr-renovo-orix\/","url_meta":{"origin":1448043,"position":4},"title":"\u00a1Cristiano hasta el 2027! Al Nassr renov\u00f3 a su m\u00e1xima estrella","author":"","date":"junio 26, 2025","format":false,"excerpt":"Cristiano Ronaldo defini\u00f3 su futuro y estar\u00e1 en el f\u00fatbol \u00e1rabe por dos a\u00f1os m\u00e1s.El eterno goleador portugu\u00e9s defender\u00e1 los colores del Al Nassr hasta el 2027 tras el anuncio de renovaci\u00f3n del equipo este jueves.Cristiano, quien con el conjunto saud\u00ed ha marcado 93 goles en 105 apariciones, envi\u00f3 un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449676,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/22\/bayer-leverkusen-xabi-alonso-final-europa-league-atalanta-orix\/","url_meta":{"origin":1448043,"position":5},"title":"El Bayer Leverkusen de Xabi Alonso pierde la final de la Europa League y se corta su racha hist\u00f3rica","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Fueron 51 partidos sin perder. El Bayer Leverkusen de Xabi Alonso hab\u00eda conseguido lo que nadie hab\u00eda logrado en Europa (la racha de invictos m\u00e1s larga) y consigui\u00f3 por primera vez que un equipo ganara la Bundesliga sin perder. Pero ese mi\u00e9rcoles el Atalanta lo fren\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448043"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448043\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}