{"id":1448320,"date":"2024-04-21T00:03:48","date_gmt":"2024-04-21T07:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/"},"modified":"2024-04-21T00:03:48","modified_gmt":"2024-04-21T07:03:48","slug":"mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/","title":{"rendered":"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios"},"content":{"rendered":"<p>(CNN) &#8212; M\u00e1s de una decena de personas sufrieron heridas no mortales este s\u00e1bado por la noche durante una colisi\u00f3n de tranv\u00edas en Universal Studios en California, confirm\u00f3 la Oficina del Sheriff del Condado de Los \u00c1ngeles a CNN.<\/p>\n<p>El conductor del tranv\u00eda indic\u00f3 que se produjo una falla mec\u00e1nica que provoc\u00f3 que uno de los carros chocara contra un riel y que varios pasajeros cayeran, dijo la oficina del sheriff, agregando que el incidente ocurri\u00f3 alrededor de las 9 p.m. PST.<\/p>\n<p>&#171;Posiblemente 14 o 15&#187; personas resultaron heridas, dijo la oficina del sheriff.<\/p>\n<p>&#171;Hubo un incidente con el tranv\u00eda en el parque tem\u00e1tico este s\u00e1bado que result\u00f3 en m\u00faltiples lesiones leves, confirmadas por el Departamento de Bomberos del Condado de Los \u00c1ngeles&#187;, dijo un portavoz de Universal Studios Hollywood en un comunicado. &#171;Estamos trabajando para apoyar a nuestros invitados y comprender las circunstancias que llevaron al accidente&#187;.<\/p>\n<p>Noticia en desarrollo<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; M\u00e1s de una decena de personas sufrieron heridas no mortales este s\u00e1bado por la noche durante una colisi\u00f3n de tranv\u00edas en Universal Studios en California, confirm\u00f3 la Oficina del Sheriff del Condado de Los \u00c1ngeles a CNN. El conductor del tranv\u00eda indic\u00f3 que se produjo una falla mec\u00e1nica que provoc\u00f3 que uno de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448320","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; M\u00e1s de una decena de personas sufrieron heridas no mortales este s\u00e1bado por la noche durante una colisi\u00f3n de tranv\u00edas en Universal Studios en California, confirm\u00f3 la Oficina del Sheriff del Condado de Los \u00c1ngeles a CNN. El conductor del tranv\u00eda indic\u00f3 que se produjo una falla mec\u00e1nica que provoc\u00f3 que uno de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-21T07:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios\",\"datePublished\":\"2024-04-21T07:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/\"},\"wordCount\":194,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/\",\"name\":\"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-21T07:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios - Noticias","og_description":"(CNN) &#8212; M\u00e1s de una decena de personas sufrieron heridas no mortales este s\u00e1bado por la noche durante una colisi\u00f3n de tranv\u00edas en Universal Studios en California, confirm\u00f3 la Oficina del Sheriff del Condado de Los \u00c1ngeles a CNN. El conductor del tranv\u00eda indic\u00f3 que se produjo una falla mec\u00e1nica que provoc\u00f3 que uno de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-21T07:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/"},"author":{"name":"","@id":""},"headline":"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios","datePublished":"2024-04-21T07:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/"},"wordCount":194,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/","name":"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-21T07:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e1s de una decena de personas resultaron heridas en una colisi\u00f3n de tranv\u00edas en Universal Studios","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/21\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-21T07:03:48Z","datePublished":"2024-04-21T07:03:48Z","dateModified":"2024-04-21T07:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e1s de una decena de personas resultaron heridas en una colisi\\u00f3n de tranv\\u00edas en Universal Studios\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/21\\\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/21\\\/mas-decena-de-personas-resultaron-heridas-en-colision-tranvias-en-universal-studios-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-21T07:03:48Z\",\"datePublished\":\"2024-04-21T07:03:48Z\",\"dateModified\":\"2024-04-21T07:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450159,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/08\/tres-personas-heridas-dos-ataques-tiburones-playas-vecinas-de-florida-con-solo-90-minutos-de-diferencia-trax\/","url_meta":{"origin":1448320,"position":0},"title":"Tres personas resultaron heridas en dos ataques de tiburones en playas vecinas de Florida con solo 90 minutos de diferencia","author":"","date":"junio 8, 2024","format":false,"excerpt":"(CNN) -- Tres personas resultaron heridas en dos ataques de tiburones con solo 90 minutos de diferencia este viernes en playas vecinas en el condado de Walton, Florida, dicen las autoridades.Los ataques ocurrieron a unas 6 kil\u00f3metros\u00a0 de distancia y dejaron a dos personas en condici\u00f3n cr\u00edtica y una tercera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469602,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/27\/tres-heridos-tiroteo-idaho-trax\/","url_meta":{"origin":1448320,"position":1},"title":"Tiroteo contra la Oficina del Sheriff en Idaho deja tres heridos; un hombre fue abatido, dicen autoridades","author":"","date":"diciembre 27, 2025","format":false,"excerpt":"Un atacante armado con varias armas abri\u00f3 fuego en el vest\u00edbulo de la Oficina del Sheriff de Idaho y en la calle el viernes, hiriendo a tres personas antes de ser abatido en un enfrentamiento con la polic\u00eda, dijo el sheriff local.El presunto atacante dispar\u00f3 contra una camioneta afuera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471991,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/07\/fuertes-tormentas-tornados-destructivos-8-muertos-trax\/","url_meta":{"origin":1448320,"position":2},"title":"Fuertes tormentas que generaron tornados destructivos dejan al menos ocho muertos en el centro de EE.UU.","author":"","date":"marzo 7, 2026","format":false,"excerpt":"Fuertes tormentas llevaron tornados da\u00f1inos a partes del centro de Estados Unidos el jueves y el viernes, reduciendo edificios a montones de escombros y matando a al menos ocho personas.La amenaza de tiempo severo que comenz\u00f3 el mi\u00e9rcoles disminuir\u00e1 en gran medida despu\u00e9s de este s\u00e1bado.Un pu\u00f1ado de tormentas severas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457048,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/28\/bomberos-pasajeros-heridos-colision-tren-camion-florida-trax\/","url_meta":{"origin":1448320,"position":3},"title":"3 bomberos y 12 pasajeros resultaron heridos en la colisi\u00f3n de un tren con un cami\u00f3n de bomberos en Florida","author":"","date":"diciembre 28, 2024","format":false,"excerpt":"Tres bomberos y 12 pasajeros resultaron heridos cuando un tren colision\u00f3 con un cami\u00f3n de bomberos que respond\u00eda a una llamada de emergencia este s\u00e1bado por la ma\u00f1ana en Delray Beach, Florida, dijeron las autoridades.Una investigaci\u00f3n sobre la causa de la colisi\u00f3n est\u00e1 en marcha, liderada por el Departamento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447481,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/27\/ataque-arma-blanca-muertos-heridos-rockford-illinois-trax\/","url_meta":{"origin":1448320,"position":4},"title":"Ataque con arma blanca deja 4 muertos y 7 heridos en una zona residencial de Rockford, Illinois, seg\u00fan las autoridades","author":"","date":"marzo 27, 2024","format":false,"excerpt":"(CNN) -- Cuatro personas fueron encontradas muertas y otras siete resultaron heridas en un apu\u00f1alamiento a trav\u00e9s de m\u00faltiples \u00e1reas en Rockford, Illinois, este mi\u00e9rcoles por la tarde, dijo la Polic\u00eda. Un sospechoso est\u00e1 bajo custodia.Una ni\u00f1a de 15 a\u00f1os, una mujer de 63 a\u00f1os, un hombre de 49 a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450400,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/16\/multiples-personas-heridas-tiroteo-parque-acuatico-michigan-trax\/","url_meta":{"origin":1448320,"position":5},"title":"Al menos nueve personas recibieron disparos, incluidos dos ni\u00f1os, en un centro recreativo de Michigan antes de que el sospechoso sea encontrado muerto, dice la Polic\u00eda","author":"","date":"junio 16, 2024","format":false,"excerpt":"(CNN) --\u00a0 \u00a0Un sospechoso del tiroteo que hiri\u00f3 al menos a nueve personas en un \u00e1rea recreativa en Rochester Hills, Michigan, este s\u00e1bado fue encontrado muerto en una casa cercana, dijo el sheriff del condado de Oakland, Michael Bouchard.El sospechoso, un hombre de 42 a\u00f1os cuyo nombre a\u00fan no ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448320"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448320\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}