{"id":1448369,"date":"2024-04-22T08:03:44","date_gmt":"2024-04-22T15:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/"},"modified":"2024-04-22T08:03:44","modified_gmt":"2024-04-22T15:03:44","slug":"ecuador-que-sigue-consulta-popular-referendo-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/","title":{"rendered":"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Los ecuatorianos manifestaron este domingo su apoyo a nueve de las 11 propuestas de\u00a0reformas legales y constitucionales planteadas por el presidente Daniel Noboa, espec\u00edficamente las enfocadas en seguridad y justicia, seg\u00fan los resultados oficiales preliminares del conteo r\u00e1pido del referendo y consulta popular que se llevaron adelante.<\/p>\n<p>Cerca del 72% de los habilitados para votar participaron en el proceso del domingo, seg\u00fan el Consejo Nacional Electoral.<\/p>\n<p>La consulta estaba dividida en cinco preguntas para \u201creferendo\u201d que implican cambios a la Constituci\u00f3n y otras seis preguntas para \u201cconsulta popular\u201d que conllevan reformas y temas de inter\u00e9s nacional. \u00danicamente dos no recibieron el visto bueno mayoritario, las vinculadas a arbitrajes internacionales y empleo.<\/p>\n<p>Tras ser aprobadas, estas propuestas requerir\u00e1n procedimientos posteriores para su total vigencia y ejecuci\u00f3n. Algunos de estos par\u00e1metros est\u00e1n estipulados en normativas ya existentes en Ecuador y otros en los denominados \u201canexos\u201d de la propuesta de consulta popular y referendo.<\/p>\n<p>A continuaci\u00f3n te explicamos cu\u00e1les fueron las propuestas que recibieron un apoyo minoritario y qu\u00e9 cambios implican en la pol\u00edtica de seguridad y el sistema judicial ecuatoriano.<\/p>\n<p>Apoyo de las Fuerzas Armadas a las tareas de la Polic\u00eda Nacional<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que se permita el apoyo complementario de las Fuerzas Armadas en las funciones de la Polic\u00eda Nacional para combatir el crimen organizado, reformando parcialmente la Constituci\u00f3n?<\/p>\n<p>Esta propuesta de enmienda constitucional qued\u00f3 allanada en diciembre del a\u00f1o pasado cuando la Asamblea Nacional aprob\u00f3 un proyecto de reforma constitucional para que las Fuerzas Armadas apoyen en las tareas de seguridad interna a la Polic\u00eda Nacional. Sin embargo, para su ejecuci\u00f3n se requer\u00eda la realizaci\u00f3n del referendo, donde m\u00e1s del 70% manifest\u00f3 su visto bueno al plan, seg\u00fan los resultados del Consejo Nacional Electoral.<\/p>\n<p>La cristalizaci\u00f3n del apoyo de las Fuerzas Armadas a la Polic\u00eda Nacional en tareas de seguridad interna tendr\u00e1 algunos par\u00e1metros que ya est\u00e1n establecidos en la reforma aprobada en diciembre por el Parlamento.<\/p>\n<p>Las funciones de coordinaci\u00f3n estar\u00e1n subordinadas a las disposiciones del presidente de la Rep\u00fablica.<br \/>\nLas tareas complementarias se ce\u00f1ir\u00e1n a los delitos de narcotr\u00e1fico, lavado de activos, tr\u00e1fico de armas y de personas, terrorismo, miner\u00eda ilegal, extorsi\u00f3n, intimidaci\u00f3n y delincuencia organizada.<br \/>\nEl apoyo complementario se activa cuando el presidente de la Rep\u00fablica, previa solicitud del comandante general de la Polic\u00eda, convoca al Consejo Nacional de Seguridad P\u00fablica y del Estado (COSEPE) para elaborar un \u201cinforme motivado\u201d que determine la pertinencia, casos y \u00e1mbitos de actuaci\u00f3n de los militares.<br \/>\nSobre la base del informe motivado, el presidente suscribir\u00e1 un decreto disponiendo el apoyo de las Fuerzas Armadas.<\/p>\n<p>\u201cEl hecho de reformar la Constituci\u00f3n no es que habilita directamente para que Fuerzas Armadas y Polic\u00eda Nacional puedan actuar, sino que tiene que haber un decreto ejecutivo en el cual se decrete esa necesidad a trav\u00e9s de un informe del Consejo de Seguridad P\u00fablica y del Estado\u201d, dijo a CNN Andr\u00e9 Benavides.<\/p>\n<p>Extradici\u00f3n de ecuatorianos<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con permitir la extradici\u00f3n de ecuatorianos, con las condiciones, requisitos, restricciones e impedimentos establecidos en la Constituci\u00f3n, los instrumentos internacionales y en la ley, enmendando la Constituci\u00f3n y reformando las leyes?<\/p>\n<p>En la actualidad, la Constituci\u00f3n establece que \u201cning\u00fan\u201d ecuatoriano podr\u00e1 ser extraditado y el referendo propon\u00eda una enmienda para que esto ocurra, as\u00ed como una reforma a la Ley de Extradici\u00f3n. Seg\u00fan los resultados preliminares, cerca de un 65% de los votantes respald\u00f3 la propuesta.<\/p>\n<p>\u201cSe va a poder extraditar a ecuatorianos, pero se necesita que existan convenios de extradici\u00f3n entre el Ecuador y el pa\u00eds requirente\u201d, precisa Benavides.<\/p>\n<p>Adicionalmente, el anexo de esta pregunta detalla que la extradici\u00f3n se llevar\u00e1 a cabo con la condici\u00f3n de que no se aplique la pena de muerte y tratos inhumanos, crueles o degradantes.<\/p>\n<p>Establece que \u201cno se conceder\u00e1 la extradici\u00f3n por delitos pol\u00edticos y conexos, con la exclusi\u00f3n del terrorismo, los delitos contra la humanidad y otros establecidos en los convenios internacionales\u201d.<\/p>\n<p>Judicaturas especializadas<\/p>\n<p>\u201c\u00bfEst\u00e1 usted de acuerdo con el establecimiento de judicaturas especializadas en materia constitucional, tanto en primera como en segunda instancia, para el conocimiento de las garant\u00edas jurisdiccionales que les corresponda, enmendando la Constituci\u00f3n y reformando la Ley Org\u00e1nica de Garant\u00edas Jurisdiccionales y Control Constitucional?<\/p>\n<p>A trav\u00e9s de esta pregunta, que obtuvo cerca de un 60% de votos por el &#171;s\u00ed&#187; seg\u00fan los resultados preliminares, Noboa propon\u00eda que no se abuse de las acciones de protecci\u00f3n o del habeas corpus que \u2014en algunos casos\u2014 han beneficiado a l\u00edderes de bandas criminales o presos con sentencias en firme que han logrado salir de prisi\u00f3n sin completar sus sentencias. En ocasiones, estas acciones se han interpuesto en lugares distintos a la jurisdicci\u00f3n a la que corresponde una causa.<\/p>\n<p>En anexo relacionado a esta pregunta del referendo, se\u00f1ala que esto \u201cha producido que jueces que no tienen formaci\u00f3n en materia constitucional se distraigan de los casos que s\u00ed son de su \u00e1mbito de especialidad\u201d.<\/p>\n<p>El objetivo es que jueces especializados en materia constitucional sean \u00fanicamente los que definan la pertinencia o no de estas acciones dentro de su jurisdicci\u00f3n. La propuesta da un plazo de un a\u00f1o para que se ejecuten las reformas y se cree la infraestructura adecuada.<\/p>\n<p>Fuerzas Armadas y c\u00e1rceles<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que las Fuerzas Armadas realicen control de armas, municiones, explosivos y accesorios, permanentemente, en las rutas, caminos, v\u00edas y corredores autorizados para el ingreso a los centros de rehabilitaci\u00f3n social?<\/p>\n<p>Esta pregunta, que obtuvo el visto favorable de cerca del 70% de los votantes seg\u00fan los resultados preliminares, no conten\u00eda anexo, y \u00fanicamente citaba algunos considerandos de leyes ya aprobadas que permiten a las Fuerzas Armadas involucrarse en el control de las inmediaciones de las c\u00e1rceles y v\u00edas del pa\u00eds. El objetivo del Gobierno de Noboa es que los ciudadanos se pronunciaran si est\u00e1n a favor o no de que estas acciones sean ejecutadas.<\/p>\n<p>Recordaba adem\u00e1s que la tenencia de armas, municiones y explosivos est\u00e1 a cargo del Ministerio de Defensa y del Comando Conjunto de las Fuerzas Armadas. Y que las Fuerzas Armadas con su actuaci\u00f3n prevengan \u201cagresiones a la vida de las personas privadas de la libertad\u201d.<\/p>\n<p>Incremento de penas frente a ciertos delitos<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que se incrementen las penas de los delitos de terrorismo y su financiaci\u00f3n, producci\u00f3n y tr\u00e1fico il\u00edcito de sustancias catalogadas sujetas a fiscalizaci\u00f3n, delincuencia organizada, asesinato, sicariato, trata de personas, secuestro extorsivo, tr\u00e1fico de armas, lavado de activos y actividad il\u00edcita de recursos mineros, reformando el C\u00f3digo Org\u00e1nico Integral Penal?<\/p>\n<p>A prop\u00f3sito del aumento sustancial de las muertes violentas en Ecuador, el narcotr\u00e1fico y el crimen organizado, el Gobierno de Noboa promueve el incremento de las penas en los delitos de terrorismo y su financiaci\u00f3n, producci\u00f3n y tr\u00e1fico il\u00edcito de sustancias catalogadas sujetas a fiscalizaci\u00f3n, delincuencia organizada, asesinato, sicariato, trata de personas, secuestro extorsivo, tr\u00e1fico de armas, lavado de activos y actividad il\u00edcita de recursos mineros.<\/p>\n<p>Aunque no establece en cu\u00e1nto se incrementar\u00edan las penas, el anexo de esta pregunta que tuvo aproximadamente un 68% de votos por &#171;s\u00ed&#187; se\u00f1ala que en caso de la aprobaci\u00f3n el presidente de la Rep\u00fablica, en el plazo de 5 d\u00edas posteriores a la publicaci\u00f3n de los resultados, remitir\u00e1 un proyecto de ley reformatoria al C\u00f3digo Penal que contenga los ajustes en estas penas. La Asamblea Nacional tendr\u00e1 60 d\u00edas para debatir y aprobar dicha reforma legal.<\/p>\n<p>Cumplimiento de penas frente a ciertos delitos<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que las personas privadas de la libertad cumplan la totalidad de su pena dentro del centro de rehabilitaci\u00f3n social en los delitos detallados en el Anexo de la pregunta, reformando el C\u00f3digo Org\u00e1nico Integral Penal?<\/p>\n<p>La finalidad de esta propuesta de reforma, que cont\u00f3 con el respaldo de cerca del 67% de los votantes seg\u00fan los resultados preliminares, es que las sentencias en determinados delitos se cumplan en su integridad dentro de las prisiones sin la posibilidad de acceso a libertad condicional o reg\u00edmenes abiertos o semiabiertos. Esto aplicar\u00eda \u2014seg\u00fan el anexo de la pregunta\u2014 para personas con sentencias por delitos como financiaci\u00f3n del terrorismo; reclutamiento de ni\u00f1os, ni\u00f1as y adolescentes con fines delictivos; secuestro extorsivo; producci\u00f3n il\u00edcita de droga; actividad il\u00edcita de recursos mineros, armas de fuego, municiones y explosivos prohibidos no autorizados; tenencia y porte no autorizado de armas; extorsi\u00f3n; revelaci\u00f3n de identidad de agente encubierto, informante, testigo, persona protegida o funcionario judicial protegido; tr\u00e1fico de influencias y testaferrismo.<\/p>\n<p>La Asamblea contar\u00e1 con un plazo m\u00e1ximo de 60 d\u00edas para debatir y aprobar esta reforma legal.<\/p>\n<p>Delito vinculado a tenecia de armas de las Fuerzas Armadas o la Polic\u00eda Nacional<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que se tipifique el delito de tenencia o porte de armas, municiones o componentes que son de uso privativo de las Fuerzas Armadas o la Polic\u00eda Nacional, sin afectar a las armas de fuego permitidas para uso civil, reformando el C\u00f3digo Org\u00e1nico Integral Penal?<\/p>\n<p>Ante el aumento de la incautaci\u00f3n de armas de origen militar y policial en el pa\u00eds, la consulta popular planteaba que se distinga la tenencia y porte de armas cuando no son de uso privativo de la fuerza p\u00fablica. Aproximadamente el 64% de la poblaci\u00f3n manifest\u00f3 su apoyo a esta propuesta, seg\u00fan los resultados preliminares.<\/p>\n<p>Tras la aprobaci\u00f3n, seg\u00fan las disposiciones, el presidente de la Rep\u00fablica, en un plazo de 5 d\u00edas posteriores a la publicaci\u00f3n de resultados, remitir\u00e1 el proyecto de ley a la Asamblea que tendr\u00e1 60 d\u00edas para debatirla y aprobarla.<\/p>\n<p>Uso de armas involucradas en delitos<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que las armas, sus partes o piezas, explosivos, municiones o accesorios que fueron instrumentos u objeto material de un delito puedan destinarse al uso inmediato de la Polic\u00eda Nacional o las Fuerzas Armadas, reformando el C\u00f3digo Org\u00e1nico Integral Penal?<\/p>\n<p>El Gobierno se\u00f1ala que, hasta diciembre de 2023, exist\u00edan 42.166 armas de fuego y 494.316 municiones incautadas en los centros de acopio de evidencia de la Polic\u00eda Nacional. Para darle una finalidad a esas armas, la consulta propon\u00eda que pasen a manos de la fuerza p\u00fablica, algo que obtuvo aproximadamente un 64% de apoyo.<\/p>\n<p>Actualmente, el C\u00f3digo Penal contempla una pena de \u201ccomiso penal\u201d a los bienes (armas) cuando fueron usados como instrumentos, productos o r\u00e9ditos en la comisi\u00f3n de un delito.<\/p>\n<p>\u201cEl proceso para llegar al comiso penal puede ser reformado con la finalidad de que se pueda disponer de las armas, sus partes o piezas, explosivos, municiones o accesorios en tiempos y etapas menores\u201d, argument\u00f3 el Gobierno.<\/p>\n<p>Seg\u00fan el procedimiento, el presidente remitir\u00e1 un proyecto de reforma legal tras la aprobaci\u00f3n de la propuesta y la Asamblea tendr\u00e1 60 d\u00edas para aprobarla.<\/p>\n<p>Titularidad de los bienes de origen il\u00edcito<\/p>\n<p>\u00bfEst\u00e1 usted de acuerdo con que el Estado proceda a ser el titular (propietario) de los bienes de origen il\u00edcito o injustificado, simplificando el procedimiento de la Ley Org\u00e1nica de Extinci\u00f3n de Dominio?<\/p>\n<p>A trav\u00e9s de esta reforma, el presidente Noboa plantea que el procedimiento para que el Estado se apropie de los bienes adquiridos de forma il\u00edcita sea m\u00e1s \u00e1gil y r\u00e1pido que el que establece la actual Ley de Extinci\u00f3n de Dominio ecuatoriana.<\/p>\n<p>El anexo de esta pregunta no detalla espec\u00edficamente c\u00f3mo se propone la reforma, pero s\u00ed que tras ser aprobada el presidente de la Rep\u00fablica ser\u00e1 quien env\u00ede en un plazo de 5 d\u00edas posteriores a la publicaci\u00f3n de resultados de la consulta una reforma a la Ley de Extinci\u00f3n de Dominio que deber\u00e1 tramitar la Asamblea en 60 d\u00edas.<\/p>\n<p>El abogado constitucionalista Andr\u00e9 Benavides dijo a CNN que la Asamblea \u2014en caso de aprobarse la consulta y el referendo, como muestran los resultados\u2014 no podr\u00e1 negarse a aprobar estas reformas conforme lo propuesto pues responden a un mandato popular de obligatorio cumplimiento.<\/p>\n<p>Con informaci\u00f3n de Ana Mar\u00eda Ca\u00f1izares<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Los ecuatorianos manifestaron este domingo su apoyo a nueve de las 11 propuestas de\u00a0reformas legales y constitucionales planteadas por el presidente Daniel Noboa, espec\u00edficamente las enfocadas en seguridad y justicia, seg\u00fan los resultados oficiales preliminares del conteo r\u00e1pido del referendo y consulta popular que se llevaron adelante. Cerca del 72% de los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448369","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Los ecuatorianos manifestaron este domingo su apoyo a nueve de las 11 propuestas de\u00a0reformas legales y constitucionales planteadas por el presidente Daniel Noboa, espec\u00edficamente las enfocadas en seguridad y justicia, seg\u00fan los resultados oficiales preliminares del conteo r\u00e1pido del referendo y consulta popular que se llevaron adelante. Cerca del 72% de los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T15:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa?\",\"datePublished\":\"2024-04-22T15:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/\"},\"wordCount\":2150,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/\",\"name\":\"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-22T15:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Los ecuatorianos manifestaron este domingo su apoyo a nueve de las 11 propuestas de\u00a0reformas legales y constitucionales planteadas por el presidente Daniel Noboa, espec\u00edficamente las enfocadas en seguridad y justicia, seg\u00fan los resultados oficiales preliminares del conteo r\u00e1pido del referendo y consulta popular que se llevaron adelante. Cerca del 72% de los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-22T15:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa?","datePublished":"2024-04-22T15:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/"},"wordCount":2150,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/","name":"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-22T15:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa?","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/ecuador-que-sigue-consulta-popular-referendo-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-22T15:03:44Z","datePublished":"2024-04-22T15:03:44Z","dateModified":"2024-04-22T15:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 sigue para Ecuador tras la consulta popular y el referendo en el que se aprobaron 9 de las 11 propuestas de Noboa?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/22\\\/ecuador-que-sigue-consulta-popular-referendo-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/22\\\/ecuador-que-sigue-consulta-popular-referendo-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-22T15:03:44Z\",\"datePublished\":\"2024-04-22T15:03:44Z\",\"dateModified\":\"2024-04-22T15:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448205,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/17\/ecuador-referendo-consulta-cambios-orix\/","url_meta":{"origin":1448369,"position":0},"title":"\u00bfPor qu\u00e9 hay referendo y consulta este domingo en Ecuador y qu\u00e9 cambios legales y constitucionales propone?","author":"","date":"abril 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los ecuatorianos volver\u00e1n a las urnas este domingo 21 de abril para decidir sobre reformas legales y cambios a la Constituci\u00f3n planteados por el presidente Daniel Noboa a trav\u00e9s de 11 preguntas \u2014de referendo y consulta popular\u2014 enfocadas en las \u00e1reas de seguridad, justicia, empleo y arbitrajes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448710,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/30\/irene-velez-secretaria-comunicacion-ecuador-orix\/","url_meta":{"origin":1448369,"position":1},"title":"Irene V\u00e9lez es la nueva secretaria de Comunicaci\u00f3n de Ecuador en reemplazo de Roberto Izurieta","author":"","date":"abril 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La columnista y analista pol\u00edtica Irene V\u00e9lez Froment, de 32 a\u00f1os, es la nueva secretaria de Comunicaci\u00f3n del Gobierno del presidente de Ecuador, Daniel Noboa, y tendr\u00e1 el reto de dirigir la pol\u00edtica comunicacional para los pr\u00f3ximos meses de administraci\u00f3n.As\u00ed lo dio a conocer este martes Roberto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448502,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/25\/casi-7-de-cada-10-ecuatorianos-rechazaron-preguntas-referendo-de-noboa-sobre-economia-y-empleo-trax\/","url_meta":{"origin":1448369,"position":2},"title":"Casi 7 de cada 10 ecuatorianos rechazaron las preguntas del referendo de Noboa sobre econom\u00eda y empleo","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) -- Mientras las preguntas sobre seguridad incluidas en el referendo y la consulta popular impulsados por Daniel Noboa obtuvieron un apoyo mayoritario de los ecuatorianos, aquellas sobre econom\u00eda y empleo fueron rechazadas por casi 7 de cada 10 ciudadanos, de acuerdo con los datos del Consejo Nacional\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448291,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/19\/preguntas-referendo-consulta-popular-ecuador-implicaciones-alcances-orix\/","url_meta":{"origin":1448369,"position":3},"title":"\u00bfCu\u00e1les son las preguntas del referendo y la consulta popular en Ecuador? Esta es una gu\u00eda de sus implicaciones y alcances","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La papeleta electoral que recibir\u00e1n los votantes en Ecuador este domingo 21 de abril durante el referendo y la consulta popular incluir\u00e1 11 preguntas a las que los ciudadanos deber\u00e1n responder \u201cs\u00ed\u201d o \u201cno\u201d, como una expresi\u00f3n de aprobaci\u00f3n o rechazo a la propuesta de reformas legales y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448399,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/23\/5-cosas-23-abril-referendo-ecuador-orix\/","url_meta":{"origin":1448369,"position":4},"title":"Las 5 cosas que debes saber este 23 de abril: \u00bfQu\u00e9 sigue para Ecuador tras la consulta popular y el referendo?","author":"","date":"abril 23, 2024","format":false,"excerpt":"Encuentran fosa com\u00fan en un hospital de Gaza. TikTok promete desafiar legalmente su posible prohibici\u00f3n en EE.UU. Momento \"m\u00e1gico\": surfista comparte ola con una manada de delfines. Esto es lo que debes saber para comenzar el d\u00eda.\u00a0Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu correo1. \u00bfQu\u00e9\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448366,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/resultados-parciales-referendo-ecuador-consulta-popular-orix\/","url_meta":{"origin":1448369,"position":5},"title":"Resultados parciales del referendo y consulta popular en Ecuador","author":"","date":"abril 22, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) -- La presidenta del Consejo Nacional Electoral de Ecuador, Diana Atamaint inform\u00f3 este domingo en cadena nacional los resultados de conteo r\u00e1pido del referendo celebrado en Ecuador.Los resultados iniciales, seg\u00fan inform\u00f3 Atamaint, fueron los siguientes:PREGUNTAS DE REFERENDOPREGUNTA A:\u00bfEst\u00e1 usted de acuerdo con que se permita el apoyo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448369"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448369\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}