{"id":1448384,"date":"2024-04-22T18:03:46","date_gmt":"2024-04-23T01:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/"},"modified":"2024-04-22T18:03:46","modified_gmt":"2024-04-23T01:03:46","slug":"lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/","title":{"rendered":"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo este lunes que el incidente que tuvo la candidata presidencial del oficialismo Claudia Sheinbaum durante su gira de campa\u00f1a por Chiapas el domingo, en donde fue abordada por hombres encapuchados en su paso por la sierra, podr\u00eda ser un montaje con propaganda de opositores.<\/p>\n<p>\u201cS\u00ed fueron personas encapuchadas las que detuvieron la camioneta en que se trasladaba Claudia, eso lo podemos decir. Grabando. Y ya cuando pasan esas cosas ya sabemos que es muy probable que sea propaganda, porque el que va a hacer un planteamiento ni va encapuchado ni est\u00e1 grabando\u201d, dijo L\u00f3pez Obrador en su conferencia matutina, sin ofrecer pruebas sobre el presunto montaje.<\/p>\n<p>&#171;Claudia Sheinbaum va a tener que romper con el presidente&#187;, dice el experto Lorenzo C\u00f3rdova<\/p>\n<p>El auto en el que se desplazaba Sheinbaum fue detenido por hombres encapuchados cuando se desplazaba por el estado de Chiapas, en donde encabez\u00f3 actos de campa\u00f1a. Los individuos le pidieron a Sheinbaum que, de llegar al poder, no se olvide de los problemas de seguridad que sufre la zona serrana de Chiapas.<\/p>\n<p>El propio L\u00f3pez Obrador mostr\u00f3 en la conferencia de prensa el incidente, en el que Sheinbaum escucha desde el asiento del copiloto con la ventana abierta a un grupo de personas vestidas de negro, que no revelaron su identidad, pidi\u00e9ndole que el Gobierno haga algo por la regi\u00f3n.<\/p>\n<p>&#171;Acu\u00e9rdese de la gente pobre, nada m\u00e1s eso le queremos decir, no estamos en contra del gobierno, ll\u00e9vese eso en su mente. No estamos en contra de ustedes. Somos como pueblo, estamos por ac\u00e1 tres d\u00edas por semana cuidando a nuestro pueblo&#187;, le dice una de las personas encapuchadas a la candidata.<\/p>\n<p>\u00bfQu\u00e9 implicar\u00eda para M\u00e9xico tener su primera presidenta y en qu\u00e9 se diferencian Claudia Sheinbaum y X\u00f3chitl G\u00e1lvez?<\/p>\n<p>&#171;Si alguien tiene una denuncia, \u00bfpara qu\u00e9 se va a encapuchar?&#187;, cuestion\u00f3 el mandatario cuando se le pregunt\u00f3 por los hechos del domingo. L\u00f3pez Obrador agreg\u00f3 que no es inusual que las personas busquen a los candidatos para hacer peticiones pero que &#171;se quejan sin taparse la cara&#187;.<\/p>\n<p>Sheinbaum declar\u00f3 ante medios locales que le pareci\u00f3 &#171;muy extra\u00f1o&#187; el intercambio con los encapuchados, y que no se sinti\u00f3 intimidada.<\/p>\n<p>Este viernes, el Gobierno de Estados Unidos emiti\u00f3 una restricci\u00f3n de viaje para sus empleados en ciertas zonas de Chiapas por \u201cel aumento de la violencia y las preocupaciones de seguridad\u201d. Las \u00e1reas restringidas incluyen algunas carreteras y caminos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo este lunes que el incidente que tuvo la candidata presidencial del oficialismo Claudia Sheinbaum durante su gira de campa\u00f1a por Chiapas el domingo, en donde fue abordada por hombres encapuchados en su paso por la sierra, podr\u00eda ser un montaje con propaganda de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448384","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo este lunes que el incidente que tuvo la candidata presidencial del oficialismo Claudia Sheinbaum durante su gira de campa\u00f1a por Chiapas el domingo, en donde fue abordada por hombres encapuchados en su paso por la sierra, podr\u00eda ser un montaje con propaganda de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T01:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas\",\"datePublished\":\"2024-04-23T01:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/\"},\"wordCount\":470,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/\",\"name\":\"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-23T01:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/","og_locale":"es_ES","og_type":"article","og_title":"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, dijo este lunes que el incidente que tuvo la candidata presidencial del oficialismo Claudia Sheinbaum durante su gira de campa\u00f1a por Chiapas el domingo, en donde fue abordada por hombres encapuchados en su paso por la sierra, podr\u00eda ser un montaje con propaganda de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-23T01:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/"},"author":{"name":"","@id":""},"headline":"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas","datePublished":"2024-04-23T01:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/"},"wordCount":470,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/","name":"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-23T01:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"L\u00f3pez Obrador minimiza la petici\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/22\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-23T01:03:46Z","datePublished":"2024-04-23T01:03:46Z","dateModified":"2024-04-23T01:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"L\\u00f3pez Obrador minimiza la petici\\u00f3n de un grupo de encapuchados que interceptaron a Claudia Sheinbaum en Chiapas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/22\\\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/22\\\/lopez-obrador-peticion-encapuchados-claudia-sheinbaum-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-23T01:03:46Z\",\"datePublished\":\"2024-04-23T01:03:46Z\",\"dateModified\":\"2024-04-23T01:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449569,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/17\/ola-violencia-chiapas-semanas-elecciones-mexico-lucero-lopez-mata-orix\/","url_meta":{"origin":1448384,"position":0},"title":"C\u00f3mo escal\u00f3 la ola de violencia en Chiapas, a dos semanas de las elecciones en M\u00e9xico","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La muerte de la candidata a alcaldesa Lucero L\u00f3pez Maza en el municipio de La Concordia, en Chiapas, en un ataque que dej\u00f3 otros cinco fallecidos, volvi\u00f3 a manchar de sangre la campa\u00f1a electoral en el estado mexicano, donde operan grupos criminales de tr\u00e1fico de drogas y de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452944,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/22\/morena-luisa-alcalde-presidenta-lopez-obrador-orix\/","url_meta":{"origin":1448384,"position":1},"title":"Morena elige a Luisa Mar\u00eda Alcalde como su nueva presidenta; el hijo de L\u00f3pez Obrador ser\u00e1 secretario de Organizaci\u00f3n","author":"","date":"septiembre 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El partido oficialista Morena eligi\u00f3 este domingo a quienes conformar\u00e1n su nueva dirigencia, que a partir de ahora estar\u00e1 encabezada por Luisa Mar\u00eda Alcalde como presidenta y Carolina Rangel como secretaria general, inform\u00f3 el l\u00edder partidista saliente, Mario Delgado, en un mensaje en su cuenta de X\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449947,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/02\/quien-es-claudia-sheinbaum-presidenta-electa-elecciones-mexico-ganadora-orix\/","url_meta":{"origin":1448384,"position":2},"title":"\u00bfQui\u00e9n es Claudia Sheinbaum? As\u00ed es la ganadora de la elecci\u00f3n presidencial en M\u00e9xico","author":"","date":"junio 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00a0Claudia Sheinbaum, exjefa de Gobierno de la Ciudad de M\u00e9xico, es la ganadora de la elecci\u00f3n presidencial de M\u00e9xico seg\u00fan los resultados preliminares y ser\u00e1 la sucesora de Andr\u00e9s Manuel L\u00f3pez Obrador.Sheinbaum ser\u00e1 la primera presidenta en la historia de M\u00e9xico.Elecciones M\u00e9xico 2024 en vivo: \u00faltima hora,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447498,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/28\/milei-amlo-xochitl-galvez-claudia-sheinbaum-orix\/","url_meta":{"origin":1448384,"position":3},"title":"X\u00f3chitl G\u00e1lvez y Claudia Sheinbaum responden a Milei luego de que llamara &#171;ignorante&#187; a AMLO","author":"","date":"marzo 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, fue objeto de duras palabras del mandatario de Argentina, Javier Milei. En entrevista con Andr\u00e9s Oppenheimer para CNN, el gobernante argentino llam\u00f3 a su hom\u00f3logo mexicano un \"ignorante\". El tema lleg\u00f3 a la campa\u00f1a presidencial: tanto la candidata oficialista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446461,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/quien-es-claudia-sheinbaum-elecciones-presidenciales-mexico-morena-orix-2\/","url_meta":{"origin":1448384,"position":4},"title":"\u00bfQui\u00e9n es Claudia Sheinbaum? As\u00ed es la candidata que representa a Morena en M\u00e9xico","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Claudia Sheinbaum, exjefa de Gobierno de la Ciudad de M\u00e9xico, es la candida del gobernante partido Morena para los comicios de junio de 2024, en los que se elegir\u00e1 al sucesor del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.Sheinbaum parte en la campa\u00f1a como favorita, seg\u00fan encuestas. \u00bfQui\u00e9n es?Claudia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445732,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/20\/quien-es-claudia-sheinbaum-asi-es-la-candidata-que-representa-a-morena-en-mexico\/","url_meta":{"origin":1448384,"position":5},"title":"\u00bfQui\u00e9n es Claudia Sheinbaum? As\u00ed es la candidata que representa a Morena en M\u00e9xico","author":"","date":"febrero 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Claudia Sheinbaum, exjefa de Gobierno de la Ciudad de M\u00e9xico, es la candida del gobernante partido Morena para los comicios de junio de 2024, en los que se elegir\u00e1 al sucesor del presidente Andr\u00e9s Manuel L\u00f3pez Obrador.Sheinbaum parte en la campa\u00f1a como favorita, seg\u00fan encuestas. \u00bfQui\u00e9n es?Claudia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448384"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448384\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}