{"id":1448458,"date":"2024-04-24T03:03:44","date_gmt":"2024-04-24T10:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/"},"modified":"2024-04-24T03:03:44","modified_gmt":"2024-04-24T10:03:44","slug":"queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/","title":{"rendered":"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores"},"content":{"rendered":"<p>(CNN) &#8212; Un sindicato que representa a los ingenieros de Boeing aleg\u00f3 que el fabricante de aviones tom\u00f3 represalias contra dos empleados que, en ese momento, trabajaban en nombre de la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA) para supervisar la fabricaci\u00f3n.<\/p>\n<p>Las acusaciones salieron a la luz en los \u00faltimos d\u00edas despu\u00e9s de que la Sociedad de Empleados Profesionales de Ingenier\u00eda Aeroespacial (SPEEA) presentara una queja ante la Junta Nacional de Relaciones Laborales en nombre de uno de los dos ingenieros que buscaban descubrir un informe de la investigaci\u00f3n interna de Boeing ( BA ) sobre el incidente que fue presentado ante la FAA.<\/p>\n<p>La denuncia y un comunicado de prensa emitido este martes por el sindicato describen c\u00f3mo los dos trabajadores \u201cinsistieron en que la empresa reevaluara el trabajo de ingenier\u00eda anterior en el 777 y el 787 para tener en cuenta un nuevo aviso de la FAA\u201d en 2022.<\/p>\n<p>SPEEA dice que Boeing inicialmente rechaz\u00f3 rehacer el trabajo antes de aceptar hacerlo, pero luego supuestamente tom\u00f3 represalias contra los dos en sus revisiones de desempe\u00f1o.<\/p>\n<p>El sindicato dice que est\u00e1 intentando apelar una decisi\u00f3n de no cambiar la evaluaci\u00f3n de desempe\u00f1o de uno de los trabajadores. En el comunicado de prensa dec\u00eda que \u201cel otro (trabajador) renunci\u00f3 a Boeing por la forma en que fue tratado\u201d.<\/p>\n<p>La denuncia, fechada el 18 de abril, dice que &#171;estos dos empleados recibieron (id\u00e9nticamente) calificaciones degradadas en la parte &#8216;Valores de desempe\u00f1o'&#187; de una revisi\u00f3n de desempe\u00f1o despu\u00e9s de plantear sus inquietudes. Contin\u00faa diciendo que uno de los empleados &#171;present\u00f3 un &#8216;Informe Speak Up&#8217; para cuestionar esta aparente represalia&#187;. Luego, Boeing investig\u00f3 el incidente, pero el sindicato dice que la compa\u00f1\u00eda no le proporcion\u00f3 una copia del informe.<\/p>\n<p>Boeing dice que la investigaci\u00f3n fue parte de un proceso confidencial y que el informe s\u00f3lo pod\u00eda compartirse con la FAA.<\/p>\n<p>\u201cTenemos tolerancia cero con las represalias y alentamos a nuestros empleados a hablar cuando ven un problema. Despu\u00e9s de una extensa revisi\u00f3n de la documentaci\u00f3n y de entrevistar a m\u00e1s de una docena de testigos, nuestros investigadores no encontraron evidencia de represalias o interferencia. Hemos determinado que las acusaciones no tienen fundamento\u201d, dijo Boeing en un comunicado.<\/p>\n<p>La FAA dice que est\u00e1 investigando la situaci\u00f3n.<\/p>\n<p>La semana pasada, un denunciante de Boeing, Sam Salehpour, dijo al Congreso que le preocupa la forma en que Boeing ha estado fusionando sus fuselajes en el 787 y el 777 y que enfrentaba represalias despu\u00e9s de plantear sus preocupaciones.<\/p>\n<p>La denuncia presentada en nombre de los dos ingenieros se refiere a un tema diferente: las redes inform\u00e1ticas a bordo de los aviones. El sindicato dice que los gerentes de Boeing &#171;se opusieron firmemente&#187; a volver a ejecutar los c\u00e1lculos relacionados con los sistemas bas\u00e1ndose en nuevas suposiciones, citando costos y retrasos en la producci\u00f3n, pero que Boeing finalmente acept\u00f3.<\/p>\n<p>\u201cDespu\u00e9s de casi seis meses de debate, los dos ingenieros, con el respaldo de la FAA, prevalecieron. Boeing volvi\u00f3 a hacer el an\u00e1lisis requerido\u201d, dice el comunicado de prensa.<\/p>\n<p>El sindicato dice que las evaluaciones negativas de desempe\u00f1o podr\u00edan perjudicar a los ingenieros cuando se trata de ascensos o podr\u00edan provocar despidos.<\/p>\n<p>Cronolog\u00eda de Boeing: una mirada a los turbulentos problemas del gigante a\u00e9reo en los \u00faltimos a\u00f1os<\/p>\n<p>&#171;Incluso despu\u00e9s de que el gerente de los dos ingenieros admitiera que los hab\u00eda calificado mal a ambos a petici\u00f3n de los gerentes del 777 y del 787, que se hab\u00edan visto obligados a volver a presentar su trabajo, Boeing se neg\u00f3 a cambiar las evaluaciones de desempe\u00f1o de los ingenieros&#187;, dice el comunicado de prensa. .<\/p>\n<p>\u201cYa sea que se trate de &#8216;Represalia&#8217; con R may\u00fascula o no, el hecho es que los dos miembros designados por la ODA para la SPEEA hicieron lo correcto y se mantuvieron firmes a pesar de la fuerte presi\u00f3n de Boeing, y luego fueron golpeados con evaluaciones de desempe\u00f1o que perjudicaron sus carreras. Esto ayuda a mostrar por qu\u00e9 Boeing no tiene una cultura de seguridad saludable\u201d, dijo en el comunicado el Director de Desarrollo Estrat\u00e9gico de SPEEA, Rich Plunkett.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un sindicato que representa a los ingenieros de Boeing aleg\u00f3 que el fabricante de aviones tom\u00f3 represalias contra dos empleados que, en ese momento, trabajaban en nombre de la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA) para supervisar la fabricaci\u00f3n. Las acusaciones salieron a la luz en los \u00faltimos d\u00edas despu\u00e9s de que la Sociedad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448458","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un sindicato que representa a los ingenieros de Boeing aleg\u00f3 que el fabricante de aviones tom\u00f3 represalias contra dos empleados que, en ese momento, trabajaban en nombre de la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA) para supervisar la fabricaci\u00f3n. Las acusaciones salieron a la luz en los \u00faltimos d\u00edas despu\u00e9s de que la Sociedad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-24T10:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores\",\"datePublished\":\"2024-04-24T10:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/\"},\"wordCount\":743,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/\",\"name\":\"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-24T10:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores - Noticias","og_description":"(CNN) &#8212; Un sindicato que representa a los ingenieros de Boeing aleg\u00f3 que el fabricante de aviones tom\u00f3 represalias contra dos empleados que, en ese momento, trabajaban en nombre de la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA) para supervisar la fabricaci\u00f3n. Las acusaciones salieron a la luz en los \u00faltimos d\u00edas despu\u00e9s de que la Sociedad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-24T10:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/"},"author":{"name":"","@id":""},"headline":"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores","datePublished":"2024-04-24T10:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/"},"wordCount":743,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/","name":"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-24T10:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/24\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-24T10:03:44Z","datePublished":"2024-04-24T10:03:44Z","dateModified":"2024-04-24T10:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Queja laboral revela acusaciones de represalias de Boeing contra dos trabajadores\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/24\\\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/24\\\/queja-laboral-revela-acusaciones-de-represalias-de-boeing-contra-dos-trabajadores-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-24T10:03:44Z\",\"datePublished\":\"2024-04-24T10:03:44Z\",\"dateModified\":\"2024-04-24T10:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452669,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/14\/huelga-boeing-trabajadores-trax\/","url_meta":{"origin":1448458,"position":0},"title":"De qu\u00e9 se trata realmente la huelga de Boeing","author":"","date":"septiembre 14, 2024","format":false,"excerpt":"(CNN) -- En el centro de la huelga de Boeing que comenz\u00f3 este viernes hay una historia sobre lo que ocurre cuando los ejecutivos taca\u00f1os pierden el rumbo y recae en los trabajadores la responsabilidad de que todo vuelva a la normalidad.El a\u00f1o pasado, Boeing no obtuvo beneficios. De hecho,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465094,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/04\/boeing-huelga-menos-tres-plantas-defensa-trax\/","url_meta":{"origin":1448458,"position":1},"title":"Boeing enfrenta su segunda huelga en menos de un a\u00f1o en tres plantas de defensa","author":"","date":"agosto 4, 2025","format":false,"excerpt":"Boeing sufri\u00f3 el lunes su segunda huelga en menos de un a\u00f1o, cuando 3.200 maquinistas contratados por hora abandonaron sus trabajos aeroespaciales en el \u00e1rea de San Luis.Los miembros de la Asociaci\u00f3n Internacional de Maquinistas (IAM) votaron para autorizar una huelga en tres plantas de defensa a partir de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456834,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/21\/huelga-contra-amazon-extiende-trax\/","url_meta":{"origin":1448458,"position":2},"title":"Los conductores del sindicato Teamsters ampl\u00edan la huelga contra Amazon","author":"","date":"diciembre 21, 2024","format":false,"excerpt":"El sindicato de los Teamsters anunci\u00f3 en la noche del viernes que los trabajadores de un enorme centro de clasificaci\u00f3n y distribuci\u00f3n de Amazon en Staten Island, Nueva York, se unieron a los miles de miembros del sindicato que comenzaron una huelga esta semana contra el gigante del comercio electr\u00f3nico.Pero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457104,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/31\/2024-boeing-peor-tragedia-aerea-trax\/","url_meta":{"origin":1448458,"position":3},"title":"El terrible a\u00f1o de Boeing termina con la peor tragedia a\u00e9rea de 2024","author":"","date":"diciembre 31, 2024","format":false,"excerpt":"El mal a\u00f1o de Boeing termin\u00f3 en tragedia el domingo, cuando un 737 de la aerol\u00ednea coreana de bajo costo Jeju Air se estrell\u00f3, con un saldo de 179 pasajeros y tripulaci\u00f3n muertos.A\u00fan no est\u00e1 claro qu\u00e9 caus\u00f3 el siniestro, y la investigaci\u00f3n podr\u00eda llevar meses. Por el momento no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450453,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/17\/ceo-boeing-lejos-perfecta-fallas-seguridad-trax\/","url_meta":{"origin":1448458,"position":4},"title":"CEO de Boeing admite que la empresa est\u00e1 &#171;lejos de ser perfecta&#187; despu\u00e9s de una avalancha de fallas de seguridad","author":"","date":"junio 17, 2024","format":false,"excerpt":"(CNN) -- El CEO de Boeing, Dave Calhoun, planea disculparse por las recientes fallas de seguridad de Boeing en un testimonio ante el Senado este martes y admitir problemas con su sistema de seguridad, pero rechazar\u00e1 las afirmaciones de algunos denunciantes de que la compa\u00f1\u00eda cre\u00f3 los problemas al tomar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458451,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/08\/amazon-sindicato-carolina-del-norte-trax\/","url_meta":{"origin":1448458,"position":5},"title":"Amazon enfrenta un nuevo desaf\u00edo sindical en Carolina del Norte","author":"","date":"febrero 8, 2025","format":false,"excerpt":"Carolina del Norte es un estado generalmente hostil a los sindicatos. Amazon es una empresa que, hist\u00f3ricamente, es extremadamente hostil a los sindicatos. Ahora, un nuevo sindicato intenta representar a m\u00e1s de 4.000 trabajadores de Amazon en una de las instalaciones del minorista en l\u00ednea all\u00ed.La Junta Nacional de Relaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448458"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448458\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}