{"id":1448488,"date":"2024-04-24T19:03:44","date_gmt":"2024-04-25T02:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/"},"modified":"2024-04-24T19:03:44","modified_gmt":"2024-04-25T02:03:44","slug":"boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/","title":{"rendered":"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Boeing registr\u00f3 unas p\u00e9rdidas ligeramente inferiores en el primer trimestre en comparaci\u00f3n con el mismo periodo del a\u00f1o anterior, pero se\u00f1al\u00f3 que la correcci\u00f3n de los problemas que acapararon la atenci\u00f3n tras el incidente de Alaska Air retrasar\u00e1 su recuperaci\u00f3n financiera y le costar\u00e1 US$ 443 millones en compensaciones a sus clientes de las aerol\u00edneas.<\/p>\n<p>Boeing registr\u00f3 una p\u00e9rdida de explotaci\u00f3n de US$ 388 millones, o US$ 1,13 por acci\u00f3n, frente a los US$ 440 millones que perdi\u00f3 sobre esa base un a\u00f1o antes. Esta cifra fue significativamente inferior a las previsiones de los analistas de US$ 1,63 por acci\u00f3n en el trimestre. Pero la mejora se produjo fuera de su unidad clave de aviones comerciales, donde las p\u00e9rdidas por operaciones casi se duplicaron hasta US$ 1.100 millones.<\/p>\n<p>\u00bfTendr\u00e1 p\u00e9rdidas Alaska Airlines despu\u00e9s del incidente con un Boeing 737 Max 9?<\/p>\n<p>Los ingresos cayeron US$ 1.400 millones, o un 8%, hasta los US$ 16.600 millones, ya que los problemas del fabricante de aviones provocaron una fuerte ca\u00edda en las entregas de aviones a sus clientes del sector a\u00e9reo. La empresa obtiene la mayor parte de su dinero de las ventas de aviones comerciales solo tras las entregas a los clientes.<\/p>\n<p>Los resultados financieros, ligeramente mejores de lo esperado, no compensan a una empresa que se enfrenta a las preguntas del Congreso, los organismos reguladores y el p\u00fablico viajero sobre la calidad y seguridad de sus aviones. Boeing no s\u00f3lo se esfuerza por reparar su maltrecha reputaci\u00f3n, sino tambi\u00e9n por satisfacer a los clientes de las aerol\u00edneas que se sienten perjudicados por no recibir los aviones que se les hab\u00edan prometido. Boeing ha declarado que est\u00e1 tomando las medidas necesarias para solucionar los problemas de calidad. Pero esas medidas seguir\u00e1n provocando p\u00e9rdidas adicionales y el incumplimiento de los objetivos de entrega en los pr\u00f3ximos meses.<\/p>\n<p>Boeing ha anunciado que producir\u00e1 menos aviones 737 Max de los previstos inicialmente durante el resto del a\u00f1o, mientras intenta solucionar los problemas de sus cadenas de montaje. La producci\u00f3n de su 787 Dreamliner tambi\u00e9n se ver\u00e1 limitada por problemas con los proveedores.<\/p>\n<p>Denunciante de Boeing: &#171;Est\u00e1n poniendo a la venta aviones defectuosos&#187;<\/p>\n<p>&#171;Nos tomaremos el tiempo necesario para reforzar nuestros sistemas de gesti\u00f3n de la calidad y la seguridad, y este trabajo nos posicionar\u00e1 para un futuro m\u00e1s fuerte y estable&#187;, dijo el consejero delegado Dave Calhoun, que anunci\u00f3 durante el trimestre sus planes de dejar el cargo a finales de a\u00f1o.<\/p>\n<p>Seg\u00fan la empresa, los resultados se vieron perjudicados por las compensaciones a los clientes de las aerol\u00edneas por la inmovilizaci\u00f3n en tierra durante tres semanas de los aviones 737 Max 9, tras el incidente del 5 de enero en el que un tap\u00f3n de la puerta estall\u00f3 en un vuelo de Alaska Airlines dejando un enorme agujero en el costado del avi\u00f3n poco despu\u00e9s del despegue.<\/p>\n<p>Se desprende una parte de un avi\u00f3n en pleno vuelo de Alaska 1:24<\/p>\n<p>Alaska Air y United Airlines, las dos compa\u00f1\u00edas con m\u00e1s aviones 737 Max 9 en sus flotas, ya han anunciado que han llegado a acuerdos de compensaci\u00f3n con Boeing.<\/p>\n<p>El incidente ha desencadenado una serie de investigaciones sobre Boeing por parte de la Junta Nacional de Seguridad en el Transporte, la Administraci\u00f3n Federal de Aviaci\u00f3n y el Departamento de Justicia, la \u00faltima de las cuales podr\u00eda exponer a la empresa a responsabilidades penales. Tambi\u00e9n ha centrado la atenci\u00f3n en la seguridad y calidad de sus aviones, y en su forma de tratar a los empleados que plantean inquietudes al respecto, incluidas audiencias en el Congreso.<\/p>\n<p>Cronolog\u00eda de Boeing: una mirada a los turbulentos problemas del gigante a\u00e9reo en los \u00faltimos a\u00f1os<\/p>\n<p>Boeing ha afirmado que ha asumido un nuevo compromiso para mejorar sus problemas de calidad y seguridad y que desea que los empleados que tengan inquietudes las expongan.<\/p>\n<p>Calhoun dijo que conf\u00eda en que Boeing podr\u00e1 hacer los cambios que necesita para volver a ser rentable por primera vez desde 2018, pero dijo que los cambios que har\u00e1 retrasar\u00e1n el cronograma para volver a ser rentable.<\/p>\n<p>&#171;Si bien este esfuerzo ralentizar\u00e1 nuestro calendario de recuperaci\u00f3n, ahora estamos viendo puntos de prueba que nos dan confianza en que comenzaremos a estabilizarnos y mejorar el rendimiento en el futuro&#187;, dijo en la llamada de inversores de la compa\u00f1\u00eda.<\/p>\n<p>La empresa no quiso dar ninguna orientaci\u00f3n sobre cu\u00e1nto dinero perder\u00e1 este a\u00f1o ni sobre cu\u00e1ndo espera ser rentable exactamente. Calhoun dijo que la compa\u00f1\u00eda conf\u00eda en su objetivo de producir un flujo de caja positivo de US$ 10.000 millones al a\u00f1o, aunque dijo que ahora est\u00e1 buscando hacerlo m\u00e1s tarde en la ventana de 2025 a 2026 que se hab\u00eda fijado como objetivo.<\/p>\n<p>El pl\u00e1stico cubre el exterior del \u00e1rea del tap\u00f3n del fuselaje del Boeing 737 Max 9 de Alaska Airlines, donde un tap\u00f3n de la puerta del avi\u00f3n explot\u00f3 en un vuelo del 5 de enero. El incidente ha provocado una nueva atenci\u00f3n sobre los problemas con los controles de seguridad y calidad en Boeing. (NTSB\/Getty Images)<\/p>\n<p>&#171;Estamos absolutamente comprometidos a hacer todo lo que podamos para asegurarnos de que nuestros reguladores, nuestros clientes y, lo que es m\u00e1s importante, nuestros empleados y el p\u00fablico conf\u00edan al 100% en Boeing&#187;, dijo. &#171;Es importante que nuestra gente y nuestros accionistas comprendan lo prometedor que parece el futuro de Boeing. La demanda en toda nuestra cartera sigue siendo incre\u00edblemente fuerte. Nuestra gente es de clase mundial. Tenemos mucho trabajo por delante, pero estoy orgulloso de nuestro equipo y sigo confiando plenamente en nuestro futuro&#187;.<\/p>\n<p>Pero la agencia de calificaci\u00f3n crediticia Moody&#8217;s no conf\u00eda tanto en las perspectivas de Boeing para enderezar el rumbo. Rebaj\u00f3 la calificaci\u00f3n crediticia de la empresa a Baa2, justo un escal\u00f3n por encima del estatus de bono basura, y le ha dado una perspectiva negativa, lo que sugiere que podr\u00eda producirse otra rebaja en el horizonte.<\/p>\n<p>Moody&#8217;s cree que &#171;los vientos en contra que azotan a los aviones comerciales persistir\u00e1n al menos hasta 2026&#187;. Y se\u00f1al\u00f3 que el flujo de caja anual previsto de la empresa no alcanzar\u00e1 a los US$ 4.300 millones de deuda que vencen en 2025 ni a los US$ 8.000 millones que vencen en 2026, por lo que Boeing tendr\u00e1 que emitir nueva deuda para financiar esos d\u00e9ficits.<\/p>\n<p>AN\u00c1LISIS | La afici\u00f3n del CEO de Boeing por reducir costos no se aplica a sus viajes en el jet de la compa\u00f1\u00eda<\/p>\n<p>Las acciones de Boeing (BA), que hab\u00edan perdido un 35% en lo que va de a\u00f1o hasta el cierre del martes, cayeron otro 3% en las operaciones de la tarde tras la llamada de los inversores, despu\u00e9s de haber subido m\u00e1s de un 3% en las primeras operaciones por la p\u00e9rdida menor de lo previsto.<\/p>\n<p>Boeing ha tenido una serie de p\u00e9rdidas y problemas con la calidad de sus aviones que se remontan al menos a cinco a\u00f1os atr\u00e1s. Dos accidentes mortales del 737 Max a finales de 2018 y principios de 2019 en los que murieron 346 personas estuvieron vinculados a un defecto de dise\u00f1o en el avi\u00f3n y llevaron a una inmovilizaci\u00f3n de 20 meses del modelo m\u00e1s vendido de Boeing. Tuvo problemas posteriores con la calidad de los aviones una vez que el 737 Max volvi\u00f3 al servicio.<\/p>\n<p>En total, la empresa ha registrado p\u00e9rdidas operativas de US$ 31.900 millones desde el inicio de la inmovilizaci\u00f3n en 2019.<\/p>\n<p>Pero inform\u00f3 de un mes r\u00e9cord de pedidos en diciembre, coronando lo que hab\u00eda sido uno de sus mejores a\u00f1os en t\u00e9rminos de ventas de aviones comerciales. Las entregas tambi\u00e9n alcanzaron un m\u00e1ximo de cinco a\u00f1os, e incluso inform\u00f3 de un raro beneficio operativo b\u00e1sico de US$ 90 millones para el cuarto trimestre de 2023. Tambi\u00e9n anunci\u00f3 planes para aumentar la producci\u00f3n del 737 Max a lo largo de 2024 con el fin de volver a una rentabilidad sostenida.<\/p>\n<p>Pero cuando comunic\u00f3 esos mejores resultados para 2023, ya se hab\u00eda producido el incidente a bordo del vuelo de Alaska Air, echando por tierra las esperanzas de que estaba a punto de dejar atr\u00e1s sus problemas financieros.<\/p>\n<p>Aunque la NTSB no ha determinado de qui\u00e9n es espec\u00edficamente la culpa del accidente, una investigaci\u00f3n preliminar ha descubierto que el avi\u00f3n sali\u00f3 de una f\u00e1brica de Boeing sin los cuatro pernos necesarios para mantener el tap\u00f3n de la puerta en su sitio.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Boeing registr\u00f3 unas p\u00e9rdidas ligeramente inferiores en el primer trimestre en comparaci\u00f3n con el mismo periodo del a\u00f1o anterior, pero se\u00f1al\u00f3 que la correcci\u00f3n de los problemas que acapararon la atenci\u00f3n tras el incidente de Alaska Air retrasar\u00e1 su recuperaci\u00f3n financiera y le costar\u00e1 US$ 443 millones en compensaciones a sus clientes de las [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448488","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Boeing registr\u00f3 unas p\u00e9rdidas ligeramente inferiores en el primer trimestre en comparaci\u00f3n con el mismo periodo del a\u00f1o anterior, pero se\u00f1al\u00f3 que la correcci\u00f3n de los problemas que acapararon la atenci\u00f3n tras el incidente de Alaska Air retrasar\u00e1 su recuperaci\u00f3n financiera y le costar\u00e1 US$ 443 millones en compensaciones a sus clientes de las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T02:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9\",\"datePublished\":\"2024-04-25T02:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/\"},\"wordCount\":1486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/\",\"name\":\"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-25T02:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9 - Noticias","og_description":"(CNN) &#8212;\u00a0Boeing registr\u00f3 unas p\u00e9rdidas ligeramente inferiores en el primer trimestre en comparaci\u00f3n con el mismo periodo del a\u00f1o anterior, pero se\u00f1al\u00f3 que la correcci\u00f3n de los problemas que acapararon la atenci\u00f3n tras el incidente de Alaska Air retrasar\u00e1 su recuperaci\u00f3n financiera y le costar\u00e1 US$ 443 millones en compensaciones a sus clientes de las [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-25T02:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/"},"author":{"name":"","@id":""},"headline":"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9","datePublished":"2024-04-25T02:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/"},"wordCount":1486,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/","name":"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-25T02:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Boeing pagar\u00e1 US$ 443 millones a las aerol\u00edneas por la inmovilizaci\u00f3n del Max 9","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/24\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-25T02:03:44Z","datePublished":"2024-04-25T02:03:44Z","dateModified":"2024-04-25T02:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Boeing pagar\\u00e1 US$ 443 millones a las aerol\\u00edneas por la inmovilizaci\\u00f3n del Max 9\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/24\\\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/24\\\/boeing-pagara-443-millones-aerolineas-inmovilizacion-max-9-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-25T02:03:44Z\",\"datePublished\":\"2024-04-25T02:03:44Z\",\"dateModified\":\"2024-04-25T02:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458004,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/01\/29\/elon-musk-boeing-air-force-one-trax\/","url_meta":{"origin":1448488,"position":0},"title":"Elon Musk visita Boeing por el retraso de los nuevos aviones Air Force One","author":"","date":"enero 29, 2025","format":false,"excerpt":"Elon Musk aprovech\u00f3 su nuevo rol dedicado a la eficiencia gubernamental para visitar las operaciones de su competidor Boeing y analizar la demora en la renovaci\u00f3n de dos aviones 747 para convertirlos en la pr\u00f3xima generaci\u00f3n de aviones Air Force One, dijo el martes el CEO de Boeing, Kelly Ortberg.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448499,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/25\/ford-informa-de-una-perdida-masiva-por-cada-vehiculo-electrico-que-vendio-trax\/","url_meta":{"origin":1448488,"position":1},"title":"Ford informa de una p\u00e9rdida masiva por cada veh\u00edculo el\u00e9ctrico que vendi\u00f3","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- La unidad de veh\u00edculos el\u00e9ctricos de Ford inform\u00f3 que las p\u00e9rdidas se dispararon en el primer trimestre a US$ 1.300 millones, o us$ 132.000 por cada uno de los 10.000 veh\u00edculos que vendi\u00f3 en los primeros tres meses del a\u00f1o, lo que contribuy\u00f3 a reducir las ganancias de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449608,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/20\/trump-media-perdida-300-millones-trimestre-trax\/","url_meta":{"origin":1448488,"position":2},"title":"Trump Media perdi\u00f3 m\u00e1s de US$ 300 millones el \u00faltimo trimestre con ingresos muy escasos","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- Trump Media & Technology Group perdi\u00f3 m\u00e1s de US$ 300 millones durante el primer trimestre y gener\u00f3 muy pocos ingresos, anunci\u00f3 este lunes el propietario de Truth Social en un comunicado de prensa.Los resultados plantear\u00e1n preguntas adicionales sobre la valoraci\u00f3n multimillonaria de la nueva empresa p\u00fablica, que es\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450525,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/19\/boeing-crimen-corporativo-letal-familias-victimas-trax\/","url_meta":{"origin":1448488,"position":3},"title":"Boeing cometi\u00f3 &#171;el crimen corporativo m\u00e1s letal de la historia de EE.UU.&#187; y deber\u00eda ser multada con US$ 24.000 millones, dicen familias de v\u00edctimas","author":"","date":"junio 19, 2024","format":false,"excerpt":"Nueva York (CNN) -- Las familias que perdieron a sus seres queridos en dos accidentes de Boeing 737 Max dijeron el mi\u00e9rcoles que la compa\u00f1\u00eda cometi\u00f3 el \"crimen corporativo m\u00e1s letal de la historia de EE.UU.\" y pidieron al Departamento de Justicia que multe a la empresa con el m\u00e1ximo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465094,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/04\/boeing-huelga-menos-tres-plantas-defensa-trax\/","url_meta":{"origin":1448488,"position":4},"title":"Boeing enfrenta su segunda huelga en menos de un a\u00f1o en tres plantas de defensa","author":"","date":"agosto 4, 2025","format":false,"excerpt":"Boeing sufri\u00f3 el lunes su segunda huelga en menos de un a\u00f1o, cuando 3.200 maquinistas contratados por hora abandonaron sus trabajos aeroespaciales en el \u00e1rea de San Luis.Los miembros de la Asociaci\u00f3n Internacional de Maquinistas (IAM) votaron para autorizar una huelga en tres plantas de defensa a partir de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457104,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/31\/2024-boeing-peor-tragedia-aerea-trax\/","url_meta":{"origin":1448488,"position":5},"title":"El terrible a\u00f1o de Boeing termina con la peor tragedia a\u00e9rea de 2024","author":"","date":"diciembre 31, 2024","format":false,"excerpt":"El mal a\u00f1o de Boeing termin\u00f3 en tragedia el domingo, cuando un 737 de la aerol\u00ednea coreana de bajo costo Jeju Air se estrell\u00f3, con un saldo de 179 pasajeros y tripulaci\u00f3n muertos.A\u00fan no est\u00e1 claro qu\u00e9 caus\u00f3 el siniestro, y la investigaci\u00f3n podr\u00eda llevar meses. Por el momento no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448488"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448488\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}