{"id":1448500,"date":"2024-04-25T03:03:37","date_gmt":"2024-04-25T10:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/"},"modified":"2024-04-25T03:03:37","modified_gmt":"2024-04-25T10:03:37","slug":"rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","title":{"rendered":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio"},"content":{"rendered":"<p>(CNN) &#8212; Rusia vet\u00f3 este mi\u00e9rcoles una resoluci\u00f3n de las Naciones Unidas que propon\u00eda prohibir el uso de armas nucleares en el espacio exterior en medio de preocupaciones respaldadas por la inteligencia estadounidense de que Mosc\u00fa est\u00e9 tratando de desarrollar un dispositivo nuclear capaz de destruir sat\u00e9lites.<\/p>\n<p>El embajador ruso, Vassily Nebenzia, describi\u00f3 el borrador de la ONU como un \u201cespect\u00e1culo sucio\u201d y una \u201cestrategia c\u00ednica\u201d preparada por los partidarios de la resoluci\u00f3n, Estados Unidos y Jap\u00f3n.<\/p>\n<p>En febrero, el presidente Joe Biden confirm\u00f3 que Estados Unidos tiene informaci\u00f3n de que Rusia est\u00e1 desarrollando una capacidad nuclear antisat\u00e9lite. Posteriormente, tres fuentes familiarizadas con la inteligencia le dijeron a CNN que el arma podr\u00eda destruir sat\u00e9lites al crear una ola de energ\u00eda masiva cuando se detone.<\/p>\n<p>Antes de la votaci\u00f3n, altos funcionarios estadounidenses afirmaron que Rusia podr\u00eda estar ocultando algo si veta el texto.<\/p>\n<p>La embajadora estadounidense Linda Thomas-Greenfield se hizo eco de esas afirmaciones en su discurso despu\u00e9s de la votaci\u00f3n de este mi\u00e9rcoles.<\/p>\n<p>\u201cY por eso el veto de hoy plantea la pregunta: \u00bfPor qu\u00e9? \u00bfPor qu\u00e9, si ustedes siguen las reglas, no apoyar\u00edan una resoluci\u00f3n que las reafirme?\u201d ella pregunt\u00f3.<\/p>\n<p>\u201c\u00bfQu\u00e9 podr\u00edas estar escondiendo? Es desconcertante. Y es una pena\u201d.<\/p>\n<p>El embajador de Estados Unidos tambi\u00e9n conden\u00f3 la abstenci\u00f3n de China y dijo que Beijing \u201cha demostrado que preferir\u00eda defender a Rusia como su socio menor, que salvaguardar el r\u00e9gimen global de no proliferaci\u00f3n\u201d.<\/p>\n<p>Thomas-Greenfield dijo que la votaci\u00f3n de este mi\u00e9rcoles &#171;marca una oportunidad real perdida para reconstruir la confianza muy necesaria en las obligaciones existentes de control de armas&#187;.<\/p>\n<p>Una resoluci\u00f3n redactada por Estados Unidos y Jap\u00f3n hab\u00eda recibido apoyo interregional de m\u00e1s de 60 estados miembros.<\/p>\n<p>Tambi\u00e9n pidi\u00f3 a los estados miembros de la ONU que no desarrollen armas nucleares u otras armas de destrucci\u00f3n masiva dise\u00f1adas para ser colocadas en la \u00f3rbita de la Tierra.<\/p>\n<p>Amenaza nuclear<\/p>\n<p>La amenaza potencial de las armas nucleares en el espacio se ha visto amplificada por la invasi\u00f3n rusa de Ucrania , que ha desencadenado el conflicto terrestre m\u00e1s importante en Europa desde la Segunda Guerra Mundial y ha llevado las relaciones entre Estados Unidos y Rusia \u2013los dos mayores estados con armas nucleares del mundo\u2013 a nuevos m\u00ednimos.<\/p>\n<p>Los comentarios de la Casa Blanca sobre la perspectiva de un arma espacial nuclear rusa han profundizado esas preocupaciones.<\/p>\n<p>Los expertos dicen que este tipo de arma podr\u00eda tener el potencial de acabar con megaconstelaciones de peque\u00f1os sat\u00e9lites, como el Starlink de SpaceX, que Ucrania ha utilizado con \u00e9xito para contrarrestar a las tropas rusas.Es casi seguro que esto ser\u00eda \u201cun arma de \u00faltimo recurso\u201d para Rusia, dijeron el funcionario estadounidense y otras fuentes, porque causar\u00eda el mismo da\u00f1o a cualquier sat\u00e9lite ruso que tambi\u00e9n estuviera en el \u00e1rea.<\/p>\n<p>El presidente ruso, Vladimir Putin, dijo en marzo que Mosc\u00fa est\u00e1 dispuesto a utilizar armas nucleares si existe una amenaza a la existencia del Estado ruso, pero &#171;nunca ha habido tal necesidad&#187;.<\/p>\n<p>Tambi\u00e9n dijo a los funcionarios que los proyectos espaciales, incluida la instalaci\u00f3n de una unidad de energ\u00eda nuclear en el espacio, deber\u00edan ser una prioridad y recibir una financiaci\u00f3n adecuada.<\/p>\n<p>El a\u00f1o pasado, Putin despleg\u00f3 armas nucleares t\u00e1cticas en su vecino aliado Bielorrusia, y el expresidente ruso y vicepresidente del Consejo de Seguridad de Rusia, Dmitry Medvedev, dijo que las armas nucleares estrat\u00e9gicas podr\u00edan usarse para defender territorios incorporados a Rusia de Ucrania.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Rusia vet\u00f3 este mi\u00e9rcoles una resoluci\u00f3n de las Naciones Unidas que propon\u00eda prohibir el uso de armas nucleares en el espacio exterior en medio de preocupaciones respaldadas por la inteligencia estadounidense de que Mosc\u00fa est\u00e9 tratando de desarrollar un dispositivo nuclear capaz de destruir sat\u00e9lites. El embajador ruso, Vassily Nebenzia, describi\u00f3 el borrador [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448500","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Rusia vet\u00f3 este mi\u00e9rcoles una resoluci\u00f3n de las Naciones Unidas que propon\u00eda prohibir el uso de armas nucleares en el espacio exterior en medio de preocupaciones respaldadas por la inteligencia estadounidense de que Mosc\u00fa est\u00e9 tratando de desarrollar un dispositivo nuclear capaz de destruir sat\u00e9lites. El embajador ruso, Vassily Nebenzia, describi\u00f3 el borrador [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-25T10:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio\",\"datePublished\":\"2024-04-25T10:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/\"},\"wordCount\":654,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/\",\"name\":\"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-25T10:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio - Noticias","og_description":"(CNN) &#8212; Rusia vet\u00f3 este mi\u00e9rcoles una resoluci\u00f3n de las Naciones Unidas que propon\u00eda prohibir el uso de armas nucleares en el espacio exterior en medio de preocupaciones respaldadas por la inteligencia estadounidense de que Mosc\u00fa est\u00e9 tratando de desarrollar un dispositivo nuclear capaz de destruir sat\u00e9lites. El embajador ruso, Vassily Nebenzia, describi\u00f3 el borrador [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-25T10:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/"},"author":{"name":"","@id":""},"headline":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio","datePublished":"2024-04-25T10:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/"},"wordCount":654,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","name":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-25T10:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-25T10:03:37Z","datePublished":"2024-04-25T10:03:37Z","dateModified":"2024-04-25T10:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Rusia veta resoluci\\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/25\\\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/25\\\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-25T10:03:37Z\",\"datePublished\":\"2024-04-25T10:03:37Z\",\"dateModified\":\"2024-04-25T10:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449650,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/21\/ee-uu-rusia-arma-contraespacial-trax\/","url_meta":{"origin":1448500,"position":0},"title":"EE.UU. considera probable que Rusia lanz\u00f3 un arma contraespacial la semana pasada","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) -- EE.UU. considera probable que Rusia lanz\u00f3 la semana pasada un arma contraespacial que est\u00e1 cerca de un sat\u00e9lite gubernamental estadounidense en \u00f3rbita cercana y es capaz de atacarlo, declar\u00f3 el lunes en la ONU el embajador de Estados Unidos, Robert Wood.No es la primera vez que Rusia lanza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446203,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/02\/capacidades-militares-rusia-espacio-orix\/","url_meta":{"origin":1448500,"position":1},"title":"\u00bfArmas en el espacio? Estas son las capacidades militares de Rusia en la \u00f3rbita terrestre","author":"","date":"marzo 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00bfEst\u00e1 Rusia desarrollando armas nucleares para utilizar en el espacio? De acuerdo con fuentes del sector inteligencia de Estados Unidos, eso parece.\u00bfEs eso algo nuevo? Bueno, no tanto.En una exclusiva de CNN publicada a mediados de febrero, estas fuentes hablaron de un nuevo tipo de arma nuclear\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446444,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/capacidades-militares-rusia-espacio-orix-2\/","url_meta":{"origin":1448500,"position":2},"title":"\u00bfArmas en el espacio? Estas son las capacidades militares de Rusia en la \u00f3rbita terrestre","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00bfEst\u00e1 Rusia desarrollando armas nucleares para utilizar en el espacio? De acuerdo con fuentes del sector inteligencia de Estados Unidos, eso parece.\u00bfEs eso algo nuevo? Bueno, no tanto.En una exclusiva de CNN publicada a mediados de febrero, estas fuentes hablaron de un nuevo tipo de arma nuclear\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459992,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/16\/pentagono-rusia-china-capacidades-militares-espacio-trax\/","url_meta":{"origin":1448500,"position":3},"title":"El Pent\u00e1gono monitorea de cerca a Rusia y China mientras prueban capacidades militares en el espacio","author":"","date":"marzo 16, 2025","format":false,"excerpt":"Funcionarios militares de Estados Unidos creen que Rusia y China est\u00e1n probando agresivamente nuevas capacidades espaciales ofensivas, al se\u00f1alar una serie de misiones de entrenamiento de sat\u00e9lites realizadas por ambos pa\u00edses en los \u00faltimos meses como evidencia creciente de un esfuerzo por militarizar el espacio exterior.Tan recientemente como la semana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448082,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/14\/que-paises-tienen-mas-armas-nucleares-mundo-trax\/","url_meta":{"origin":1448500,"position":4},"title":"\u00bfHay armas nucleares en Medio Oriente? Estos son datos sobre los arsenales at\u00f3micos globales","author":"","date":"abril 14, 2024","format":false,"excerpt":"(CNN) -- En el mundo hay actualmente unas 12.500 armas nucleares, seg\u00fan la ONU. Y aunque lograr el desarme nuclear mundial ha sido uno de los objetivos m\u00e1s antiguos de las Naciones Unidas, desde 1946, a\u00fan hoy hay una \"frustraci\u00f3n debido a la lentitud del desarme nuclear\".En marzo el presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468391,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/11\/16\/tratado-nuclear-ee-uu-rusia-expirar-trax\/","url_meta":{"origin":1448500,"position":5},"title":"El \u00faltimo pacto nuclear entre EE.UU. y Rusia est\u00e1 por expirar en medio de amenazas de Trump y Putin y pruebas nucleares","author":"","date":"noviembre 16, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, y el presidente de Rusia, Vladimir Putin, llevan semanas intercambiando amenazas de reanudar las pruebas nucleares, una escalada que se inici\u00f3 con las fanfarronadas de Putin sobre las pruebas del misil de propulsi\u00f3n nuclear Poseid\u00f3n a finales de octubre.D\u00edas despu\u00e9s, Trump declar\u00f3 que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448500"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448500\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}