{"id":1448539,"date":"2024-04-26T03:03:51","date_gmt":"2024-04-26T10:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/"},"modified":"2024-04-26T03:03:51","modified_gmt":"2024-04-26T10:03:51","slug":"hubble-imagen-mancuerna-cosmica-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/","title":{"rendered":"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una &#171;mancuerna c\u00f3smica&#187;"},"content":{"rendered":"<p>(CNN) &#8212; El telescopio espacial Hubble capt\u00f3 una nueva y asombrosa imagen del gas brillante expulsado por una estrella moribunda, que en este caso resulta parecerse a una &#171;mancuerna c\u00f3smica&#187;.<\/p>\n<p>El retrato tambi\u00e9n puede incluir pruebas de que la estrella engull\u00f3 a otra, en una forma de canibalismo estelar, antes de colapsar.<\/p>\n<p>La NASA difundi\u00f3 la imagen de la Peque\u00f1a Nebulosa de la Mancuerna, tambi\u00e9n conocida como Messier 76 o M76, para celebrar el 34 aniversario del lanzamiento del observatorio espacial el 24 de abril de 1990.<\/p>\n<p>La imagen fue publicada por la NASA en ocasi\u00f3n del 34 aniversario del telescopio Hubble.<\/p>\n<p>La nebulosa, situada a 3.400 a\u00f1os-luz de distancia en la constelaci\u00f3n de Perseo, es un caparaz\u00f3n de gases en expansi\u00f3n expulsado por una estrella gigante roja moribunda. El objeto c\u00f3smico se conoce como nebulosa planetaria, pero no tiene nada que ver con los planetas.<\/p>\n<p>Las nebulosas planetarias suelen tener una estructura redondeada y se llamaron as\u00ed porque en un principio se parec\u00edan a los discos a partir de los cuales se forman los planetas, cuando el astr\u00f3nomo franc\u00e9s Charles Messier descubri\u00f3 una por primera vez en 1764. Pierre M\u00e9chain descubri\u00f3 la nebulosa de la Peque\u00f1a Campana en 1780 y los astr\u00f3nomos la observaron en detalle por primera vez en 1891. Desde entonces, esta fotog\u00e9nica nebulosa ha sido una de las favoritas de astr\u00f3nomos profesionales y aficionados debido a su forma \u00fanica.<\/p>\n<p>Si los investigadores confirman que la nebulosa contiene pruebas de un caso de canibalismo c\u00f3smico, podr\u00eda demostrar la existencia de una compa\u00f1era de la gigante roja, teorizada desde hace tiempo.<\/p>\n<p>Violencia estelar<\/p>\n<p>La nebulosa de la Peque\u00f1a Campana incluye un anillo que, desde nuestra perspectiva, parece m\u00e1s bien una barra central que conecta dos l\u00f3bulos a ambos lados del anillo. Antes de que la envejecida estrella gigante roja colapsara, liber\u00f3 un anillo de gas y polvo. Los astr\u00f3nomos creen que, posteriormente, una estrella compa\u00f1era le dio forma, y el anillo de gas y polvo acab\u00f3 formando un grueso disco.<\/p>\n<p>La estrella compa\u00f1era, una vez en \u00f3rbita alrededor de la gigante roja, no aparece en la imagen del Hubble. Seg\u00fan un comunicado de la NASA, los astr\u00f3nomos creen que la gigante roja se trag\u00f3 a su compa\u00f1era y, estudiando el anillo, podr\u00edan obtener &#171;pruebas forenses&#187; de este acto de canibalismo c\u00f3smico.<\/p>\n<p>Desde su colapso, la estrella gigante roja se ha transformado en un remanente estelar muerta conocido como estrella enana blanca ultradensa. La enana blanca tiene una temperatura abrasadora de 138.871 grados Celsius, lo que la convierte en 24 veces m\u00e1s caliente que la superficie de nuestro Sol y en una de las estrellas enanas blancas m\u00e1s calientes conocidas.<\/p>\n<p>La enana blanca es la luz blanca brillante en el centro de la nebulosa en la imagen del Hubble.<\/p>\n<p>Mientras tanto, los dos l\u00f3bulos que se ven en el retrato representan gas caliente que escapa y es arrastrado por una fuerza similar a la de un hurac\u00e1n a medida que el material se desprende de la estrella moribunda, impuls\u00e1ndolo a trav\u00e9s del espacio a m\u00e1s de 3 millones de kil\u00f3metros por hora. El viento estelar que se desprende de la estrella choca con el gas m\u00e1s fr\u00edo y de movimiento m\u00e1s lento expulsado inicialmente por la estrella anteriormente, que puede verse en los l\u00f3bulos.<\/p>\n<p>La radiaci\u00f3n ultravioleta de la abrasadora estrella caliente hace que los gases brillen en diferentes colores que representan distintos elementos, como el rojo para indicar el nitr\u00f3geno y el azul para el ox\u00edgeno.<\/p>\n<p>Los astr\u00f3nomos calculan que dentro de 15.000 a\u00f1os la nebulosa desaparecer\u00e1 del cielo nocturno a medida que siga expandi\u00e9ndose y oscureci\u00e9ndose.<\/p>\n<p>El legado del Hubble<\/p>\n<p>La nebulosa de la Peque\u00f1a Campana es solo uno de los 53.000 objetos astron\u00f3micos que el Hubble ha observado a lo largo de 34 a\u00f1os y, hasta la fecha, el telescopio ha realizado 1,6 millones de observaciones. Astr\u00f3nomos de todo el mundo conf\u00edan en el telescopio, y en su creciente base de datos, para realizar nuevos descubrimientos.<\/p>\n<p>&#171;El telescopio espacial es la misi\u00f3n de astrof\u00edsica espacial cient\u00edficamente m\u00e1s productiva de la historia de la NASA&#187;, seg\u00fan un comunicado de la NASA.<\/p>\n<p>El Hubble y el Telescopio Espacial James Webb funcionan como complementos entre s\u00ed, recopilando observaciones a trav\u00e9s de diferentes longitudes de onda de luz para obtener una visi\u00f3n m\u00e1s n\u00edtida y profunda del universo, en la que los astr\u00f3nomos tratan de desentra\u00f1ar los misterios que rodean a las supernovas, las galaxias lejanas, los exoplanetas y otras rarezas celestes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El telescopio espacial Hubble capt\u00f3 una nueva y asombrosa imagen del gas brillante expulsado por una estrella moribunda, que en este caso resulta parecerse a una &#171;mancuerna c\u00f3smica&#187;. El retrato tambi\u00e9n puede incluir pruebas de que la estrella engull\u00f3 a otra, en una forma de canibalismo estelar, antes de colapsar. La NASA difundi\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448539","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una &quot;mancuerna c\u00f3smica&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una &quot;mancuerna c\u00f3smica&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El telescopio espacial Hubble capt\u00f3 una nueva y asombrosa imagen del gas brillante expulsado por una estrella moribunda, que en este caso resulta parecerse a una &#171;mancuerna c\u00f3smica&#187;. El retrato tambi\u00e9n puede incluir pruebas de que la estrella engull\u00f3 a otra, en una forma de canibalismo estelar, antes de colapsar. La NASA difundi\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T10:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una &#171;mancuerna c\u00f3smica&#187;\",\"datePublished\":\"2024-04-26T10:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/\"},\"wordCount\":826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/\",\"name\":\"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una \\\"mancuerna c\u00f3smica\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-26T10:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una &#171;mancuerna c\u00f3smica&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una \"mancuerna c\u00f3smica\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una \"mancuerna c\u00f3smica\" - Noticias","og_description":"(CNN) &#8212; El telescopio espacial Hubble capt\u00f3 una nueva y asombrosa imagen del gas brillante expulsado por una estrella moribunda, que en este caso resulta parecerse a una &#171;mancuerna c\u00f3smica&#187;. El retrato tambi\u00e9n puede incluir pruebas de que la estrella engull\u00f3 a otra, en una forma de canibalismo estelar, antes de colapsar. La NASA difundi\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-26T10:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/"},"author":{"name":"","@id":""},"headline":"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una &#171;mancuerna c\u00f3smica&#187;","datePublished":"2024-04-26T10:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/"},"wordCount":826,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/","name":"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una \"mancuerna c\u00f3smica\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-26T10:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una &#171;mancuerna c\u00f3smica&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La NASA celebra los 34 a\u00f1os del telescopio Hubble con la imagen de una &#171;mancuerna c\u00f3smica&#187;","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/hubble-imagen-mancuerna-cosmica-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-26T10:03:51Z","datePublished":"2024-04-26T10:03:51Z","dateModified":"2024-04-26T10:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La NASA celebra los 34 a\\u00f1os del telescopio Hubble con la imagen de una &#171;mancuerna c\\u00f3smica&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/26\\\/hubble-imagen-mancuerna-cosmica-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/26\\\/hubble-imagen-mancuerna-cosmica-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-26T10:03:51Z\",\"datePublished\":\"2024-04-26T10:03:51Z\",\"dateModified\":\"2024-04-26T10:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1456201,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/02\/nueva-imagen-galaxia-sombrero-aspecto-muy-diferente-trax\/","url_meta":{"origin":1448539,"position":0},"title":"Una nueva imagen de una galaxia parecida a un sombrero revela un aspecto muy diferente","author":"","date":"diciembre 2, 2024","format":false,"excerpt":"(CNN) -- El telescopio espacial James Webb capt\u00f3 una nueva y sorprendente imagen de una galaxia vecina estudiada durante mucho tiempo, la galaxia del Sombrero, revelando una perspectiva que parece bastante diferente del sombrero mexicano de ala ancha que le da nombre.La imagen tomada con el instrumento MIRI (Mid-Infrared Instrument)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451817,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/13\/supernova-1181-zombie-estrella-trax\/","url_meta":{"origin":1448539,"position":1},"title":"Una supernova brill\u00f3 en el cielo nocturno hace 1.000 a\u00f1os. Ahora, los astr\u00f3nomos encontraron los restos de su &#171;estrella zombi&#187;","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN) -- Durante seis meses de 1181, una estrella moribunda dej\u00f3 su huella en el cielo nocturno.El llamativo objeto apareci\u00f3 tan brillante como Saturno en las proximidades de la constelaci\u00f3n de Casiopea, y las cr\u00f3nicas hist\u00f3ricas de China y Jap\u00f3n lo registraron como una \"estrella invitada\".Los astr\u00f3nomos chinos utilizaban este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450157,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/07\/telescopio-hubble-en-modo-seguro-aqui-plan-nasa-para-mantenerlo-vivo-trax\/","url_meta":{"origin":1448539,"position":2},"title":"El hist\u00f3rico telescopio Hubble ha entrado en &#171;modo seguro&#187;. Aqu\u00ed est\u00e1 el plan de la NASA para mantenerlo vivo","author":"","date":"junio 7, 2024","format":false,"excerpt":"(CNN) -- El Telescopio Espacial Hubble pasar\u00e1 a una nueva forma de operar que tiene como objetivo evitar que el observatorio espacial experimente fallas en su capacidad para observar el universo, seg\u00fan funcionarios de la NASA.El hist\u00f3rico telescopio, que ha capturado impresionantes im\u00e1genes del cosmos durante 34 a\u00f1os , ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449760,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/25\/nasa-mision-prefire-polares-tierra-trax\/","url_meta":{"origin":1448539,"position":3},"title":"La NASA lanza la misi\u00f3n PREFIRE para estudiar las regiones polares de la Tierra","author":"","date":"mayo 25, 2024","format":false,"excerpt":"(CNN) -- La NASA lanz\u00f3 el primero de dos sat\u00e9lites de investigaci\u00f3n que medir\u00e1n cu\u00e1nto calor se pierde en el espacio desde el \u00c1rtico y la Ant\u00e1rtida.El sat\u00e9lite del tama\u00f1o de una caja de zapatos despeg\u00f3 este s\u00e1bado a las 7:42 p.m., hora local (3:42 a.m. ET) a bordo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465771,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/22\/que-es-una-luna-negra-trax\/","url_meta":{"origin":1448539,"position":4},"title":"\u00bfQu\u00e9 es una luna negra? Esto es lo que puedes esperar en el cielo este fin de semana","author":"","date":"agosto 22, 2025","format":false,"excerpt":"La luna recibe muchos nombres. Agosto tuvo la luna llena de esturi\u00f3n, mientras que en marzo los observadores del cielo pudieron haber presenciado la luna de sangre, que ocurre cuando el sat\u00e9lite parece volverse rojo durante un eclipse lunar. Tambi\u00e9n puede que hayas o\u00eddo hablar de la luna azul, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450419,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/16\/telescopio-webb-colision-asteroides-gigantes-trax\/","url_meta":{"origin":1448539,"position":5},"title":"Observaciones del telescopio Webb insin\u00faan una colisi\u00f3n de asteroides gigantes en un sistema planetario cercano","author":"","date":"junio 16, 2024","format":false,"excerpt":"(CNN) -- Es probable que en los \u00faltimos a\u00f1os se haya producido una colisi\u00f3n entre asteroides gigantes en un sistema estelar vecino llamado Beta Pictoris. Dos observatorios espaciales diferentes ayudan a contar la historia.El sistema Beta Pictoris, ubicado a 63 a\u00f1os luz de la Tierra, intrig\u00f3 durante mucho tiempo a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448539"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448539\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}