{"id":1448540,"date":"2024-04-26T03:03:51","date_gmt":"2024-04-26T10:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/"},"modified":"2024-04-26T03:03:51","modified_gmt":"2024-04-26T10:03:51","slug":"anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/","title":{"rendered":"Anne Hathaway detalla las &#171;asquerosas&#187; pruebas de qu\u00edmica que hizo en los a\u00f1os 2000"},"content":{"rendered":"<p>(CNN) &#8212; La actriz ganadora del Oscar Anne Hathaway cont\u00f3 que tuvo que besar a una serie de actores durante un proceso de audici\u00f3n en la d\u00e9cada de 2000 para &#171;probar la qu\u00edmica&#187; ante la c\u00e1mara.<\/p>\n<p>A sus 41 a\u00f1os y con decenas de pel\u00edculas a sus espaldas, Hathaway revel\u00f3 que al principio de su carrera accedi\u00f3 a la &#171;asquerosa&#187; petici\u00f3n de &#171;besarse&#187; con actores masculinos para probar su idoneidad para una pel\u00edcula sin nombre.<\/p>\n<p>En declaraciones a la revista V Magazine en una entrevista publicada el lunes, Hathaway dijo: &#171;En los a\u00f1os 2000 \u2014y esto me ocurri\u00f3 a m\u00ed\u2014 se consideraba normal pedir a un actor que se besara con otros actores para comprobar si hab\u00eda qu\u00edmica. En realidad es la peor forma de hacerlo&#187;.<\/p>\n<p>&#171;Me dijeron: &#8216;Hoy vienen diez chicos y t\u00fa est\u00e1s en el reparto. \u00bfNo est\u00e1s emocionada de besarte con todos ellos?&#187;.<\/p>\n<p>&#171;Y pens\u00e9: &#8216;\u00bfHay algo malo en m\u00ed?&#8217; porque no estaba emocionada. Pens\u00e9 que sonaba asqueroso. Y yo era tan joven y terriblemente consciente de lo f\u00e1cil que era perderlo todo por ser tachada de &#8216;dif\u00edcil&#8217;, as\u00ed que simplemente fing\u00ed que estaba emocionada y segu\u00ed adelante&#187;.<\/p>\n<p>&#171;No era un juego de poder, nadie intentaba ser horrible o hacerme da\u00f1o. Simplemente era una \u00e9poca muy diferente y ahora sabemos que no se debe hacer&#187;.<\/p>\n<p>Hathaway, que gan\u00f3 un Oscar a la mejor actriz de reparto por su papel en &#171;Les Mis\u00e9rables&#187; de 2012, est\u00e1 actualmente promocionando su nueva pel\u00edcula, &#171;The Idea of You&#187;.<\/p>\n<p>En ella interpreta a Sol\u00e8ne, una madre soltera que inicia un inesperado romance con el cantante de una popular banda de chicos tras conocerse en Coachella.<\/p>\n<p>Anne Hathaway reflexiona sobre el &#171;odio&#187; que soport\u00f3 despu\u00e9s de ganar su premio Oscar<\/p>\n<p>Anne Hathaway y Nicholas Galitzine asisten al estreno mundial de &#171;The Idea Of You&#187; durante el SXSW en The Paramount Theater el 16 de marzo de 2024 en Austin, Texas. (Cr\u00e9dito: Daniel Boczarski\/Getty Images)<\/p>\n<p>El cantante, Hayes, es interpretado por el actor brit\u00e1nico Nicholas Galitzine. A la pregunta de c\u00f3mo lo eligieron para el papel, Hathaway \u2014que tambi\u00e9n es productora de la pel\u00edcula\u2014 respondi\u00f3: &#171;Pedimos a cada uno de los actores que entraban que eligieran una canci\u00f3n que creyeran que le encantar\u00eda a su personaje, que pondr\u00edan para que mi personaje bailara, y luego hac\u00edamos una peque\u00f1a improvisaci\u00f3n&#187;.<\/p>\n<p>&#171;Me sentaba en una silla como si hubi\u00e9ramos llegado de cenar o de dar un paseo o algo as\u00ed, puls\u00e1bamos el play y nos pon\u00edamos a bailar juntos&#187;.<\/p>\n<p>Galitzine, que tambi\u00e9n protagoniza &#171;Mary &#038; George&#187; con Julianne Moore, eligi\u00f3 a The Alabama Shakes, seg\u00fan Hathaway.<\/p>\n<p>&#171;Y fue muy f\u00e1cil&#187;, dijo. &#171;Escuch\u00e9 la voz de Brittany [la vocalista de Alabama Shakes] y empec\u00e9 a sonre\u00edr. Y \u00e9l [Galitzine] me vio sonre\u00edr, as\u00ed que se relaj\u00f3 y empezamos a bailar&#187;.<\/p>\n<p>&#171;Nadie estaba alardeando. Nadie intentaba conseguir el puesto. Simplemente est\u00e1bamos bailando. Mir\u00e9 y Michael Showalter, nuestro director, estaba radiante. Chispeante&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La actriz ganadora del Oscar Anne Hathaway cont\u00f3 que tuvo que besar a una serie de actores durante un proceso de audici\u00f3n en la d\u00e9cada de 2000 para &#171;probar la qu\u00edmica&#187; ante la c\u00e1mara. A sus 41 a\u00f1os y con decenas de pel\u00edculas a sus espaldas, Hathaway revel\u00f3 que al principio de su [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448540","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anne Hathaway detalla las &quot;asquerosas&quot; pruebas de qu\u00edmica que hizo en los a\u00f1os 2000 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anne Hathaway detalla las &quot;asquerosas&quot; pruebas de qu\u00edmica que hizo en los a\u00f1os 2000 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La actriz ganadora del Oscar Anne Hathaway cont\u00f3 que tuvo que besar a una serie de actores durante un proceso de audici\u00f3n en la d\u00e9cada de 2000 para &#171;probar la qu\u00edmica&#187; ante la c\u00e1mara. A sus 41 a\u00f1os y con decenas de pel\u00edculas a sus espaldas, Hathaway revel\u00f3 que al principio de su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T10:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Anne Hathaway detalla las &#171;asquerosas&#187; pruebas de qu\u00edmica que hizo en los a\u00f1os 2000\",\"datePublished\":\"2024-04-26T10:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/\"},\"wordCount\":548,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/\",\"name\":\"Anne Hathaway detalla las \\\"asquerosas\\\" pruebas de qu\u00edmica que hizo en los a\u00f1os 2000 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-26T10:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anne Hathaway detalla las &#171;asquerosas&#187; pruebas de qu\u00edmica que hizo en los a\u00f1os 2000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anne Hathaway detalla las \"asquerosas\" pruebas de qu\u00edmica que hizo en los a\u00f1os 2000 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Anne Hathaway detalla las \"asquerosas\" pruebas de qu\u00edmica que hizo en los a\u00f1os 2000 - Noticias","og_description":"(CNN) &#8212; La actriz ganadora del Oscar Anne Hathaway cont\u00f3 que tuvo que besar a una serie de actores durante un proceso de audici\u00f3n en la d\u00e9cada de 2000 para &#171;probar la qu\u00edmica&#187; ante la c\u00e1mara. A sus 41 a\u00f1os y con decenas de pel\u00edculas a sus espaldas, Hathaway revel\u00f3 que al principio de su [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-26T10:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/"},"author":{"name":"","@id":""},"headline":"Anne Hathaway detalla las &#171;asquerosas&#187; pruebas de qu\u00edmica que hizo en los a\u00f1os 2000","datePublished":"2024-04-26T10:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/"},"wordCount":548,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/","name":"Anne Hathaway detalla las \"asquerosas\" pruebas de qu\u00edmica que hizo en los a\u00f1os 2000 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-26T10:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Anne Hathaway detalla las &#171;asquerosas&#187; pruebas de qu\u00edmica que hizo en los a\u00f1os 2000"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Anne Hathaway detalla las &#171;asquerosas&#187; pruebas de qu\u00edmica que hizo en los a\u00f1os 2000","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-26T10:03:51Z","datePublished":"2024-04-26T10:03:51Z","dateModified":"2024-04-26T10:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Anne Hathaway detalla las &#171;asquerosas&#187; pruebas de qu\\u00edmica que hizo en los a\\u00f1os 2000\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/26\\\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/26\\\/anne-hathaway-casting-besos-quimica-2000-idea-of-you-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-26T10:03:51Z\",\"datePublished\":\"2024-04-26T10:03:51Z\",\"dateModified\":\"2024-04-26T10:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448673,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/29\/anne-hathaway-cinco-anos-sobria-trax\/","url_meta":{"origin":1448540,"position":0},"title":"Anne Hathaway revela que lleva cinco a\u00f1os sobria","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN) -- Anne Hathaway comparti\u00f3 por primera vez que perdi\u00f3 el inter\u00e9s en beber despu\u00e9s de una fuerte resaca en 2018. Ahora lleva cinco a\u00f1os sobria.Hathaway hab\u00eda dado a conocer su decisi\u00f3n de evitar el alcohol durante una aparici\u00f3n en el \u201cEllen DeGeneres Show\u201d, donde explic\u00f3 que en ese momento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473416,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/22\/anne-hathaway-mas-bellos-del-mundo-2026-people-orix\/","url_meta":{"origin":1448540,"position":1},"title":"Anne Hathaway lidera el conteo de &#171;Los m\u00e1s bellos del mundo&#187; 2026 de People","author":"","date":"abril 22, 2026","format":false,"excerpt":"La revista People revel\u00f3 las celebridades que integran su conteo \u201cLos m\u00e1s bellos del mundo\u201d de 2026. En esta edici\u00f3n, Anne Hathaway fue elegida para encabezar la lista.La actriz, de 43 a\u00f1os y pr\u00f3xima a estrenar The Devil Wears Prada 2, expres\u00f3 en la entrevista que atraviesa una etapa de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468276,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/11\/12\/meryl-streep-anne-hathaway-devil-wears-prada-2-trax\/","url_meta":{"origin":1448540,"position":2},"title":"&#171;Ya era hora&#187;: Meryl Streep y Anne Hathaway, juntas de nuevo en el adelanto de &#171;The Devil Wears Prada 2&#187;","author":"","date":"noviembre 12, 2025","format":false,"excerpt":"El avance de \u201cThe Devil Wears Prada 2\u201d se estren\u00f3 este mi\u00e9rcoles, y es justo lo que el mundo necesitaba.En \u00e9l se ve a Meryl Streep como Miranda Priestly caminando con tacones rojos por las oficinas de la revista ficticia Runway. Antes de entrar al ascensor, se le une Andy\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473731,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/05\/02\/berkshire-hathaway-reservas-record-greg-abel-trax\/","url_meta":{"origin":1448540,"position":3},"title":"As\u00ed le fue a Berkshire Hathaway en su primer trimestre sin Warren Buffett como CEO","author":"","date":"mayo 2, 2026","format":false,"excerpt":"Berkshire Hathaway (BRK.B) anunci\u00f3 este s\u00e1bado ganancias operativas de US$ 11.350 millones y una reserva de efectivo r\u00e9cord en el primer trimestre bajo la direcci\u00f3n de Greg Abel, sucesor del renombrado inversor Warren Buffett.La enorme reserva de efectivo de Berkshire Hathaway ascendi\u00f3 a m\u00e1s de US$ 397.000 millones en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456938,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/24\/pelicula-christopher-nolan-adaptacion-odisea-homero-trax\/","url_meta":{"origin":1448540,"position":4},"title":"La pr\u00f3xima pel\u00edcula de Christopher Nolan ser\u00e1 una adaptaci\u00f3n repleta de celebridades de &#8216;La Odisea&#8217; de Homero","author":"","date":"diciembre 24, 2024","format":false,"excerpt":"El director ganador del Oscar Christopher Nolan llevar\u00e1 al p\u00fablico a la m\u00edtica Grecia con su m\u00e1s reciente proyecto.Universal Pictures anunci\u00f3 esta semana que Nolan dirigir\u00e1 una adaptaci\u00f3n cinematogr\u00e1fica de \u201cLa Odisea\u201d, un antiguo poema que se cree fue escrito por Homero entre 750 y 650 a. C. y que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449505,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/15\/warren-buffett-revela-misteriosa-empresa-inversion-miles-de-millones-de-dolares-trax\/","url_meta":{"origin":1448540,"position":5},"title":"Warren Buffett finalmente revela la misteriosa empresa en la que invirti\u00f3 miles de millones de d\u00f3lares","author":"","date":"mayo 15, 2024","format":false,"excerpt":"(CNN) --\u00a0 El misterio termin\u00f3: Berkshire Hathaway de Warren Buffett revel\u00f3 una importante participaci\u00f3n en la compa\u00f1\u00eda de seguros Chubb, revelando finalmente la inversi\u00f3n que mantiene en secreto desde el a\u00f1o pasado.Berkshire revel\u00f3 que adquiri\u00f3 casi 26 millones de acciones de Chubb en una presentaci\u00f3n de este mi\u00e9rcoles ante la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448540"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448540\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}