{"id":1448554,"date":"2024-04-26T10:03:49","date_gmt":"2024-04-26T17:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/"},"modified":"2024-04-26T10:03:49","modified_gmt":"2024-04-26T17:03:49","slug":"capturan-comisionado-presidencial-el-salvador-corrupcion-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/","title":{"rendered":"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0La Polic\u00eda Nacional Civil de El Salvador arrest\u00f3 el jueves a Christian Flores Sandoval, comisionado presidencial para proyectos estrat\u00e9gicos, por supuestos v\u00ednculos con hechos de corrupci\u00f3n, inform\u00f3 la Fiscal\u00eda General en un mensaje en su cuenta de X.<\/p>\n<p>Las autoridades dicen que Flores se val\u00eda del cargo y \u201cexig\u00eda dinero a personas y empresas a cambio de beneficios y participaci\u00f3n preferencial en proyectos estrat\u00e9gicos del gobierno\u201d.<\/p>\n<p>Flores no se ha pronunciado tras la captura y CNN intenta establecer si ya cuenta con representaci\u00f3n legal para obtener comentarios.<\/p>\n<p>\u201cEn el nuevo pa\u00eds que estamos construyendo nadie est\u00e1 por encima de la ley\u201d, dijo Rodolfo Delgado, fiscal general de El Salvador, en un mensaje en X.<\/p>\n<p>El Salvador ofrece 5.000 pasaportes a trabajadores extranjeros calificados<\/p>\n<p>Las autoridades aseguran que esta captura es el inicio de una amplia investigaci\u00f3n para deducir responsabilidades de este\u00a0y otros delitos de corrupci\u00f3n.<\/p>\n<p>\u201cNo es el primero y tampoco ser\u00e1 el \u00faltimo\u201d, escribi\u00f3 Nayib Bukele\u00a0este jueves\u00a0en su cuenta de X. Bukele est\u00e1 de licencia de su cargo, aprobada por la Asamblea Legislativa, desde diciembre para participar en las elecciones de febrero en las que result\u00f3 reelecto, pese a que la Constituci\u00f3n proh\u00edbe la reelecci\u00f3n inmediata. Su segundo mandato, de cinco a\u00f1os, comienza\u00a0el 1 de junio.<\/p>\n<p>\u201cSi Dios permite, nuestra guerra contra la corrupci\u00f3n ser\u00e1 tan exitosa como nuestra guerra contra las pandillas\u201d, agreg\u00f3 Bukele en su mensaje acompa\u00f1ado de la grabaci\u00f3n donde anunci\u00f3 que, con excepci\u00f3n del fiscal general, se investigar\u00e1 a todo el Ejecutivo.<\/p>\n<p>Guerra contra la corrupci\u00f3n<\/p>\n<p>Bukele ya hab\u00eda dicho en junio de 2023, en su discurso por el\u00a0cuarto a\u00f1o de su mandato, que su Gobierno impulsar\u00eda una guerra frontal contra la corrupci\u00f3n. En ese momento, anunci\u00f3 adem\u00e1s la construcci\u00f3n de una c\u00e1rcel para los corruptos.<\/p>\n<p>\u201cAs\u00ed como hemos combatido frontalmente a las pandillas con toda la fuerza del Estado y con todas las herramientas legales que podemos, sin titubear en ning\u00fan momento, as\u00ed tambi\u00e9n iniciaremos una guerra frontal contra la corrupci\u00f3n\u201d, asegur\u00f3 Bukele el a\u00f1o pasado en cadena nacional de radio y televisi\u00f3n.<\/p>\n<p>La pol\u00edtica de Bukele contra las pandillas ha sido criticada por organismos locales e internacionales de derechos humanos porque consideran que viola los derechos humanos. Amnist\u00eda Internacional, por ejemplo, ha solicitado, sin \u00e9xito, la derogatoria del r\u00e9gimen de excepci\u00f3n que, desde su entrada en vigor, en marzo de 2022, ha permitido la captura de casi 80.000 personas.<\/p>\n<p>Como parte de la lucha contra la corrupci\u00f3n anunciada por Bukele, las autoridades de El Salvador detuvieron en agosto de 2023 al asesor presidencial de seguridad, Alejandro Muyshondt, bajo se\u00f1alamientos de ser un doble agente desde 2019 y filtrar informaci\u00f3n al expresidente Mauricio Funes (2009-2014). Muyshondt muri\u00f3 en febrero bajo custodia del Estado antes de ser enjuiciado.<\/p>\n<p>Patricia Alvarez, madre de Muyshondt y Lucrecia Landaverde, su abogada, denunciaron los que consideraron actos de tortura que habr\u00eda sufrido el exasesor de seguridad, ya que el cuerpo presentaba hematomas. Su expediente cl\u00ednico fue extraviado en el hospital, seg\u00fan reportes de medios locales.<\/p>\n<p>Las autoridades no han respondido los se\u00f1alamientos hechos por la familia. De hecho, el caso fue manejado con total hermetismo.<\/p>\n<p>Otro caso es el de Erick Garc\u00eda, exdiputado de Nuevas Ideas, partido al que pertenece Bukele, a quien acusan de haber cometido el delito de falsedad ideol\u00f3gica al elaborar un documento para hacer constar que le prest\u00f3\u00a0US$ 90.000 a su asesor jur\u00eddico, pero que la transacci\u00f3n nunca existi\u00f3. El juicio contra Garc\u00eda comenz\u00f3\u00a0este martes. Garc\u00eda se ha declarado inocente y la Fiscal\u00eda ha pedido al tribunal de sentencia que lo condene a seis a\u00f1os de c\u00e1rcel.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0La Polic\u00eda Nacional Civil de El Salvador arrest\u00f3 el jueves a Christian Flores Sandoval, comisionado presidencial para proyectos estrat\u00e9gicos, por supuestos v\u00ednculos con hechos de corrupci\u00f3n, inform\u00f3 la Fiscal\u00eda General en un mensaje en su cuenta de X. Las autoridades dicen que Flores se val\u00eda del cargo y \u201cexig\u00eda dinero a personas y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448554","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0La Polic\u00eda Nacional Civil de El Salvador arrest\u00f3 el jueves a Christian Flores Sandoval, comisionado presidencial para proyectos estrat\u00e9gicos, por supuestos v\u00ednculos con hechos de corrupci\u00f3n, inform\u00f3 la Fiscal\u00eda General en un mensaje en su cuenta de X. Las autoridades dicen que Flores se val\u00eda del cargo y \u201cexig\u00eda dinero a personas y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T17:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n\",\"datePublished\":\"2024-04-26T17:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/\"},\"wordCount\":676,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/\",\"name\":\"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-26T17:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0La Polic\u00eda Nacional Civil de El Salvador arrest\u00f3 el jueves a Christian Flores Sandoval, comisionado presidencial para proyectos estrat\u00e9gicos, por supuestos v\u00ednculos con hechos de corrupci\u00f3n, inform\u00f3 la Fiscal\u00eda General en un mensaje en su cuenta de X. Las autoridades dicen que Flores se val\u00eda del cargo y \u201cexig\u00eda dinero a personas y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-26T17:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/"},"author":{"name":"","@id":""},"headline":"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n","datePublished":"2024-04-26T17:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/"},"wordCount":676,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/","name":"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-26T17:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Capturan a comisionado presidencial de El Salvador por presunta corrupci\u00f3n","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/26\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-26T17:03:49Z","datePublished":"2024-04-26T17:03:49Z","dateModified":"2024-04-26T17:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Capturan a comisionado presidencial de El Salvador por presunta corrupci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/26\\\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/26\\\/capturan-comisionado-presidencial-el-salvador-corrupcion-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-26T17:03:49Z\",\"datePublished\":\"2024-04-26T17:03:49Z\",\"dateModified\":\"2024-04-26T17:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465025,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/07\/31\/reeleccion-presidencial-indefinida-el-salvador-orix\/","url_meta":{"origin":1448554,"position":0},"title":"Asamblea Legislativa aprueba reelecci\u00f3n presidencial indefinida en El Salvador","author":"","date":"julio 31, 2025","format":false,"excerpt":"La Asamblea Legislativa de El Salvador allan\u00f3 este jueves el camino para que Nayib Bukele, actual presidente de El Salvador en su segundo mandato, pueda optar a un tercer periodo, tras aprobar varias reformas a la Constituci\u00f3n. Con 57 votos a favor y 3 en contra, de 60 posibles, los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452552,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/09\/muere-director-policia-el-salvador-orix\/","url_meta":{"origin":1448554,"position":1},"title":"Mueren el director de la Polic\u00eda de El Salvador y ocho personas m\u00e1s en un accidente de helic\u00f3ptero","author":"","date":"septiembre 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El director de la Polic\u00eda Nacional Civil de El Salvador, Mauricio Arriaza Chicas, muri\u00f3 al estrellarse el helic\u00f3ptero UH-1H de la Fuerza A\u00e9rea Salvadore\u00f1a en el que viajaba en Pasaquina, departamento de La Uni\u00f3n, a unos 190 kil\u00f3metros de San Salvador, seg\u00fan confirm\u00f3 la Polic\u00eda a trav\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444470,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/26\/cuando-son-las-elecciones-de-el-salvador-2024-y-que-se-votara\/","url_meta":{"origin":1448554,"position":2},"title":"\u00bfCu\u00e1ndo son las elecciones de El Salvador 2024 y que se votar\u00e1?","author":"","date":"enero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- M\u00e1s de 6 millones de salvadore\u00f1os est\u00e1n convocados para votar en las pr\u00f3ximas elecciones nacionales de febrero.Se van a votar m\u00faltiples cargos, pero el que m\u00e1s llama la atenci\u00f3n es el de presidente, ya que el actual mandatario Nayib Bukele busca un segundo mandato de cinco a\u00f1os.Si\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465185,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/06\/eeuu-rechaza-comparar-reeleccion-bukele-el-salvador-regimenes-dictatoriales-orix\/","url_meta":{"origin":1448554,"position":3},"title":"EE.UU. rechaza comparaci\u00f3n del Gobierno de Bukele con &#171;reg\u00edmenes dictatoriales&#187; tras aprobaci\u00f3n de reelecci\u00f3n indefinida","author":"","date":"agosto 6, 2025","format":false,"excerpt":"El Gobierno de Estados Unidos dijo que rechaza comparar el proceso legislativo en El Salvador que habilit\u00f3 la reelecci\u00f3n sin restricciones y despeja el camino a nuevos mandatos del presidente Nayib Bukele con \u201creg\u00edmenes dictatoriales ileg\u00edtimos\u201d.El posicionamiento de EE.UU. llega despu\u00e9s de que la Asamblea Legislativa de El Salvador aprobara\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457756,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/01\/22\/muere-nicaragua-expresidente-el-salvador-mauricio-funes-orix\/","url_meta":{"origin":1448554,"position":4},"title":"Muere en Nicaragua el expresidente de El Salvador Mauricio Funes","author":"","date":"enero 22, 2025","format":false,"excerpt":"El expresidente de El Salvador Mauricio Funes Cartagena muri\u00f3 la noche del martes en Nicaragua, tras una \u201cgrave dolencia cr\u00f3nica\u201d, inform\u00f3 en un comunicado el Ministerio de Salud del Gobierno de Daniel Ortega. Horas antes, en otro comunicado, dijeron que la salud del mandatario, de 65 a\u00f1os, se hab\u00eda visto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460352,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/24\/corte-suprema-justicia-el-salvador-legalidad-detencion-venezolanos-deportados-eeuu-orix\/","url_meta":{"origin":1448554,"position":5},"title":"Piden a la Corte Suprema de Justicia de El Salvador evaluar la legalidad de la detenci\u00f3n de venezolanos deportados por EE.UU.","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Un equipo de abogados salvadore\u00f1os que representa a los familiares de 30 venezolanos enviados por Estados Unidos a una c\u00e1rcel de El Salvador pidi\u00f3 este lunes a la Corte Suprema de Justicia de este pa\u00eds que eval\u00fae la legalidad de la detenci\u00f3n.Uno de ellos, Jaime Ortega, dijo que fueron contratados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448554"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448554\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}