{"id":1448625,"date":"2024-04-27T23:03:42","date_gmt":"2024-04-28T06:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/"},"modified":"2024-04-27T23:03:42","modified_gmt":"2024-04-28T06:03:42","slug":"escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/","title":{"rendered":"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska"},"content":{"rendered":"<p>(CNN) &#8212; Una persona muri\u00f3 y otra result\u00f3 gravemente herida despu\u00e9s de que un equipo de escalada de dos personas cayera desde 304 metros mientras ascend\u00eda una monta\u00f1a en el Parque Nacional Denali de Alaska este jueves.<\/p>\n<p>Los dos escaladores con cuerdas estaban subiendo la ruta &#171;la escalera mec\u00e1nica&#187; en el monte Johnson, que es una &#171;escalada alpina empinada y t\u00e9cnica en la cara sureste del pico&#187; que involucra una &#171;mezcla de roca empinada, hielo y nieve&#187;, seg\u00fan un comunicado\u00a0del parque.<\/p>\n<p>Otro grupo de escaladores en la misma ruta vio la ca\u00edda y alert\u00f3 al Centro de Comunicaciones Regional de Alaska alrededor de las 10:45 pm, dijo el parque. Luego descendieron hasta las v\u00edctimas y confirmaron que uno de los escaladores hab\u00eda muerto en la ca\u00edda. El segundo escalador sufri\u00f3 &#171;lesiones traum\u00e1ticas graves&#187;, seg\u00fan el comunicado.<\/p>\n<p>&#171;Los socorristas cavaron una cueva en la nieve y atendieron las heridas del escalador superviviente durante toda la noche&#187;, dice el comunicado.<\/p>\n<p>A la ma\u00f1ana siguiente, el piloto del helic\u00f3ptero de rescate a gran altitud de Denali y dos monta\u00f1istas respondieron al incidente. Un guardabosques fue bajado hasta el grupo de escaladores y luego trasladaron al paciente herido a un glaciar plano y lo subieron al helic\u00f3ptero.<\/p>\n<p>Fueron trasladados en avi\u00f3n a Talkeetna, Alaska, donde el escalador superviviente fue trasladado a una ambulancia a\u00e9rea de LifeMed en el aeropuerto estatal de Talkeetna para recibir tratamiento, seg\u00fan el parque.<\/p>\n<p>El helic\u00f3ptero y los guardaparques regresaron al lugar del accidente esa misma ma\u00f1ana con la esperanza de recuperar el cuerpo del escalador muerto, pero tuvieron que regresar debido al deterioro del tiempo, seg\u00fan el comunicado.<\/p>\n<p>&#171;Los guardabosques del NPS regresar\u00e1n al sitio cuando las condiciones clim\u00e1ticas lo permitan&#187;, dijo el parque.<\/p>\n<p>La identidad del escalador muerto no se divulgar\u00e1 hasta que se notifique a la familia, seg\u00fan el parque.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Una persona muri\u00f3 y otra result\u00f3 gravemente herida despu\u00e9s de que un equipo de escalada de dos personas cayera desde 304 metros mientras ascend\u00eda una monta\u00f1a en el Parque Nacional Denali de Alaska este jueves. Los dos escaladores con cuerdas estaban subiendo la ruta &#171;la escalera mec\u00e1nica&#187; en el monte Johnson, que es [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448625","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Una persona muri\u00f3 y otra result\u00f3 gravemente herida despu\u00e9s de que un equipo de escalada de dos personas cayera desde 304 metros mientras ascend\u00eda una monta\u00f1a en el Parque Nacional Denali de Alaska este jueves. Los dos escaladores con cuerdas estaban subiendo la ruta &#171;la escalera mec\u00e1nica&#187; en el monte Johnson, que es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-28T06:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska\",\"datePublished\":\"2024-04-28T06:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/\"},\"wordCount\":370,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/\",\"name\":\"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-28T06:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska - Noticias","og_description":"(CNN) &#8212; Una persona muri\u00f3 y otra result\u00f3 gravemente herida despu\u00e9s de que un equipo de escalada de dos personas cayera desde 304 metros mientras ascend\u00eda una monta\u00f1a en el Parque Nacional Denali de Alaska este jueves. Los dos escaladores con cuerdas estaban subiendo la ruta &#171;la escalera mec\u00e1nica&#187; en el monte Johnson, que es [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-28T06:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/"},"author":{"name":"","@id":""},"headline":"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska","datePublished":"2024-04-28T06:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/"},"wordCount":370,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/","name":"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-28T06:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un escalador muere y otro sobrevive con heridas traum\u00e1ticas tras una ca\u00edda de 300 metros desde una monta\u00f1a en el Parque Nacional Denali de Alaska","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/27\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-28T06:03:42Z","datePublished":"2024-04-28T06:03:42Z","dateModified":"2024-04-28T06:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un escalador muere y otro sobrevive con heridas traum\\u00e1ticas tras una ca\\u00edda de 300 metros desde una monta\\u00f1a en el Parque Nacional Denali de Alaska\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/27\\\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/27\\\/escalador-muere-otro-sobrevive-heridas-traumaticas-tras-caida-300-metros-montana-parque-nacional-denali-de-alaska-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-28T06:03:42Z\",\"datePublished\":\"2024-04-28T06:03:42Z\",\"dateModified\":\"2024-04-28T06:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449820,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/28\/alpinista-monte-everest-record-ascenso-mas-rapido-realizado-por-mujer-trax\/","url_meta":{"origin":1448625,"position":0},"title":"Alpinista del Monte Everest establece r\u00e9cord de ascenso m\u00e1s r\u00e1pido realizado por una mujer","author":"","date":"mayo 28, 2024","format":false,"excerpt":"(CNN) -- \u2014 Veinticuatro horas y 26 minutos, sin parar a dormir: la nepal\u00ed Phunjo Lama acaba de batir el r\u00e9cord mundial de ascensi\u00f3n m\u00e1s r\u00e1pida al monte Everest por una mujer.Su viaje desde el campo base del Everest hasta la cima dur\u00f3 14 horas y 31 minutos, luego el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446486,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/nepal-escaladores-monte-everest-utilizar-chip-seguimiento-trax-2\/","url_meta":{"origin":1448625,"position":1},"title":"Nepal establece una nueva condici\u00f3n para todos los que quieran escalar el Everest","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- En el marco del inicio de la temporada de 2024 en el monte Everest, Nepal anunci\u00f3 un nuevo requisito para todos los alpinistas: deber\u00e1n alquilar y utilizar chips de seguimiento en su viaje.\"Las empresas de renombre ya los utilizaban, pero ahora es obligatorio para todos los escaladores\", dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446135,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/29\/nepal-escaladores-monte-everest-utilizar-chip-seguimiento-trax\/","url_meta":{"origin":1448625,"position":2},"title":"Nepal establece una nueva condici\u00f3n para todos los que quieran escalar el Everest","author":"","date":"febrero 29, 2024","format":false,"excerpt":"(CNN) -- En el marco del inicio de la temporada de 2024 en el monte Everest, Nepal anunci\u00f3 un nuevo requisito para todos los alpinistas: deber\u00e1n alquilar y utilizar chips de seguimiento en su viaje.\"Las empresas de renombre ya los utilizaban, pero ahora es obligatorio para todos los escaladores\", dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461433,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/21\/drones-suministros-monte-everest-escalada-trax\/","url_meta":{"origin":1448625,"position":3},"title":"Los drones podr\u00e1n entregar suministros en el Monte Everest este a\u00f1o y cambiar la escalada para siempre","author":"","date":"abril 21, 2025","format":false,"excerpt":"En la cima del mundo, entre glaciares blancos pr\u00edstinos y rocas imponentes, reina el silencio. De repente, lo rompe una escalera que cae del cielo.Milan Pandey est\u00e1 sentado de nuevo en el Campo Base del Everest, contemplando vistas que pocos han visto jam\u00e1s. Lleg\u00f3 all\u00ed sin necesidad de usar crampones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468007,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/11\/04\/avalancha-nepal-muertes-alpinistas-desaparecidos-trax\/","url_meta":{"origin":1448625,"position":4},"title":"Ciudadano franc\u00e9s y gu\u00edas nepaleses mueren en una avalancha en una monta\u00f1a de Nepal; otros alpinistas est\u00e1n desaparecidos","author":"","date":"noviembre 4, 2025","format":false,"excerpt":"Una avalancha que arras\u00f3 un campamento en el monte Yalung Ri de Nepal este lunes mat\u00f3 al menos a tres personas, y cuatro escaladores extranjeros siguen desaparecidos, seg\u00fan informaron las autoridades.Al menos 16 personas estaban escalando la monta\u00f1a de 5.630 metros (18.471 pies) cuando la avalancha azot\u00f3 el campamento base\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456317,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/06\/alpinistas-ee-uu-canada-accidente-nueva-zelandia-trax\/","url_meta":{"origin":1448625,"position":5},"title":"Tres alpinistas de EE.UU. y Canad\u00e1 habr\u00edan muerto en una ca\u00edda en el pico m\u00e1s alto de Nueva Zelandia","author":"","date":"diciembre 6, 2024","format":false,"excerpt":"Dos estadounidenses y un canadiense que desaparecieron tras intentar hacer cumbre en la monta\u00f1a m\u00e1s alta de Nueva Zelandia se dan por muertos, seg\u00fan inform\u00f3 este viernes la Polic\u00eda local, que suspendi\u00f3 las operaciones de b\u00fasqueda.Kurt Blair, de 56 a\u00f1os, Carlos Romero, de 50, y el ciudadano canadiense fueron dados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448625"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448625\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}