{"id":1448665,"date":"2024-04-29T12:03:47","date_gmt":"2024-04-29T19:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/"},"modified":"2024-04-29T12:03:47","modified_gmt":"2024-04-29T19:03:47","slug":"bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/","title":{"rendered":"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds"},"content":{"rendered":"<p>Puerto Pr\u00edncipe, Hait\u00ed (CNN) &#8212; La foto de Vitel&#8217;homme Innocent en la lista de los diez m\u00e1s buscados del FBI sugiere a un hombre enloquecido: ojos desorbitados y salvajes, dientes al descubierto. Es la foto que cabr\u00eda esperar del l\u00edder de una banda acusada de desestabilizar una naci\u00f3n, que afirma estar bajo protecci\u00f3n divina y por cuya cabeza se ofrece una recompensa de US$ 2 millones por presuntos secuestros.<\/p>\n<p>En persona, proyecta una imagen diferente, al menos para los invitados. Poderoso, s\u00ed, rodeado de ac\u00f3litos armados que saltan ante su mirada, pero tambi\u00e9n cuidadosamente sol\u00edcito, con una nevera llena de s\u00e1ndwiches para sus visitantes y una tendencia a filosofar en la conversaci\u00f3n.<\/p>\n<p>Tras semanas de negociaciones, CNN se adentr\u00f3 en el mundo del crimen organizado en Hait\u00ed a principios de este mes para hablar con Innocent, cuyo grupo armado Kraze Bary\u00e9 forma parte de los grupos armados aliados que han sumido a Hait\u00ed en una crisis de anarqu\u00eda. Es una voz influyente entre los l\u00edderes de las bandas del pa\u00eds, y uno de los que cree que hay que restablecer la paz. \u00bfPero en qu\u00e9 condiciones?<\/p>\n<p>L\u00edder pandillero Jimmy &#171;Barbecue&#187; Cherizier afirm\u00f3 que los grupos ilegales est\u00e1n abiertos al &#171;di\u00e1logo&#187; en Hait\u00ed<\/p>\n<p>La semana pasada, a las afueras del distrito de Tabarre, en Puerto Pr\u00edncipe, la capital de Hait\u00ed, un cami\u00f3n nos condujo a trav\u00e9s de un laberinto de tortuosos caminos de terracer\u00eda, pasando por puestos de control vigilados por guardias armados con pasamonta\u00f1as y m\u00e1scaras de Halloween. Atravesamos lo que anta\u00f1o fue un barrio acomodado. Las buganvillas rosas a\u00fan se derramaban por encima de los altos muros y un campo de f\u00fatbol verde se abr\u00eda a unas vistas gloriosas de la ciudad.<\/p>\n<p>Ahora es casi una ciudad fantasma. Coches y motos empezaron a seguirnos, con sus conductores enmascarados y armas largas asomando por las ventanillas. Algunos veh\u00edculos llevaban las banderas rojas y azules de un convoy diplom\u00e1tico.<\/p>\n<p>Un miembro de Kraze Bary\u00e9 en Puerto Pr\u00edncipe, Hait\u00ed, el 18 de abril de 2024. Cr\u00e9dito: Evelio Contreras\/CNN<\/p>\n<p>Al cabo de unos 45 minutos, un autom\u00f3vil dorado se puso delante y se detuvo. Innocent se baj\u00f3 del veh\u00edculo. Era delgado y aparentemente ven\u00eda desarmado, vestido con un traje batik de rayas brillantes y mocasines blandos, con una mara\u00f1a de cadenas de oro y una cruz colgada al cuello. Nos condujo al interior de una mansi\u00f3n rococ\u00f3, en la que elaborados sillones y sof\u00e1s de terciopelo dorado, vitrinas de cristal y arreglos florales de pl\u00e1stico dejaban entrever la presencia de anteriores propietarios.<\/p>\n<p>Nos sentamos, quitando los osos de peluche de los asientos para hacer sitio, y hablamos del futuro.<\/p>\n<p>&#171;El Hait\u00ed que ten\u00edamos, el Hait\u00ed perla de las Antillas en el que crecimos, a\u00fan podr\u00eda volver a ser el m\u00e1s hermoso&#187;, dijo Innocent, hablando suavemente en criollo haitiano. &#171;Un d\u00eda, alguien podr\u00eda sentarse en Champ de Mars y tomarse un helado&#187;.<\/p>\n<p>Hoy, el emblem\u00e1tico parque Champ de Mars de la capital es una zona de guerra entre bandas y polic\u00eda. Tras a\u00f1os de agitaci\u00f3n pol\u00edtica, negligencia institucional y una serie de brutales cat\u00e1strofes naturales, la mala suerte de Hait\u00ed lleg\u00f3 a su punto m\u00e1s bajo el mes pasado con una ola de violencia de bandas sin precedentes que ha cerrado Puerto Pr\u00edncipe.<\/p>\n<p>Violencia de pandillas en Hait\u00ed mat\u00f3 a m\u00e1s de 1.500 personas este a\u00f1o, seg\u00fan un informe de derechos humanos de la ONU<\/p>\n<p>El principal puerto mar\u00edtimo y el aeropuerto de la ciudad est\u00e1n a oscuras. Los ministerios han sido ocupados por refugiados que huyen de los ataques de las bandas. Los cad\u00e1veres yacen entre la basura sin recoger en las calles y en los barrios a\u00fan libres del control de las bandas han surgido vigilantes llenos de miedo, que matan y queman a los forasteros sospechosos.<\/p>\n<p>Los signos de la disfunci\u00f3n de la ciudad eran evidentes dentro del basti\u00f3n de Kraze Bary\u00e9. Dentro de la enorme casa de Innocent, el aire estaba quieto y caliente; sus soldados se afanaban por poner en marcha un generador de aire acondicionado o un ventilador. Nadie se hab\u00eda molestado en retirar el sed\u00e1n destrozado que segu\u00eda junto a la piscina, con las ventanillas reventadas y cuatro ruedas pinchadas.<\/p>\n<p>Pero el hombre del sof\u00e1 dorado prefer\u00eda hablar de un futuro mejor, un futuro que, seg\u00fan \u00e9l, las bandas de Hait\u00ed est\u00e1n dispuestas a abrir.<\/p>\n<p>Sentarse con uno de los l\u00edderes de las bandas de Hait\u00ed es controvertido en el pa\u00eds, dado el sufrimiento y el terror que los grupos armados han sembrado durante mucho tiempo. Los incendios provocados y las violaciones colectivas son las t\u00e1cticas preferidas de las bandas para someter a la poblaci\u00f3n civil, seg\u00fan los expertos, y Naciones Unidas ha registrado el asesinato de al menos 1.660 personas y el secuestro de al menos 438 personas (incluidos 21 menores) vinculadas a las bandas solo en los primeros 90 d\u00edas del a\u00f1o.<\/p>\n<p>El propio Innocent est\u00e1 sancionado por las Naciones Unidas por los numerosos abusos contra los derechos humanos cometidos por Kraze Bary\u00e9 bajo su liderazgo, y est\u00e1 buscado por la Polic\u00eda Nacional de Hait\u00ed por secuestro extorsivo, asesinato, violaci\u00f3n, violencia sexual armada, robo de veh\u00edculos, robo y destrucci\u00f3n de bienes. Su grupo es conocido por atacar directamente a la Polic\u00eda Nacional de Hait\u00ed y ha intentado apoderarse de algunos de los barrios m\u00e1s ricos de Puerto Pr\u00edncipe.<\/p>\n<p>La violencia sexual queda &#171;en gran medida impune&#187; en Hait\u00ed, dice la ONU<\/p>\n<p>En su primera entrevista con la prensa extranjera, Innocent no neg\u00f3 las muertes, los incendios provocados, las violaciones ni los secuestros cometidos por las bandas aliadas de la ciudad, y declar\u00f3 a CNN que ha cometido algunos errores. Pero calific\u00f3 los \u00faltimos meses de violencia callejera mortal como da\u00f1os colaterales. Las muertes, tanto accidentales como extrajudiciales, tambi\u00e9n han sido causadas por la polic\u00eda, se\u00f1ala, alegando que se niega a dialogar.<br \/>\nDe lo \u00fanico que se arrepiente, dice, es de haberse metido en la pol\u00edtica.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1448665-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/haiti-gang-leader-armed-men-loop-2.mp4?_=1\" \/><a href=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/haiti-gang-leader-armed-men-loop-2.mp4\">https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/haiti-gang-leader-armed-men-loop-2.mp4<\/a><\/video><\/div>\n<p>Llegada a una casa controlada por una banda en Tabarre, Puerto Pr\u00edncipe, Hait\u00ed, el 18 de abril de 2024. Cr\u00e9dito: CNN<\/p>\n<p>Las bandas y los oligarcas<\/p>\n<p>Innocent, de 37 a\u00f1os, describe la amplia alianza de bandas que atacan las instituciones de Hait\u00ed como una empresa progresista. &#171;Nuestro sue\u00f1o es deshacernos de los oligarcas que impiden que el pa\u00eds progrese&#187;, dijo sobre la coalici\u00f3n de bandas que se hace llamar Viv Ansanm o &#171;Vivir Juntos&#187;.<\/p>\n<p>En febrero, Viv Ansanm lanz\u00f3 un asalto sin precedentes contra el Estado haitiano, atacando comisar\u00edas, prisiones, edificios gubernamentales, hospitales, el palacio nacional, la biblioteca nacional, buques de carga y la compa\u00f1\u00eda p\u00fablica de electricidad. Sus ataques coincidieron con una visita del entonces primer ministro Ariel Henry a Nairobi para mantener conversaciones sobre la posibilidad de que Kenya liderara una fuerza de seguridad multinacional para reforzar la Polic\u00eda Nacional de Hait\u00ed.<\/p>\n<p>Dimite el primer ministro de Hait\u00ed y toma juramento el consejo para liderar la transici\u00f3n pol\u00edtica en una naci\u00f3n devastada por la violencia<\/p>\n<p>Henry acab\u00f3 dimitiendo, como exig\u00eda Viv Ansanm, pero Innocent afirma que las bandas se oponen ahora al consejo de gobierno de transici\u00f3n creado para sustituirlo.<\/p>\n<p>La soluci\u00f3n de Innocent: &#171;Sentarse y escuchar a Viv Ansanm&#187;.<\/p>\n<p>Entonces, sugiere, &#171;habr\u00e1 una resoluci\u00f3n lo antes posible&#187;.<\/p>\n<p>Critica al consejo de gobierno por ser m\u00e1s de lo mismo, y dice que ya es hora de que se vayan las viejas \u00e9lites pol\u00edticas, una opini\u00f3n que comparten muchos en Hait\u00ed. Pero las bandas han mantenido durante mucho tiempo una relaci\u00f3n simbi\u00f3tica con los gobernantes de la naci\u00f3n, que utilizaban a los grupos armados para presionar a sus rivales mediante secuestros y otros ataques.<\/p>\n<p>La relaci\u00f3n contin\u00faa hoy en d\u00eda, aunque las bandas de Hait\u00ed act\u00faan cada vez m\u00e1s de forma independiente para amasar dinero y poder, seg\u00fan los expertos,<\/p>\n<p>&#171;S\u00ed, tengo un grupo armado. Yo los dirijo&#187;, afirma Innocent cuando se le pregunta por la implicaci\u00f3n de Kraze Bary\u00e9 en los secuestros. &#171;Pero si lo piensas realmente, \u00bftendr\u00edan estos tipos alguna idea de a qui\u00e9n secuestrar y a qui\u00e9n no? En absoluto&#187;.<\/p>\n<p>&#171;En realidad son las mismas personas que se sientan con (la organizaci\u00f3n regional) CARICOM para representar al pa\u00eds. Si decides bloquearlos, nos llamar\u00e1n y nos dir\u00e1n: &#8216;Tengo tal y tal trabajo&#8230; Arr\u00e9glanoslo&#8217;. Y entonces te enteras de que secuestraron a tal o cual. O que han tomado a tal persona como reh\u00e9n&#187;, dice.<\/p>\n<p>Coches abandonados en la carretera entre la Embajada de EE.UU. y el basti\u00f3n de Kraze Bary\u00e9 en Puerto Pr\u00edncipe, Hait\u00ed, el 28 de abril de 2024. Cr\u00e9dito: Evelio Contreras\/CNN<\/p>\n<p>Son los funcionarios corruptos los que hoy canalizan armas y municiones a las bandas, dijo.<\/p>\n<p>&#171;Pongamos un ejemplo claro. No podemos viajar. No podemos importar. No podemos exportar. Sin embargo, siempre llegan armas. Siempre hay balas. Y no tenemos representantes en la frontera. No tenemos representantes en las aduanas. Sin embargo, todos estos materiales pasan exactamente por estos canales. \u00bfC\u00f3mo llegan hasta nosotros?&#187;, afirma.<\/p>\n<p>La corrupci\u00f3n que describe no es ning\u00fan secreto. Hait\u00ed ocupa actualmente el puesto 172 de 180 pa\u00edses en el \u00cdndice Mundial de Percepci\u00f3n de la Corrupci\u00f3n. En el \u00faltimo a\u00f1o, las sanciones de Canad\u00e1 y Estados Unidos han acusado a antiguos primeros ministros y presidentes de Hait\u00ed (entre otras docenas de haitianos influyentes) de corrupci\u00f3n y financiaci\u00f3n de las bandas del pa\u00eds, entre otros delitos.<\/p>\n<p>\u00bfQu\u00e9 est\u00e1 pasando en Hait\u00ed? D\u00eda a d\u00eda, esto ha sucedido durante la reciente ola de violencia que azota al pa\u00eds<\/p>\n<p>Conduciendo a CNN por su territorio, Innocent dijo que recuerda a los ancianos locales cultivando en Tabarre durante su juventud en las d\u00e9cadas de 1980 y 90. &#171;Por supuesto, entonces pod\u00edamos cosechar&#187;, recuerda. Hoy, culpa a la dependencia de Hait\u00ed de los alimentos importados como una muestra m\u00e1s de c\u00f3mo el pa\u00eds ha sido mal gestionado por la clase alta, robando a la gente corriente toda oportunidad econ\u00f3mica.<\/p>\n<p>Antes de alzarse en armas, afirma, sus propios negocios leg\u00edtimos, incluidos un negocio de construcci\u00f3n, un hotel y una empresa de alquiler de coches, fueron destruidos por los poderosos intereses empresariales de la zona.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1448665-2\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/haiti-gang-leader-armed-men-loop-1.mp4?_=2\" \/><a href=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/haiti-gang-leader-armed-men-loop-1.mp4\">https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/haiti-gang-leader-armed-men-loop-1.mp4<\/a><\/video><\/div>\n<p>Miembros de Kraze Bary\u00e9 montan guardia en su territorio el 18 de abril de 2024. Cr\u00e9dito: CNN<\/p>\n<p>&#171;\u00bfPor qu\u00e9 atacar a la gente corriente si intentas defender al pueblo?&#187;<\/p>\n<p>Marie-Lucie Bonhomme Opont, de 55 a\u00f1os, conocida periodista de radio y televisi\u00f3n que vivi\u00f3 en Tabarre, tiene una visi\u00f3n diferente de lo que transform\u00f3 el barrio en el lugar desolado que es hoy.<\/p>\n<p>Cuenta que en junio del a\u00f1o pasado fue asaltada por miembros de Kraze Bary\u00e9, secuestrada y llevada a conocer al propio Innocent. &#171;Era medianoche y yo estaba durmiendo cuando, de repente, o\u00ed un alboroto tremendo en el piso de abajo&#187;, recuerda. &#171;Unas 30 personas armadas irrumpieron en mi casa y empezaron a saquearla, llev\u00e1ndose cosas, incluso comida de la cocina&#187;.<\/p>\n<p>Los ladrones exigieron dinero y luego, aparentemente insatisfechos, se la llevaron con ellos. Condujeron durante unos 45 minutos, seg\u00fan Opont.<\/p>\n<p>&#171;Estaba muy asustada, unos bandidos entrando en mi casa. Me sorprendi\u00f3 que esto pudiera ocurrir en mi propia casa. S\u00e9 que son violadores, han cometido violaciones atroces y otros delitos&#187;, afirma.<\/p>\n<p>Finalmente se detuvieron en la oscuridad. Opont cuenta a CNN que el propio Innocent se acerc\u00f3 entonces a su coche y le pregunt\u00f3 si reconoc\u00eda su voz. &#171;Por supuesto que s\u00ed&#187;, dice. &#171;Sol\u00eda dar ruedas de prensa y era muy activo en las redes sociales&#187;.<\/p>\n<p>\u00c9l tambi\u00e9n pareci\u00f3 reconocerla, dirigi\u00e9ndose a Opont por su nombre. &#171;Claro que sab\u00eda qui\u00e9n era&#187;, dice ella. &#171;Todo el mundo en el barrio sabe que esa es nuestra casa. Pero por qu\u00e9 me llevaron, no lo s\u00e9. Todav\u00eda me lo pregunto&#187;. La soltaron a la ma\u00f1ana siguiente sin dar explicaciones.<\/p>\n<p>Su marido, secuestrado una semana despu\u00e9s, no recibi\u00f3 el mismo trato. Retenido a la fuerza durante varios d\u00edas sin su medicaci\u00f3n, Pierre-Louis Opont fue liberado por Kraze Bary\u00e9 solo despu\u00e9s de que extrajeran de su familia el pago de un cuantioso rescate, cuenta ella.<\/p>\n<p>Se mudaron de Tabarre inmediatamente. &#171;Es lo que en Hait\u00ed llamamos un territoire perdue&#187;, dice de su antiguo barrio, un territorio perdido.<\/p>\n<p>&#171;Es una zona roja&#187;, explica Opont. &#171;Unos d\u00edas despu\u00e9s del secuestro de mi marido, unos pandilleros se instalaron en una casa cerca de la carretera principal y disparaban a los veh\u00edculos que pasaban&#187;.<\/p>\n<p>No tiene paciencia con la pretensi\u00f3n de los l\u00edderes de las bandas de luchar para liberar Hait\u00ed.<\/p>\n<p>&#171;\u00bfPor qu\u00e9 atacar a la gente corriente si lo que pretenden es defender al pueblo?&#187;, se pregunta. &#171;Todo el barrio est\u00e1 constantemente aterrorizado por bandidos armados. \u00bfC\u00f3mo pueden las bandas decir que trabajan por el bien del pa\u00eds cuando tambi\u00e9n cometen secuestros, cuando tantas mujeres han sido v\u00edctimas de brutales violaciones?&#187;.<\/p>\n<p>Dentro del territorio de Kraze Bary\u00e9 en Puerto Pr\u00edncipe, Hait\u00ed, el 18 de abril de 2024. Cr\u00e9dito: Evelio Contreras\/CNN<\/p>\n<p>&#171;Depredador y protector&#187;<\/p>\n<p>Varios de los compa\u00f1eros de Innocent se han forjado una imagen p\u00fablica a trav\u00e9s de la prensa y las redes sociales. El expolic\u00eda Jimmy Ch\u00e9rizier, conocido como Barbeque, se presenta como un Robin Hood. Izo, de la banda &#171;Five Second&#187;, que opera cerca del principal puerto del pa\u00eds, es tambi\u00e9n un m\u00fasico que comparte videos musicales en internet. Y Lanmo Sanjou, l\u00edder de los 400 Mawozo (400 Idiotas), fue fotografiado recientemente fumando puros con un influencer en las redes sociales.<\/p>\n<p>Aunque son aliados, y a veces se re\u00fanen por videoconferencia, la alianza Viv Ansanm no significa necesariamente amistad. Acompa\u00f1ando a CNN hasta el l\u00edmite de su territorio, Innocent nos ense\u00f1\u00f3 el cauce de un r\u00edo y un frondoso paisaje arbolado. Pero nos advirti\u00f3 repetidamente de que no deb\u00edamos quedarnos mucho tiempo, ya que sus tropas se desplegaban en calzado deportivo y sandalias, con una variopinta variedad de armas preparadas.<\/p>\n<p>M\u00e1s tarde nos enterar\u00edamos de que al otro lado del cauce del r\u00edo estaba el territorio de 400 Mawozo, que presuntamente ha cooperado con Kraze Bary\u00e9 en secuestros y tambi\u00e9n intent\u00f3 matar a Innocent por una disputa de tierras, seg\u00fan dos expertos en seguridad del pa\u00eds.<\/p>\n<p>Vista del cauce de un r\u00edo en direcci\u00f3n al territorio de la banda haitiana 400 Mawozo el 18 de abril de 2024. Cr\u00e9dito: Evelio Contreras\/CNN<\/p>\n<p>En otros lugares de su vecindario, Innocent se afanaba en mostrar su liderazgo a la poblaci\u00f3n local, una postura que coincide con el papel de &#171;depredador y protector&#187; que los expertos de la ONU describen de los pandilleros haitianos, que funcionan como autoridades locales al tiempo que extorsionan a los negocios locales para pagar sus n\u00f3minas.<\/p>\n<p>Kraze Bary\u00e9 emplea a unos 100 hombres y mujeres, seg\u00fan el lugarteniente y primo de Innocent, el rubio blanquecino Dezod Augustin, de 34 a\u00f1os. El d\u00eda de la visita de CNN, varios miembros de la banda llevaban camisetas personalizadas con osos de peluche en la parte delantera y letras en la trasera que dec\u00edan &#171;Unidad de Seguridad de la Zona de Tabarre&#187;.<\/p>\n<p>Caminando lentamente por una calle sin asfaltar llena de vendedores, Innocent podr\u00eda haber sido cualquier pol\u00edtico en una reuni\u00f3n local, deteni\u00e9ndose a masajear el pie herido de una anciana del mercado y presentando a CNN a dos ciegos que hab\u00eda tomado bajo su protecci\u00f3n, culpando al Estado haitiano por no cuidar de ellos.<\/p>\n<p>Pero a medida que se acercaba el toque de queda nocturno, empezaron a aparecer botellas de cerveza y licor en las manos de nuestra comitiva. Innocent detuvo nuestra procesi\u00f3n en un puesto de comida a un lado de la carretera y pidi\u00f3 montones de cerdo guisado y pl\u00e1tanos fritos para compartir. El vendedor, un hombre de mediana edad, cumpli\u00f3 en silencio, sin mostrar reacci\u00f3n alguna ante los ayudantes armados de Innocent o los visitantes extranjeros.<\/p>\n<p>Los expertos en derechos humanos de Hait\u00ed advierten del peligro de tomarse al pie de la letra las manifestaciones de liderazgo comunitario.<\/p>\n<p>&#171;Los l\u00edderes de las bandas hablan de liberaci\u00f3n y de representar al pueblo para atraer el apoyo popular&#187;, advierte Gedeon Jean, un analista de derechos humanos de Puerto Pr\u00edncipe que ha seguido durante a\u00f1os el aumento de los secuestros cometidos por las bandas.<\/p>\n<p>&#171;Pero lo \u00fanico que quieren es m\u00e1s poder y un Estado que se acomode a su delincuencia&#187;.<\/p>\n<p>Un vendedor ambulante que vive en el territorio de Kraze Bary\u00e9 en Puerto Pr\u00edncipe, Hait\u00ed, el 18 de abril de 2024. Cr\u00e9dito: Evelio Contreras\/CNN<\/p>\n<p>Una isla estadounidense en el pa\u00eds de las bandas<\/p>\n<p>A menos de una milla de todo esto se encuentra la Embajada de EE.UU., con soldados apostados en su tejado para vigilar constantemente los matorrales que la rodean. Justo la semana pasada, miembros de Kraze Bary\u00e9 atacaron un barrio civil cercano, sacando a unas 150 personas de sus casas en la oscuridad y disparando a un hombre en el coraz\u00f3n, seg\u00fan un testigo presencial.<\/p>\n<p>Como isla dentro del territorio de Innocent, el complejo diplom\u00e1tico es una inversi\u00f3n de la propia relaci\u00f3n de Hait\u00ed con Estados Unidos; aqu\u00ed, Kraze Bary\u00e9 es la temible potencia regional, que domina los barrios de Torcell, Tabarre y Delmas por los que los estadounidenses deben cruzar para llegar a su embajada.<\/p>\n<p>Esta inc\u00f3moda geograf\u00eda tambi\u00e9n significa que Innocent se encuentra entre el resto de las bandas de Hait\u00ed y Washington, cuya capacidad y apetito de intervenci\u00f3n militar en el caos sangriento del pa\u00eds son objeto de constante especulaci\u00f3n en el pa\u00eds.<\/p>\n<p>Hasta ahora, Estados Unidos ha tratado de eludir cualquier implicaci\u00f3n militar en Hait\u00ed. M\u00e1s bien, el Secretario de Estado Antony Blinken anunci\u00f3 en marzo que Estados Unidos aportar\u00eda US$ 300 millones a una misi\u00f3n multinacional de apoyo a la seguridad del pa\u00eds. Pero hasta ahora, solo se han depositado US$ 18 millones en un Fondo Fiduciario gestionado por la ONU para la misi\u00f3n, de los que US$ 8,7 millones han sido aportados por Canad\u00e1, US$ 3,2 millones por Francia y US$ 6 millones por Estados Unidos.<\/p>\n<p>La misi\u00f3n dirigida por Kenya, que tambi\u00e9n incluir\u00eda personal de Bahamas, Bangladesh, Barbados, Benin, Chad y Jamaica, est\u00e1 actualmente en suspenso debido a la preocupaci\u00f3n por la inestabilidad pol\u00edtica de Hait\u00ed.<\/p>\n<p>Y a pesar de su condici\u00f3n de &#171;m\u00e1s buscado&#187;, o tal vez debido a ella, Innocent parece interesado en que la relaci\u00f3n de Kraze Bary\u00e9 con la embajada siga siendo de buena vecindad. &#171;Es un honor que un pa\u00eds tenga su embajada cerca de nosotros, es porque quiere colaborar con nosotros&#187;, dijo Innocent.<\/p>\n<p>El mes pasado, docenas de helic\u00f3pteros realizaron una serie de vuelos de evacuaci\u00f3n de emergencia para ciudadanos estadounidenses, aterrizando y despegando junto al edificio de la embajada, una operaci\u00f3n de alto riesgo que cualquier miembro de Kraze Bary\u00e9 habr\u00eda podido frustrar f\u00e1cilmente con unos cuantos disparos. Pero los vuelos llegaron y se fueron sin incidentes.<\/p>\n<p>Vitel&#8217;Homme Innocent, buscado por el FBI. Cr\u00e9dito: FBI<\/p>\n<p>Innocent se desentiende cuando se le pregunta sobre las acusaciones de las autoridades estadounidenses de que estuvo implicado en el secuestro en 2021 de m\u00e1s de una docena de misioneros estadounidenses y canadienses, incluidos ni\u00f1os peque\u00f1os, que permanecieron cautivos durante semanas; y en un ataque en 2022 contra la casa de una pareja de ancianos estadounidenses que se sald\u00f3 con la muerte de una mujer y la toma de su marido como reh\u00e9n para pedir un rescate antes de su liberaci\u00f3n final.<\/p>\n<p>Innocent se limita a decir que la justicia no le ha dado la oportunidad de responder a las acusaciones de Estados Unidos, pero que estar\u00eda dispuesto a defenderse ante los tribunales.<\/p>\n<p>&#171;Creemos en la ley. Queremos tomar la mejor decisi\u00f3n, consultar con un abogado y seguir el debido proceso&#187;, afirma.<\/p>\n<p>En Hait\u00ed, afirma, estar\u00eda dispuesto a enfrentarse al sistema judicial siempre y cuando la \u00e9lite corrupta tambi\u00e9n lo hiciera. &#171;Tenemos que deshacernos del sistema de los oligarcas, y estamos dispuestos tambi\u00e9n a responder ante el sistema de justicia de nuestro pa\u00eds, para que podamos ver d\u00f3nde se escond\u00eda el peor de los males&#187;.<\/p>\n<p>El Departamento de Estado no respondi\u00f3 a las peticiones de la CNN de hacer comentarios o de hablar con el embajador estadounidense en Hait\u00ed, Dennis Hankins.<\/p>\n<p>Qu\u00e9 har\u00eda falta para deponer las armas<\/p>\n<p>A pesar de todas sus demostraciones de fuerza, el control que ejercen las bandas haitianas es tenue y sus soldados suelen estar mal disciplinados y entrenados, afirman los expertos. Muchos observadores veteranos, entre ellos el exembajador de Estados Unidos Rick Barton, creen que bastar\u00eda con una peque\u00f1a fuerza de combate especializada, por ejemplo, unos cientos infantes de Marina, para detener toda la crisis y crear las condiciones adecuadas para que llegara una misi\u00f3n de seguridad multinacional m\u00e1s amplia y empezara a ayudar a la polic\u00eda haitiana.<\/p>\n<p>Hait\u00ed ya tiene un gobierno de transici\u00f3n, que jur\u00f3 su cargo el jueves. A\u00fan quedan por nombrar un nuevo jefe de gobierno y un gabinete, coordinar la llegada de una fuerza de seguridad multinacional para recuperar la capital y, finalmente, celebrar las tan esperadas elecciones.<\/p>\n<p>Hait\u00ed establece un consejo de transici\u00f3n en medio de la crisis<\/p>\n<p>Pero las bandas haitianas mantienen que merecen un asiento en la mesa de negociaciones. Si no lo consiguen, Viv Ansanm ejercer\u00e1 su influencia por otros medios, advierte Innocent.<\/p>\n<p>&#171;Lo entender\u00e1n cuando se den cuenta de que los aviones no pueden volar. Cuando vean que los inversores no pueden entrar. Cuando analicen que hay un mont\u00f3n de extranjeros que ya estaban en el pa\u00eds con proyectos que se vieron obligados a huir a sus pa\u00edses a esperar la estabilidad&#187;, dice.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1448665-3\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/innocent-haiti-gang-leader-loop-3.mp4?_=3\" \/><a href=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/innocent-haiti-gang-leader-loop-3.mp4\">https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/04\/innocent-haiti-gang-leader-loop-3.mp4<\/a><\/video><\/div>\n<p>Innocent muestra a CNN el territorio que controla en Puerto Pr\u00edncipe, Hait\u00ed, el 18 de abril de 2024. Cr\u00e9dito: CNN<\/p>\n<p>Jean, experto en derechos humanos, afirma que la dimisi\u00f3n del ex primer ministro Henry en marzo a instancias de la comunidad internacional fue un gran error que llev\u00f3 a Innocent y a otros a un camino imposible.<\/p>\n<p>La dimisi\u00f3n de Henry pareci\u00f3 validar las afirmaciones de las bandas de que son actores pol\u00edticos leg\u00edtimos; hoy, sienten que no se les ha dado el cr\u00e9dito debido, afirma Jean.<\/p>\n<p>&#171;Piensan: &#8216;Nosotros hicimos dimitir a Henry, as\u00ed que deber\u00edamos participar en la transici\u00f3n pol\u00edtica'&#187;, afirma. &#171;Pero concederles eso s\u00f3lo les validar\u00eda a\u00fan m\u00e1s&#187;.<\/p>\n<p>Entre sus demandas, las bandas quieren una amnist\u00eda bajo cualquier gobierno futuro, dice Innocent, y un plan para el futuro de los muchos j\u00f3venes que actualmente siguen sus \u00f3rdenes, dos cuestiones que tambi\u00e9n han planteado los miembros del consejo de gobierno.<\/p>\n<p>&#171;Cuando dejemos las armas, debemos saber que tenemos un Estado que aportar\u00e1 un marco para el futuro. \u00bfPuedo decirle a alguien que suelte el arma y coja una piedra para comer? En absoluto&#187;, afirma Innocent.<\/p>\n<p>&#8212; Editado por Rachel Clarke de CNN en Atlanta.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puerto Pr\u00edncipe, Hait\u00ed (CNN) &#8212; La foto de Vitel&#8217;homme Innocent en la lista de los diez m\u00e1s buscados del FBI sugiere a un hombre enloquecido: ojos desorbitados y salvajes, dientes al descubierto. Es la foto que cabr\u00eda esperar del l\u00edder de una banda acusada de desestabilizar una naci\u00f3n, que afirma estar bajo protecci\u00f3n divina y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448665","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds - Noticias\" \/>\n<meta property=\"og:description\" content=\"Puerto Pr\u00edncipe, Hait\u00ed (CNN) &#8212; La foto de Vitel&#8217;homme Innocent en la lista de los diez m\u00e1s buscados del FBI sugiere a un hombre enloquecido: ojos desorbitados y salvajes, dientes al descubierto. Es la foto que cabr\u00eda esperar del l\u00edder de una banda acusada de desestabilizar una naci\u00f3n, que afirma estar bajo protecci\u00f3n divina y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-29T19:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds\",\"datePublished\":\"2024-04-29T19:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/\"},\"wordCount\":4046,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/\",\"name\":\"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-29T19:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds - Noticias","og_description":"Puerto Pr\u00edncipe, Hait\u00ed (CNN) &#8212; La foto de Vitel&#8217;homme Innocent en la lista de los diez m\u00e1s buscados del FBI sugiere a un hombre enloquecido: ojos desorbitados y salvajes, dientes al descubierto. Es la foto que cabr\u00eda esperar del l\u00edder de una banda acusada de desestabilizar una naci\u00f3n, que afirma estar bajo protecci\u00f3n divina y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-29T19:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"20 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/"},"author":{"name":"","@id":""},"headline":"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds","datePublished":"2024-04-29T19:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/"},"wordCount":4046,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/","name":"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-29T19:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las bandas expulsaron al gobierno de Hait\u00ed. Un l\u00edder criminal buscado por el FBI afirma que est\u00e1n liberando al pa\u00eds","url":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/04\/29\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-29T19:03:47Z","datePublished":"2024-04-29T19:03:47Z","dateModified":"2024-04-29T19:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las bandas expulsaron al gobierno de Hait\\u00ed. Un l\\u00edder criminal buscado por el FBI afirma que est\\u00e1n liberando al pa\\u00eds\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/29\\\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/04\\\/29\\\/bandas-expulsaron-gobierno-haiti-lider-liberando-pais-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-29T19:03:47Z\",\"datePublished\":\"2024-04-29T19:03:47Z\",\"dateModified\":\"2024-04-29T19:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451490,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/07\/29\/haiti-disparos-cobertura-entrevista-cnn-puerto-principe-trax\/","url_meta":{"origin":1448665,"position":0},"title":"Las fuerzas de seguridad que protegen al l\u00edder de Hait\u00ed hacen disparos de &#171;cobertura&#187; tras abandonar una entrevista con CNN","author":"","date":"julio 29, 2024","format":false,"excerpt":"(CNN) -- Las fuerzas de seguridad que proteg\u00edan al l\u00edder de Hait\u00ed lo cubrieron mientras abandonaba un hospital de Puerto Pr\u00edncipe tras una entrevista con CNN, en un claro ejemplo de la violencia que sigue asolando a este pa\u00eds por parte de bandas criminales.CNN hab\u00eda estado entrevistando al primer ministro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449440,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/13\/puerto-principe-haiti-armas-drogas-trax\/","url_meta":{"origin":1448665,"position":1},"title":"En una ciudad de Ha\u00edt\u00ed aislada del mundo, las armas y las drogas siguen fluyendo","author":"","date":"mayo 13, 2024","format":false,"excerpt":"Puerto Pr\u00edncipe (CNN) -- En los raros d\u00edas en que las colinas que rodean Puerto Pr\u00edncipe se quedan en silencio, la gente lo nota.\"Si no se oyen disparos en alguna parte, probablemente las bandas se est\u00e9n quedando sin munici\u00f3n\", explica a CNN una fuente policial de la capital haitiana. \"Pero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447011,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/15\/operativo-captura-jimmy-barbecue-cherizier-haiti-pandillas-trax\/","url_meta":{"origin":1448665,"position":2},"title":"Intentan capturar al l\u00edder pandillero Jimmy &#171;Barbecue&#187; Cherizier en Hait\u00ed con un gran operativo, dicen fuentes","author":"","date":"marzo 15, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un gran operativo se lleva a cabo en Puerto Pr\u00edncipe, capital de Hait\u00ed, para capturar al l\u00edder pandillero Jimmy Cherizier, alias \"Barbecue\", seg\u00fan dijeron dos fuentes policiales a CNN. De acuerdo a las fuentes, m\u00faltiples unidades de fuerzas especiales participan en el esfuerzo.El operativo se despliega espec\u00edficamente en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456410,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/09\/masacre-pandillas-haiti-muertos-vudu-trax\/","url_meta":{"origin":1448665,"position":3},"title":"Masacre en Hait\u00ed deja m\u00e1s de 180 muertos tras acusaciones de pr\u00e1cticas de vud\u00fa, dicen ONU y grupos de derechos humanos","author":"","date":"diciembre 9, 2024","format":false,"excerpt":"El Gobierno de Hait\u00ed afirm\u00f3 que las pandillas del pa\u00eds cruzaron una \u201cl\u00ednea roja\u201d despu\u00e9s de haber matado supuestamente a m\u00e1s de 180 personas durante el fin de semana, luego de que un l\u00edder de una pandilla culpara a los practicantes del vud\u00fa por la grave enfermedad de su hijo.Un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449864,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/30\/ee-uu-negocia-pandilla-asegurar-cuerpos-misioneros-asesinados-haiti-trax\/","url_meta":{"origin":1448665,"position":4},"title":"Exclusiva: EE.UU. negocia con una pandilla para asegurar los cuerpos de los misioneros estadounidenses asesinados en Hait\u00ed","author":"","date":"mayo 30, 2024","format":false,"excerpt":"(CNN) -- El primer vuelo comercial de Estados Unidos a Hait\u00ed en meses realiz\u00f3 un sombr\u00edo viaje de ida y vuelta este jueves, regresando con los cuerpos de una joven pareja estadounidense asesinada por una pandilla en Puerto Pr\u00edncipe la semana pasada.Los restos de Davy y Natalie Lloyd fueron acompa\u00f1ados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446871,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/11\/dimite-ariel-henry-primer-ministro-haiti-trax\/","url_meta":{"origin":1448665,"position":5},"title":"Dimite el primer ministro de Hait\u00ed, Ariel Henry, mientras las bandas se desplazan a sus anchas por un pa\u00eds sumido en la crisis","author":"","date":"marzo 11, 2024","format":false,"excerpt":"(CNN) -- El asediado l\u00edder de Hait\u00ed, Ariel Henry, present\u00f3 su dimisi\u00f3n este lunes en la noche, seg\u00fan l\u00edderes regionales, tras semanas de caos creciente en la naci\u00f3n caribe\u00f1a, donde las bandas han estado atacando las estructuras gubernamentales y el orden social est\u00e1 al borde del colapso.El asesor del primer\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448665"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448665\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}