{"id":1448789,"date":"2024-05-02T15:03:42","date_gmt":"2024-05-02T22:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/"},"modified":"2024-05-02T15:03:42","modified_gmt":"2024-05-02T22:03:42","slug":"argentina-ocde-milei-mondino-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/","title":{"rendered":"Argentina inicia el proceso formal para ingresar a la OCDE"},"content":{"rendered":"<p>(CNN en Espa\u00f1ol) &#8212; La canciller de Argentina, Diana Mondino, dio comienzo este jueves al proceso de adhesi\u00f3n del pa\u00eds a la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico (OCDE), al recibir la Hoja de Ruta para convertirse en miembro.<\/p>\n<p>Mondino, tras iniciar su gira internacional en China, arrib\u00f3 la noche del mi\u00e9rcoles a Par\u00eds para participar de audiencias de trabajo que incluyen su asistencia a la Reuni\u00f3n Ministerial del Consejo de la OCDE, que tiene lugar este jueves y viernes.<\/p>\n<p>De esta manera, la ministra de Exteriores tuvo por la ma\u00f1ana un encuentro bilateral con Mathias Cormann, secretario general del organismo, y a las 11.30 am, hora local, particip\u00f3 en la ceremonia de bienvenida a las Hojas de Ruta para la Adhesi\u00f3n de Argentina e Indonesia, con la entrega formal del documento que da inicio al proceso de ingreso a la OCDE.<\/p>\n<p>Ingreso a la OCDE: qu\u00e9 beneficios puede traerle a Argentina<\/p>\n<p>Seg\u00fan inform\u00f3 la Canciller\u00eda, Mondino expres\u00f3 su agradecimiento y dijo que el objetivo del pa\u00eds es \u201chacer foco en un sistema basado en reglas, no s\u00f3lo para un mayor bienestar de nuestros ciudadanos, sino para consolidar la agenda por la libertad que Argentina est\u00e1 llevando adelante en estos momentos\u201d.<br \/>\nAdem\u00e1s, en l\u00ednea con la pol\u00edtica exterior que viene planteando el gobierno de Javier Milei, la canciller dijo que \u201cse abre un proceso nuevo que nos permitir\u00e1 volver a una inserci\u00f3n internacional\u201d. Y agreg\u00f3: \u201cComo una democracia y como miembro de una comunidad de democracias, esperamos tener un di\u00e1logo fruct\u00edfero con otros pa\u00edses miembros de la organizaci\u00f3n sobre buenas pol\u00edticas p\u00fablicas provenientes de la OCDE\u201d.<\/p>\n<p>La OCDE es un organismo internacional con sede en Par\u00eds integrada por 38 pa\u00edses, que promueve el desarrollo econ\u00f3mico y \u201cpol\u00edticas que favorezcan la prosperidad, la igualdad, las oportunidades y el bienestar para todas las personas\u201d, seg\u00fan figura en el sitio web de la entidad.<\/p>\n<p>En Latinoam\u00e9rica, solo M\u00e9xico, Chile, Colombia y Costa Rica forman parte de la OCDE, fundada en 1961 e integrada por pa\u00edses como Estados Unidos, Francia, Reino Unido, Alemania y Jap\u00f3n, entre otros. Por otro lado, cinco grandes econom\u00edas (Brasil, China, India, Indonesia y Sud\u00e1frica) operan como socios y participan en los debates de la organizaci\u00f3n, as\u00ed como de los estudios y bases estad\u00edsticas.<\/p>\n<p>El ingreso a la OCDE es un proceso exigente que requiere el cumplimiento de una serie de pautas establecidas en la Hoja de Ruta entregada al pa\u00eds postulante.<\/p>\n<p>Seg\u00fan se describe en el sitio web, los pa\u00edses deben \u201cser capaces de asumir las responsabilidades y exigencias que acompa\u00f1an al estatus de miembro activo de la organizaci\u00f3n\u201d y para verificar estos est\u00e1ndares \u201cse realiza un examen t\u00e9cnico para evaluar las pol\u00edticas y las pr\u00e1cticas del pa\u00eds en comparaci\u00f3n con las mejores pr\u00e1cticas de la OCDE\u201d. Luego de esta evaluaci\u00f3n, \u201cse estima la capacidad del pa\u00eds para implementar las normas\u201d y se indican las eventuales medidas para necesarias para cumplir dichos requisitos.<\/p>\n<p>En 2016, bajo el Gobierno de Mauricio Macri, Argentina envi\u00f3 una nota para ampliar su participaci\u00f3n en el organismo. Luego, en 2022, durante la presidencia de Alberto Fern\u00e1ndez, el organismo decidi\u00f3 iniciar las conversaciones de adhesi\u00f3n con el pa\u00eds, instancia que implica el trazado de la Hoja de Ruta.<\/p>\n<p>Luego de la asunci\u00f3n de Javier Milei en diciembre, el mandatario envi\u00f3 la solicitud de adhesi\u00f3n y se logr\u00f3 finalmente iniciar con los formalismos.<\/p>\n<p>Durante el encuentro con Cormann, Mondino estuvo acompa\u00f1ada por el embajador designado en Francia, Ian Sielecki; el secretario de Finanzas, Pablo Quirno; y el secretario de Relaciones Econ\u00f3micas Internacionales de la Canciller\u00eda, Marcelo Cima.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN en Espa\u00f1ol) &#8212; La canciller de Argentina, Diana Mondino, dio comienzo este jueves al proceso de adhesi\u00f3n del pa\u00eds a la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico (OCDE), al recibir la Hoja de Ruta para convertirse en miembro. Mondino, tras iniciar su gira internacional en China, arrib\u00f3 la noche del mi\u00e9rcoles a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448789","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Argentina inicia el proceso formal para ingresar a la OCDE - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Argentina inicia el proceso formal para ingresar a la OCDE - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN en Espa\u00f1ol) &#8212; La canciller de Argentina, Diana Mondino, dio comienzo este jueves al proceso de adhesi\u00f3n del pa\u00eds a la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico (OCDE), al recibir la Hoja de Ruta para convertirse en miembro. Mondino, tras iniciar su gira internacional en China, arrib\u00f3 la noche del mi\u00e9rcoles a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T22:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Argentina inicia el proceso formal para ingresar a la OCDE\",\"datePublished\":\"2024-05-02T22:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/\"},\"wordCount\":675,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/\",\"name\":\"Argentina inicia el proceso formal para ingresar a la OCDE - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-02T22:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argentina inicia el proceso formal para ingresar a la OCDE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argentina inicia el proceso formal para ingresar a la OCDE - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Argentina inicia el proceso formal para ingresar a la OCDE - Noticias","og_description":"(CNN en Espa\u00f1ol) &#8212; La canciller de Argentina, Diana Mondino, dio comienzo este jueves al proceso de adhesi\u00f3n del pa\u00eds a la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico (OCDE), al recibir la Hoja de Ruta para convertirse en miembro. Mondino, tras iniciar su gira internacional en China, arrib\u00f3 la noche del mi\u00e9rcoles a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-02T22:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/"},"author":{"name":"","@id":""},"headline":"Argentina inicia el proceso formal para ingresar a la OCDE","datePublished":"2024-05-02T22:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/"},"wordCount":675,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/","name":"Argentina inicia el proceso formal para ingresar a la OCDE - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-02T22:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Argentina inicia el proceso formal para ingresar a la OCDE"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Argentina inicia el proceso formal para ingresar a la OCDE","url":"http:\/\/noticiasya.com\/el-valle\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/05\/02\/argentina-ocde-milei-mondino-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-02T22:03:42Z","datePublished":"2024-05-02T22:03:42Z","dateModified":"2024-05-02T22:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Argentina inicia el proceso formal para ingresar a la OCDE\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/05\\\/02\\\/argentina-ocde-milei-mondino-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/05\\\/02\\\/argentina-ocde-milei-mondino-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-02T22:03:42Z\",\"datePublished\":\"2024-05-02T22:03:42Z\",\"dateModified\":\"2024-05-02T22:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463133,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/03\/consecuencias-aranceles-trump-peores-ocde-trax\/","url_meta":{"origin":1448789,"position":0},"title":"Las consecuencias de los aranceles de Trump son peores de lo que pens\u00e1bamos, afirma la OCDE","author":"","date":"junio 3, 2025","format":false,"excerpt":"La guerra comercial del presidente Donald Trump causar\u00e1 un da\u00f1o econ\u00f3mico mayor al esperado, tanto en Estados Unidos como en el resto del mundo, seg\u00fan nuevas previsiones de la Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico (OCDE).En un informe publicado el martes, el grupo de 38 naciones, en su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468984,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/04\/sheinbaum-jornada-laboral-mexico-region-orix\/","url_meta":{"origin":1448789,"position":1},"title":"Sheinbaum quiere reducir la jornada laboral en M\u00e9xico de 48 a 40 horas semanales: \u00bfc\u00f3mo es en el resto de la regi\u00f3n?","author":"","date":"diciembre 4, 2025","format":false,"excerpt":"M\u00e9xico se prepara para un cambio relevante en el mundo del trabajo. La presidenta Claudia Sheinbaum quiere que el pa\u00eds deje atr\u00e1s la semana laboral de 48 horas \u2014una de las m\u00e1s largas de Am\u00e9rica Latina\u2014 y se sume al grupo que apuesta por m\u00e1s tiempo de descanso y mejor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449276,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/08\/paro-general-9-mayo-argentina-transporte-horarios-orix\/","url_meta":{"origin":1448789,"position":2},"title":"Paro general del 9 de mayo en Argentina: horarios, qui\u00e9nes se adhieren, qu\u00e9 demandan y c\u00f3mo afecta al transporte","author":"","date":"mayo 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Confederaci\u00f3n General del Trabajo (CGT) realizar\u00e1 un paro nacional por 24 horas este jueves 9 de mayo en Argentina en contra de las pol\u00edticas econ\u00f3micas de Javier Milei.Se trata de la segunda medida de fuerza en cinco meses contra el gobierno. La primera fue el 24\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448841,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/03\/canciller-argentina-diana-mondino-dice-chinos-iguales-controversia-orix\/","url_meta":{"origin":1448789,"position":3},"title":"La canciller de Argentina dice que los chinos &#171;son todos iguales&#187; y desata una controversia; luego niega intenci\u00f3n discriminatoria","author":"","date":"mayo 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La ministra de Relaciones Exteriores de Argentina, Diana Mondino, desat\u00f3 una controversia este jueves al decir que una inspecci\u00f3n que el Gobierno realiz\u00f3 en la base espacial que China tiene en la provincia de Neuqu\u00e9n no pudo establecer que incluyera militares, ya que \u201cson chinos, son todos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461851,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/01\/garcia-vale-el-mercado-laboral-argentino-sigue-convaleciente-y-necesita-reformas-para-generar-empleo\/","url_meta":{"origin":1448789,"position":4},"title":"Garc\u00eda Vale: &#171;El mercado laboral argentino sigue convaleciente y necesita reformas para generar empleo&#187;","author":"","date":"mayo 1, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2014 El abogado laboralista H\u00e9ctor Garc\u00eda Vale dialog\u00f3 este jueves con Los Primeros de la Tarde sobre la situaci\u00f3n del empleo en la Argentina, los indicadores laborales de 2024 y la necesidad de reformas estructurales que incentiven la contrataci\u00f3n.\u201cSi el mercado laboral fuera un paciente, claramente sigue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460537,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/28\/agustin-etchebarne-economista-la-economia-es-una-tromba-viene-creciendo-fuerte\/","url_meta":{"origin":1448789,"position":5},"title":"Agust\u00edn Etchebarne: &#171;Estamos en una econom\u00eda con crecimiento franco&#187;","author":"","date":"marzo 28, 2025","format":false,"excerpt":"Agust\u00edn Etchebarne, economista y director general de la Fundaci\u00f3n Libertad y Progreso, analiz\u00f3 los datos del acuerdo con el FMI, anunciado por el gobierno nacional.En CNN Primera Ma\u00f1ana, afirm\u00f3 que \u201cel acuerdo trajo algunas dudas sobre el tema cambiario, se sabe que habr\u00e1 alg\u00fan cambio y trajo cierta incertidumbre, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448789"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448789\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}