{"id":1448895,"date":"2024-05-05T14:03:47","date_gmt":"2024-05-05T21:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/"},"modified":"2024-05-05T14:03:47","modified_gmt":"2024-05-05T21:03:47","slug":"israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/","title":{"rendered":"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes"},"content":{"rendered":"<p>(CNN) &#8212; El primer ministro de Israel, Benjam\u00edn Netanyahu, dijo que &#171;no puede aceptar&#187; las exigencias de Hamas para poner fin a la guerra en Gaza, en un intercambio de reproches entre ambas partes en medio de unas nuevas conversaciones sobre el cese del fuego que apenas dan se\u00f1ales de avance.<\/p>\n<p>Se cree que las conversaciones se han enfocado en un nuevo marco, propuesto por El Cairo, que exige que el grupo militante libere a los rehenes secuestrados en Israel a cambio de una pausa en las hostilidades en Gaza.<\/p>\n<p>Estos son los pa\u00edses que han roto relaciones diplom\u00e1ticas con Israel por la guerra contra Hamas en Gaza y otros motivos<\/p>\n<p>Una delegaci\u00f3n de Hamas abandon\u00f3 Egipto tras la \u00faltima ronda de agotadores meses de conversaciones, y afirm\u00f3 que &#171;se han mantenido conversaciones serias y en profundidad&#187;.<\/p>\n<p>Hab\u00eda motivos para el optimismo, ya que los medios de comunicaci\u00f3n egipcios citaban a un funcionario egipcio que afirmaba que se produjeron &#171;avances significativos&#187; en las negociaciones. Sin embargo, los comentarios m\u00e1s recientes de Israel y Hamas demuestran lo distantes que siguen ambos.<\/p>\n<p>El l\u00edder del bur\u00f3 pol\u00edtico de Hamas, Ismail Haniyeh, afirm\u00f3 este domingo en un comunicado que el grupo &#171;sigue deseando&#187; llegar a un acuerdo con los mediadores, pero que cualquier propuesta tendr\u00eda que garantizar la retirada israel\u00ed y el cese permanente de los combates en el enclave.<\/p>\n<p>Reiter\u00f3 que la delegaci\u00f3n llevaba &#171;posiciones positivas y flexibles&#187; encaminadas a detener &#171;la agresi\u00f3n contra nuestro pueblo, que es una posici\u00f3n fundamental y l\u00f3gica que sienta las bases para un futuro m\u00e1s estable&#187;.<\/p>\n<p>El jefe de Hamas, Ismail Haniyeh, volvi\u00f3 a exigir a Israel que se retire de Gaza. (Cr\u00e9dito: Vahid Salemi\/AP)<\/p>\n<p>Sin embargo, al referirse al gobierno de Israel, Haniyeh dijo que &#171;el mundo se ha convertido en reh\u00e9n de un gobierno extremista, que tiene un gran n\u00famero de problemas pol\u00edticos y cr\u00edmenes cometidos en Gaza&#187;, y acus\u00f3 a sus dirigentes de intentar &#171;sabotear los esfuerzos realizados a trav\u00e9s de los mediadores y las distintas partes&#187;.<\/p>\n<p>Netanyahu, por su part, acus\u00f3 a Hamas de plantear exigencias inaceptables en las conversaciones de El Cairo, y a\u00f1adi\u00f3 que Israel hab\u00eda &#171;demostrado su voluntad de llegar lejos&#187; en las negociaciones.<\/p>\n<p>Afirm\u00f3 que la exigencia de Hamas de que Israel se retirara de Gaza quedaba descartada.<\/p>\n<p>&#171;Hamas sigue atrincherado en sus posiciones extremas, la principal de ellas la exigencia de retirar todas nuestras fuerzas del enclave, poner fin a la guerra y dejar a Hamas intacto&#187;, dijo. &#171;El Estado de Israel no puede aceptar esto&#187;.<\/p>\n<p>&#171;No estamos dispuestos a aceptar una situaci\u00f3n en la que los batallones de Hamas salgan de sus b\u00fankeres, tomen de nuevo el control de Gaza, reconstruyan su infraestructura militar y vuelvan a amenazar a los ciudadanos de Israel en los asentamientos de los alrededores, en las ciudades del sur, en todas las partes del pa\u00eds&#187;.<\/p>\n<p>Los ni\u00f1os mueren de hambre en Gaza mientras persisten los puntos conflictivos del acuerdo de alto el fuego entre Israel y Hamas<\/p>\n<p>&#171;Israel no acceder\u00e1 a las exigencias de Hamas, que significan la rendici\u00f3n, y continuar\u00e1 los combates hasta alcanzar todos sus objetivos&#187;, afirm\u00f3 Netanyahu.<\/p>\n<p>Ofensiva inminente en Rafah<\/p>\n<p>En medio de las tensas negociaciones en curso se espera una ofensiva terrestre sobre la ciudad meridional gazat\u00ed de Rafah, donde se calcula que se refugian alrededor de 1,5 millones de palestinos que huyen de los combates en el norte.<\/p>\n<p>Estados Unidos intent\u00f3 aumentar la presi\u00f3n sobre Hamas para que acepte el acuerdo que hay sobre la mesa, al tiempo que trata de impedir que el Ej\u00e9rcito de Israel avance hacia Rafah. Recientemente, el secretario de Estado de EE.UU., Antony Blinken, mantuvo otra ronda de conversaciones de alto nivel en Israel este mi\u00e9rcoles.<\/p>\n<p>Sin embargo, el ministro de Defensa de Israel, Yoav Gallant, dijo este domingo a los soldados que esperaran &#171;una acci\u00f3n intensa en Rafah en un futuro pr\u00f3ximo, y en otros lugares de toda el enclave&#187;.<\/p>\n<p>Galant entr\u00f3 en el enclave la ma\u00f1ana de este domingo, seg\u00fan el Ministerio de Defensa, donde dijo a los soldados que Israel estaba &#171;comprometido con la eliminaci\u00f3n de Hamas y la liberaci\u00f3n de los rehenes&#187;.<\/p>\n<p>&#171;Una hambruna en toda regla&#187; est\u00e1 ocurriendo en Gaza, dice el director ejecutivo del Programa Mundial de Alimentos<\/p>\n<p>&#171;Reconocemos signos alarmantes de que Hamas en realidad no tiene la intenci\u00f3n de llegar a cualquier acuerdo general con nosotros, el significado de esto: la acci\u00f3n en Rafah y toda Gaza en un futuro pr\u00f3ximo&#187;, dijo Gallant.<\/p>\n<p>&#171;Estamos justo antes de una acci\u00f3n, estamos en alta disposici\u00f3n, las Fuerzas de Defensa de Israel (FDI) saben qu\u00e9 hacer, estamos preparados para las cosas y abarcar\u00e1 todo el enclave de norte a sur, toda la zona y dentro de Rafah&#187;.<\/p>\n<p>Aluvi\u00f3n de cohetes cerca de Kerem Shalom<\/p>\n<p>Mientras tanto, Israel cerr\u00f3 el cruce fronterizo de Kerem Shalom a los camiones humanitarios despu\u00e9s de que fuera impactado por al menos 10 cohetes la ma\u00f1ana de este domingo, seg\u00fan las FDI.<\/p>\n<p>El cruce ha sido fundamental para hacer llegar ayuda a Gaza.<\/p>\n<p>Se desconoce hasta el momento d\u00f3nde cayeron exactamente los cohetes en la zona o si hab\u00eda heridos o v\u00edctimas mortales. Las Brigadas Al-Qassam, brazo militar de Hamas, afirmaron haber atacado el cruce con cohetes.<\/p>\n<p>Tras la descarga de cohetes, el Coordinador de Actividades Gubernamentales en los Territorios (COGAT) de Israel culp\u00f3 a Hamas de que la ayuda no llegara al enclave asediado.<\/p>\n<p>En una publicaci\u00f3n en X, COGAT dijo: &#171;Hamas har\u00e1 cualquier cosa para impedir que la ayuda llegue a la poblaci\u00f3n de Gaza. En los \u00faltimos d\u00edas y en incidentes diferentes: Hamas dispar\u00f3 morteros contra el corredor con fines humanitarios, impidi\u00f3 que la ayuda viajara del sur al norte de Gaza e impidi\u00f3 que los residentes recibieran ayuda humanitaria&#187;.<\/p>\n<p>Un colaborador de CNN en Rafah, Gaza, dijo que la gente empez\u00f3 a temer, ya que inmediatamente despu\u00e9s de que los cohetes impactaran en Kerem Shalom, se escuchaba fuego de artiller\u00eda al este de la ciudad mientras aviones israel\u00edes atacaban objetivos no especificados.<\/p>\n<p>Eugenia Yosef, Tareq El-Helou y Kareem Khadder de CNN contribuyeron a este reporte<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El primer ministro de Israel, Benjam\u00edn Netanyahu, dijo que &#171;no puede aceptar&#187; las exigencias de Hamas para poner fin a la guerra en Gaza, en un intercambio de reproches entre ambas partes en medio de unas nuevas conversaciones sobre el cese del fuego que apenas dan se\u00f1ales de avance. Se cree que las [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1448895","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El primer ministro de Israel, Benjam\u00edn Netanyahu, dijo que &#171;no puede aceptar&#187; las exigencias de Hamas para poner fin a la guerra en Gaza, en un intercambio de reproches entre ambas partes en medio de unas nuevas conversaciones sobre el cese del fuego que apenas dan se\u00f1ales de avance. Se cree que las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T21:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes\",\"datePublished\":\"2024-05-05T21:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/\"},\"wordCount\":1104,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/\",\"name\":\"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-05T21:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes - Noticias","og_description":"(CNN) &#8212; El primer ministro de Israel, Benjam\u00edn Netanyahu, dijo que &#171;no puede aceptar&#187; las exigencias de Hamas para poner fin a la guerra en Gaza, en un intercambio de reproches entre ambas partes en medio de unas nuevas conversaciones sobre el cese del fuego que apenas dan se\u00f1ales de avance. Se cree que las [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-05T21:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/"},"author":{"name":"","@id":""},"headline":"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes","datePublished":"2024-05-05T21:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/"},"wordCount":1104,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/","name":"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-05T21:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Israel y Hamas intercambian reproches en medio de escasas se\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes","url":"http:\/\/noticiasya.com\/el-valle\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/05\/05\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-05T21:03:47Z","datePublished":"2024-05-05T21:03:47Z","dateModified":"2024-05-05T21:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Israel y Hamas intercambian reproches en medio de escasas se\\u00f1ales de avance en las conversaciones sobre el cese del fuego y los rehenes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/05\\\/05\\\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/05\\\/05\\\/israel-hamas-intercambian-reproches-escasas-senales-avance-conversaciones-alto-el-fuego-rehenes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-05T21:03:47Z\",\"datePublished\":\"2024-05-05T21:03:47Z\",\"dateModified\":\"2024-05-05T21:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463918,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/24\/plan-acuerdo-cese-del-fuego-israel-gaza-trax\/","url_meta":{"origin":1448895,"position":0},"title":"Israel acord\u00f3 un cese del fuego con Ir\u00e1n. \u00bfPodr\u00eda ser el de Gaza el siguiente?","author":"","date":"junio 24, 2025","format":false,"excerpt":"Tras 12 d\u00edas de intensos ataques entre Israel e Ir\u00e1n, marcados por los bombardeos estadounidenses contra instalaciones nucleares iran\u00edes durante el fin de semana y las represalias de Teher\u00e1n, el alto el fuego negociado por Estados Unidos parec\u00eda mantenerse el martes.Sin embargo, en Gaza, la ofensiva israel\u00ed no ha dado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449963,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/03\/fdi-cuatro-rehenes-israelies-gaza-muertos-trax\/","url_meta":{"origin":1448895,"position":1},"title":"Las FDI notifican a las familias de cuatro rehenes israel\u00edes retenidos en Gaza que &#171;ya no est\u00e1n vivos&#187;","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN) -- Las Fuerzas de Defensa de Israel dicen que sus representantes informaron a las familias de cuatro rehenes retenidos en Gaza \"que ya no est\u00e1n vivos\".Las FDI dijeron que hab\u00edan comunicado a las familias de Haim Perry, Yoram Metzger, Amiram Cooper y Nadav Popplewell \"que fueron brutalmente secuestrados en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446003,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/02\/25\/conversaciones-liberacion-rehenes-israel-gaza-hamas-trax\/","url_meta":{"origin":1448895,"position":2},"title":"Estados Unidos dice que se logr\u00f3 un &#171;entendimiento&#187; en las conversaciones sobre rehenes en Gaza, pero las negociaciones contin\u00faan","author":"","date":"febrero 25, 2024","format":false,"excerpt":"(CNN) -- Los negociadores han llegado a un \u201centendimiento\u201d sobre los contornos generales de un posible acuerdo para liberar a los rehenes retenidos por Hamas a cambio de un cese del fuego temporal en Gaza, dijo el domingo a CNN el asesor de Seguridad Nacional de la Casa Blanca, Jake\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466235,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/07\/propuesta-alto-fuego-liberacion-rehenes-israel-hamas-trax\/","url_meta":{"origin":1448895,"position":3},"title":"Estados Unidos presenta nuevos puntos para el alto el fuego en Medio Oriente que exigen la liberaci\u00f3n de todos los rehenes","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"Estados Unidos present\u00f3 nuevos principios para el alto el fuego en Medio Oriente que exigen la liberaci\u00f3n inmediata de todos los rehenes y el comeinzo de las negociaciones para un fin integral de la guerra, seg\u00fan dos funcionarios israel\u00edes familiarizados con las discusiones.Los principios fueron transmitidos a Hamas, seg\u00fan los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459213,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/26\/israel-hamas-nuevo-intercambio-rehenes-trax\/","url_meta":{"origin":1448895,"position":4},"title":"Israel y Hamas acuerdan un nuevo intercambio y el fr\u00e1gil alto el fuego en Gaza parece intacto","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Israel y Hamas alcanzaron un acuerdo para intercambiar los cuerpos de cuatro rehenes por la liberaci\u00f3n de cientos de presos palestinos, seg\u00fan inform\u00f3 una fuente israel\u00ed a CNN, lo que indica que el fr\u00e1gil alto el fuego en Gaza permanece intacto por ahora.Israel hab\u00eda retrasado la liberaci\u00f3n de cientos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449654,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/21\/egipto-terminos-acuerdo-alto-fuego-gaza-negociadores-trax\/","url_meta":{"origin":1448895,"position":5},"title":"Egipto cambi\u00f3 los t\u00e9rminos del acuerdo de alto el fuego en Gaza presentado a Hamas, sorprendiendo a los negociadores, seg\u00fan fuentes","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) -- Los servicios de inteligencia egipcios modificaron discretamente los t\u00e9rminos de una propuesta de alto el fuego que Israel ya hab\u00eda aprobado a principios de mes, frustrando en \u00faltima instancia un acuerdo que podr\u00eda haber liberado a rehenes israel\u00edes y prisioneros palestinos y abierto una v\u00eda para detener temporalmente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1448895"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1448895\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1448895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1448895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1448895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}