{"id":1452264,"date":"2024-08-29T03:03:53","date_gmt":"2024-08-29T10:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/"},"modified":"2024-08-29T03:03:53","modified_gmt":"2024-08-29T10:03:53","slug":"paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/","title":{"rendered":"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos"},"content":{"rendered":"<p>(CNN) &#8212; Tan solo unas semanas despu\u00e9s de finalizar los Juegos Ol\u00edmpicos de Par\u00eds, comenz\u00f3 de manera espectacular la ceremonia de apertura de los Juegos Paral\u00edmpicos, que se celebr\u00f3 fuera de un estadio por primera vez en la historia.<\/p>\n<p>140 artistas, incluidos 16 int\u00e9rpretes con discapacidad, ocuparon el centro del escenario con el desfile de atletas que comenz\u00f3 desde la parte inferior de los emblem\u00e1ticos Campos El\u00edseos antes de dirigirse a la famosa Place de la Concorde, la plaza m\u00e1s grande de la capital francesa.<\/p>\n<p>Un total de 168 delegaciones participaron en la celebraci\u00f3n.<\/p>\n<p>As\u00ed se vivi\u00f3 la inauguraci\u00f3n de los Juegos Paral\u00edmpicos en Par\u00eds<\/p>\n<p>El franc\u00e9s Micha\u00ebl J\u00e9r\u00e9miasz sostiene la llama paral\u00edmpica durante el relevo de la antorcha como parte de la ceremonia de apertura. (Cr\u00e9dito: Gonzalo Fuentes\/Pool\/AFP\/Getty Images)<\/p>\n<p>Los atletas Charles-Antoine Kouakou, Nantenin Ke\u00efta, Fabien Lamirault, Alexis Hanquinquant y \u00c9lodie Lorandi encendieron el pebetero ol\u00edmpico. (Cr\u00e9dito: Kacper Pempel\/Reuters)<\/p>\n<p>Las actuaciones musicales incluyeron una interpretaci\u00f3n de &#171;Non, je ne darete rien&#187; de Edith Piaf, a cargo de la artista francesa Christine and the Queens, una interpretaci\u00f3n de piano de Chilly Gonzales y S\u00e9bastien Tellier toc\u00f3 su \u00e9xito &#187; La Ritournelle &#171;.<\/p>\n<p>Tras el desfile, los atletas paral\u00edmpicos franceses Sandrine Martinet, triple medallista de bronce paral\u00edmpica y campeona de Para judo en R\u00edo 2016, y Arnaud Assoumani, medallista de oro paral\u00edmpico en salto de longitud F46 en Pek\u00edn 2008, prestaron juramento paral\u00edmpico.<\/p>\n<p>En una ceremonia de entrega de la antorcha entre atletas ol\u00edmpicos y paral\u00edmpicos, el seis veces medallista ol\u00edmpico y abanderado franc\u00e9s en los Juegos Ol\u00edmpicos Florent Manaudou pas\u00f3 la antorcha a Micha\u00ebl J\u00e9r\u00e9miasz, campe\u00f3n paral\u00edmpico de tenis en silla de ruedas en Pek\u00edn 2008 y ahora jefe de misi\u00f3n de la delegaci\u00f3n francesa en los Juegos Paral\u00edmpicos de Par\u00eds 2024.<\/p>\n<p>Los Juegos contar\u00e1n con m\u00e1s de 4.400 atletas que competir\u00e1n en 22 deportes paral\u00edmpicos en 549 eventos con medallas durante 11 d\u00edas.<\/p>\n<p>Se esperaba que m\u00e1s de 50.000 espectadores asistieran a la ceremonia, seg\u00fan los organizadores, y se estima que 300 millones de televidentes ver\u00edan el espect\u00e1culo.<\/p>\n<p>Tony Estanguet, presidente del Comit\u00e9 Organizador de Par\u00eds 2024, salud\u00f3 \u201cla revoluci\u00f3n paral\u00edmpica\u201d en su discurso inaugural .<\/p>\n<p>Se cree que asistieron a la ceremonia m\u00e1s de 50.000 espectadores. (Cr\u00e9dito: Julien de Rosa\/Pool\/AFP\/Getty Images)<\/p>\n<p>Los fuegos artificiales se elevan sobre la Plaza de la Concordia en Par\u00eds durante la ceremonia de apertura de los Juegos Paral\u00edmpicos de Par\u00eds. (Cr\u00e9dito: Noticias Kyodo\/Getty Images)<\/p>\n<p>\u201cLo que los hace revolucionarios es que, cuando les dijeron \u2018No\u2019, ustedes continuaron\u201d, dijo Estanguet.<\/p>\n<p>A\u00f1adi\u00f3: \u201cEsta noche nos est\u00e1n invitando a cambiar nuestras perspectivas, a cambiar nuestras actitudes, a cambiar nuestra sociedad para finalmente darle a cada persona su lugar pleno.<\/p>\n<p>\u201cPorque cuando empiece el deporte ya no veremos hombres y mujeres con discapacidad, os veremos a vosotros: veremos campeones\u201d, a\u00f1adi\u00f3.<\/p>\n<p>La competici\u00f3n comienza este jueves.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Tan solo unas semanas despu\u00e9s de finalizar los Juegos Ol\u00edmpicos de Par\u00eds, comenz\u00f3 de manera espectacular la ceremonia de apertura de los Juegos Paral\u00edmpicos, que se celebr\u00f3 fuera de un estadio por primera vez en la historia. 140 artistas, incluidos 16 int\u00e9rpretes con discapacidad, ocuparon el centro del escenario con el desfile de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452264","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Tan solo unas semanas despu\u00e9s de finalizar los Juegos Ol\u00edmpicos de Par\u00eds, comenz\u00f3 de manera espectacular la ceremonia de apertura de los Juegos Paral\u00edmpicos, que se celebr\u00f3 fuera de un estadio por primera vez en la historia. 140 artistas, incluidos 16 int\u00e9rpretes con discapacidad, ocuparon el centro del escenario con el desfile de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-29T10:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos\",\"datePublished\":\"2024-08-29T10:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/\"},\"wordCount\":560,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/\",\"name\":\"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-29T10:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos - Noticias","og_description":"(CNN) &#8212; Tan solo unas semanas despu\u00e9s de finalizar los Juegos Ol\u00edmpicos de Par\u00eds, comenz\u00f3 de manera espectacular la ceremonia de apertura de los Juegos Paral\u00edmpicos, que se celebr\u00f3 fuera de un estadio por primera vez en la historia. 140 artistas, incluidos 16 int\u00e9rpretes con discapacidad, ocuparon el centro del escenario con el desfile de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-29T10:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/"},"author":{"name":"","@id":""},"headline":"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos","datePublished":"2024-08-29T10:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/"},"wordCount":560,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/","name":"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-29T10:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Par\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\u00edmpicos","url":"http:\/\/noticiasya.com\/el-valle\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/08\/29\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-29T10:03:53Z","datePublished":"2024-08-29T10:03:53Z","dateModified":"2024-08-29T10:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Par\\u00eds acoge por primera vez una fascinante ceremonia de apertura al aire libre de los Juegos Paral\\u00edmpicos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/08\\\/29\\\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/08\\\/29\\\/paris-fascinante-ceremonia-apertura-al-aire-libre-de-los-juegos-paralimpicos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-29T10:03:53Z\",\"datePublished\":\"2024-08-29T10:03:53Z\",\"dateModified\":\"2024-08-29T10:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452247,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/28\/fotos-ceremonia-inauguracion-juegos-paralimpicos-paris-2024-orix\/","url_meta":{"origin":1452264,"position":0},"title":"FOTOS | Ceremonia de inauguraci\u00f3n de los Juegos Paral\u00edmpicos de Par\u00eds 2024","author":"","date":"agosto 28, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Los Juegos Paral\u00edmpicos de Par\u00eds 2024 iniciaron este mi\u00e9rcoles con su ceremonia de inauguraci\u00f3n en la plaza de la Concordia y los Campos El\u00edseos.El evento reunen a los 4.400 atletas paral\u00edmpicos m\u00e1s destacados del mundo, quienes competir\u00e1n en diversas disciplinas durante once d\u00edas.Los Juegos Paral\u00edmpicos de Par\u00eds 2024\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471400,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/18\/indignacion-ucrania-atletas-rusos-bielorrusos-paralimpicos-trax\/","url_meta":{"origin":1452264,"position":1},"title":"Indignaci\u00f3n en Ucrania: autoridades no participar\u00e1n de los Juegos Paral\u00edmpicos de Invierno tras una pol\u00e9mica decisi\u00f3n","author":"","date":"febrero 18, 2026","format":false,"excerpt":"Las autoridades ucranianas no asistir\u00e1n a los Juegos Paral\u00edmpicos de Invierno de 2026 en Mil\u00e1n Cortina en marzo, tras la decisi\u00f3n del Comit\u00e9 Paral\u00edmpico Internacional (CPI) de permitir que los atletas rusos y bielorrusos compitan bajo sus respectivas banderas nacionales, seg\u00fan un ministro ucraniano.Matvii Bidnyi, ministro de Deportes de Ucrania,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452281,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/29\/haidee-aceves-mexico-primera-medalla-paralimpica-paris-2024-rompe-record-continente-americano-orix\/","url_meta":{"origin":1452264,"position":2},"title":"Haidee Aceves le da a M\u00e9xico su primera medalla paral\u00edmpica de Par\u00eds 2024 y rompe r\u00e9cord del continente americano","author":"","date":"agosto 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Haidee Viviana Aceves P\u00e9rez obtuvo este jueves el segundo lugar en la carrera de 100 metros dorso clase S2 de la paranataci\u00f3n femenina y le dio a M\u00e9xico su primera medalla en los Juegos Paral\u00edmpicos de Par\u00eds 2024.La deportista mexicana \u2013originaria del estado de Jalisco\u2013 gan\u00f3 la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451450,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/07\/26\/fotos-mejores-imagenes-ceremonia-inauguracion-juegos-olimpicos-paris-2024-orix\/","url_meta":{"origin":1452264,"position":3},"title":"FOTOS | Las mejores im\u00e1genes de la ceremonia de inauguraci\u00f3n de los Juegos Ol\u00edmpicos de Par\u00eds 2024","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La ceremonia se celebra a orillas del r\u00edo Sena: es la primera vez que la ceremonia no tiene lugar en el interior de un estadio. El viernes ha estado marcado por lluvias.El exfutbolista franc\u00e9s Zinedine Zidane aparece en una pantalla antes de la ceremonia de apertura de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448159,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","url_meta":{"origin":1452264,"position":4},"title":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos","author":"","date":"abril 16, 2024","format":false,"excerpt":"(CNN) -- La llama de los Juegos Ol\u00edmpicos de Par\u00eds 2024 se encendi\u00f3 en Olimpia, la cuna de los antiguos Juegos Ol\u00edmpicos. La llama comenzar\u00e1 ahora su recorrido en un relevo para encender el pebetero que marcar\u00e1 la apertura de los Juegos en julio.Dignatarios y miembros del p\u00fablico se reunieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470958,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/06\/fotos-ceremonia-inauguracion-juegos-olimpicos-invierno-2026-trax\/","url_meta":{"origin":1452264,"position":5},"title":"En fotos: la ceremonia de inauguraci\u00f3n de los Juegos Ol\u00edmpicos de Invierno 2026","author":"","date":"febrero 6, 2026","format":false,"excerpt":"Los Juegos Ol\u00edmpicos de Invierno est\u00e1n de vuelta, y la fiesta ya comenz\u00f3 en Italia con una ceremonia de apertura repleta de estrellas que incluye a Andrea Bocelli y Mariah Carey.La ceremonia principal se lleva a cabo en el famoso estadio San Siro en Mil\u00e1n, pero tambi\u00e9n hay eventos sat\u00e9lite\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1452264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1452264"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1452264\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1452264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1452264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1452264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}