{"id":1452342,"date":"2024-09-01T23:03:50","date_gmt":"2024-09-02T06:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/"},"modified":"2024-09-01T23:03:50","modified_gmt":"2024-09-02T06:03:50","slug":"israel-huelga-muerte-rehenes-furia-netanyahu-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/","title":{"rendered":"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes"},"content":{"rendered":"<p>(CNN) &#8212; Israel se prepara el lunes para una huelga nacional que amenaza con paralizar &#171;toda&#187; la econom\u00eda tras la furia que se desat\u00f3 p\u00fablicamente por la muerte de seis cautivos en los t\u00faneles de Hamas bajo Gaza, mientras aumentan los llamamientos al primer ministro Benjamin Netanyahu para que garantice un acuerdo de alto el fuego a cambio de los rehenes.<\/p>\n<p>Desde la bulliciosa Tel Aviv hasta la ciudad meridional israel\u00ed de Eilat, decenas de miles de israel\u00edes salieron a la calle el domingo en una de las mayores protestas a escala nacional desde el inicio de la guerra de Israel contra Hamas. Y los manifestantes han prometido continuar su movimiento.<\/p>\n<p>La huelga general, que comenz\u00f3 el lunes por la ma\u00f1ana, refleja la ira hacia Netanyahu, a quien algunas familias de los rehenes y sus partidarios acusan de obstaculizar los esfuerzos para llegar a un acuerdo.<\/p>\n<p>A\u00fan no estaba claro el alcance de la huelga a primera hora del lunes, pero sus partidarios han prometido una respuesta nacional.<\/p>\n<p>Se esperaba que tres de las v\u00edctimas, entre ellas el israel\u00ed-estadounidense Hersh Goldberg-Polin, fueran liberadas en un eventual alto el fuego, seg\u00fan dijeron funcionarios israel\u00edes a CNN. Las autopsias mostraron que hab\u00edan recibido disparos a corta distancia el jueves o el viernes por la ma\u00f1ana; las fuerzas israel\u00edes anunciaron la recuperaci\u00f3n de sus cuerpos de un t\u00fanel subterr\u00e1neo en Rafah el s\u00e1bado.<\/p>\n<p>Hersh Goldberg-Polin, el estadounidense-israel\u00ed que se convirti\u00f3 en s\u00edmbolo del sufrimiento por los rehenes<\/p>\n<p>Los detalles de sus muertes avivaron la ira, palpable en todo el pa\u00eds, mientras los manifestantes bloqueaban carreteras, ondeaban banderas israel\u00edes y coreaban &#171;no les abandonaremos&#187; en referencia a los m\u00e1s de 100 rehenes, incluidos 35 que se cree que han muerto, retenidos en Gaza, seg\u00fan datos de la fficina del Primer Ministro israel\u00ed. La gran mayor\u00eda de esos rehenes fueron tomados durante el ataque de Hamas contra Israel del 7 de octubre, en el que murieron unas 1.200 personas y m\u00e1s de 200 fueron tomadas cautivas.<\/p>\n<p>En Tel Aviv, un grupo de manifestantes se situ\u00f3 detr\u00e1s de un cementerio simulado mientras sujetaban carteles que dec\u00edan &#171;nombrado por Benjamin Netanyahu&#187;, mientras culpaban al primer ministro de la muerte de los rehenes.<\/p>\n<p>M\u00e1s tarde por la noche, la polic\u00eda lanz\u00f3 granadas aturdidoras contra los manifestantes que bloqueaban la autopista Ayalon de la ciudad, seg\u00fan un video verificado por CNN. Naama Lazimi, miembro del Parlamento israel\u00ed presente en la manifestaci\u00f3n, declar\u00f3 en X que las granadas aturdidoras &#171;fueron lanzadas hacia ambos lados donde se encontraban los manifestantes por sorpresa y sin previo aviso&#187;.<\/p>\n<p>La polic\u00eda utiliza un ca\u00f1\u00f3n de agua durante la protesta del domingo en Tel Aviv. (Cr\u00e9dito: Tomer Appelbaum\/Reuters)<\/p>\n<p>La polic\u00eda israel\u00ed tambi\u00e9n dispar\u00f3 espuma de un ca\u00f1\u00f3n de agua contra los manifestantes que se encontraban en la carretera, lo que provoc\u00f3 que los manifestantes corearan: &#171;Agente, \u00bfa qui\u00e9n mantiene a salvo?&#187;.<\/p>\n<p>La polic\u00eda detuvo a 29 personas en la ciudad, acus\u00e1ndolas de vandalismo, alteraci\u00f3n del orden p\u00fablico y agresi\u00f3n a agentes.<\/p>\n<p>El Foro de Familiares de Rehenes y Desaparecidos afirm\u00f3 que al menos 700.000 personas participaron en las protestas en todo Israel, de las cuales se calcula que 550.000 lo hicieron en Tel Aviv. CNN no puede verificar las cifras de forma independiente y ha pedido a la polic\u00eda israel\u00ed que facilite una estimaci\u00f3n del tama\u00f1o de la multitud.<\/p>\n<p>En Tel Aviv, la multitud estaba visiblemente emocionada; muchos gritaron &#171;lo siento&#187; mientras se recitaban los nombres de los seis rehenes por un altavoz durante la protesta, que seg\u00fan los organizadores fue la mayor desde el comienzo de la guerra.<\/p>\n<p>Una manifestante dijo a CNN que estaba all\u00ed para mostrar su apoyo a su primo, cuyo cad\u00e1ver fue repatriado por las Fuerzas de Defensa de Israel (FDI) durante la noche. &#171;Estoy aqu\u00ed todas las semanas, quer\u00eda mostrar a su padre y a otros padres que estamos aqu\u00ed para ellos&#187;, dijo. &#171;Y por otro lado, estamos incre\u00edblemente enfadados con el gobierno. Lo que han estado haciendo es imperdonable&#187;.<\/p>\n<p>En Jerusal\u00e9n, los manifestantes pidieron la dimisi\u00f3n de Netanyahu mientras el gobierno celebraba una reuni\u00f3n del gabinete. Eden Kramer, que acudi\u00f3 a la concentraci\u00f3n con un ni\u00f1o peque\u00f1o en un cochecito, dijo que tambi\u00e9n se manifestaba por el futuro del ni\u00f1o. &#171;Esperamos que todo el mundo salga hoy para llevar un mensaje al gobierno: No podemos seguir as\u00ed&#187;, dijo.<\/p>\n<p>Acuerdo bajo cuestionamientos<\/p>\n<p>El descubrimiento de los cad\u00e1veres de los seis rehenes ha puesto en tela de juicio las negociaciones para un acuerdo.<\/p>\n<p>Ha aumentado el escepticismo sobre la voluntad de Netanyahu de llegar a un acuerdo dada la feroz oposici\u00f3n de los ministros de extrema derecha de su coalici\u00f3n. El futuro pol\u00edtico del primer ministro israel\u00ed depende en gran medida de sus socios de coalici\u00f3n de extrema derecha, varios de los cuales ya han amenazado con abandonar el gobierno y provocar su colapso si acepta el acuerdo.<\/p>\n<p>Durante una reuni\u00f3n del gabinete celebrada el domingo, el ministro de Defensa israel\u00ed, Yoav Gallant, arremeti\u00f3 contra el gobierno israel\u00ed por lo que, en su opini\u00f3n, era dar prioridad al control de una zona fronteriza clave conocida como el corredor Philadelphi frente a un acuerdo para liberar a los rehenes, calific\u00e1ndolo de &#171;verg\u00fcenza moral&#187;.<\/p>\n<p>El corredor Philadelphi, un tramo de 14 kil\u00f3metros que discurre a lo largo de la frontera entre Gaza y Egipto, est\u00e1 actualmente controlado por las FDI. El despliegue de tropas israel\u00edes a lo largo del corredor durante la primera fase de un acuerdo de alto el fuego ha sido un importante punto de discordia entre Israel y Hamas, que sostiene que las tropas israel\u00edes deben retirarse de la zona fronteriza. Netanyahu afirma que el control del corredor es necesario para impedir que Hamas reanude el contrabando de armas a trav\u00e9s de t\u00faneles situados bajo \u00e9l.<\/p>\n<p>Gallant, que se ha visto cada vez m\u00e1s aislado dentro del gabinete de Netanyahu en la cuesti\u00f3n del acuerdo sobre los rehenes, advirti\u00f3 el domingo a sus colegas que &#171;si seguimos por este camino, no conseguiremos alcanzar los objetivos que nos hemos fijado&#187;.<\/p>\n<p>Y a\u00f1adi\u00f3: &#171;Si queremos a los rehenes vivos, no tenemos tiempo&#187;.<\/p>\n<p>Miles de israel\u00edes, incluidas familias de los rehenes, asisten a una concentraci\u00f3n frente a la &#171;Plaza de los rehenes&#187; cerca del Museo de Arte de Tel Aviv, Israel, el 31 de agosto de 2024. (Cr\u00e9dito: Gili Yaari\/NurPhoto\/Getty Images)<\/p>\n<p>Un funcionario de alto rango estadounidense afirm\u00f3 que los asesinatos de los rehenes pon\u00edan en duda la seriedad de Hamas a la hora de intentar alcanzar un acuerdo, ya que tres de ellos iban a ser liberados como parte del entendimiento para un alto el fuego.<\/p>\n<p>&#171;Funcionarios estadounidenses hab\u00edan estado trabajando en un paquete final junto con Qatar y Egipto. El paquete inclu\u00eda a Hersh (Goldberg-Polin) y a varios de los rehenes que acaban de ser ejecutados&#187;, declar\u00f3 el domingo el alto funcionario estadounidense.<\/p>\n<p>&#171;Esto pone en duda la seriedad de Hamas respecto a un acuerdo, incluso mientras tambi\u00e9n aumenta la presi\u00f3n sobre Israel y Netanyahu personalmente&#187;.<\/p>\n<p>Una fuente familiarizada con las conversaciones de alto el fuego dijo a CNN que no estaba claro c\u00f3mo afectar\u00edan las muertes a las discusiones, a\u00f1adiendo que el impacto probablemente se ver\u00e1 en el pr\u00f3ximo d\u00eda o dos.<\/p>\n<p>La &#171;situaci\u00f3n es complicada&#187;, dijo la fuente. Actualmente no hay negociaciones conjuntas en persona con las partes, pero la fuente dijo que las discusiones contin\u00faan a trav\u00e9s de los canales regulares.<\/p>\n<p>El presidente de Estados Unidos, Joe Biden, y la vicepresidenta Kamala Harris se reunir\u00e1n el lunes en la Sala de Situaci\u00f3n con el equipo estadounidense que negocia un acuerdo, seg\u00fan la Casa Blanca.<\/p>\n<p>&#171;En una espiral descendente&#187;<\/p>\n<p>El ministro de Finanzas de Israel, Bezalel Smotrich, de extrema derecha, ha pedido al fiscal general del pa\u00eds que solicite medidas cautelares urgentes para impedir la huelga nacional prevista para el lunes.<\/p>\n<p>En una carta dirigida al fiscal general Gali Baharav-Miara, Smotrich argument\u00f3 que una huelga perjudicar\u00eda a la econom\u00eda en tiempos de guerra y sentar\u00eda un peligroso precedente. La oficina del fiscal general a\u00fan no ha comentado la petici\u00f3n.<\/p>\n<p>Anteriormente hab\u00eda dado instrucciones al departamento de salarios del Ministerio de Hacienda para que transmitiera la directiva de que no se pagar\u00eda a nadie que se sumara a la huelga del lunes.<\/p>\n<p>El presidente del mayor sindicato de Israel, conocido como Histadrut, advirti\u00f3 el domingo que el pa\u00eds estaba &#171;en una espiral descendente, y no dejamos de recibir bolsas para cad\u00e1veres&#187;.<\/p>\n<p>Arnon Bar-David, que convoc\u00f3 la huelga, dijo en rueda de prensa que &#171;solo una huelga conmocionar\u00eda, y por eso he decidido que a partir de ma\u00f1ana a las seis de la ma\u00f1ana, toda la econom\u00eda israel\u00ed se paralizar\u00e1&#187;.<\/p>\n<p>A\u00f1adi\u00f3 que la huelga incluir\u00eda el cierre del aeropuerto Ben-Gurion. En un comunicado, el aeropuerto Ben-Gurion dijo que estar\u00eda &#171;abierto para vuelos y aterrizajes el lunes 2 de septiembre&#187;.<\/p>\n<p>La Universidad Hebrea de Jerusal\u00e9n dijo que se unir\u00eda a la huelga, que describi\u00f3 como una &#171;respuesta a la tr\u00e1gica noticia del asesinato de nuestra estudiante Carmel Gat, junto con otros cinco rehenes israel\u00edes&#187;.<\/p>\n<p>Gat, terapeuta ocupacional de 40 a\u00f1os, fue sacada por Hamas de la casa de sus padres en el kibutz fronterizo de Be&#8217;eri, en el sur de Israel, el 7 de octubre.<\/p>\n<p>Eyad Kourdi, Jeremy Diamond y Mike Schwartz de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Israel se prepara el lunes para una huelga nacional que amenaza con paralizar &#171;toda&#187; la econom\u00eda tras la furia que se desat\u00f3 p\u00fablicamente por la muerte de seis cautivos en los t\u00faneles de Hamas bajo Gaza, mientras aumentan los llamamientos al primer ministro Benjamin Netanyahu para que garantice un acuerdo de alto el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452342","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Israel se prepara el lunes para una huelga nacional que amenaza con paralizar &#171;toda&#187; la econom\u00eda tras la furia que se desat\u00f3 p\u00fablicamente por la muerte de seis cautivos en los t\u00faneles de Hamas bajo Gaza, mientras aumentan los llamamientos al primer ministro Benjamin Netanyahu para que garantice un acuerdo de alto el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-02T06:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes\",\"datePublished\":\"2024-09-02T06:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/\"},\"wordCount\":1679,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/\",\"name\":\"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-09-02T06:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes - Noticias","og_description":"(CNN) &#8212; Israel se prepara el lunes para una huelga nacional que amenaza con paralizar &#171;toda&#187; la econom\u00eda tras la furia que se desat\u00f3 p\u00fablicamente por la muerte de seis cautivos en los t\u00faneles de Hamas bajo Gaza, mientras aumentan los llamamientos al primer ministro Benjamin Netanyahu para que garantice un acuerdo de alto el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/","og_site_name":"Noticias","article_published_time":"2024-09-02T06:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/"},"author":{"name":"","@id":""},"headline":"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes","datePublished":"2024-09-02T06:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/"},"wordCount":1679,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/","url":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/","name":"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-09-02T06:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes","url":"http:\/\/noticiasya.com\/el-valle\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/09\/01\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-09-02T06:03:50Z","datePublished":"2024-09-02T06:03:50Z","dateModified":"2024-09-02T06:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Israel se prepara para una huelga general en medio del dolor y la furia por la muerte de otros seis rehenes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/09\\\/01\\\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/09\\\/01\\\/israel-huelga-muerte-rehenes-furia-netanyahu-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-09-02T06:03:50Z\",\"datePublished\":\"2024-09-02T06:03:50Z\",\"dateModified\":\"2024-09-02T06:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1465361,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/10\/familias-rehenes-convocan-protesta-nacional-israel-trax\/","url_meta":{"origin":1452342,"position":0},"title":"Familias de rehenes convocan a protesta nacional mientras Israel se prepara para intensificar su guerra en Gaza","author":"","date":"agosto 10, 2025","format":false,"excerpt":"Las familias de los rehenes israel\u00edes cautivos en Gaza est\u00e1n convocando a una protesta general a nivel nacional el pr\u00f3ximo domingo, en protesta por la reciente decisi\u00f3n del gabinete de seguridad israel\u00ed de expandir su guerra y tomar el control de la ciudad de Gaza.\u201cParalizaremos el pa\u00eds para salvar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452388,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/03\/brutales-tacticas-hamas-nueva-fase-guerra-rehenes-trax\/","url_meta":{"origin":1452342,"position":1},"title":"Las nuevas y brutales t\u00e1cticas de Hamas se\u00f1alan una nueva fase en la guerra y en la crisis de los rehenes","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN) --\u00a0Ante el anuncio de que los combatientes que custodian a los rehenes israel\u00edes en los edificios y t\u00faneles de Gaza ten\u00edan \"nuevas instrucciones\" de matarlos si las fuerzas israel\u00edes se acercaban, Hamas se\u00f1al\u00f3 la apertura de un escalofriante nuevo cap\u00edtulo en una guerra ya de por s\u00ed brutal.Aprovechando un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459750,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/nueva-york-despide-guardias-prision-huelga-trax\/","url_meta":{"origin":1452342,"position":2},"title":"Nueva York despidi\u00f3 a m\u00e1s de 2.000 guardias penitenciarios por no volver a trabajar tras una huelga de semanas","author":"","date":"marzo 10, 2025","format":false,"excerpt":"Nueva York despidi\u00f3 a m\u00e1s de 2.000 guardias de prisi\u00f3n el lunes por no regresar al trabajo tras una huelga de semanas que paraliz\u00f3 el sistema penitenciario del estado, pero inform\u00f3 que suficientes agentes hab\u00edan vuelto al trabajo para declarar la huelga como terminada.\u201cDespu\u00e9s de 22 d\u00edas de una huelga\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447733,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/04\/biden-netanyahu-proteger-civiles-gaza-trax\/","url_meta":{"origin":1452342,"position":3},"title":"Biden le advierte a Netanyahu que proteja a los civiles en Gaza o enfrente las consecuencias","author":"","date":"abril 4, 2024","format":false,"excerpt":"Washington (CNN) -- El presidente Joe Biden dijo este jueves al primer ministro de Israel Benjamin Netanyahu que la situaci\u00f3n humanitaria general en Gaza es inaceptable y advirti\u00f3 a Israel que tome medidas para hacer frente a la crisis o se enfrentar\u00e1 a las consecuencias, una dura declaraci\u00f3n del aliado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452476,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/06\/analisis-esfuerzo-estadounidense-acuerdo-israel-hamas-trax\/","url_meta":{"origin":1452342,"position":4},"title":"AN\u00c1LISIS | La presi\u00f3n de Estados Unidos por un acuerdo entre Israel y Hamas es un fracaso repetido. Pero EE.UU. no puede abandonar","author":"","date":"septiembre 6, 2024","format":false,"excerpt":"(CNN) -- Durante meses, Estados Unidos persigui\u00f3 un espejismo: un acuerdo para liberar a los rehenes de Gaza, poner fin a la agon\u00eda de los civiles palestinos y detener los combates entre Israel y Hamas.Pero su objetivo nunca ha parecido tan remoto, y el Gobierno de Biden rara vez ha\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450001,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/03\/netanyahu-elegir-gobierno-acuerdo-alto-fuego-trax\/","url_meta":{"origin":1452342,"position":5},"title":"AN\u00c1LISIS | Netanyahu puede verse obligado a elegir entre la supervivencia de su gobierno y un acuerdo de cese del fuego","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN) \u2013 El primer ministro de Israel, Benjam\u00edn Netanyahu, podr\u00eda verse obligado a elegir entre aceptar un acuerdo de cese del fuego con Hamas o mantener su gobierno en el poder.Pero mientras se enfrenta a esa elecci\u00f3n, Netanyahu tambi\u00e9n busca una manera de evitarla por completo.Durante meses, Netanyahu equilibr\u00f3 cautelosamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1452342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1452342"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1452342\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1452342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1452342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1452342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}