{"id":1452367,"date":"2024-09-02T17:03:44","date_gmt":"2024-09-03T00:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/"},"modified":"2024-09-02T17:03:44","modified_gmt":"2024-09-03T00:03:44","slug":"analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/","title":{"rendered":"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos"},"content":{"rendered":"<p>(CNN) &#8212; Ahora que los ni\u00f1os est\u00e1n de regreso en el colegio, muchas escuelas no les permiten llevar sus tel\u00e9fonos a clase. En muchas ciudades y estados se han propuesto o aprobado leyes para prohibir los tel\u00e9fonos en las escuelas. La mayor\u00eda de las escuelas ya tienen pol\u00edticas que los proh\u00edben para uso no acad\u00e9mico, seg\u00fan el Centro Nacional de Estad\u00edsticas Educativas.<\/p>\n<p>Los padres suelen cuestionar estas pol\u00edticas porque quieren poder contactar con sus hijos en caso de emergencia, como un tiroteo en la escuela.\u00a0Sin embargo, las investigaciones sugieren que no s\u00f3lo es una buena idea que los menores guarden sus tel\u00e9fonos mientras est\u00e1n en clase, sino que no deber\u00edan llevarlos a la escuela en absoluto.<\/p>\n<p>La adicci\u00f3n a Internet puede afectar el cerebro de los adolescentes, seg\u00fan un nuevo estudio<\/p>\n<p>Alrededor del 97% de los ni\u00f1os de 11 a 17 a\u00f1os utilizan sus tel\u00e9fonos durante el horario escolar, durante una media de 43 minutos, seg\u00fan un estudio de Common Sense Media de 2023. Si consultan sus tel\u00e9fonos entre clase y clase o durante el almuerzo y el recreo, es probable que est\u00e9n preocupados por lo que ven en sus pantallas y, por lo tanto, pasen menos tiempo hablando, jugando o incluso simplemente pasando el rato con sus amigos.<\/p>\n<p>Esa preocupaci\u00f3n no es saludable porque, como escribi\u00f3 el psic\u00f3logo social Jonathan Haidt en &#171;The Anxious Generation: How the Great Rewiring of Childhood is Causing an Epidemic of Mental Illness&#187;, una de las cosas m\u00e1s importantes que deber\u00edan hacer los j\u00f3venes es jugar con sus iguales.<\/p>\n<p>Los menores aprenden durante el juego a desenvolverse en la din\u00e1mica social y adquieren habilidades al averiguar c\u00f3mo realizar diferentes actividades. El juego les ense\u00f1a que pueden manejar otros retos a los que se enfrentar\u00e1n en el futuro, lo que, seg\u00fan Haidt, puede ayudarles a protegerse de la ansiedad.<\/p>\n<p>Los ni\u00f1os pueden pasar menos tiempo hablando y pasando el rato con sus amigos si est\u00e1n ocupados comprobando sus tel\u00e9fonos durante el almuerzo o el recreo. Cr\u00e9dito: Klaus Vedfelt\/Digital Vision\/Getty Images<\/p>\n<p>Los tel\u00e9fonos inteligentes no est\u00e1n haciendo a los ni\u00f1os m\u00e1s inteligentes<\/p>\n<p>Pero los tel\u00e9fonos no s\u00f3lo est\u00e1n entrometi\u00e9ndose en el tiempo de los ni\u00f1os fuera de clase. En una encuesta realizada en junio por el Pew Research Center, el 72% de los profesores de institutos p\u00fablicos afirmaron que las distracciones por tel\u00e9fono m\u00f3vil son un problema importante en sus aulas. Si los ni\u00f1os est\u00e1n echando miradas furtivas a sus tel\u00e9fonos, es imposible que est\u00e9n prestando atenci\u00f3n a lo que se supone que deber\u00edan estar aprendiendo. Un amplio conjunto de pruebas nos dice que el cerebro humano no puede realizar varias tareas a la vez: s\u00f3lo podemos hacer una cosa a la vez.<\/p>\n<p>Un indicador de que los estudiantes no est\u00e1n aprendiendo tanto en la escuela como lo hac\u00edan en la era anterior a los tel\u00e9fonos son las puntuaciones en el ACT, un examen estandarizado que mide si tienen las habilidades de ingl\u00e9s, lectura, matem\u00e1ticas y ciencias necesarias para los cursos universitarios de primer a\u00f1o. El a\u00f1o pasado, las puntuaciones del ACT cayeron al nivel m\u00e1s bajo en m\u00e1s de 30 a\u00f1os, seg\u00fan la organizaci\u00f3n que administra el examen.<\/p>\n<p>Como profesora que ha impartido clases en cinco universidades desde 2010, yo misma he sido testigo de esta tendencia. Cuando empec\u00e9 a dar clases, antes de que los smartphones se hicieran omnipresentes, muchos de mis alumnos llegaban mejor preparados para concentrarse y trabajar en largos pasajes de lectura que ahora.<\/p>\n<p>Por supuesto, es f\u00e1cil imaginar c\u00f3mo responder\u00e1n los ni\u00f1os si les pedimos que dejen sus tel\u00e9fonos en casa: prometer\u00e1n no mirarlos durante la jornada escolar. Por desgracia, no es razonable esperar que luchen contra el impulso de mirar productos que est\u00e1n dise\u00f1ados para ser adictivos, con funciones como el desplazamiento sin fondo y las notificaciones continuas. El adolescente medio recibe 237 notificaciones telef\u00f3nicas al d\u00eda en su tel\u00e9fono, seg\u00fan el estudio de Common Sense Media, y una cuarta parte de ellas durante la jornada escolar.<\/p>\n<p>Enviar a los ni\u00f1os a la escuela sin tel\u00e9fonos inteligentes les obliga a concentrarse en lo que ocurre delante de ellos y no en sus pantallas. Esa es otra habilidad importante que aprender.\u00a0&#171;La vida centrada en el tel\u00e9fono dificulta que las personas est\u00e9n plenamente presentes con los dem\u00e1s cuando est\u00e1n con otros, y que se sienten en silencio consigo mismas cuando est\u00e1n solas&#187;, advirti\u00f3 Haidt.<\/p>\n<p>As\u00ed ven los adolescentes el impacto de las redes sociales en su salud mental<\/p>\n<p>Tel\u00e9fonos inteligentes y seguridad<\/p>\n<p>Adem\u00e1s, la idea de que llevar un tel\u00e9fono hace que los ni\u00f1os est\u00e9n m\u00e1s seguros suele ser un mito.<\/p>\n<p>Los tel\u00e9fonos pueden distraer peligrosamente a los adolescentes. En una de mis charlas recientes en un colegio privado, la psic\u00f3loga del centro dijo a los padres que ve regularmente a sus hijos salir del colegio mirando sus pantallas mientras cruzan las calles de Manhattan. As\u00ed que, en primer lugar, los tel\u00e9fonos pueden provocar emergencias.<\/p>\n<p>Por supuesto, si los ni\u00f1os tienen una crisis de camino a casa desde el colegio, en la mayor\u00eda de los lugares de Estados Unidos habr\u00e1 negocios y personas alrededor con tel\u00e9fonos que estar\u00e1n dispuestos a dejarles llamar a sus padres.<\/p>\n<p>Del mismo modo, aunque muchos padres desear\u00edan poder ponerse en contacto con sus hijos en el impensable caso de un tiroteo en la escuela, los ni\u00f1os estar\u00e1n m\u00e1s seguros si permanecen tranquilos y concentrados en las instrucciones que reciban de los administradores de la escuela o de las fuerzas del orden.<\/p>\n<p>Los adolescentes sienten menos apoyo emocional del que sus padres creen que reciben, seg\u00fan un nuevo informe<\/p>\n<p>Adem\u00e1s, los ni\u00f1os suelen tener experiencias extraordinariamente peligrosas con sus tel\u00e9fonos. En agosto, un informe de Thorn, una organizaci\u00f3n sin fines de lucro que lucha contra los abusos sexuales a menores, revel\u00f3 que la gran mayor\u00eda -el 59%- de los j\u00f3venes afirm\u00f3 haber tenido experiencias en l\u00ednea que han sido potencialmente da\u00f1inas. Uno de cada 3 menores y 1 de cada 5 preadolescentes dijeron haber tenido experiencias sexuales en l\u00ednea con alguien que cre\u00edan que era un adulto, seg\u00fan el informe.<\/p>\n<p>Es cierto que dejar que los ni\u00f1os lleven tel\u00e9fonos a la escuela puede facilitar la coordinaci\u00f3n de cosas como las recogidas despu\u00e9s de las actividades extraescolares. Si los ni\u00f1os realmente necesitan un tel\u00e9fono para comunicarse con sus padres -quiz\u00e1 porque padecen una enfermedad y necesitan poder localizar a alguien en caso de emergencia o porque los arreglos para recogerlos son tan complicados que no se puede fijar una hora y un lugar por adelantado- una opci\u00f3n que Haidt recomend\u00f3 es un tel\u00e9fono plegable a la antigua usanza.<\/p>\n<p>Tener uno les permite enviar mensajes de texto o llamar, pero no conectarse a las redes sociales.<\/p>\n<p>Es poco probable que enviar a los ni\u00f1os a la escuela con tel\u00e9fonos inteligentes les haga m\u00e1s inteligentes o seguros. Es m\u00e1s probable que les distraiga y les impida centrarse en el aprendizaje.<\/p>\n<p>Sin tel\u00e9fono, los ni\u00f1os pueden centrarse en interactuar con sus compa\u00f1eros, aprender y estar plenamente presentes en su entorno, en lugar de que estas cosas compitan por su atenci\u00f3n con los influencers y los memes de Internet.<\/p>\n<p>Nota del editor: Kara Alaimo es profesora asociada de Comunicaci\u00f3n en la Universidad Fairleigh Dickinson. Su libro &#171;Over the Influence: Why Social Media Is Toxic for Women and Girls &#8211; And How We Can Take It Back&#187; fue publicado recientemente por Alcove Press. S\u00edguela en Instagram, Facebook y X.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Ahora que los ni\u00f1os est\u00e1n de regreso en el colegio, muchas escuelas no les permiten llevar sus tel\u00e9fonos a clase. En muchas ciudades y estados se han propuesto o aprobado leyes para prohibir los tel\u00e9fonos en las escuelas. La mayor\u00eda de las escuelas ya tienen pol\u00edticas que los proh\u00edben para uso no acad\u00e9mico, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452367","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Ahora que los ni\u00f1os est\u00e1n de regreso en el colegio, muchas escuelas no les permiten llevar sus tel\u00e9fonos a clase. En muchas ciudades y estados se han propuesto o aprobado leyes para prohibir los tel\u00e9fonos en las escuelas. La mayor\u00eda de las escuelas ya tienen pol\u00edticas que los proh\u00edben para uso no acad\u00e9mico, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-03T00:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos\",\"datePublished\":\"2024-09-03T00:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/\"},\"wordCount\":1382,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/\",\"name\":\"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-09-03T00:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos - Noticias","og_description":"(CNN) &#8212; Ahora que los ni\u00f1os est\u00e1n de regreso en el colegio, muchas escuelas no les permiten llevar sus tel\u00e9fonos a clase. En muchas ciudades y estados se han propuesto o aprobado leyes para prohibir los tel\u00e9fonos en las escuelas. La mayor\u00eda de las escuelas ya tienen pol\u00edticas que los proh\u00edben para uso no acad\u00e9mico, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/","og_site_name":"Noticias","article_published_time":"2024-09-03T00:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/"},"author":{"name":"","@id":""},"headline":"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos","datePublished":"2024-09-03T00:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/"},"wordCount":1382,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/","url":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/","name":"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-09-03T00:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"AN\u00c1LISIS | Los tel\u00e9fonos inteligentes no hacen m\u00e1s inteligentes a sus hijos","url":"http:\/\/noticiasya.com\/el-valle\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/09\/02\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-09-03T00:03:44Z","datePublished":"2024-09-03T00:03:44Z","dateModified":"2024-09-03T00:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"AN\\u00c1LISIS | Los tel\\u00e9fonos inteligentes no hacen m\\u00e1s inteligentes a sus hijos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/09\\\/02\\\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/09\\\/02\\\/analisis-telefonos-inteligentes-no-hacen-mas-inteligentes-hijos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-09-03T00:03:44Z\",\"datePublished\":\"2024-09-03T00:03:44Z\",\"dateModified\":\"2024-09-03T00:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449823,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/05\/29\/apple-recorto-precios-iphone-en-china-las-ventas-se-estan-recuperando-trax\/","url_meta":{"origin":1452367,"position":0},"title":"Apple recort\u00f3 los precios del iPhone en China. Las ventas se est\u00e1n recuperando","author":"","date":"mayo 29, 2024","format":false,"excerpt":"(CNN) -- El repunte de las ventas del iPhone de Apple en China est\u00e1 cobrando impulso, despu\u00e9s de que la compa\u00f1\u00eda redujera agresivamente los precios en su mayor mercado extranjero para atraer a los consumidores que buscaban activamente gangas en una econom\u00eda d\u00e9bil.Los env\u00edos de tel\u00e9fonos celulares de marcas extranjeras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457149,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/01\/02\/deepfakes-danos-ninos-trax\/","url_meta":{"origin":1452367,"position":1},"title":"AN\u00c1LISIS | Los deepfakes pueden causar da\u00f1os duraderos a los ni\u00f1os","author":"","date":"enero 2, 2025","format":false,"excerpt":"Si tu hijo no ha visto un deepfake de alguien relacionado con su escuela, es probable que un amigo o su maestro s\u00ed est\u00e9 al tanto de alguno.Los deepfakes son im\u00e1genes, videos o grabaciones de audio falsas creadas por inteligencia artificial que parecen reales pero han sido manipuladas digitalmente o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466330,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/10\/iphone-air-apple-telefonos-inteligentes-emocionantes-trax\/","url_meta":{"origin":1452367,"position":2},"title":"iPhone Air: el \u00faltimo intento de Apple por hacer que los tel\u00e9fonos inteligentes vuelvan a ser emocionantes","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Durante buena parte de la \u00faltima d\u00e9cada, las c\u00e1maras m\u00e1s n\u00edtidas, las pantallas m\u00e1s grandes y la mayor duraci\u00f3n de la bater\u00eda han definido las actualizaciones anuales de los tel\u00e9fonos inteligentes.Pero eso puede que ya no sea suficiente para deslumbrar a los consumidores, al menos en opini\u00f3n de Apple.La compa\u00f1\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458849,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/17\/meta-intentando-inventar-futuro-trax\/","url_meta":{"origin":1452367,"position":3},"title":"Meta sigue intentando inventar el futuro; pero sin \u00e9xito todav\u00eda","author":"","date":"febrero 17, 2025","format":false,"excerpt":"Con Facebook se inici\u00f3 la era moderna de las redes sociales a principios de la d\u00e9cada de 2000, pero las ambiciones de expansi\u00f3n de su empresa matriz, Meta, durante la \u00faltima d\u00e9cada no han tenido el mismo \u00e9xito. De todos modos, al parecer sigue intent\u00e1ndolo de nuevo con su \u00faltimo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465887,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/26\/que-esperar-lanzamiento-nuevo-iphone-9-de-septiembre-trax\/","url_meta":{"origin":1452367,"position":4},"title":"\u00bfQu\u00e9 esperar del lanzamiento del nuevo iPhone este 9 de septiembre?","author":"","date":"agosto 26, 2025","format":false,"excerpt":"Apple celebrar\u00e1 un evento el 9 de septiembre, seg\u00fan dijo la compa\u00f1\u00eda en una invitaci\u00f3n a la prensa el martes, donde probablemente anunciar\u00e1 el iPhone 17 y nuevos Apple Watch, entre otros posibles nuevos dispositivos.Apple rara vez comparte detalles sobre productos futuros antes de anunciarlos, pero la compa\u00f1\u00eda ha estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471668,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/26\/ia-gigantes-tecnologicas-trax\/","url_meta":{"origin":1452367,"position":5},"title":"La IA causa sensaci\u00f3n en todas partes, excepto donde m\u00e1s se esperar\u00eda. Dos gigantes tecnol\u00f3gicas trabajan para cambiar eso","author":"","date":"febrero 26, 2026","format":false,"excerpt":"La inteligencia artificial est\u00e1 empezando a cambiar la forma en que las personas trabajan, buscan informaci\u00f3n e incluso establecen relaciones sociales. Sin embargo, muy poco ha cambiado en los dispositivos que solemos usar para acceder a la IA: los tel\u00e9fonos inteligentes.Samsung quiere cambiar eso con su Galaxy S26, una nueva\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1452367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1452367"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1452367\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1452367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1452367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1452367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}