{"id":1455902,"date":"2024-11-18T10:03:54","date_gmt":"2024-11-18T18:03:54","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/"},"modified":"2024-11-18T10:03:54","modified_gmt":"2024-11-18T18:03:54","slug":"juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/","title":{"rendered":"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso"},"content":{"rendered":"<p>(CNN) &#8212; El primer testigo llamado en el segundo d\u00eda del juicio contra el venezolano Jos\u00e9 Ibarra, quien est\u00e1 acusado de matar a la estudiante de enfermer\u00eda Laken Riley mientras ella trotaba en el campus de la Universidad de Georgia el 22 de febrero, fue un agente de polic\u00eda de la Universidad de Georgia, quien testific\u00f3 haber visto lesiones en Ibarra que, seg\u00fan \u00e9l, &#171;parec\u00edan rasgu\u00f1os de u\u00f1as&#187;.<\/p>\n<p>\u201cMientras hablaba con \u00e9l, not\u00e9 que ten\u00eda un rasgu\u00f1o en el brazo derecho, en el b\u00edceps\u201d, dijo el sargento Joshua Epps al tribunal el lunes por la ma\u00f1ana, al describir su encuentro con Ibarra la ma\u00f1ana del 23 de febrero. \u201cEn el brazo izquierdo, ten\u00eda un rasgu\u00f1o en el antebrazo que era muy similar, que en mi mente, me parec\u00edan rasgu\u00f1os de u\u00f1a\u201d.<\/p>\n<p>Sobre esa misma l\u00ednea, el cabo Rafael Sayan dijo en la corte este lunes que el sospechoso del homicidio de Laken Riley no ten\u00eda una explicaci\u00f3n para los rasgu\u00f1os en sus brazos, incluido lo que parec\u00eda ser un ara\u00f1azo reciente en su mu\u00f1eca, seg\u00fan un agente de polic\u00eda de la Universidad de Georgia que lo interrog\u00f3 en espa\u00f1ol.<\/p>\n<p>&#171;Dijo que ten\u00eda un rasgu\u00f1o, pero no explic\u00f3 exactamente d\u00f3nde ni c\u00f3mo&#187;, afirm\u00f3.<\/p>\n<p>Se le hab\u00eda pedido a Sayan que llevara a cabo el interrogatorio de Jos\u00e9 Ibarra porque el agente que respondi\u00f3 inicialmente no habla espa\u00f1ol. En el video de la c\u00e1mara corporal reproducido en la corte, se puede ver a Ibarra se\u00f1alando sus brazos y mu\u00f1ecas mientras habla con el polic\u00eda.<\/p>\n<p>\u201cPrimero dice, \u2018No tengo nada all\u00ed\u2026 no hay nada all\u00ed\u2019\u201d, testific\u00f3 Sayan mientras se reproduc\u00eda el video. \u201cLuego comienza a se\u00f1alarlo de nuevo, diciendo, \u2018Oh, es solo un rasgu\u00f1o\u2019\u201d.<\/p>\n<p>Laken Riley sali\u00f3 a correr por la ma\u00f1ana. Menos de 30 minutos despu\u00e9s, estaba muerta. Lo que sabemos sobre sus \u00faltimos momentos<\/p>\n<p>Sayan dijo que el rasgu\u00f1o en la mu\u00f1eca izquierda de Ibarra parec\u00eda estar h\u00famedo con fluido corporal, lo que sugiere que era reciente. \u201cNo parec\u00eda muy viejo\u201d, dijo el agente.<\/p>\n<p>Ibarra fue acusado de 10 cargos: homicidio premeditado, tres cargos de homicidio con agravantes, secuestro con lesiones corporales, asalto agravado con intenci\u00f3n de violar, agresi\u00f3n agravada, obstrucci\u00f3n de una persona que realiza una llamada de emergencia, manipulaci\u00f3n de evidencia y \u201cPeeping Tom\u201d, seg\u00fan la acusaci\u00f3n judicial.<\/p>\n<p>La defensa y la fiscal\u00eda acordaron el martes un juicio sin jurado, lo que significa que el juez, no un jurado, escuchar\u00e1 pruebas y testimonios y decidir\u00e1 el destino de Ibarra. El juez del Tribunal Superior H. Patrick Haggard se\u00f1al\u00f3 que el juicio que comenz\u00f3 la ma\u00f1ana del viernes, continuar\u00e1 esta semana.<\/p>\n<p>La madre de Riley, Allyson Phillips, fue vista llorando en la corte este lunes mientras se reproduc\u00edan las im\u00e1genes de Ibarra hablando de sus heridas.<\/p>\n<p>Casa de Jos\u00e9 Ibarra: guantes de cocina y dispositivos electr\u00f3nicos recolectados<\/p>\n<p>Annie Moorman, especialista en la escena del crimen de la Oficina de Investigaciones de Georgia, testific\u00f3 que ella y otros investigadores buscaron evidencia en el apartamento de Jos\u00e9 Ibarra el d\u00eda despu\u00e9s de la muerte de Laken Riley.<\/p>\n<p>Los investigadores recolectaron varios guantes pl\u00e1sticos de cocina \u201cestilo restaurante\u201d y dispositivos electr\u00f3nicos, testific\u00f3.<\/p>\n<p>El descubrimiento de los guantes fue notable porque \u201cm\u00e1s temprano ese d\u00eda, los agentes hab\u00edan localizado guantes que hab\u00edan sido descritos como parecidos a estos en un arbusto en el complejo de apartamentos\u201d, testific\u00f3 Moorman.<\/p>\n<p>No encontraron ning\u00fan rastro de sangre en el apartamento, testific\u00f3.<\/p>\n<p>Hermanos de Jos\u00e9 Ibarra: lo que dijeron en el interrogatorio<\/p>\n<p>El acusado, Jos\u00e9 Antonio Ibarra, tiene dos hermanos venezolanos que enfrentan sus propios problemas legales y que probablemente desempe\u00f1ar\u00e1n un papel clave en el juicio.<\/p>\n<p>Los tres hermanos fueron interrogados y detenidos por la polic\u00eda en Athens, Georgia, el 23 de febrero, el d\u00eda despu\u00e9s de la muerte de Laken Riley, en parte porque coincid\u00edan con una descripci\u00f3n del sospechoso.<\/p>\n<p>La fiscal\u00eda dijo que la evidencia de ADN vincula a Jos\u00e9 Ibarra con el homicidio y excluye a los hermanos, pero la defensa ha tratado de cuestionar la calidad de esa evidencia y an\u00e1lisis de ADN. Los hermanos han sido citados para comparecer ante el tribunal el mi\u00e9rcoles.<\/p>\n<p>Diego Ibarra, el hermano mayor, se declar\u00f3 culpable en julio de dos cargos de posesi\u00f3n de un documento fraudulento, seg\u00fan la Fiscal\u00eda del Distrito Medio de Georgia. Admiti\u00f3 poseer una tarjeta de residente permanente estadounidense falsificada, seg\u00fan la oficina.<\/p>\n<p>Diego Ibarra enfrenta un m\u00e1ximo de diez a\u00f1os de prisi\u00f3n, seguidos de hasta tres a\u00f1os de libertad supervisada y una multa de US$ 250.000 por cargo. Sigue detenido por el gobierno federal.<\/p>\n<p>Diego Ibarra se encontr\u00f3 por primera vez con agentes de la Patrulla Fronteriza de Estados Unidos en abril de 2023 y fue procesado para su deportaci\u00f3n inmediata, seg\u00fan documentos judiciales. \u201cAleg\u00f3 tener miedo de regresar a Venezuela\u201d y fue liberado debido a una constataci\u00f3n de miedo cre\u00edble, en espera de la resoluci\u00f3n de su solicitud de asilo, seg\u00fan documentos judiciales.<\/p>\n<p>Argenis Ibarra, el hermano menor, fue inculpado por acusaci\u00f3n federal de dos cargos cada uno de posesi\u00f3n de un documento fraudulento, seg\u00fan la Fiscal\u00eda del Distrito Medio de Georgia. Se enfrenta a un m\u00e1ximo de diez a\u00f1os de prisi\u00f3n, seguidos de hasta tres a\u00f1os de libertad supervisada y una multa de US$ 250.000 por cada cargo.<\/p>\n<p>Seg\u00fan la acusaci\u00f3n, Argenis Ibarra supuestamente pose\u00eda una tarjeta de residente permanente estadounidense fraudulenta y una tarjeta de seguridad social estadounidense falsificada a su nombre. Argenis Ibarra hizo su comparecencia inicial ante un tribunal federal el 11 de julio y fue detenido.<\/p>\n<p>Si Jos\u00e9 Antonio Ibarra es condenado por los cargos m\u00e1s graves, los fiscales tienen la intenci\u00f3n de pedir una sentencia de cadena perpetua sin posibilidad de libertad condicional, seg\u00fan los registros judiciales.<\/p>\n<p>Con informaci\u00f3n de Holly Yan,\u00a0Nick Valencia,\u00a0Devon Sayers de CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El primer testigo llamado en el segundo d\u00eda del juicio contra el venezolano Jos\u00e9 Ibarra, quien est\u00e1 acusado de matar a la estudiante de enfermer\u00eda Laken Riley mientras ella trotaba en el campus de la Universidad de Georgia el 22 de febrero, fue un agente de polic\u00eda de la Universidad de Georgia, quien [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1455902","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El primer testigo llamado en el segundo d\u00eda del juicio contra el venezolano Jos\u00e9 Ibarra, quien est\u00e1 acusado de matar a la estudiante de enfermer\u00eda Laken Riley mientras ella trotaba en el campus de la Universidad de Georgia el 22 de febrero, fue un agente de polic\u00eda de la Universidad de Georgia, quien [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-18T18:03:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso\",\"datePublished\":\"2024-11-18T18:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/\"},\"wordCount\":1084,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/\",\"name\":\"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-11-18T18:03:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso - Noticias","og_description":"(CNN) &#8212; El primer testigo llamado en el segundo d\u00eda del juicio contra el venezolano Jos\u00e9 Ibarra, quien est\u00e1 acusado de matar a la estudiante de enfermer\u00eda Laken Riley mientras ella trotaba en el campus de la Universidad de Georgia el 22 de febrero, fue un agente de polic\u00eda de la Universidad de Georgia, quien [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/","og_site_name":"Noticias","article_published_time":"2024-11-18T18:03:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/"},"author":{"name":"","@id":""},"headline":"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso","datePublished":"2024-11-18T18:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/"},"wordCount":1084,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/","url":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/","name":"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-11-18T18:03:54+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Juicio contra Jos\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso","url":"http:\/\/noticiasya.com\/el-valle\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2024\/11\/18\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-11-18T18:03:54Z","datePublished":"2024-11-18T18:03:54Z","dateModified":"2024-11-18T18:03:54Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Juicio contra Jos\\u00e9 Ibarra por la muerte de Laken Riley: lo que se conoce del caso\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/11\\\/18\\\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2024\\\/11\\\/18\\\/juicio-contra-jose-ibarra-migrante-venezolano-muerte-laken-riley-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-11-18T18:03:54Z\",\"datePublished\":\"2024-11-18T18:03:54Z\",\"dateModified\":\"2024-11-18T18:03:54Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455948,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/20\/riley-laken-familia-jose-ibarra-juicio-trax\/","url_meta":{"origin":1455902,"position":0},"title":"La agon\u00eda de una madre: lo que Allyson Phillips soport\u00f3 durante el juicio del hombre acusado de matar a su hija, Laken Riley","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) -- Para la madre de Laken Riley, la angustia de perder a una hija en un espantoso ataque se ve amplificada por el horror de escuchar detalles sobre los \u00faltimos minutos de la vida de su hija.Sin embargo, la implacable b\u00fasqueda de justicia llev\u00f3 a Allyson Phillips a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455959,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/20\/juez-sentencia-jose-ibarra-cadena-perpetua-asesinato-laken-riley-trax\/","url_meta":{"origin":1455902,"position":1},"title":"El juez sentencia a Jos\u00e9 Ibarra a cadena perpetua por el asesinato de Laken Riley","author":"","date":"noviembre 20, 2024","format":false,"excerpt":"(CNN) \u2014 El juez H. Patrick Haggard sentenci\u00f3 este mi\u00e9rcoles a Jos\u00e9 Ibarra a cadena perpetua sin posibilidad de libertad condicional por el asesinato de Laken Riley mientras corr\u00eda por el bosque en la Universidad de Georgia.Haggard determin\u00f3 que Ibarra era culpable de cada uno de los 10 cargos que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456019,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/21\/fiscalia-juicio-asesinato-laken-riley-cadena-perpetua-trax\/","url_meta":{"origin":1455902,"position":2},"title":"Por qu\u00e9 la Fiscal\u00eda en el juicio por el asesinato de Laken Riley pidi\u00f3 cadena perpetua","author":"","date":"noviembre 21, 2024","format":false,"excerpt":"(CNN) -- Cuando Deborah Gonzalez se postul\u00f3 para ser elegida fiscal de Distrito del Circuito Judicial Occidental de Georgia en 2020, no ocult\u00f3 su posici\u00f3n sobre la pena capital.\"No apoyo la pena de muerte\", escribi\u00f3 Gonzalez en Twitter, ahora X, en septiembre de 2020. \"Es cruel e inhumana. Como fiscal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446730,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/07\/detencion-diego-ibarra-tren-aragua-georgia-orix\/","url_meta":{"origin":1455902,"position":3},"title":"Autoridades de EE.UU. confirman la detenci\u00f3n de presunto miembro del Tren de Aragua en Georgia","author":"","date":"marzo 7, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 Documentos de la Fiscal\u00eda de Georgia, en Estados Unidos, dan cuenta de una supuesta vinculaci\u00f3n entre Diego Jos\u00e9 Ibarra, el hermano del sospechoso de la muerte de la estudiante de enfermer\u00eda Laken Riley, hallada muerta a finales de febrero en el campus de la Universidad de Georgia,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455923,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/19\/juicio-caso-laken-riley-jose-ibarra-trax\/","url_meta":{"origin":1455902,"position":4},"title":"Juicio por el asesinato de Laken Riley, en vivo: \u00faltima hora del caso y el acusado, Jos\u00e9 Ibarra","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"Haz click aqu\u00ed para ver las actualizaciones m\u00e1s recientesThe-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455103,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/10\/15\/trump-inmigracion-comentarios-bill-clinton-laken-riley-trax\/","url_meta":{"origin":1455902,"position":5},"title":"La campa\u00f1a de Trump intenta aprovechar a su favor el tema de la inmigraci\u00f3n tras los comentarios de Bill Clinton sobre Laken Riley","author":"","date":"octubre 15, 2024","format":false,"excerpt":"(CNN) -- La campa\u00f1a del expresidente Donald Trump est\u00e1 tratando de utilizar en su favor el comentario del expresidente Bill Clinton el domingo de que la muerte de la estudiante de enfermer\u00eda de Georgia, Laken Riley, \"probablemente no habr\u00eda ocurrido\" si los migrantes, incluido su presunto asesino, hubieran sido \"debidamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1455902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1455902"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1455902\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1455902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1455902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1455902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}