{"id":1459695,"date":"2025-03-09T12:03:39","date_gmt":"2025-03-09T19:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/"},"modified":"2025-03-09T12:03:39","modified_gmt":"2025-03-09T19:03:39","slug":"leales-gobierno-siria-acusados-ejecutar-civiles-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/","title":{"rendered":"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia"},"content":{"rendered":"<p>Hombres armados leales al Gobierno de Siria llevaron a cabo ejecuciones sobre el terreno y hablaron de purificar el pa\u00eds, seg\u00fan testigos presenciales y v\u00eddeos, ofreciendo una imagen espantosa de una represi\u00f3n contra los restos del antiguo r\u00e9gimen de Assad que se convirti\u00f3 en una espiral de matanzas comunales.<\/p>\n<p>Siria ha vivido el peor estallido de violencia desde el derrocamiento del expresidente Bashar al Assad a finales del a\u00f1o pasado, despu\u00e9s de que hombres armados descendieran este jueves sobre el coraz\u00f3n de los alauitas en lo que las autoridades sirias dijeron que era un intento de acabar con la insurgencia de los rebeldes a\u00fan leales al antiguo gobierno.<\/p>\n<p>La Red Siria de Derechos Humanos (SNHR, por sus siglas en ingl\u00e9s), un grupo de observaci\u00f3n independiente con sede en el Reino Unido, afirm\u00f3 que al menos 642 personas hab\u00edan muerto a causa de la violencia, entre ellas decenas de civiles que perdieron la vida despu\u00e9s de que las fuerzas gubernamentales cometieran \u201cejecuciones generalizadas sobre el terreno\u201d de j\u00f3venes y adultos.<\/p>\n<p>El presidente interino de Siria, Ahmad al-Sharaa, hizo el domingo un llamamiento a la unidad nacional y calific\u00f3 los enfrentamientos de \u00abdesaf\u00edos esperados\u00bb. Su oficina ha ordenado la formaci\u00f3n de un comit\u00e9 independiente para investigar. La CNN se ha puesto en contacto con el gobierno sirio para recabar sus comentarios.<\/p>\n<p>\u201cHombres armados iban de casa en casa atacando a la gente como forma de entretenimiento\u2026 Nos declararon la yihad desde toda Siria\u201d, dijo un residente de la ciudad de Latakia, que prefiri\u00f3 permanecer en el anonimato por preocupaci\u00f3n de la seguridad de su familia que a\u00fan permanece en la ciudad.<\/p>\n<p>El residente, que huy\u00f3 de la ciudad el s\u00e1bado despu\u00e9s de 30 a\u00f1os viviendo all\u00ed, dijo a CNN que empezaron a ver cad\u00e1veres en las calles ya el martes.<\/p>\n<p>\u201cLa gente hu\u00eda, los que no pod\u00edan eran asesinados\u201d, dijo Bashir, otro residente de Latakia, a CNN. \u201cMi t\u00edo de 70 a\u00f1os, profesor de historia, y su mujer de 60 fueron asesinados a sangre fr\u00eda en su casa\u201d, dijo. Ambos eran alauitas y resid\u00edan en la ciudad de Baniyas, en la provincia occidental de Tartous.<\/p>\n<p>\u201cTemo por mi vida y por la de mis dos hijos\u201d, declar\u00f3 Bashir.<\/p>\n<p>Hombres armados empezaron a dirigirse en masa a Latakia y Tartous el jueves por la noche tras los informes de ataques de leales a Assad contra las nuevas fuerzas gubernamentales sirias estacionadas en las ciudades alauitas.<\/p>\n<p>Rasha Sadeq, alauita de 35 a\u00f1os, madre de tres hijos y residente en Homs, dijo a CNN que el fin de semana recibi\u00f3 una llamada telef\u00f3nica del socio comercial de su hermano en la que le dec\u00eda que su madre y sus dos hermanos hab\u00edan sido asesinados por grupos armados leales al nuevo gobierno en Baniyas.<\/p>\n<p>\u201cEstuve constantemente en contacto con mi familia; me dijeron que se o\u00edan disparos\u201d, declar\u00f3, y a\u00f1adi\u00f3 que su familia hab\u00eda dicho que tambi\u00e9n hab\u00edan o\u00eddo c\u00e1nticos religiosos. Su familia eran civiles y no pro-Assad, dijo.<\/p>\n<p>La familia Assad, miembro de la minoritaria secta alauita, gobern\u00f3 Siria durante m\u00e1s de medio siglo hasta que Bashar fue derrocado en diciembre por militantes islamistas sun\u00edes que pretend\u00edan remodelar el orden pol\u00edtico y sectario del pa\u00eds. El grupo, liderado por Ahmad al-Sharaa, ex militante de Al Qaeda, prometi\u00f3 igualdad pol\u00edtica y representaci\u00f3n a las distintas sectas de las diversas poblaciones \u00e9tnicas y religiosas de Siria.<\/p>\n<p>La seguridad sigue siendo un reto importante para la nueva administraci\u00f3n. Los alau\u00edes de Siria \u2014alrededor del 10% de la poblaci\u00f3n\u2014 ocupaban un lugar destacado en el r\u00e9gimen de Assad, y aunque muchos alau\u00edes han entregado sus armas desde diciembre, muchos otros no lo han hecho.<\/p>\n<p>Los ataques comenzaron esta semana tras conocerse que los leales a Assad hab\u00edan tendido una emboscada y matado a miembros de Hayat Tahrir al-Sham, el grupo rebelde que encabez\u00f3 la rebeli\u00f3n que derroc\u00f3 al exl\u00edder sirio.<\/p>\n<p>\u201cLos leales a Assad no estar\u00e1n en los pueblos que atacaron, estos (hombres armados) estaban matando a gente normal en esos pueblos\u201d, dijo Bashir a CNN.<\/p>\n<p>Una fuente del gobierno sirio dijo a los medios estatales que se hab\u00edan perpetrado \u201cviolaciones individuales\u201d despu\u00e9s de que \u201cgrandes multitudes no organizadas\u201d se desplazaran a la zona.<\/p>\n<p>El gobierno sirio dijo a CNN el s\u00e1bado que al menos 150 de sus fuerzas de seguridad hab\u00edan muerto desde el jueves y 300 hab\u00edan sido capturados en enfrentamientos con leales a Assad.<\/p>\n<p>CNN no puede confirmar de forma independiente el n\u00famero de v\u00edctimas.<\/p>\n<p>Varios videos aparecieron en las redes sociales mostrando convoyes de hombres armados en veh\u00edculos que se dirig\u00edan a las ciudades de Latakia y Tartous en el periodo previo a la violencia.<\/p>\n<p>\u201cEra la batalla por la liberaci\u00f3n. Ahora es la batalla por la purificaci\u00f3n (de Siria)\u201d, dice un narrador que acompa\u00f1a a los convoyes armados. No est\u00e1 claro cu\u00e1ndo se film\u00f3 exactamente el video.<\/p>\n<p>\u201cA los alau\u00edes, venimos a masacraros a ustedes y a sus padres\u201d, dec\u00eda un hombre con uniforme militar en lo que parec\u00eda acento egipcio en uno de los videos filmados de noche.<\/p>\n<p>\u201cTodo el mundo va a salir con armas, les mostraremos la (fuerza) de los sun\u00edes\u201d. CNN no ha podido geolocalizar el video, que parece mostrar un gran n\u00famero de veh\u00edculos.<\/p>\n<p>Pronto empezaron a aparecer reportes de horribles actos de violencia. Videos geolocalizados por CNN mostraban decenas de cuerpos tendidos en el suelo en el pueblo de Al Mukhtareyah mientras la gente lloraba.<\/p>\n<p>\u201cEstos son los cerdos alauitas\u201d, se oye decir a una voz antes de disparar a un cuerpo aparentemente sin vida en campo abierto en otro v\u00eddeo. No est\u00e1 claro d\u00f3nde ni cu\u00e1ndo se produjo el tiroteo.<\/p>\n<p>Otro video difundido en las redes sociales sirias mostraba a un hombre vestido con uniforme militar que se acercaba a una casa en motocicleta y le dec\u00eda a su morador que mirara a la c\u00e1mara antes de dispararle.<\/p>\n<p>\u201cTe he descubierto, descarado\u201d, dice riendo el atacante. \u201c\u00bfTodav\u00eda no est\u00e1s muerto? Todav\u00eda no est\u00e1s muerto\u201d, dice antes de dispararle de nuevo.<\/p>\n<p>En otro, un hombre vestido con uniforme militar pide a un cautivo que salga de un edificio y luego le dice que ladre como un perro antes de dispararle mortalmente.<\/p>\n<p>CNN no ha podido verificar ninguno de estos dos videos, pero son algunos de los que han aparecido en los \u00faltimos d\u00edas, en los que aparentemente se ven asesinatos grabados por las c\u00e1maras.<\/p>\n<p>Los ataques plantean grandes interrogantes sobre la nueva administraci\u00f3n siria, que se ha esforzado por distanciarse de su pasado yihadista.<\/p>\n<p>\u201cLo que ha ocurrido desde hace tres meses hasta hoy, equivale a lo que los Assad nos hicieron en cinco d\u00e9cadas. Los Assad eran criminales, y estos (nuevos gobernantes) tambi\u00e9n lo son\u201d, dijo Bashir.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hombres armados leales al Gobierno de Siria llevaron a cabo ejecuciones sobre el terreno y hablaron de purificar el pa\u00eds, seg\u00fan testigos presenciales y v\u00eddeos, ofreciendo una imagen espantosa de una represi\u00f3n contra los restos del antiguo r\u00e9gimen de Assad que se convirti\u00f3 en una espiral de matanzas comunales. Siria ha vivido el peor estallido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459695","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hombres armados leales al Gobierno de Siria llevaron a cabo ejecuciones sobre el terreno y hablaron de purificar el pa\u00eds, seg\u00fan testigos presenciales y v\u00eddeos, ofreciendo una imagen espantosa de una represi\u00f3n contra los restos del antiguo r\u00e9gimen de Assad que se convirti\u00f3 en una espiral de matanzas comunales. Siria ha vivido el peor estallido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-09T19:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia\",\"datePublished\":\"2025-03-09T19:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/\"},\"wordCount\":1224,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/\",\"name\":\"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-09T19:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia - Noticias","og_description":"Hombres armados leales al Gobierno de Siria llevaron a cabo ejecuciones sobre el terreno y hablaron de purificar el pa\u00eds, seg\u00fan testigos presenciales y v\u00eddeos, ofreciendo una imagen espantosa de una represi\u00f3n contra los restos del antiguo r\u00e9gimen de Assad que se convirti\u00f3 en una espiral de matanzas comunales. Siria ha vivido el peor estallido [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-09T19:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/"},"author":{"name":"","@id":""},"headline":"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia","datePublished":"2025-03-09T19:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/"},"wordCount":1224,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/","name":"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-09T19:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/09\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-09T19:03:39Z","datePublished":"2025-03-09T19:03:39Z","dateModified":"2025-03-09T19:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Acusan a fuerzas leales al Gobierno de Siria de ejecutar a civiles en medio del estallido de violencia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/09\\\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/09\\\/leales-gobierno-siria-acusados-ejecutar-civiles-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-09T19:03:39Z\",\"datePublished\":\"2025-03-09T19:03:39Z\",\"dateModified\":\"2025-03-09T19:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459809,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/violencia-siria-presidente-assad-trax\/","url_meta":{"origin":1459695,"position":0},"title":"Mueren familias enteras por la violencia sectaria en Siria, seg\u00fan la ONU","author":"","date":"marzo 12, 2025","format":false,"excerpt":"Grupos armados mataron a familias enteras, incluidas mujeres y ni\u00f1os, durante un brote de violencia sectaria en Siria la semana pasada, seg\u00fan afirm\u00f3 el martes la oficina de Derechos Humanos de Naciones Unidas.El derramamiento de sangre en el n\u00facleo costero del exgobernante Bashar al-Assad se sald\u00f3 con m\u00e1s de 800\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459746,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/siria-estallo-violencia-nuevo-esto-sabemos-trax\/","url_meta":{"origin":1459695,"position":1},"title":"\u00bfQu\u00e9 est\u00e1 pasando en Siria y por qu\u00e9 estall\u00f3 la violencia de nuevo? Esto sabemos","author":"","date":"marzo 10, 2025","format":false,"excerpt":"La operaci\u00f3n militar en Siria contra los restos del antiguo r\u00e9gimen de Assad ha llegado a su fin, tras desatar algunos de los peores episodios de violencia vividos en el pa\u00eds en a\u00f1os.Cientos de personas han muerto en la represi\u00f3n y los enfrentamientos entre las fuerzas de seguridad y los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459691,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/09\/presidente-siria-enfrentamientos-muertos-trax\/","url_meta":{"origin":1459695,"position":2},"title":"Presidente interino de Siria califica los enfrentamientos que dejaron m\u00e1s de 600 muertos como &#171;desaf\u00edos esperados&#187;","author":"","date":"marzo 9, 2025","format":false,"excerpt":"El l\u00edder interino de Siria ha calificado los d\u00edas de violentos enfrentamientos entre las fuerzas progubernamentales y los partidarios del derrocado expresidente Bashar al-Assad como \u201cdesaf\u00edos esperados\u201d, mientras que un monitor inform\u00f3 que el n\u00famero de muertos aument\u00f3 a 642 personas.Testigos acusan a los partidarios del gobierno de llevar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459678,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/08\/enfrentamientos-siria-cientos-muertos-trax\/","url_meta":{"origin":1459695,"position":3},"title":"Los enfrentamientos en Siria han causado m\u00e1s de 300 muertos desde el jueves, seg\u00fan un grupo de monitoreo","author":"","date":"marzo 8, 2025","format":false,"excerpt":"Los enfrentamientos entre las fuerzas de seguridad gubernamentales y los partidarios del derrocado expresidente Bashar al-Assad han causado la muerte de al menos 311 personas en Siria desde el jueves, seg\u00fan un grupo de seguimiento que advierte que el n\u00famero real de v\u00edctimas mortales podr\u00eda ser \u201cmucho mayor\u201d.Las fuerzas gubernamentales\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459669,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/08\/cientos-muertos-enfrentamientos-siria-trax\/","url_meta":{"origin":1459695,"position":4},"title":"Reportan cientos de muertos en enfrentamientos en Siria en el peor episodio de violencia desde la ca\u00edda del r\u00e9gimen de Assad","author":"","date":"marzo 8, 2025","format":false,"excerpt":"En el peor brote de disturbios desde que el gobierno de transici\u00f3n sirio asumi\u00f3 el poder, cientos de personas han muerto o resultado heridas en enfrentamientos entre las fuerzas de seguridad y partidarios del expresidente Bashar al-Assad.Los enfrentamientos estallaron el jueves en las regiones de Latakia y Tartous, en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456971,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/26\/muertes-fuerzas-seguridad-siria-al-assad-trax\/","url_meta":{"origin":1459695,"position":5},"title":"Mueren al menos 14 miembros de servicios de seguridad en una &#171;emboscada&#187; por parte de las fuerzas del derrocado al-Assad","author":"","date":"diciembre 26, 2024","format":false,"excerpt":"Al menos 14 miembros de las fuerzas del orden murieron durante la noche del mi\u00e9rcoles en el oeste de Siria en una \u201cemboscada\u201d tendida por las antiguas fuerzas del depuesto l\u00edder Bashar al-Assad, seg\u00fan inform\u00f3 este jueves el nuevo Ministerio del Interior.El ataque en el campo de la regi\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459695"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459695\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}