{"id":1459736,"date":"2025-03-10T12:03:44","date_gmt":"2025-03-10T19:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/"},"modified":"2025-03-10T12:03:44","modified_gmt":"2025-03-10T19:03:44","slug":"consecuencias-despidos-noaa-moriran-personas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/","title":{"rendered":"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. &#171;Morir\u00e1n personas&#187;, temen cient\u00edficos"},"content":{"rendered":"<p>Los empleados de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) que siguen en activo y con sentimiento de culpa intentan \u201crecoger los pedazos\u201d y averiguar c\u00f3mo seguir ofreciendo al p\u00fablico informaci\u00f3n que puede salvar vidas, tras el sorprendente despido el jueves de cientos de los principales expertos estadounidenses en predicci\u00f3n meteorol\u00f3gica y ciencias de la Tierra.<\/p>\n<p>\u201cEs una enorme herida autoinfligida. Es un d\u00eda duro\u201d, dijo un empleado del Servicio Meteorol\u00f3gico Nacional, dependiente de la NOAA. \u201cEs un d\u00eda sombr\u00edo y no s\u00e9 cu\u00e1l es la soluci\u00f3n\u201d.<\/p>\n<p>Cientos de empleados fueron despedidos, potencialmente hasta 800, dijeron fuentes cercanas a la agencia. La mayor\u00eda de las divisiones de la agencia, que emplea a cient\u00edficos y especialistas en meteorolog\u00eda, oc\u00e9anos, biodiversidad, clima y otros campos de investigaci\u00f3n y vigilancia planetaria, se vieron afectadas.<\/p>\n<p>Todav\u00eda no se conoce el alcance de los da\u00f1os causados por los recortes, pero ya empiezan a formarse grietas. Cient\u00edficos y pol\u00edticos est\u00e1n dando la voz de alarma sobre sus posibles consecuencias en todos los \u00e1mbitos, desde la seguridad de las personas hasta la econom\u00eda.<\/p>\n<p>\u201cLos buques no podr\u00e1n navegar con seguridad por nuestras v\u00edas navegables. Los agricultores no dispondr\u00e1n de los datos necesarios para gestionar sus cultivos. La fuerza de trabajo de la NOAA mantiene a la gente viva y proporciona a las comunidades las herramientas de apoyo cient\u00edfico para proteger a sus familias y hacer crecer sus negocios\u201d, dijo en un comunicado la senadora Maria Cantwell, dem\u00f3crata por Washington. \u201cEsta acci\u00f3n es un golpe directo a nuestra econom\u00eda, porque la fuerza de trabajo especializada de la NOAA proporciona productos y servicios que apoyan m\u00e1s de un tercio del PIB de la naci\u00f3n\u201d.<\/p>\n<p>Muchos de los cient\u00edficos y miembros del personal afectados expresaron su frustraci\u00f3n, tristeza, sorpresa y enfado por haber perdido tan repentinamente el \u201c<a href=\"https:\/\/bsky.app\/profile\/zacklabe.com\/post\/3lj6x7gk3uc2s\">trabajo de sus sue\u00f1os\u201d<\/a>.<\/p>\n<p>Elon Musk y el Gobierno de Trump \u201csimplemente no entienden el concepto de ayudar a la gente por el bien de ayudar a la gente sin tener algunos motivos ocultos\u201d, dijo Tom Di Liberto, un especialista en asuntos p\u00fablicos y cient\u00edfico clim\u00e1tico despedido de NOAA el jueves. \u201cNo entienden el concepto de lo que es la NOAA, que no es m\u00e1s que el servicio a los dem\u00e1s\u201d.<\/p>\n<p>M\u00e1s de 100 de los empleados despedidos pertenec\u00edan al Servicio Meteorol\u00f3gico Nacional, seg\u00fan declar\u00f3 el exadministrador de la NOAA Rick Spinrad en una rueda de prensa. CNN inform\u00f3 anteriormente que los despidos parec\u00edan haberse realizado de forma que se minimizara el rastro de papel, dificultando que las organizaciones de empleados e incluso los supervisores directos supieran qui\u00e9n hab\u00eda sido despedido y cu\u00e1ndo.<\/p>\n<p>Los recortes se hicieron, con pocas excepciones, a los empleados en pr\u00e1cticas en funciones de trabajo en todos los \u00e1mbitos, e incluy\u00f3 a los meteor\u00f3logos que emiten advertencias para salvar vidas al p\u00fablico de tornados, huracanes y otras amenazas meteorol\u00f3gicas extremas, las mismas advertencias que alimentan las alertas que recibe en su aplicaci\u00f3n meteorol\u00f3gica de elecci\u00f3n.<\/p>\n<p>\u201cSin las advertencias de fen\u00f3menos meteorol\u00f3gicos extremos, huracanes, tsunamis, la morir\u00e1n personas\u201d, dijo el senador dem\u00f3crata Chris Van Hollen en una rueda de prensa el viernes, \u201cy otros sufrir\u00e1n mucho, incluyendo enormes p\u00e9rdidas materiales\u201d.<\/p>\n<p>Los recortes afectaron a los llamados empleados en pr\u00e1cticas, aunque no necesariamente estaban al principio de sus carreras o carec\u00edan de experiencia. Algunos de los empleados m\u00e1s veteranos de la NOAA, reci\u00e9n ascendidos o que por fin hab\u00edan encontrado un puesto fijo tras a\u00f1os de trabajo contratado, fueron despedidos indiscriminadamente.<\/p>\n<p>\u201cSomos el grupo que tiene la combinaci\u00f3n \u00fanica de motivaci\u00f3n\/impulso al principio de la carrera, pero tambi\u00e9n suficiente experiencia para ser r\u00e1pidamente eficaces a medida que somos promovidos a nuevas funciones\u201d, dijo en X Andrew Hazelton, investigador de la Divisi\u00f3n de Investigaci\u00f3n de Huracanes de la NOAA. \u201cEste no es el grupo del que te deshar\u00edas si quisieras hacer una organizaci\u00f3n m\u00e1s eficiente; es lo que har\u00edas si quisieras destruir una organizaci\u00f3n\u201d.<\/p>\n<p>Entre ellos estaba Zack Labe, cuyo trabajo consist\u00eda en utilizar la IA y el aprendizaje autom\u00e1tico para mejorar las previsiones a largo plazo, un especialista que Di Liberto calific\u00f3 de \u201clogro\u201d para la NOAA. \u201c\u00bfLa gente que hemos contratado en el \u00faltimo a\u00f1o, m\u00e1s o menos? Oh, Dios m\u00edo, todo el mundo estaba tan emocionado de que estuvieran aqu\u00ed, para trabajar en ese tipo de cosas, porque era una experiencia que no ten\u00edamos\u201d.<\/p>\n<p>M\u00e1s all\u00e1 de los despidos, algunos de los meteor\u00f3logos m\u00e1s experimentados del Servicio Meteorol\u00f3gico Nacional (NWS, por sus siglas en ingl\u00e9s) se acogieron a la llamada \u201cbaja indemnizada\u201d ofrecida a todos los empleados federales a finales de enero. Entr\u00f3 en vigor el viernes, agravando las p\u00e9rdidas en la agencia. Entre ellos se encuentran una docena de los 40 meteor\u00f3logos jefes de las oficinas del <a href=\"https:\/\/www.weather.gov\/organization\/regional\">centro de EE.UU.<\/a>, una regi\u00f3n que incluye Nebraska y otros estados propensos a los tornados, seg\u00fan tiene conocimiento CNN.<\/p>\n<p>Al menos cuatro meteor\u00f3logos con m\u00e1s de 30 a\u00f1os de experiencia en el NWS anunciaron en las redes sociales que el viernes era su \u00faltimo d\u00eda.<\/p>\n<p>\u201cSe necesitan a\u00f1os para que la gente entienda c\u00f3mo funcionan las cosas\u201d, dijo un empleado del servicio meteorol\u00f3gico, a\u00f1adiendo que estos meteor\u00f3logos jefes son profundas fuentes de conocimiento local, incluyendo qu\u00e9 lugares son m\u00e1s propensos a inundarse a nivel local a cada gestor de emergencias del condado.<\/p>\n<p>Los recortes de esta semana tambi\u00e9n han afectado a un equipo cuyo trabajo ha resultado vital para la precisi\u00f3n de las previsiones de huracanes.<\/p>\n<p>El Centro Nacional de Huracanes emite pron\u00f3sticos, pero sus predicciones se basan en modelos meteorol\u00f3gicos, entre ellos uno desarrollado y puesto a punto por cient\u00edficos como Hazelton, que trabajaba en el Sistema de An\u00e1lisis y Pron\u00f3stico de Huracanes de la NOAA hasta que fue apartado de la agencia el jueves debido a su situaci\u00f3n de prueba, seg\u00fan comparti\u00f3 en las redes sociales. El programa es la <a href=\"https:\/\/www.noaa.gov\/news\/new-noaa-system-ushers-in-next-generation-of-hurricane-modeling-forecasting\">pr\u00f3xima generaci\u00f3n<\/a> de tecnolog\u00eda de previsi\u00f3n de huracanes que trabaja para mejorar las previsiones de trayectoria e intensidad.<\/p>\n<p>Los pron\u00f3sticos de rastreo de tormentas del Centro Nacional de Huracanes durante la temporada 2024 establecieron nuevos r\u00e9cords de precisi\u00f3n en cada marco de tiempo de 12 horas a cinco d\u00edas en el futuro, seg\u00fan un <a href=\"https:\/\/www.nhc.noaa.gov\/pdf\/NHC_Verification_Report_Preview.pdf\">informe preliminar<\/a> publicado el lunes.<\/p>\n<p>El centro tambi\u00e9n avanz\u00f3 en la predicci\u00f3n de la intensificaci\u00f3n r\u00e1pida, uno de los retos de investigaci\u00f3n m\u00e1s dif\u00edciles de superar en este campo. Nueve de 11 huracanes se intensificaron r\u00e1pidamente en el Atl\u00e1ntico la temporada pasada, algo cada vez m\u00e1s probable a medida que el mundo se calienta debido a la contaminaci\u00f3n por combustibles f\u00f3siles.<\/p>\n<p>El control cada vez mejor del Centro sobre la trayectoria de los huracanes y su intensidad cuando tocan tierra se debe al Programa de Mejora de las Previsiones de Huracanes, del que forma parte el antiguo equipo de Hazelton.<\/p>\n<p>\u201cSe trata leg\u00edtimamente de una importante mejora cient\u00edfica\u201d, dijo Hazelton en las redes sociales sobre los resultados de previsi\u00f3n del centro que su trabajo ayud\u00f3 a lograr, solo tres d\u00edas antes de ser despedido.<\/p>\n<p>Los despidos del jueves tambi\u00e9n incluyeron a empleados reci\u00e9n contratados en un \u00e1rea que Elon Musk y el presidente Donald Trump han dicho que apoyan: aumentar el dominio de la IA de Estados Unidos.<\/p>\n<p>La combinaci\u00f3n de la predicci\u00f3n meteorol\u00f3gica con el aprendizaje autom\u00e1tico m\u00e1s avanzado es un campo de investigaci\u00f3n de vanguardia que los modeladores inform\u00e1ticos llevan a\u00f1os estudiando. La agencia europea de predicci\u00f3n meteorol\u00f3gica, el Centro Europeo de Predicci\u00f3n Meteorol\u00f3gica a Medio Plazo, ha obtenido resultados notables en el campo de la IA. El martes, el centro <a href=\"https:\/\/www.eurekalert.org\/news-releases\/1074025\">anunci\u00f3 <\/a>que su modelo meteorol\u00f3gico basado en IA superaba la precisi\u00f3n de los modelos convencionales hasta en un 20%.<\/p>\n<p>Empleados actuales y antiguos de la NOAA dijeron a CNN que las divisiones de modelos de previsi\u00f3n de la agencia fueron destripadas por los despidos.<\/p>\n<p>\u201cTodo el mundo se queja de que el modelo estadounidense (GFS) no es el mejor. Pues bien, no vas a conseguir que sea el mejor despidiendo a un mont\u00f3n de gente que trabaja en \u00e9l. Eso retrasa mucho a Estados Unidos\u201d, dijo Di Liberto.<\/p>\n<p>Hay 122 oficinas locales del Servicio Meteorol\u00f3gico Nacional esparcidas en el mapa de Estados Unidos. Cada una de ellas cuenta con meteor\u00f3logos y otro personal con conocimientos especializados del tiempo y el clima de su zona designada, para la que suelen emitir previsiones y advertencias exclusivas.<\/p>\n<p>Pero la escasez de personal, incluso antes de los recortes, hab\u00eda obligado a algunas oficinas a asumir las funciones de otras. Esta pr\u00e1ctica suele emplearse en situaciones de emergencia a corto plazo, como una actualizaci\u00f3n de las computadoras, o si un tornado se cierne sobre la oficina y los propios meteor\u00f3logos tienen que ponerse a cubierto.<\/p>\n<p>Tras los recortes de esta semana, podr\u00eda convertirse en algo m\u00e1s permanente, y tiene un coste, ya que el estr\u00e9s se agrava con el tiempo, lo que provoca bajas o p\u00e9rdidas adicionales de personal, dijo un empleado del servicio meteorol\u00f3gico.<\/p>\n<p>\u201cSe trata de un intenso trabajo por turnos, y el estr\u00e9s ha aumentado exponencialmente\u201d, dijo el cient\u00edfico del clima Di Liberto. \u201cEstas personas no son magos; el agotamiento es real\u201d.<\/p>\n<p>Se avecinan futuros recortes, incluso mientras el NWS y otras agencias de la NOAA intentan averiguar c\u00f3mo operar tras las p\u00e9rdidas actuales. Un memor\u00e1ndum reciente de la Oficina de Gesti\u00f3n y Presupuesto y la Oficina de Gesti\u00f3n de Personal esboza c\u00f3mo hacer recortes espec\u00edficos en todo el gobierno federal en las pr\u00f3ximas semanas.<\/p>\n<p>\u201cEstamos en la fase uno\u201d, dijo un empleado del NWS. \u201c\u00bfCu\u00e1ndo tocaremos fondo? No lo s\u00e9. Esto sigue as\u00ed, una y otra vez\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los empleados de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) que siguen en activo y con sentimiento de culpa intentan \u201crecoger los pedazos\u201d y averiguar c\u00f3mo seguir ofreciendo al p\u00fablico informaci\u00f3n que puede salvar vidas, tras el sorprendente despido el jueves de cientos de los principales expertos estadounidenses en predicci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459736","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. &quot;Morir\u00e1n personas&quot;, temen cient\u00edficos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. &quot;Morir\u00e1n personas&quot;, temen cient\u00edficos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los empleados de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) que siguen en activo y con sentimiento de culpa intentan \u201crecoger los pedazos\u201d y averiguar c\u00f3mo seguir ofreciendo al p\u00fablico informaci\u00f3n que puede salvar vidas, tras el sorprendente despido el jueves de cientos de los principales expertos estadounidenses en predicci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-10T19:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. &#171;Morir\u00e1n personas&#187;, temen cient\u00edficos\",\"datePublished\":\"2025-03-10T19:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/\"},\"wordCount\":1789,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/\",\"name\":\"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. \\\"Morir\u00e1n personas\\\", temen cient\u00edficos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-10T19:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. &#171;Morir\u00e1n personas&#187;, temen cient\u00edficos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. \"Morir\u00e1n personas\", temen cient\u00edficos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. \"Morir\u00e1n personas\", temen cient\u00edficos - Noticias","og_description":"Los empleados de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) que siguen en activo y con sentimiento de culpa intentan \u201crecoger los pedazos\u201d y averiguar c\u00f3mo seguir ofreciendo al p\u00fablico informaci\u00f3n que puede salvar vidas, tras el sorprendente despido el jueves de cientos de los principales expertos estadounidenses en predicci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-10T19:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/"},"author":{"name":"","@id":""},"headline":"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. &#171;Morir\u00e1n personas&#187;, temen cient\u00edficos","datePublished":"2025-03-10T19:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/"},"wordCount":1789,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/","name":"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. \"Morir\u00e1n personas\", temen cient\u00edficos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-10T19:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. &#171;Morir\u00e1n personas&#187;, temen cient\u00edficos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los estadounidenses y la econom\u00eda sufrir\u00edan consecuencias de los despidos en la NOAA. &#171;Morir\u00e1n personas&#187;, temen cient\u00edficos","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/consecuencias-despidos-noaa-moriran-personas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-10T19:03:44Z","datePublished":"2025-03-10T19:03:44Z","dateModified":"2025-03-10T19:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los estadounidenses y la econom\\u00eda sufrir\\u00edan consecuencias de los despidos en la NOAA. &#171;Morir\\u00e1n personas&#187;, temen cient\\u00edficos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/10\\\/consecuencias-despidos-noaa-moriran-personas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/10\\\/consecuencias-despidos-noaa-moriran-personas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-10T19:03:44Z\",\"datePublished\":\"2025-03-10T19:03:44Z\",\"dateModified\":\"2025-03-10T19:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459312,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/27\/noaa-trabajadores-federales-despidos-trax\/","url_meta":{"origin":1459736,"position":0},"title":"La Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica despide a unos 800 empleados y es posible que este viernes haya m\u00e1s","author":"","date":"febrero 27, 2025","format":false,"excerpt":"La administraci\u00f3n Trump apunt\u00f3 su mirada a la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) donde alrededor de 800 empleados han sido despedidos, seg\u00fan dos fuentes cercanas a la agencia.Es posible que haya m\u00e1s despidos este viernes, dijo una de las fuentes, lo que podr\u00eda costar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466965,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/29\/huracan-tierra-cierre-gobierno-trax\/","url_meta":{"origin":1459736,"position":1},"title":"\u00bfQu\u00e9 sucede si un hurac\u00e1n toca tierra mientras el Gobierno de EE.UU. est\u00e1 cerrado?","author":"","date":"septiembre 29, 2025","format":false,"excerpt":"Los dos enormes sistemas tropicales que se arremolinan frente a la costa sudeste son un duro recordatorio de que el potencial cierre del Gobierno se avecina en medio de la temporada de huracanes del Atl\u00e1ntico.Los meteor\u00f3logos de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461082,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/11\/proyecto-presupuesto-trump-destruye-investigacion-meteorologica-climatica-trax\/","url_meta":{"origin":1459736,"position":2},"title":"El proyecto de presupuesto de Trump destruye la investigaci\u00f3n meteorol\u00f3gica y clim\u00e1tica en Estados Unidos","author":"","date":"abril 11, 2025","format":false,"excerpt":"El Gobierno de Donald Trump planea eliminar la rama de investigaci\u00f3n de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s), cerrar todos los laboratorios meteorol\u00f3gicos y clim\u00e1ticos, y desmantelar su presupuesto junto con el de otras oficinas de la NOAA, seg\u00fan documentos internos obtenidos por CNN.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467905,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/10\/31\/cazadores-huracanes-sin-cobrar-cierre-gobierno-trax\/","url_meta":{"origin":1459736,"position":3},"title":"Melissa fue uno de los ciclones m\u00e1s fuertes registrados. Los cazadores de huracanes de la NOAA volaron hacia \u00e9l sin cobrar","author":"","date":"octubre 31, 2025","format":false,"excerpt":"Azotados por vientos violentos y fuertes turbulencias, los cazadores de huracanes de la Administraci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica (NOAA, por sus siglas en ingl\u00e9s) han pasado la \u00faltima semana sumergi\u00e9ndose en el ojo de Melissa, un cicl\u00f3n de ferocidad hist\u00f3rica, para recopilar datos vitales. Lo han hecho sin descanso, las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460032,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/trump-despidio-cientificos-noaa-peor-momento-posible-trax\/","url_meta":{"origin":1459736,"position":4},"title":"Trump despidi\u00f3 a los cient\u00edficos que monitorean el oc\u00e9ano en el peor momento posible","author":"","date":"marzo 17, 2025","format":false,"excerpt":"Uno de los trabajos de Heather Welch, antes de ser despedida mediante un correo electr\u00f3nico en el que le conced\u00edan apenas 90 minutos para hacer las maletas y marcharse, consist\u00eda en evitar las colisiones entre los buques y las ballenas que navegan por las aguas de la costa oeste de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459157,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/24\/trabajadores-federales-correo-electronico-musk-trax\/","url_meta":{"origin":1459736,"position":5},"title":"&#171;Es un caos&#187;: trabajadores federales se quedan en el limbo mientras el reloj marca el l\u00edmite del correo electr\u00f3nico de Musk","author":"","date":"febrero 24, 2025","format":false,"excerpt":"Los trabajadores federales pasaron este lunes tratando de averiguar c\u00f3mo, o incluso si deb\u00edan, responder al correo masivo de Elon Musk del fin de semana, en el que les dec\u00eda que explicaran su trabajo de la semana pasada o se arriesgaban perder su empleo.Tras un d\u00eda de directrices confusas y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459736"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459736\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}