{"id":1459752,"date":"2025-03-10T20:03:39","date_gmt":"2025-03-11T03:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/"},"modified":"2025-03-10T20:03:39","modified_gmt":"2025-03-11T03:03:39","slug":"expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/","title":{"rendered":"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n"},"content":{"rendered":"<p>A menos de una semana de iniciado el juicio en su contra, el expresidente de Per\u00fa Pedro Castillo anunci\u00f3 que iniciar\u00e1 una huelga de hambre en el penal de Barbadillo, donde se encuentra detenido desde diciembre de 2022.<\/p>\n<p>\u201cHe decidido acatar a partir de la fecha una huelga de hambre, acto que me lleva a tomar por las injusticias que se vienen cometiendo conmigo\u201d, dijo en una carta difundida en su cuenta de X, firmada por \u00e9l y por su abogado, Walter Ayala.<\/p>\n<p>Castillo dice estar recluido \u201cinjustamente\u201d por actos que \u201cnunca\u201d cometi\u00f3.<\/p>\n<p>El exmandatario tambi\u00e9n se\u00f1al\u00f3 que el tribunal que lo juzgar\u00e1 est\u00e1 integrado por \u201cuna jueza que ha adelantado opini\u00f3n\u201d en su contra, en referencia a Norma Carbajal Ch\u00e1vez.<\/p>\n<p>Ayala, abogado de Castillo y exministro de Defensa, dijo a CNN que en febrero se rechaz\u00f3 una recusaci\u00f3n presentada contra la jueza Carbajal Ch\u00e1vez. Por ello, la defensa de Castillo se\u00f1al\u00f3 que ha presentado un habeas corpus \u201cpara que se dejen sin efecto todo lo avanzado en el juicio oral hasta que se vuelva a confirmar un nuevo tribunal id\u00f3neo e imparcial\u201d.<\/p>\n<p>La jueza no ha respondido a la solicitud de comentarios de CNN.<\/p>\n<p>Una fuente cercana al proceso dijo a CNN que \u201clos magistrados solo responden a temas jurisdiccionales y que la audiencia continuar\u00e1 ma\u00f1ana como est\u00e1 previsto\u201d.<\/p>\n<p>El martes de la semana pasada se inici\u00f3 el juicio contra el exmandatario, quien enfrenta una acusaci\u00f3n por rebeli\u00f3n, entre otros cargos. De ser hallado culpable, enfrentar\u00eda una pena de hasta 34 a\u00f1os de prisi\u00f3n.<\/p>\n<p>Durante la primera audiencia en su contra, Castillo, quien gobern\u00f3 entre el 28 de julio de 2021 y el 7 de diciembre de 2022, se neg\u00f3 a acreditar a su abogado defensor y se\u00f1al\u00f3 que no pod\u00eda someterse a un juicio donde \u201ctodo parece estar confinado\u201d. El expresidente dijo estar \u201csecuestrado en el penal de Barbadillo\u201d y calific\u00f3 el proceso de \u201cpantomima\u201d. Tras la declaraci\u00f3n del exmandatario, la sala le asign\u00f3 un defensor p\u00fablico.<\/p>\n<p>\u201cJam\u00e1s he cometido el delito de rebeli\u00f3n\u201d, insisti\u00f3 Castillo, y se\u00f1al\u00f3 que su mensaje en cadena nacional el 7 de diciembre 2022, cuando anunci\u00f3 la disoluci\u00f3n del Congreso, fue solo \u201cun discurso pol\u00edtico\u201d. Tras el mensaje, en el que Castillo orden\u00f3 cerrar el Parlamento, intervenir el sistema de Justicia y gobernar mediante decretos-ley, el entonces presidente fue detenido y puesto en prisi\u00f3n.<\/p>\n<p>Tras su detenci\u00f3n, el Congreso declar\u00f3 la vacancia presidencial y nombr\u00f3 presidenta a la vicepresidenta Dina Boluarte, seg\u00fan la sucesi\u00f3n contemplada en la Constituci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A menos de una semana de iniciado el juicio en su contra, el expresidente de Per\u00fa Pedro Castillo anunci\u00f3 que iniciar\u00e1 una huelga de hambre en el penal de Barbadillo, donde se encuentra detenido desde diciembre de 2022. \u201cHe decidido acatar a partir de la fecha una huelga de hambre, acto que me lleva a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459752","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"A menos de una semana de iniciado el juicio en su contra, el expresidente de Per\u00fa Pedro Castillo anunci\u00f3 que iniciar\u00e1 una huelga de hambre en el penal de Barbadillo, donde se encuentra detenido desde diciembre de 2022. \u201cHe decidido acatar a partir de la fecha una huelga de hambre, acto que me lleva a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T03:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n\",\"datePublished\":\"2025-03-11T03:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/\"},\"wordCount\":463,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/\",\"name\":\"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-11T03:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n - Noticias","og_description":"A menos de una semana de iniciado el juicio en su contra, el expresidente de Per\u00fa Pedro Castillo anunci\u00f3 que iniciar\u00e1 una huelga de hambre en el penal de Barbadillo, donde se encuentra detenido desde diciembre de 2022. \u201cHe decidido acatar a partir de la fecha una huelga de hambre, acto que me lleva a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-11T03:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/"},"author":{"name":"","@id":""},"headline":"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n","datePublished":"2025-03-11T03:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/"},"wordCount":463,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/","name":"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-11T03:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Expresidente de Per\u00fa Pedro Castillo inicia huelga de hambre en prisi\u00f3n","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-11T03:03:39Z","datePublished":"2025-03-11T03:03:39Z","dateModified":"2025-03-11T03:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Expresidente de Per\\u00fa Pedro Castillo inicia huelga de hambre en prisi\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/10\\\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/10\\\/expresidente-peru-pedro-castillo-inicia-huelga-de-hambre-prision-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-11T03:03:39Z\",\"datePublished\":\"2025-03-11T03:03:39Z\",\"dateModified\":\"2025-03-11T03:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459950,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/pedro-castillo-peru-levanta-huelga-hambre-regresa-penal-orix\/","url_meta":{"origin":1459752,"position":0},"title":"Pedro Castillo, expresidente de Per\u00fa, levanta huelga de hambre y regresa al penal de Barbadillo","author":"","date":"marzo 14, 2025","format":false,"excerpt":"El expresidente de Per\u00fa Pedro Castillo levant\u00f3 la huelga de hambre que hab\u00eda comenzado este lunes \u2015al se\u00f1alar \u201cinjusticias\u201d en el proceso penal en su contra\u2015, inform\u00f3 este viernes el Poder Judicial del pa\u00eds sudamericano.Al inicio de la audiencia del caso realizada este viernes por la ma\u00f1ana, una funcionaria de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459888,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/hospitalizan-pedro-castillo-expresidente-peru-orix\/","url_meta":{"origin":1459752,"position":1},"title":"Hospitalizan a Pedro Castillo, expresidente de Per\u00fa","author":"","date":"marzo 13, 2025","format":false,"excerpt":"El expresidente de Per\u00fa, Pedro Castillo, fue \u201ctrasladado al Hospital II Vitarte de Essalud, a fin de verificar su estado de salud\u201d, inform\u00f3 en X el Instituto Nacional Penitenciario.Una relatora presente en el proceso inform\u00f3 que Castillo present\u00f3 una descompensaci\u00f3n y fue trasladado para descartar un \u201ctrastorno hidroelectrol\u00edtico y una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459087,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/22\/peru-protesta-contra-mexico-por-apoyo-pedro-castillo-orix\/","url_meta":{"origin":1459752,"position":2},"title":"Per\u00fa protesta contra M\u00e9xico por apoyo de Sheinbaum al expresidente Pedro Castillo","author":"","date":"febrero 22, 2025","format":false,"excerpt":"El Gobierno de Per\u00fa protest\u00f3 este viernes contra M\u00e9xico luego de que la presidenta de M\u00e9xico, Claudia Sheinbaum, expresara apoyo al expresidente peruano Pedro Castillo y calificara de \u201cinjusticia\u201d el proceso penal al que est\u00e1 sujeto en su pa\u00eds, donde est\u00e1 detenido desde hace m\u00e1s de dos a\u00f1os.\u201cLas declaraciones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459532,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/05\/expresidente-pedro-castillo-dice-esta-secuestrado-carcel-orix\/","url_meta":{"origin":1459752,"position":3},"title":"Expresidente de Per\u00fa, Pedro Castillo, dice que juicio en su contra es una &#171;pantomima&#187; y que est\u00e1 &#171;secuestrado&#187; en la c\u00e1rcel","author":"","date":"marzo 5, 2025","format":false,"excerpt":"A las 9 de la ma\u00f1ana de este martes, Pedro Castillo ingres\u00f3 a la sala de audiencias del Poder Judicial, construida en la c\u00e1rcel donde est\u00e1 preso desde diciembre de 2022. Lo hizo sin un abogado defensor.El expresidente no mir\u00f3 a la prensa nacional ni extranjera, con la que no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447936,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/10\/jorge-glas-exvicepresidente-de-ecuador-inicia-huelga-de-hambre-dice-un-miembro-de-su-equipo-a-cnn\/","url_meta":{"origin":1459752,"position":4},"title":"Jorge Glas, exvicepresidente de Ecuador, inicia huelga de hambre, dice un miembro de su equipo a CNN","author":"","date":"abril 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El exvicepresidente de Ecuador Jorge Glas, recluido en la c\u00e1rcel de m\u00e1xima seguridad de La Roca en Guayaquil desde el s\u00e1bado, empez\u00f3 una huelga de hambre este mi\u00e9rcoles, seg\u00fan confirm\u00f3 un miembro de su equipo a CNN.\u201cEst\u00e1 en un hueco, sin luz\u201d, dijo la fuente a CNN.\u00bfQui\u00e9n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455516,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/01\/evo-morales-suspender-bloqueos-huelga-de-hambre-bolivia-orix\/","url_meta":{"origin":1459752,"position":5},"title":"Evo Morales pide a sus partidarios suspender bloqueos y dice que har\u00e1 huelga de hambre para exigir di\u00e1logo con el Gobierno","author":"","date":"noviembre 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El expresidente de Bolivia Evo Morales pidi\u00f3 a sus simpatizantes que suspendan los bloqueos que realizan desde hace casi tres semanas en varios puntos del pa\u00eds y dijo que iniciar\u00e1 una huelga de hambre para exigir al Gobierno mesas de di\u00e1logo en temas econ\u00f3micos y pol\u00edticos.Durante una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459752"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459752\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}