{"id":1459761,"date":"2025-03-11T05:03:50","date_gmt":"2025-03-11T12:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/"},"modified":"2025-03-11T05:03:50","modified_gmt":"2025-03-11T12:03:50","slug":"mahmoud-khalil-columbia-ice-tarjeta-verde-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/","title":{"rendered":"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia?"},"content":{"rendered":"<p>El presidente Donald Trump ha comparado a Mahmoud Khalil con un simpatizante terrorista. Otros lo describen como un activista palestino, se\u00f1alado por su abierto apoyo a su propio pueblo.<\/p>\n<p>Pero mucho antes de ser<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/11\/eeuu\/mahmoud-khalil-columbia-universidad-israel-trax\"> arrestado por agentes federales <\/a>el s\u00e1bado por la noche, Khalil dijo a CNN que se sent\u00eda llamado a abogar por la liberaci\u00f3n tanto del pueblo palestino como del jud\u00edo como refugiado.<\/p>\n<p>\u201cComo estudiante palestino, creo que la liberaci\u00f3n del pueblo palestino y la del pueblo jud\u00edo est\u00e1n entrelazadas y van de la mano, y no se puede lograr una sin la otra\u201d, declar\u00f3 a la CNN la primavera pasada, cuando era uno de los negociadores que representaban a los estudiantes manifestantes durante las conversaciones con la administraci\u00f3n de la Universidad de Columbia.<\/p>\n<p>\u201cNuestro movimiento es un movimiento por la justicia social, la libertad y la igualdad para todos\u201d, afirm\u00f3.<\/p>\n<p>Khalil, que termin\u00f3 su trabajo de maestr\u00eda en la Universidad de Columbia en diciembre y es residente legal de Estados Unidos, fue arrestado y detenido por agentes federales despu\u00e9s de que su abogada dijo que su tarjeta verde fue revocada por la administraci\u00f3n Trump.<\/p>\n<p>Su abogada, Amy Greer, dijo que la esposa de Khalil, que es ciudadana estadounidense, tambi\u00e9n estaba presente durante su arresto y est\u00e1 embarazada de ocho meses.<\/p>\n<p>Un juez federal bloque\u00f3 cualquier esfuerzo inmediato de la administraci\u00f3n Trump para deportar a Khalil, a \u00faltima hora de la tarde del lunes. El juez Jesse Furman orden\u00f3 una audiencia sobre el caso de Khalil que se celebrar\u00e1 el mi\u00e9rcoles por la ma\u00f1ana en la ciudad de Nueva York.<\/p>\n<p>Greer dijo que habl\u00f3 con Khalil el lunes, y \u00e9l est\u00e1 \u201csaludable y su \u00e1nimo no se ve afectado por su situaci\u00f3n\u201d<\/p>\n<p>\u201cFue elegido como ejemplo para sofocar una disidencia totalmente legal, en violaci\u00f3n de la Primera Enmienda\u201d, dijo en un comunicado. \u201cEl objetivo del Gobierno es tan transparente como ilegal\u201d.<\/p>\n<p>Pero hay quienes -incluidos Trump y su administraci\u00f3n- ven el activismo propalestino de Khalil como actos de antisemitismo y de apoyo a Hamas.<\/p>\n<p>\u201cSiguiendo mis decretos previamente firmados, el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) aprehendi\u00f3 y detuvo con orgullo a Mahmoud Khalil, un estudiante extranjero radical pro Hamas en el campus de la Universidad de Columbia\u201d, public\u00f3 Trump el lunes en Truth Social. \u201cEste es el primer arresto de muchos por venir\u201d.<\/p>\n<p>Khalil se encuentra en un centro de detenci\u00f3n en Jena, Luisiana, seg\u00fan una fuente con conocimiento directo del caso. Esto es lo que sabemos de \u00e9l<\/p>\n<p>En una entrevista concedida a CNN el a\u00f1o pasado, Kahlil declar\u00f3 que hab\u00eda nacido como refugiado palestino en Siria, pero que su familia era originaria de Tiber\u00edades, ciudad israel\u00ed conocida en el pasado por su mezcla de poblaci\u00f3n jud\u00eda y \u00e1rabe.<\/p>\n<p>Durante la guerra \u00e1rabe-israel\u00ed de 1948, millones de palestinos fueron expulsados a la fuerza de ciudades como Tiber\u00edades, en lo que se conoci\u00f3 como \u201cla Nakba\u201d o cat\u00e1strofe.<\/p>\n<p>Khalil creci\u00f3 en Siria y se licenci\u00f3 en Inform\u00e1tica en la Universidad Libanesa Americana, seg\u00fan su perfil de <a href=\"https:\/\/www.linkedin.com\/in\/khalilmahmoud\/\">LinkedIn<\/a>. Antes de matricularse en Columbia, desempe\u00f1\u00f3 varios cargos en el \u00e1mbito del desarrollo internacional, entre ellos en la Oficina de Asuntos Exteriores, Commonwealth y Desarrollo del Reino Unido.<\/p>\n<p>En 2023, Khalil empez\u00f3 a estudiar para obtener un m\u00e1ster en Administraci\u00f3n P\u00fablica en la Escuela de Asuntos Internacionales y P\u00fablicos de Columbia. Entonces, Hamas atac\u00f3 Israel el 7 de octubre de 2023.<\/p>\n<p>La guerra entre Israel y Hamas puso a la Universidad de Columbia y a sus estudiantes en el punto de mira nacional cuando las manifestaciones propalestinas se extendieron por los campus universitarios.<\/p>\n<p>Bas\u00e1ndose en una <a href=\"https:\/\/www.cnn.com\/2024\/05\/11\/us\/columbia-commencement-protests-1968-reaj\/index.html\">tradici\u00f3n de protestas antibelicistas<\/a> lideradas por estudiantes en Columbia, una coalici\u00f3n de estudiantes estableci\u00f3 campamentos en el campus, celebr\u00f3 m\u00edtines y organiz\u00f3 \u201cteach-ins\u201d. Pero el movimiento tambi\u00e9n se vio empa\u00f1ado por casos de antisemitismo desenfrenado, que Khalil repudi\u00f3.<\/p>\n<p>\u201cPor supuesto, no hay lugar para el antisemitismo\u201d, declar\u00f3 a CNN en abril. \u201cLo que estamos presenciando es un sentimiento antipalestino que est\u00e1 adoptando diferentes formas y el antisemitismo, la islamofobia, el racismo (son) algunas de estas formas\u201d.<\/p>\n<p>Khalil a\u00f1adi\u00f3 que decidi\u00f3 no participar directamente en las acampadas estudiantiles porque no quer\u00eda arriesgarse a que la universidad le revocara el visado de estudiante.<\/p>\n<p>En cambio, pronunci\u00f3 discursos y fue uno de los estudiantes seleccionados para dirigir los debates con los administradores de la universidad en nombre de Columbia University Apartheid Divest, una coalici\u00f3n de organizaciones estudiantiles que exig\u00eda, entre otras cosas, que la universidad renunciara a sus v\u00ednculos financieros con Israel y un alto el fuego en Gaza.<\/p>\n<p>\u201cSiempre digo que somos los afortunados que hemos llegado hasta aqu\u00ed para hablar en nombre de nuestro pueblo, oprimido en Palestina, en los campos de refugiados y en las ciudades palestinas\u201d, dijo Khalil, y a\u00f1adi\u00f3 que a veces se ha sentido \u201cculpable de la supervivencia\u201d por su incapacidad para \u201chacer algo significativo por el pueblo (palestino)\u201d que no fuera protestar.<\/p>\n<p>\u201cTuve miedo de participar activamente en protestas en algunos momentos por diferentes amenazas (y) por las pol\u00edticas de la universidad al respecto, pero de nuevo, nos organizamos. Nos impusimos para hacer algo por nuestra gente\u201d.<\/p>\n<p>D\u00edas despu\u00e9s de que Khalil hablara con CNN, la universidad incumpli\u00f3 el plazo para llegar a un acuerdo sobre la desinversi\u00f3n. En respuesta, los estudiantes, as\u00ed como personas no afiliadas a la universidad, entraron en el Hamilton Hall de Columbia y se atrincheraron en su interior. Finalmente, la universidad solicit\u00f3 ayuda policial para desalojar a los manifestantes y m\u00e1s de 280 personas fueron detenidas, seg\u00fan la <a href=\"https:\/\/www.cnn.com\/2024\/05\/02\/us\/columbia-university-protests-arrest-charges\/index.html\">Polic\u00eda de Nueva York.<\/a><\/p>\n<p>Despu\u00e9s de la manifestaci\u00f3n en Hamilton Hall, Khalil declar\u00f3 a <a href=\"https:\/\/www.bbc.com\/news\/live\/world-us-canada-68924299\">BBC<\/a> que la universidad hab\u00eda decidido suspenderlo, pero que luego se retract\u00f3 bruscamente.<\/p>\n<p>\u201cDijeron que tras revisar las pruebas, no ten\u00edan pruebas para suspenderme\u201d, declar\u00f3 a <a href=\"https:\/\/www.bbc.com\/news\/live\/world-us-canada-68924299\">BBC<\/a>. \u201cEso demuestra lo aleatoria que fue la suspensi\u00f3n\u2026 lo hicieron al azar y sin el debido proceso\u201d.<\/p>\n<p>Ahora, casi un a\u00f1o despu\u00e9s, el abogado de Khalil, as\u00ed como defensores de la Primera Enmienda, afirman que se enfrenta a una denegaci\u00f3n similar del debido proceso, tras su detenci\u00f3n por agentes federales el s\u00e1bado.<\/p>\n<p>Ben Wizner, director del Proyecto de Expresi\u00f3n, Privacidad y Tecnolog\u00eda de la Uni\u00f3n Americana de Libertades Civiles, calific\u00f3 la detenci\u00f3n de Khalil de \u201csin precedentes, ilegal y antiestadounidense\u201d.<\/p>\n<p>\u201cLa Primera Enmienda protege a todos en Estados Unidos. Las acciones del gobierno tienen obviamente la intenci\u00f3n de intimidar y enfriar la expresi\u00f3n de un lado de un debate p\u00fablico\u201d, dijo Wizner en un <a href=\"https:\/\/www.aclu.org\/press-releases\/aclu-strongly-condemns-unlawful-arrest-and-detention-of-columbia-student-activist\">comunicado<\/a> el lunes.<\/p>\n<p>M\u00e1s de 1,7 millones de personas han firmado una carta para exigir la \u201c<a href=\"https:\/\/actionnetwork.org\/letters\/demand-the-immediate-release-of-columbia-student-pro-palestine-advocate-mahmoud-khalil-from-dhs-detention\">liberaci\u00f3n inmediata<\/a>\u201d de Khalil, seg\u00fan una petici\u00f3n en Action Network. Y en la ciudad de Nueva York, cientos de personas se concentraron el lunes ante el edificio federal Jacob K. Javits -donde el ICE tiene una oficina local- para protestar por la detenci\u00f3n de Khalil, coreando \u201cQueremos justicia, ustedes dicen \u2018\u00bfc\u00f3mo?\u2019 \u00a1Liberen a Mahmoud Khalil ya!\u201d.<\/p>\n<p>Aun as\u00ed, hay quienes celebraron la mano dura de la administraci\u00f3n Trump contra el antisemitismo y sus supuestos cabecillas en los campus universitarios. En una declaraci\u00f3n <a href=\"https:\/\/x.com\/ADL\/status\/1898918587437338827\">publicada en X<\/a>, la Liga Antidifamaci\u00f3n (ADL, por sus siglas en ingl\u00e9s) elogi\u00f3 a la administraci\u00f3n por su determinaci\u00f3n de frenar el antisemitismo.<\/p>\n<p>\u201cEsta acci\u00f3n ilustra a\u00fan m\u00e1s esa determinaci\u00f3n al responsabilizar a los presuntos autores de sus actos\u201d, dijo la ADL. \u201cObviamente, cualquier acci\u00f3n de deportaci\u00f3n o revocaci\u00f3n de una tarjeta verde o visado debe llevarse a cabo en consonancia con las debidas protecciones procesales requeridas\u201d.<\/p>\n<p><em>Jeff Winter, Alaa Elassar y Shimon Prokupecz de CNN contribuyeron a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Donald Trump ha comparado a Mahmoud Khalil con un simpatizante terrorista. Otros lo describen como un activista palestino, se\u00f1alado por su abierto apoyo a su propio pueblo. Pero mucho antes de ser arrestado por agentes federales el s\u00e1bado por la noche, Khalil dijo a CNN que se sent\u00eda llamado a abogar por la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459761","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente Donald Trump ha comparado a Mahmoud Khalil con un simpatizante terrorista. Otros lo describen como un activista palestino, se\u00f1alado por su abierto apoyo a su propio pueblo. Pero mucho antes de ser arrestado por agentes federales el s\u00e1bado por la noche, Khalil dijo a CNN que se sent\u00eda llamado a abogar por la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T12:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia?\",\"datePublished\":\"2025-03-11T12:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/\"},\"wordCount\":1374,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/\",\"name\":\"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-11T12:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia? - Noticias","og_description":"El presidente Donald Trump ha comparado a Mahmoud Khalil con un simpatizante terrorista. Otros lo describen como un activista palestino, se\u00f1alado por su abierto apoyo a su propio pueblo. Pero mucho antes de ser arrestado por agentes federales el s\u00e1bado por la noche, Khalil dijo a CNN que se sent\u00eda llamado a abogar por la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-11T12:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia?","datePublished":"2025-03-11T12:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/"},"wordCount":1374,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/","name":"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-11T12:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia?","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-11T12:03:50Z","datePublished":"2025-03-11T12:03:50Z","dateModified":"2025-03-11T12:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQui\\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/11\\\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/11\\\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-11T12:03:50Z\",\"datePublished\":\"2025-03-11T12:03:50Z\",\"dateModified\":\"2025-03-11T12:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463783,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/20\/juez-activista-palestino-mahmoud-khalil-liberado-viernes-trax\/","url_meta":{"origin":1459761,"position":0},"title":"Juez ordena liberar a Mahmoud Khalil, el activista palestino en el centro de una larga batalla contra la deportaci\u00f3n","author":"","date":"junio 20, 2025","format":false,"excerpt":"Un juez federal orden\u00f3 este viernes que se ponga en libertad al activista palestino Mahmoud Khalil de un centro de detenci\u00f3n del Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s) de Louisiana, m\u00e1s de tres meses despu\u00e9s de que fuera detenido frente a su apartamento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459806,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/","url_meta":{"origin":1459761,"position":1},"title":"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia","author":"","date":"marzo 12, 2025","format":false,"excerpt":"Cuando los abogados de Mahmoud Khalil entren el mi\u00e9rcoles en el Tribunal Thurgood Marshall de Estados Unidos, en Nueva York, tendr\u00e1n una misi\u00f3n en mente: conseguir que su cliente, un activista palestino, sea liberado de un centro del ICE en Louisiana y regrese a Nueva York para estar m\u00e1s cerca\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461132,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/13\/juez-autoriza-deportacion-mahmoud-khalil-trax\/","url_meta":{"origin":1459761,"position":2},"title":"Un juez de inmigraci\u00f3n autoriza la deportaci\u00f3n del activista Mahmoud Khalil. \u00bfQu\u00e9 sigue?","author":"","date":"abril 13, 2025","format":false,"excerpt":"Si bien la decisi\u00f3n de un juez de inmigraci\u00f3n de que Mahmoud Khalil, graduado de la Universidad de Columbia y residente legal permanente en EE.UU., puede ser deportado es una victoria para la administraci\u00f3n Trump, la batalla legal contra su detenci\u00f3n y deportaci\u00f3n est\u00e1 lejos de terminar.La decisi\u00f3n de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461197,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/14\/mohsen-mahdawi-columbia-universidad-trump-trax\/","url_meta":{"origin":1459761,"position":3},"title":"Estudiante palestino iba a asistir a su \u00faltima entrevista para obtener la ciudadan\u00eda. Ahora se enfrenta a la deportaci\u00f3n","author":"","date":"abril 14, 2025","format":false,"excerpt":"Un estudiante palestino de la Universidad de Columbia acudi\u00f3 este lunes a una oficina de inmigraci\u00f3n de Vermont con la esperanza de comenzar el paso final para convertirse en ciudadano estadounidense. Pero en lugar de tener una entrevista, Mohsen Mahdawi, que ha vivido en Estados Unidos durante una d\u00e9cada, fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459753,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/mahmoud-khalil-columbia-universidad-israel-trax\/","url_meta":{"origin":1459761,"position":4},"title":"Juez bloquea el intento de deportar a activista palestino que ayud\u00f3 a dirigir las protestas estudiantiles de Columbia","author":"","date":"marzo 10, 2025","format":false,"excerpt":"Un juez federal de Nueva York prohibi\u00f3 temporalmente que la administraci\u00f3n del presidente Donald Trump deporte a Mahmoud Khalil, un activista palestino de la Universidad de Columbia arrestado el s\u00e1bado por la noche, hasta una audiencia programada para el mi\u00e9rcoles, seg\u00fan documentos judiciales.No est\u00e1 claro si comparecer\u00e1 ante el tribunal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467206,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/10\/08\/barghouti-liberacion-israel-trax\/","url_meta":{"origin":1459761,"position":5},"title":"Hamas exige la liberaci\u00f3n de un destacado preso palestino. Para Israel, esto podr\u00eda ser una l\u00ednea roja","author":"","date":"octubre 8, 2025","format":false,"excerpt":"Pocos pol\u00edticos gozan de tanto respeto entre los palestinos como como Marwan Barghouti, el preso palestino m\u00e1s destacado, quien cumple cinco cadenas perpetuas en una c\u00e1rcel israel\u00ed.El exl\u00edder del partido Fatah en la Ribera Occidental es, por mucho, la figura pol\u00edtica m\u00e1s popular en los territorios palestinos ocupados, a pesar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459761"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459761\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}