{"id":1459826,"date":"2025-03-12T09:03:41","date_gmt":"2025-03-12T16:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/"},"modified":"2025-03-12T09:03:41","modified_gmt":"2025-03-12T16:03:41","slug":"israel-civiles-escudos-humanos-gaza-investigacion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/","title":{"rendered":"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n"},"content":{"rendered":"<p>Las fuerzas armadas israel\u00edes est\u00e1n investigando el uso de civiles palestinos como escudos humanos por parte de los soldados durante las operaciones en Gaza, seg\u00fan informaron las Fuerzas de Defensa de Israel (FDI) a CNN el martes por la noche.<\/p>\n<p>Esta es la primera vez que las fuerzas armadas reconocen que existe una \u201csospecha razonable\u201d de que los soldados obligaron a civiles a participar en operaciones militares.<\/p>\n<p>CNN inform\u00f3 anteriormente que soldados israel\u00edes obligaron a civiles en Gaza a entrar en casas y t\u00faneles potencialmente llenos de trampas explosivas para evitar poner en peligro a sus efectivos.<\/p>\n<p>\u201cEn varios casos, la Divisi\u00f3n de Investigaci\u00f3n Criminal de la Polic\u00eda Militar abri\u00f3 investigaciones tras surgir sospechas razonables sobre el uso de palestinos para misiones militares durante las operaciones\u201d, dijeron las FDI.<\/p>\n<p>Las FDI no confirmaron cu\u00e1ntas investigaciones se hab\u00edan abierto, ni a qui\u00e9n se estaba investigando.<\/p>\n<p>\u201cEsas investigaciones a\u00fan est\u00e1n en curso y, por lo tanto, no se pueden proporcionar otros detalles en este momento\u201d, seg\u00fan las FDI.<\/p>\n<p>En una entrevista con CNN a finales del a\u00f1o pasado, un soldado israel\u00ed dijo que su unidad hab\u00eda obligado a un palestino a entrar en un edificio delante de las tropas. \u201cSi hay alguna trampa explosiva, explotar\u00e1n ellos y no nosotros\u201d, explic\u00f3.<\/p>\n<p>Seg\u00fan los informes, la pr\u00e1ctica era tan com\u00fan en las fuerzas armadas israel\u00edes que ten\u00eda un nombre: \u201cprotocolo del mosquito\u201d.<\/p>\n<p>Se desconoce la escala y el alcance exactos de esta pr\u00e1ctica por parte de las fuerzas armadas israel\u00edes. Pero el testimonio del soldado y de cinco civiles el a\u00f1o pasado indicaba que estaba muy extendida en todo el territorio: en el norte de Gaza, Ciudad de Gaza, Khan Younis y Rafah.<\/p>\n<p>Uno de los civiles, Mohammad Saad, de 20 a\u00f1os, dijo a CNN que los soldados de las FDI lo hab\u00edan detenido en Rafah.<\/p>\n<p>\u201cNos ped\u00edan cosas como: \u2018mueve esta alfombra\u2019, diciendo que estaban buscando t\u00faneles\u201d, dijo. \u201c\u2019Graba debajo de las escaleras\u2019, dec\u00edan. Si encontraban algo, nos dec\u00edan que lo sac\u00e1ramos. Por ejemplo, nos ped\u00edan que sac\u00e1ramos las pertenencias de la casa, que limpi\u00e1ramos aqu\u00ed, que movi\u00e9ramos el sof\u00e1, que abri\u00e9ramos la nevera y que abri\u00e9ramos el armario\u201d.<\/p>\n<p>En el momento del informe de CNN, en octubre, las FDI afirmaron que los protocolos militares \u201cproh\u00edben estrictamente el uso de civiles detenidos de Gaza para operaciones militares\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las fuerzas armadas israel\u00edes est\u00e1n investigando el uso de civiles palestinos como escudos humanos por parte de los soldados durante las operaciones en Gaza, seg\u00fan informaron las Fuerzas de Defensa de Israel (FDI) a CNN el martes por la noche. Esta es la primera vez que las fuerzas armadas reconocen que existe una \u201csospecha razonable\u201d [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459826","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Las fuerzas armadas israel\u00edes est\u00e1n investigando el uso de civiles palestinos como escudos humanos por parte de los soldados durante las operaciones en Gaza, seg\u00fan informaron las Fuerzas de Defensa de Israel (FDI) a CNN el martes por la noche. Esta es la primera vez que las fuerzas armadas reconocen que existe una \u201csospecha razonable\u201d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T16:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n\",\"datePublished\":\"2025-03-12T16:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/\"},\"wordCount\":458,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/\",\"name\":\"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-12T16:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n - Noticias","og_description":"Las fuerzas armadas israel\u00edes est\u00e1n investigando el uso de civiles palestinos como escudos humanos por parte de los soldados durante las operaciones en Gaza, seg\u00fan informaron las Fuerzas de Defensa de Israel (FDI) a CNN el martes por la noche. Esta es la primera vez que las fuerzas armadas reconocen que existe una \u201csospecha razonable\u201d [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-12T16:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/"},"author":{"name":"","@id":""},"headline":"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n","datePublished":"2025-03-12T16:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/"},"wordCount":458,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/","name":"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-12T16:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\u00f3n","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/israel-civiles-escudos-humanos-gaza-investigacion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-12T16:03:41Z","datePublished":"2025-03-12T16:03:41Z","dateModified":"2025-03-12T16:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Israel reconoce posible uso de civiles como escudos humanos en las operaciones militares de Gaza e inicia una investigaci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/12\\\/israel-civiles-escudos-humanos-gaza-investigacion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/12\\\/israel-civiles-escudos-humanos-gaza-investigacion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-12T16:03:41Z\",\"datePublished\":\"2025-03-12T16:03:41Z\",\"dateModified\":\"2025-03-12T16:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1456275,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/05\/amnistia-internacional-pruebas-acusar-israel-genocidio-gaza-trax\/","url_meta":{"origin":1459826,"position":0},"title":"Amnist\u00eda Internacional dice que hay &#171;pruebas suficientes&#187; para acusar a Israel de genocidio en Gaza","author":"","date":"diciembre 5, 2024","format":false,"excerpt":"Amnist\u00eda Internacional dijo este mi\u00e9rcoles que hab\u00eda reunido \u201cpruebas suficientes para creer\u201d que la conducta de Israel durante la guerra de Gaza equivale a genocidio contra el pueblo palestino, acusaci\u00f3n que el Gobierno israel\u00ed ha negado con vehemencia.El informe, de 296 p\u00e1ginas, detalla las pruebas reunidas a lo largo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466499,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/16\/onu-israel-genocidio-gaza-trax\/","url_meta":{"origin":1459826,"position":1},"title":"Comisi\u00f3n de la ONU afirma que Israel est\u00e1 cometiendo genocidio en Gaza","author":"","date":"septiembre 16, 2025","format":false,"excerpt":"Una investigaci\u00f3n independiente de las Naciones Unidas concluy\u00f3 por primera vez que Israel ha cometido genocidio contra los palestinos en Gaza y que los principales l\u00edderes del pa\u00eds han incitado al genocidio, en lo que describi\u00f3 como la \u201cconclusi\u00f3n m\u00e1s autorizada de la ONU hasta la fecha\u201d.En un informe de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460908,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/07\/adolescente-palestino-estadounidense-muere-soldados-israelies-trax\/","url_meta":{"origin":1459826,"position":2},"title":"Adolescente palestino-estadounidense muere por disparos de soldados israel\u00edes en la Ribera Occidental, seg\u00fan funcionarios","author":"","date":"abril 7, 2025","format":false,"excerpt":"Soldados israel\u00edes mataron a un adolescente palestino-estadounidense e hirieron a otros dos este domingo en la Ribera Occidental ocupada, seg\u00fan funcionarios palestinos.La gobernadora de Ramallah, Laila Ghannam, inform\u00f3 que un ni\u00f1o palestino-estadounidense de 14 a\u00f1os muri\u00f3 a causa de disparos de tropas israel\u00edes en la aldea de Turmusaya. Otros dos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461417,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/20\/fuerzas-armadas-israelies-fallos-profesionales-soldados-muerte-medicos-palestinos-gaza-trax\/","url_meta":{"origin":1459826,"position":3},"title":"Fuerzas Armadas israel\u00edes admiten que fallos profesionales de sus soldados causaron la muerte de m\u00e9dicos palestinos en Gaza","author":"","date":"abril 20, 2025","format":false,"excerpt":"Las Fuerzas Armadas israel\u00edes afirmaron que \u201cfallos profesionales\u201d llevaron a la muerte de 15 param\u00e9dicos y socorristas en un incidente en Gaza en marzo, seg\u00fan una investigaci\u00f3n publicada el domingo.La investigaci\u00f3n identific\u00f3 varios errores durante el incidente, as\u00ed como incumplimientos de \u00f3rdenes y una falta de reporte completo del hecho,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464023,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/27\/fdi-rechazan-informe-soldados-disparar-palestinos-comida-trax\/","url_meta":{"origin":1459826,"position":4},"title":"Las FDI rechazan informe que afirma que se orden\u00f3 a soldados disparar contra palestinos que esperaban comida","author":"","date":"junio 27, 2025","format":false,"excerpt":"Las fuerzas israel\u00edes negaron un nuevo informe que afirma que se orden\u00f3 a soldados disparar contra palestinos desarmados que esperaban ayuda humanitaria en Gaza, despu\u00e9s de que se reportara la muerte de cientos de personas al acercarse a los puntos de distribuci\u00f3n de alimentos en las \u00faltimas semanas.Este viernes, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460308,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/23\/muertos-gaza-guerra-israel-hamas-ministerio-salud-trax\/","url_meta":{"origin":1459826,"position":5},"title":"50.000 personas han muerto en Gaza desde el inicio de la guerra entre Israel y Hamas, dice Ministerio de Salud","author":"","date":"marzo 23, 2025","format":false,"excerpt":"M\u00e1s de 50.000 palestinos han muerto en Gaza desde que comenz\u00f3 la guerra de Israel con Hamas, dijo este domingo el Ministerio de Salud del territorio, un hito sombr\u00edo para una guerra sin final a la vista mientras Israel reanuda los combates y advierte de d\u00edas a\u00fan m\u00e1s dif\u00edciles por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459826"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459826\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}