{"id":1459828,"date":"2025-03-12T09:03:42","date_gmt":"2025-03-12T16:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/"},"modified":"2025-03-12T09:03:42","modified_gmt":"2025-03-12T16:03:42","slug":"jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/","title":{"rendered":"Jorge Macri: &#171;Patricia Bullrich le falta el respeto a los porte\u00f1os&#187;"},"content":{"rendered":"<p>Jorge Macri, jefe de Gobierno porte\u00f1o, visit\u00f3 este mi\u00e9rcoles el estudio de CNN Radio para conversar con Nacho Gir\u00f3n y el equipo sobre su gesti\u00f3n, su v\u00ednculo con la provincia de Buenos Aires y el Gobierno Nacional, los presos en la Ciudad y la pol\u00e9mica con Patricia Bullrich, entre otros temas.<\/p>\n<p>En La Ma\u00f1ana de CNN, Macri indic\u00f3 que \u201ces un desaf\u00edo mucho m\u00e1s grande que Vicente L\u00f3pez\u201d, en tanto que se refiri\u00f3 al v\u00ednculo con la provincia de Buenos Aires: \u201cNo tiene mecanismos de contenci\u00f3n\u201d.<\/p>\n<p>\u201cLa provincia deber\u00eda tener paradores pero no tiene, entonces la gente en la calle viene ac\u00e1\u201d, explic\u00f3, y dijo que \u201cla provincia tiene una actitud de pasar por debajo del radar\u201d.<\/p>\n<p><strong>La relaci\u00f3n con el Gobierno Nacional<\/strong><\/p>\n<p>\u201cPens\u00e9 que \u00edbamos a tener un mejor nivel de relaci\u00f3n con algunos actores\u201d, expres\u00f3 el alcalde porte\u00f1o, y sostuvo que \u201cel Gobierno anterior nos sac\u00f3 recursos de Coparticipaci\u00f3n\u201d.<\/p>\n<p>\u201cNo somos del mismo espacio pol\u00edtico que Milei y yo lo vot\u00e9\u201d, confes\u00f3, y adelat\u00f3 que \u201cclaramente vamos a competir con La Libertad Avanza\u201d.<\/p>\n<p><strong>Los presos en la Ciudad<\/strong><\/p>\n<p>En este sentido, Jorge Macri aclar\u00f3 que \u201ces falso que est\u00e9 firmado el traspaso del Servicio Penitenciario\u201d-<\/p>\n<p>\u201cLos presos no est\u00e1n donde deber\u00edan estar\u201d, indic\u00f3, mientras que explic\u00f3 que \u201clas comisar\u00edas no son lugares para tener detenidos\u201d.<\/p>\n<p><strong>Su visi\u00f3n de Patricia Bullrich<\/strong><\/p>\n<p>Seg\u00fan Jorge Macri, \u201cPatricia es h\u00e1bil, tira t\u00edtulos f\u00e1cil\u201d.<\/p>\n<p>\u201cQue Patricia Bullrich diga que Mauricio Macri es el jefe de Gobierno es una falta de respeto a los porte\u00f1os\u201d, lanz\u00f3, y a\u00f1adi\u00f3 que a la ministra de Seguridad \u201cle gusta hacer pol\u00edtica con la chicana\u201d.<\/p>\n<p><strong>El desdoblamiento de las elecciones porte\u00f1as<\/strong><\/p>\n<p>\u201cYo banco una elecci\u00f3n desdoblada\u201d, revel\u00f3 Jorge Macri.<\/p>\n<p>Y agreg\u00f3: \u201cLos porte\u00f1os se merecen un momento para discutir los temas de la Ciudad\u201d.<\/p>\n<p><strong>Los alquileres en la Ciudad<\/strong><\/p>\n<p>\u201cLos alquileres en la Ciudad bajaron con la Ley nueva\u201d, record\u00f3, y dijo que \u201cel desaf\u00edo es generar pol\u00edticas activas para comprar vivienda\u201d.<\/p>\n<p>\u201cHoy pod\u00e9s sacar una hipoteca en pozo\u201d, acot\u00f3, y reconoci\u00f3 que \u201cla soluci\u00f3n profunda a la vivienda es que vos puedas ser propietario\u201d.<\/p>\n<p><strong>La marcha de hinchas por los jubilados<\/strong><\/p>\n<p>Finalmente, sobre la marcha de los jubilados, Jorge Macri afirm\u00f3: \u201cEstamos ocupados para que ninguna barra venga a agredir\u201d.<\/p>\n<p>\u201cSi alguien se quiere manifestar, que lo haga cumpliendo la Ley\u201d, cerr\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Macri, jefe de Gobierno porte\u00f1o, visit\u00f3 este mi\u00e9rcoles el estudio de CNN Radio para conversar con Nacho Gir\u00f3n y el equipo sobre su gesti\u00f3n, su v\u00ednculo con la provincia de Buenos Aires y el Gobierno Nacional, los presos en la Ciudad y la pol\u00e9mica con Patricia Bullrich, entre otros temas. En La Ma\u00f1ana de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459828","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jorge Macri: &quot;Patricia Bullrich le falta el respeto a los porte\u00f1os&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jorge Macri: &quot;Patricia Bullrich le falta el respeto a los porte\u00f1os&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Jorge Macri, jefe de Gobierno porte\u00f1o, visit\u00f3 este mi\u00e9rcoles el estudio de CNN Radio para conversar con Nacho Gir\u00f3n y el equipo sobre su gesti\u00f3n, su v\u00ednculo con la provincia de Buenos Aires y el Gobierno Nacional, los presos en la Ciudad y la pol\u00e9mica con Patricia Bullrich, entre otros temas. En La Ma\u00f1ana de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T16:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jorge Macri: &#171;Patricia Bullrich le falta el respeto a los porte\u00f1os&#187;\",\"datePublished\":\"2025-03-12T16:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/\"},\"wordCount\":450,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/\",\"name\":\"Jorge Macri: \\\"Patricia Bullrich le falta el respeto a los porte\u00f1os\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-12T16:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jorge Macri: &#171;Patricia Bullrich le falta el respeto a los porte\u00f1os&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jorge Macri: \"Patricia Bullrich le falta el respeto a los porte\u00f1os\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/","og_locale":"es_ES","og_type":"article","og_title":"Jorge Macri: \"Patricia Bullrich le falta el respeto a los porte\u00f1os\" - Noticias","og_description":"Jorge Macri, jefe de Gobierno porte\u00f1o, visit\u00f3 este mi\u00e9rcoles el estudio de CNN Radio para conversar con Nacho Gir\u00f3n y el equipo sobre su gesti\u00f3n, su v\u00ednculo con la provincia de Buenos Aires y el Gobierno Nacional, los presos en la Ciudad y la pol\u00e9mica con Patricia Bullrich, entre otros temas. En La Ma\u00f1ana de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/","og_site_name":"Noticias","article_published_time":"2025-03-12T16:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/"},"author":{"name":"","@id":""},"headline":"Jorge Macri: &#171;Patricia Bullrich le falta el respeto a los porte\u00f1os&#187;","datePublished":"2025-03-12T16:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/"},"wordCount":450,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/","url":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/","name":"Jorge Macri: \"Patricia Bullrich le falta el respeto a los porte\u00f1os\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-12T16:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jorge Macri: &#171;Patricia Bullrich le falta el respeto a los porte\u00f1os&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jorge Macri: &#171;Patricia Bullrich le falta el respeto a los porte\u00f1os&#187;","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-12T16:03:42Z","datePublished":"2025-03-12T16:03:42Z","dateModified":"2025-03-12T16:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jorge Macri: &#171;Patricia Bullrich le falta el respeto a los porte\\u00f1os&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/12\\\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/12\\\/jorge-macri-patricia-bullrich-le-falta-el-respeto-a-los-portenos\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-12T16:03:42Z\",\"datePublished\":\"2025-03-12T16:03:42Z\",\"dateModified\":\"2025-03-12T16:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459168,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/25\/clara-muzzio-no-hay-ningun-motivo-para-que-el-gobierno-nacional-y-la-ministra-bullrich-no-se-hagan-cargo-de-los-detenidos\/","url_meta":{"origin":1459828,"position":0},"title":"Clara Muzzio: &#171;No hay ning\u00fan motivo para que el gobierno nacional y la ministra Bullrich no se hagan cargo de los detenidos&#187;","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Clara Muzzio, vicejefa del Gobierno de la Ciudad Aut\u00f3noma de Buenos Aires, se refiri\u00f3 a la situaci\u00f3n en las c\u00e1rceles en el distrito porte\u00f1o, la controversia con la Naci\u00f3n y la relaci\u00f3n con la ministra de Seguridad Nacional, Patricia Bullrich, y el exjefe de Gobierno, Horacio Rodr\u00edguez Larreta.En CNN Primera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462899,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/28\/ramon-lanus-intendente-de-san-isidro-no-es-el-momento-de-marcarle-matices-a-la-libertad-avanza\/","url_meta":{"origin":1459828,"position":1},"title":"Ram\u00f3n Lan\u00fas, intendente de San Isidro: &#171;No es el momento de marcarle matices a La Libertad Avanza&#187;","author":"","date":"mayo 28, 2025","format":false,"excerpt":"Ram\u00f3n Lan\u00fas, intendente de San Isidro, habl\u00f3 este mi\u00e9rcoles en CNN Radio sobre el acuerdo entre el PRO y LLA en la provincia de Buenos Aires, las diferencias que hubo en el marco de la elecciones legislativas porte\u00f1as y consider\u00f3 que \u201cno es el momento de marcar los matices\u201d con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459126,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/24\/pilar-ramirez-queremos-motosierra-de-verdad-y-jorge-macri-tiene-una-tijerita\/","url_meta":{"origin":1459828,"position":2},"title":"Pilar Ram\u00edrez: &#171;Queremos motosierra de verdad y Jorge Macri tiene una tijerita&#187;","author":"","date":"febrero 24, 2025","format":false,"excerpt":"Pilar Ram\u00edrez, presidente de La Libertad Avanza en la Ciudad de Buenos Aires y jefa del bloque en la Legislatura, visit\u00f3 este lunes los estudios de CNN Radio para conversar con Nacho Gir\u00f3n y el equipo de La Ma\u00f1ana de CNN de la interna del oficialismo en territorio porte\u00f1o, las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462078,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/07\/fernando-de-andreis-el-cambio-de-bullrich-a-la-libertad-avanza-es-una-traicion-al-votante-del-pro\/","url_meta":{"origin":1459828,"position":3},"title":"Fernando de Andreis: &#171;El cambio de Bullrich a La Libertad Avanza es una traici\u00f3n al votante del PRO&#187;","author":"","date":"mayo 7, 2025","format":false,"excerpt":"Fernando de Andreis, exsecretario general de la Presidencia de Mauricio Macri, visit\u00f3 este mi\u00e9rcoles los estudios de CNN Radio para conversar sobre el v\u00ednculo del PRO con La Libertad Avanza, la gesti\u00f3n de Javier Milei, y mientras calific\u00f3 como una \u201ctraici\u00f3n\u201d la decisi\u00f3n de Patricia Bullrich de afiliarse a LLA\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460629,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/31\/jorge-telerman-buenos-aires-esta-gobernada-por-gente-que-no-tiene-la-experiencia-ni-el-conocimiento-para-la-ciudad\/","url_meta":{"origin":1459828,"position":4},"title":"Jorge Telerman: Buenos Aires est\u00e1 &#171;gobernada por gente que no tiene la experiencia ni el conocimiento de la ciudad&#187;","author":"","date":"marzo 31, 2025","format":false,"excerpt":"Jorge Telerman, exjefe de gobierno porte\u00f1o y candidato a legislador porte\u00f1o por el espacio e Horacio Rodr\u00edguez Larreta, analiz\u00f3 las elecciones en la ciudad de Buenos Aires y la gesti\u00f3n de Jorge Macri.En CNN Primera Ma\u00f1ana, afirm\u00f3 que en \u201clas elecciones legislativas tiene que ver en c\u00f3mo abordamos los problemas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459174,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/25\/ojala-milei-se-saque-de-encima-lo-peor-del-kirchnerismo\/","url_meta":{"origin":1459828,"position":5},"title":"Waldo Wolff: &#171;Ojal\u00e1 Milei se saque de encima lo peor del kirchnerismo&#187;","author":"","date":"febrero 25, 2025","format":false,"excerpt":"Waldo Wolff, ministro de Seguridad de la Ciudad de Buenos Aires, visit\u00f3 este martes los estudios de CNN Radio Argentina para conversar sobre la relaci\u00f3n con La Libertad Avanza, remarc\u00f3 sus diferencias con Pilar Ram\u00edrez y Horacio Rodr\u00edguez Larreta y habl\u00f3 sobre las fugas de los detenidos en las comisar\u00edas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459828"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459828\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}