{"id":1459861,"date":"2025-03-13T04:03:48","date_gmt":"2025-03-13T11:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/"},"modified":"2025-03-13T04:03:48","modified_gmt":"2025-03-13T11:03:48","slug":"spacex-mision-tripulacion-astronautas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/","title":{"rendered":"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra"},"content":{"rendered":"<p>Una tripulaci\u00f3n de astronautas internacionales programada para ser lanzada hacia la Estaci\u00f3n Espacial Internacional (EEI) en una misi\u00f3n que relevar\u00e1 a Butch Wilmore y Suni Williams de la NASA, lo que les permitir\u00e1 regresar a casa despu\u00e9s de un <a href=\"https:\/\/www.cnn.com\/2025\/02\/13\/science\/boeing-starliner-astronauts-stuck-space\/index.html\">viaje inesperadamente largo y pol\u00edticamente cargado<\/a>, tendr\u00e1 que esperar un poco m\u00e1s.<\/p>\n<p>El vuelo Crew-10, parte de una rotaci\u00f3n rutinaria del personal de la EEI, es operado en conjunto por la NASA y SpaceX. El despegue estaba programado para el mi\u00e9rcoles por la noche desde el Centro Espacial Kennedy en la Florida, pero la compa\u00f1\u00eda cancel\u00f3 el intento de lanzamiento debido a un problema con el sistema terrestre de la plataforma de despegue.<\/p>\n<p>El problema surgi\u00f3 de un sistema hidr\u00e1ulico utilizado para controlar una de las dos abrazaderas que sujetan la parte superior del cohete mientras est\u00e1 colocado verticalmente sobre la plataforma de tierra antes del lanzamiento.<\/p>\n<p>\u201cEste es un problema terrestre. Todo estaba bien con el cohete y la nave espacial\u201d, declar\u00f3 el portavoz de la NASA, Darrol Nail, en la transmisi\u00f3n en vivo.<\/p>\n<p>SpaceX dijo m\u00e1s temprano el mi\u00e9rcoles que podr\u00eda lanzar la misi\u00f3n Crew-10 nuevamente el jueves a las 7:26 p.m. (hora de Miami), aunque a\u00fan no se ha tomado una decisi\u00f3n sobre si se aprovechar\u00e1 esa oportunidad.<\/p>\n<p>Cuando se lance la misi\u00f3n, una c\u00e1psula Dragon de SpaceX, montada sobre uno de los cohetes Falcon 9 de la compa\u00f1\u00eda, llevar\u00e1 a los cuatro astronautas de la Crew-10 (Nichole Ayers y Anne McClain de la NASA, Takuya Onishi de la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n y el cosmonauta de Roscosmos Kirill Peskov) a la \u00f3rbita.<\/p>\n<p>Una vez en la estaci\u00f3n espacial, Ayers, McClain, Onishi y Peskov pasar\u00e1n unos d\u00edas aclimat\u00e1ndose al laboratorio en \u00f3rbita durante un per\u00edodo de transferencia con los astronautas de la Crew-9, un equipo que incluye a Williams y Wilmore, as\u00ed como a Nick Hague de la NASA y Aleksandr Gorbunov de Roscosmos.<\/p>\n<p>Williams, Wilmore y el resto de la Crew-9 regresar\u00e1n a la Tierra una vez finalizado el periodo de traspaso. El equipo de la Crew-9 ten\u00eda previsto desacoplarse de la estaci\u00f3n el 16 de marzo si el intento de lanzamiento del mi\u00e9rcoles resultaba exitoso. No est\u00e1 claro cu\u00e1nto podr\u00eda cambiar la fecha de salida ahora que SpaceX ha cancelado un posible despegue el mi\u00e9rcoles.<\/p>\n<p>Williams y Wilmore han estado en \u00f3rbita desde junio pasado, cuando pilotaron el vuelo de prueba tripulado inaugural de la c\u00e1psula Starliner de Boeing. Preve\u00edan permanecer en el espacio aproximadamente una semana. Sin embargo, numerosos problemas detectados durante su viaje a la EEI, incluyendo fugas de helio y problemas de propulsi\u00f3n, llevaron a la NASA a considerar que el regreso del veh\u00edculo Starliner con astronautas era demasiado arriesgado.<\/p>\n<p>Si bien Crew-9 y Crew-10 son parte de las operaciones de rutina que llevan a cabo la NASA y SpaceX para mantener la estaci\u00f3n espacial con todo el personal, las misiones se han convertido en el foco de <a href=\"https:\/\/www.cnn.com\/2025\/02\/11\/science\/nasa-boeing-astronauts-spacex\/index.html\">una controversia p\u00fablica<\/a> que involucra afirmaciones del presidente Donald Trump y Elon Musk (el CEO de SpaceX que ahora es un importante asesor presidencial) sobre la administraci\u00f3n del expresidente Joe Biden.<\/p>\n<p>Aunque la NASA anunci\u00f3 en agosto, antes de las elecciones de 2024 o de la investidura de Trump, que planeaba regresar a Williams y Wilmore a la Tierra en un veh\u00edculo SpaceX, Musk ha afirmado repetidamente este a\u00f1o que el predecesor de Trump rechaz\u00f3 una oferta de SpaceX para traer a Williams y Wilmore a casa antes por \u201crazones pol\u00edticas\u201d.<\/p>\n<p>Musk no ha dicho exactamente qu\u00e9 se le pudo haber propuesto ni a qui\u00e9n se lo ofrecieron.<\/p>\n<p>Un ex alto  funcionario de la NASA dijo a CNN que SpaceX nunca comunic\u00f3 tal propuesta a los l\u00edderes de la agencia y que la NASA probablemente no habr\u00eda considerado la idea de todos modos.<\/p>\n<p>Si Musk hubiera hecho la oferta a alguien fuera de la direcci\u00f3n de la NASA, se\u00f1al\u00f3 la fuente, \u201cestoy seguro de que habr\u00edan respondido y dicho: \u2018Bueno, eso nos costar\u00eda varios cientos de millones de d\u00f3lares adicionales que no tenemos para una nueva c\u00e1psula Dragon y un cohete Falcon 9\u2019\u201d.<strong><\/strong><\/p>\n<p>Y en una <a href=\"https:\/\/www.youtube.com\/watch?v=lgTU1qVZoyw\">conferencia<\/a> de prensa en agosto de 2024 , Steve Stich, gerente del programa de tripulaci\u00f3n comercial de la NASA, dijo a los periodistas que la agencia espacial \u201cnunca consider\u00f3 esa opci\u00f3n\u201d, refiri\u00e9ndose a la idea de volar una misi\u00f3n SpaceX separada dedicada a recuperar a Williams y Wilmore en lugar de regresarlos a la Tierra a bordo de un vuelo de rutina previamente programado.<\/p>\n<p>\u201cSimplemente no ten\u00eda sentido seguir adelante y acelerar un vuelo (de SpaceX) para traer de regreso a Butch y Suni antes\u201d, dijo Stich.<\/p>\n<p>Aun as\u00ed, Musk ha dicho en entrevistas y publicaciones en las redes sociales que hizo la oferta a la Casa Blanca de Biden y que fue rechazada, aunque no est\u00e1 claro por qu\u00e9 no habr\u00eda presentado la propuesta a los organizadores de la misi\u00f3n en la NASA.<\/p>\n<p>Un exmiembro del personal de la Casa Blanca no respondi\u00f3 a una solicitud de comentarios.<\/p>\n<p>Cuando la NASA anunci\u00f3 sorpresivamente en agosto de 2024 que la Starliner regresar\u00eda a casa vac\u00eda, Williams y Wilmore fueron reasignados a una misi\u00f3n tripulada de SpaceX. Esto signific\u00f3 que ambos se unir\u00edan al personal oficial de la EEI y a la Crew-9, que se lanz\u00f3 en septiembre con dos asientos vac\u00edos para Williams y Wilmore.<\/p>\n<p>Si bien la Crew-9 originalmente estaba programada para regresar en febrero, la NASA dijo en diciembre que la misi\u00f3n se retrasar\u00eda hasta fines de marzo debido a problemas con una nueva c\u00e1psula Crew Dragon que SpaceX estaba preparando para volar a los astronautas de la Crew-10.<\/p>\n<p>El mes pasado, la agencia espacial anunci\u00f3 que SpaceX adelantar\u00eda la fecha de lanzamiento de la Crew-10 varias semanas al optar por utilizar una c\u00e1psula <a href=\"https:\/\/www.cnn.com\/2025\/02\/11\/science\/nasa-boeing-astronauts-spacex\/index.html\">Crew Dragon diferente, previamente utilizada<\/a> para la misi\u00f3n.<\/p>\n<p>La NASA ha mantenido que es esencial lanzar al personal de la Crew-10 a la ISS y permitir que el traspaso, que durar\u00e1 varios d\u00edas, se lleve a cabo antes de que Williams, Wilmore y el resto de los astronautas de la Crew-9 regresen a la Tierra.<\/p>\n<p>La decisi\u00f3n de mantener a Williams y Wilmore en la EEI en lugar de lanzar una misi\u00f3n de emergencia para regresarlos a la Tierra se tom\u00f3 como parte de los esfuerzos de la NASA por mantener la estaci\u00f3n espacial con personal completo. Esto permiti\u00f3 a los astronautas veteranos intervenir y apoyar las actividades diarias del laboratorio orbital, ya que ambos hab\u00edan sido entrenados antes de su vuelo de prueba en Starliner para unirse a la tripulaci\u00f3n de la EEI como parte del plan de contingencia de la NASA.<\/p>\n<p>La agencia espacial busca mantener al menos cuatro representantes de Estados Unidos y sus pa\u00edses socios a bordo del laboratorio en todo momento.<\/p>\n<p>Por su parte, Williams y Wilmore han dicho repetidamente que disfrutan su tiempo en el espacio.<\/p>\n<p>\u201cEste es mi lugar feliz\u201d, dijo Williams en septiembre. \u201cMe encanta estar aqu\u00ed arriba en el espacio. Es simplemente divertido. Sabe, cada d\u00eda haces algo que es trabajo \u2014entre comillas\u2014, puedes hacerlo al rev\u00e9s. Puedes hacerlo de lado, lo que a\u00f1ade una perspectiva un poco diferente\u201d.<\/p>\n<p>Tambi\u00e9n han buscado disipar las acusaciones de que fueron abandonados por la administraci\u00f3n anterior.<\/p>\n<p>\u201cEsa ha sido la narrativa desde el primer d\u00eda: varados, abandonados, atascados, y lo entiendo, ambos lo entendemos\u201d, dijo Wilmore a Anderson Cooper de CNN el mes pasado cuando se le pidi\u00f3 que respondiera a los comentarios de Musk y Trump sobre la misi\u00f3n. \u201cAy\u00fadennos a cambiar la narrativa; cambi\u00e9mosla a: preparados y comprometidos a pesar de lo que han estado escuchando. Eso es lo que preferimos\u201d.<\/p>\n<p>A\u00fan as\u00ed, Wilmore a\u00f1adi\u00f3 le\u00f1a al fuego a las especulaciones sobre las afirmaciones de Musk respecto de una oferta para regresar a los astronautas antes de tiempo durante una conferencia de prensa realizada desde la estaci\u00f3n espacial el 4 de marzo.<\/p>\n<p>\u201cSolo puedo decir que lo que dice el se\u00f1or Musk es absolutamente cierto\u201d, afirm\u00f3 Wilmore.<\/p>\n<p>Sin embargo, a\u00f1adi\u00f3: \u00abNo tenemos informaci\u00f3n al respecto. Lo que se ofreci\u00f3, lo que se ofreci\u00f3, lo que no se ofreci\u00f3, a qui\u00e9n se ofreci\u00f3, c\u00f3mo se desarroll\u00f3 el proceso\u2026 simplemente no tenemos esa informaci\u00f3n\u00bb.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una tripulaci\u00f3n de astronautas internacionales programada para ser lanzada hacia la Estaci\u00f3n Espacial Internacional (EEI) en una misi\u00f3n que relevar\u00e1 a Butch Wilmore y Suni Williams de la NASA, lo que les permitir\u00e1 regresar a casa despu\u00e9s de un viaje inesperadamente largo y pol\u00edticamente cargado, tendr\u00e1 que esperar un poco m\u00e1s. El vuelo Crew-10, parte [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459861","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una tripulaci\u00f3n de astronautas internacionales programada para ser lanzada hacia la Estaci\u00f3n Espacial Internacional (EEI) en una misi\u00f3n que relevar\u00e1 a Butch Wilmore y Suni Williams de la NASA, lo que les permitir\u00e1 regresar a casa despu\u00e9s de un viaje inesperadamente largo y pol\u00edticamente cargado, tendr\u00e1 que esperar un poco m\u00e1s. El vuelo Crew-10, parte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T11:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra\",\"datePublished\":\"2025-03-13T11:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/\"},\"wordCount\":1486,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/\",\"name\":\"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-13T11:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra - Noticias","og_description":"Una tripulaci\u00f3n de astronautas internacionales programada para ser lanzada hacia la Estaci\u00f3n Espacial Internacional (EEI) en una misi\u00f3n que relevar\u00e1 a Butch Wilmore y Suni Williams de la NASA, lo que les permitir\u00e1 regresar a casa despu\u00e9s de un viaje inesperadamente largo y pol\u00edticamente cargado, tendr\u00e1 que esperar un poco m\u00e1s. El vuelo Crew-10, parte [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-13T11:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/"},"author":{"name":"","@id":""},"headline":"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra","datePublished":"2025-03-13T11:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/"},"wordCount":1486,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/","name":"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-13T11:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"SpaceX renuncia a intento de lanzar misi\u00f3n de intercambio de tripulaci\u00f3n que permitir\u00e1 a dos astronautas volver a la Tierra","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/spacex-mision-tripulacion-astronautas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-13T11:03:48Z","datePublished":"2025-03-13T11:03:48Z","dateModified":"2025-03-13T11:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"SpaceX renuncia a intento de lanzar misi\\u00f3n de intercambio de tripulaci\\u00f3n que permitir\\u00e1 a dos astronautas volver a la Tierra\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/13\\\/spacex-mision-tripulacion-astronautas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/13\\\/spacex-mision-tripulacion-astronautas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-13T11:03:48Z\",\"datePublished\":\"2025-03-13T11:03:48Z\",\"dateModified\":\"2025-03-13T11:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471245,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/14\/mision-spacex-nasa-llega-eei-trax\/","url_meta":{"origin":1459861,"position":0},"title":"La misi\u00f3n de SpaceX y la NASA llega a la EEI, relevando a la tripulaci\u00f3n m\u00ednima de astronautas","author":"","date":"febrero 14, 2026","format":false,"excerpt":"Una c\u00e1psula de SpaceX que transportaba a cuatro astronautas lleg\u00f3 el s\u00e1bado a la Estaci\u00f3n Espacial Internacional, devolviendo al laboratorio orbital su dotaci\u00f3n completa un mes despu\u00e9s de que una tripulaci\u00f3n anterior tuviera que salir de emergencia debido a un problema m\u00e9dico, dejando atr\u00e1s a una tripulaci\u00f3n m\u00ednima.La misi\u00f3n, llamada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444087,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/18\/spacex-lanzo-la-tercera-mision-comercial-de-astronautas-a-la-estacion-espacial-internacional\/","url_meta":{"origin":1459861,"position":1},"title":"SpaceX lanz\u00f3 la tercera misi\u00f3n comercial de astronautas a la Estaci\u00f3n Espacial Internacional","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN) -- SpaceX lanz\u00f3 Axiom Space Mission 3 (Ax-3), la tercera misi\u00f3n comercial de astronautas a la Estaci\u00f3n Espacial Internacional, el jueves a las 4:49 p.m. (hora de Miami).Se trata de la \u201cprimera misi\u00f3n comercial de astronautas totalmente europea a la Estaci\u00f3n Espacial Internacional\u201d, seg\u00fan Axiom.A bordo se encuentran el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470077,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/01\/14\/nasa-astronautas-crew-11-estacion-espacial-internacional-trax\/","url_meta":{"origin":1459861,"position":2},"title":"Cuatro astronautas abandonar\u00e1n la Estaci\u00f3n Espacial Internacional, dejando solo a tres tripulantes a cargo","author":"","date":"enero 14, 2026","format":false,"excerpt":"Cuatro astronautas est\u00e1n a punto de abandonar la Estaci\u00f3n Espacial Internacional (EEI) debido a un problema de salud, y su partida anticipada, sin precedentes, dejar\u00e1 una tripulaci\u00f3n m\u00ednima a cargo del puesto orbital.Cuando la tripulaci\u00f3n aborde la c\u00e1psula SpaceX que los llevar\u00e1 de regreso a la Tierra, solo tres personas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471186,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/13\/spacex-nasa-envio-astronautas-estacion-espacial-trax\/","url_meta":{"origin":1459861,"position":3},"title":"SpaceX y NASA preparan env\u00edo de astronautas a la Estaci\u00f3n Espacial Internacional y reforzar su tripulaci\u00f3n de tres personas","author":"","date":"febrero 13, 2026","format":false,"excerpt":"Una c\u00e1psula de SpaceX pronto transportar\u00e1 a cuatro astronautas a la Estaci\u00f3n Espacial Internacional, lo que permitir\u00e1 que el laboratorio en \u00f3rbita vuelva a contar con su personal completo despu\u00e9s de un mes de operar con una tripulaci\u00f3n m\u00ednima.La misi\u00f3n, denominada Crew-12, despegar\u00e1 no antes de las 5:15 a.m., hora\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460067,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/18\/quienes-son-suni-williams-butch-wilmore-astronautas-nasa-eei-orix\/","url_meta":{"origin":1459861,"position":4},"title":"\u00bfQui\u00e9nes son Suni Williams y Butch Wilmore, los astronautas que vuelven tras estar varados en la EEI?","author":"","date":"marzo 18, 2025","format":false,"excerpt":"Suni Williams y Butch Wilmore, de la NASA, quienes acapararon la atenci\u00f3n internacional cuando su breve estancia prevista en el espacio se prolong\u00f3 hasta convertirse en una misi\u00f3n de nueve meses con gran carga pol\u00edtica, finalmente regresan a casa.Los astronautas subieron a bordo de la c\u00e1psula Crew Dragon de SpaceX\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451783,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/12\/astronautas-starlines-boeing-permanecer-espacio-trax\/","url_meta":{"origin":1459861,"position":5},"title":"Los astronautas del Starliner de Boeing podr\u00edan permanecer en el espacio otros seis meses. Esto es lo que har\u00edan","author":"","date":"agosto 12, 2024","format":false,"excerpt":"(CNN) -- Cuando los astronautas Suni Williams y Butch Wilmore abandonaron la Tierra rumbo a la Estaci\u00f3n Espacial Internacional (EEI) hace dos meses, dejaron sus maletas para llevarse un equipo clave. Al mando de la prueba de vuelo tripulada inaugural de la nave espacial Starliner de Boeing, partieron sin sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459861"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459861\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}