{"id":1459865,"date":"2025-03-13T06:04:02","date_gmt":"2025-03-13T13:04:02","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/"},"modified":"2025-03-13T06:04:02","modified_gmt":"2025-03-13T13:04:02","slug":"alimentos-automoviles-arancele-trump-acero-aluminio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/","title":{"rendered":"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio"},"content":{"rendered":"<p>Es f\u00e1cil para los estadounidenses pensar que los aranceles al aluminio y al acero del presidente Donald Trump no les afectar\u00e1n. Despu\u00e9s de todo, la mayor\u00eda no compramos metales en bruto. Sin embargo, <a href=\"https:\/\/www.cnn.com\/2025\/03\/12\/economy\/trump-steel-aluminum-tariffs-hnk-intl\/index.html\">los aranceles del 25%<\/a> implementados el mi\u00e9rcoles a\u00fan podr\u00edan afectar el bolsillo de los consumidores.<\/p>\n<p>Desde latas de comida, cerveza y refrescos hasta autom\u00f3viles y mucho m\u00e1s, el acero y el aluminio se utilizan en innumerables productos de consumo. Y gran parte de ese acero y aluminio proviene del extranjero, lo que significa que las empresas podr\u00edan repercutir el coste de los aranceles a los consumidores estadounidenses.<\/p>\n<p>Si bien todav\u00eda es demasiado pronto para que los directores ejecutivos digan exactamente c\u00f3mo las tarifas cambiar\u00e1n sus estructuras de costos y, como resultado, los precios que cobran a los clientes, varios ya han advertido que pronto podr\u00edan producirse aumentos de precios.<\/p>\n<p>Mick Beekhuizen, CEO de Campbell\u2019s Company, dijo que el fabricante de alimentos y bebidas importa acero de Canad\u00e1 para fabricar latas.<\/p>\n<p>\u201cEstamos trabajando estrechamente con nuestros proveedores para mitigar el posible impacto\u201d, declar\u00f3 en la presentaci\u00f3n de resultados de la compa\u00f1\u00eda este mes. \u201cAl mismo tiempo, dependiendo de la duraci\u00f3n y el alcance de estos aranceles, podr\u00edamos tener que tomar otras medidas\u201d. Esto, a\u00f1adi\u00f3, podr\u00eda llevar a una revisi\u00f3n de los precios de algunos de nuestros productos.<\/p>\n<p>Campell\u2019s se neg\u00f3 a compartir m\u00e1s detalles con CNN sobre c\u00f3mo los aranceles al acero y al aluminio podr\u00edan afectar los precios al consumidor.<\/p>\n<p>En algunos casos, las empresas podr\u00edan buscar alternativas al aluminio o al acero para sus envases. Por ejemplo, el CEO de Coca-Cola, James Quincey, declar\u00f3 el mes pasado que la compa\u00f1\u00eda se prepara para envasar m\u00e1s de sus productos en <a href=\"https:\/\/www.cnn.com\/2025\/03\/02\/business\/coke-aluminum-cans-tariffs\/index.html\">pl\u00e1stico y vidrio<\/a> en lugar de aluminio para evitar el aumento de los costos de los insumos si los aranceles entraran en vigor.<\/p>\n<p>Pero advirti\u00f3 que los externos podr\u00edan estar exagerando el impacto del aumento del 25% en el precio del aluminio en relaci\u00f3n con el sistema total. No es insignificante, pero no va a cambiar radicalmente un negocio multimillonario estadounidense. Aun as\u00ed, Quincey afirm\u00f3: \u00abSer\u00eda mejor no aplicar el arancel\u00bb.<\/p>\n<p>Un solo autom\u00f3vil puede contener cientos, si no miles, de kilos de acero y aluminio.<\/p>\n<p>Pero, en el futuro inmediato, los fabricantes de autom\u00f3viles pueden quedar <a href=\"https:\/\/www.cnn.com\/2025\/02\/10\/politics\/tariffs-steel-aluminum-trump\/index.html\">aislados de los aranceles<\/a> porque a menudo fijan las tarifas en contratos plurianuales.<\/p>\n<p>Por ejemplo, el director financiero de General Motors, Paul Jacobson, declar\u00f3 el mes pasado, durante la presentaci\u00f3n de resultados del fabricante de autom\u00f3viles, que una cantidad significativa del acero que obtiene, fabricado principalmente en Estados Unidos, tiene un precio relativamente fijo durante algunos a\u00f1os. Sin embargo, GM no est\u00e1 protegida de las subidas repentinas de los precios de las materias primas debido a los aranceles, afirm\u00f3. \u201cProbablemente habr\u00e1 un aumento de los costos relacionado con los precios del mercado, pero deber\u00eda disminuir con el tiempo\u201d.<\/p>\n<p>Los electrodom\u00e9sticos, como refrigeradores, sistemas de calefacci\u00f3n, ventilaci\u00f3n y aire acondicionado, lavadoras y secadoras, tambi\u00e9n requieren cantidades significativas de acero y aluminio y podr\u00edan volverse m\u00e1s caros como resultado de los aranceles.<\/p>\n<p>Roxanne Warner, vicepresidenta senior y controladora de Whirlpool, dijo recientemente que la mayor\u00eda de las materias primas de la compa\u00f1\u00eda, como el acero, tienen \u201ccontratos cerrados por un m\u00ednimo de un a\u00f1o\u201d.<\/p>\n<p>\u201cTambi\u00e9n creemos que, dado que producimos el 80% de lo que vendemos en Estados Unidos\u2026 estamos en una posici\u00f3n bastante buena (con respecto a los aranceles)\u201d, a\u00f1adi\u00f3, hablando en una conferencia de inversores de Raymond James este mes.<\/p>\n<p>Al mismo tiempo, cuando Trump impuso un arancel del 25% al \u200b\u200bacero y del 10% al aluminio en 2018, con algunas excepciones, <a href=\"https:\/\/www.cnn.com\/2018\/10\/24\/business\/whirlpool-earnings-trade\/index.html\">Whirlpool inform\u00f3<\/a> que vio aumentar los precios de las materias primas, incrementando sus costos en US$ 350 millones.<\/p>\n<p>\u201cAproximadamente el 96% del acero utilizado en nuestras f\u00e1bricas estadounidenses proviene de proveedores nacionales\u201d, declar\u00f3 un portavoz de Whirlpool a CNN en un comunicado por correo electr\u00f3nico. \u201cAun as\u00ed, entendemos que esto tendr\u00e1 consecuencias y evaluaremos el impacto general en relaci\u00f3n con las recientes decisiones comerciales de EE.UU. y cualquier acci\u00f3n futura de sus socios comerciales\u201d.<\/p>\n<p>Whirlpool no respondi\u00f3 a la pregunta de CNN sobre si la proporci\u00f3n de acero estadounidense que utiliza ha cambiado desde 2018. Tampoco especific\u00f3 la proporci\u00f3n de aluminio estadounidense utilizada en productos fabricados en Estados Unidos.<\/p>\n<p>Los sistemas de filtraci\u00f3n de agua se construyen utilizando esos metales, lo que significa que incluso el agua del grifo podr\u00eda resultar m\u00e1s cara como resultado de las tarifas.<\/p>\n<p>John Stauch, CEO de Pentair, una empresa de tratamiento de agua que fabrica equipos municipales utilizados para suministrar agua potable a hogares y empresas, dijo que la compa\u00f1\u00eda compra aluminio y acero por valor de US$ 100 millones fuera de Estados Unidos.<\/p>\n<p>Adem\u00e1s, Stauch afirm\u00f3 que Pentair compra componentes por valor de US$ 125 millones a China, donde los productos que no son de acero ni aluminio que llegan a EE.UU. ya est\u00e1n sujetos a un arancel del 20 %. En total, los aranceles vigentes les cuestan US$ 50 millones, a\u00f1adi\u00f3.<\/p>\n<p>\u201cA partir del 1 y el 15 de abril, planeamos implementar aumentos de precios en todas las empresas\u201d, dijo en una conferencia industrial de JPMorgan el martes.<\/p>\n<p>A medida que aumentan los costos de filtraci\u00f3n de agua, los proveedores podr\u00edan trasladar el precio a los consumidores cobr\u00e1ndoles tarifas m\u00e1s altas.<\/p>\n<p>\u201cSupongo que, en general, todos estamos en el mismo terreno de juego\u201d, a\u00f1adi\u00f3 Stauch, refiri\u00e9ndose a la competencia en el sector de la filtraci\u00f3n de agua. \u201cGeneralmente, lo que har\u00edamos ser\u00eda aumentar los precios de forma generalizada y, por lo tanto, esforzarnos por vender el producto con el que podamos obtener la mayor rentabilidad\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es f\u00e1cil para los estadounidenses pensar que los aranceles al aluminio y al acero del presidente Donald Trump no les afectar\u00e1n. Despu\u00e9s de todo, la mayor\u00eda no compramos metales en bruto. Sin embargo, los aranceles del 25% implementados el mi\u00e9rcoles a\u00fan podr\u00edan afectar el bolsillo de los consumidores. Desde latas de comida, cerveza y refrescos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459865","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio - Noticias\" \/>\n<meta property=\"og:description\" content=\"Es f\u00e1cil para los estadounidenses pensar que los aranceles al aluminio y al acero del presidente Donald Trump no les afectar\u00e1n. Despu\u00e9s de todo, la mayor\u00eda no compramos metales en bruto. Sin embargo, los aranceles del 25% implementados el mi\u00e9rcoles a\u00fan podr\u00edan afectar el bolsillo de los consumidores. Desde latas de comida, cerveza y refrescos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T13:04:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio\",\"datePublished\":\"2025-03-13T13:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/\"},\"wordCount\":1035,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/\",\"name\":\"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-13T13:04:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio - Noticias","og_description":"Es f\u00e1cil para los estadounidenses pensar que los aranceles al aluminio y al acero del presidente Donald Trump no les afectar\u00e1n. Despu\u00e9s de todo, la mayor\u00eda no compramos metales en bruto. Sin embargo, los aranceles del 25% implementados el mi\u00e9rcoles a\u00fan podr\u00edan afectar el bolsillo de los consumidores. Desde latas de comida, cerveza y refrescos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-13T13:04:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/"},"author":{"name":"","@id":""},"headline":"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio","datePublished":"2025-03-13T13:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/"},"wordCount":1035,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/","name":"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-13T13:04:02+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"De los alimentos a los autom\u00f3viles: qu\u00e9 podr\u00edan pagar m\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-13T13:04:02Z","datePublished":"2025-03-13T13:04:02Z","dateModified":"2025-03-13T13:04:02Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"De los alimentos a los autom\\u00f3viles: qu\\u00e9 podr\\u00edan pagar m\\u00e1s los estadounidenses por aranceles de Trump al acero y al aluminio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/13\\\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/13\\\/alimentos-automoviles-arancele-trump-acero-aluminio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-13T13:04:02Z\",\"datePublished\":\"2025-03-13T13:04:02Z\",\"dateModified\":\"2025-03-13T13:04:02Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459804,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/trump-acero-aluminio-aranceles-trax\/","url_meta":{"origin":1459865,"position":0},"title":"Trump impone amplios aranceles del 25% a todo el acero y aluminio importado en EE.UU.","author":"","date":"marzo 12, 2025","format":false,"excerpt":"El presidente Donald Trump impuso este mi\u00e9rcoles un arancel general del 25% a todas las importaciones de acero y aluminio en Estados Unidos, una medida que amenaza con hacer subir los precios de una amplia gama de bienes de consumo e industriales para los estadounidenses.Es la \u00faltima bala en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463173,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/04\/aranceles-acero-aluminio-duplica-trump-trax\/","url_meta":{"origin":1459865,"position":1},"title":"La administraci\u00f3n Trump acaba de duplicar los aranceles a las importaciones de acero y aluminio. \u00bfQu\u00e9 implica esto?","author":"","date":"junio 4, 2025","format":false,"excerpt":"Los aranceles estadounidenses sobre el acero y el aluminio se duplicaron al 50 % a las 12:01 a.m. hora de Miami de este mi\u00e9rcoles, una medida celebrada por la asediada industria sider\u00fargica estadounidense, pero preocupante para los sectores que utilizan estos metales con frecuencia, desde fabricantes de autom\u00f3viles hasta la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460736,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/02\/alcance-aranceles-trump-graficos-trax\/","url_meta":{"origin":1459865,"position":2},"title":"El alcance de los aranceles de Trump en 4 gr\u00e1ficos","author":"","date":"abril 2, 2025","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, prometi\u00f3 imponer aranceles rec\u00edprocos d\u00f3lar por d\u00f3lar a los pa\u00edses que cree que tratan a Estados Unidos de manera injusta en el comercio, ya sea a trav\u00e9s de altos aranceles o barreras no arancelarias. Ha afirmado que sus nuevos aranceles crear\u00e1n empleos y estimular\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459774,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/11\/aranceles-canada-amenaza-trump-industria-automovilistica-trax\/","url_meta":{"origin":1459865,"position":3},"title":"Trump amenaza con nuevos aranceles a Canad\u00e1 y advierte que har\u00e1 que cierre su industria automovil\u00edstica","author":"","date":"marzo 11, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, amenaz\u00f3 el martes con una fuerte escalada en la incipiente guerra comercial con Canad\u00e1 en represalia por el recargo a las exportaciones de Ontario sobre la electricidad estadounidense.Trump dijo que responder\u00eda al recargo del 25% aplicado por Ontario a la electricidad destinada a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458492,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/09\/trump-aranceles-importacion-aluminio-acero-trax\/","url_meta":{"origin":1459865,"position":4},"title":"Trump anunciar\u00e1 otro arancel para las importaciones de acero y aluminio; posible impacto para Canad\u00e1 y M\u00e9xico","author":"","date":"febrero 9, 2025","format":false,"excerpt":"El presidente de EE.UU. Donald Trump, hablando con los periodistas en el Air Force One el domingo, dijo que planeaba anunciar un arancel del 25% sobre todas las importaciones de acero y aluminio a Estados Unidos el lunes.\u201cTambi\u00e9n anunciaremos aranceles al acero el lunes\u201d, dijo, y agreg\u00f3, \u201ccualquier acero que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459833,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/eeuu-aranceles-reciprocos-aluminio-acero-sheinbaum-2-abril-orix\/","url_meta":{"origin":1459865,"position":5},"title":"M\u00e9xico decidir\u00e1 a partir del 2 de abril si impone a EE.UU. aranceles rec\u00edprocos al aluminio y al acero, dice Sheinbaum","author":"","date":"marzo 12, 2025","format":false,"excerpt":"La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este mi\u00e9rcoles que el pa\u00eds esperar\u00e1 al 2 de abril para decidir si impone aranceles rec\u00edprocos a las importaciones de acero y aluminio.Al confirmar que este d\u00eda entraron en vigor los aranceles de 25% impuestos por el Gobierno de Donald Trump a todas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459865"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459865\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}