{"id":1459887,"date":"2025-03-13T13:03:44","date_gmt":"2025-03-13T20:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/"},"modified":"2025-03-13T13:03:44","modified_gmt":"2025-03-13T20:03:44","slug":"ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/","title":{"rendered":"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump"},"content":{"rendered":"<p>Un mes antes de la segunda vuelta electoral en Ecuador y a pocos d\u00edas del debate presidencial obligatorio, el Gobierno del presidente Daniel Noboa \u2015quien compite para permanecer en el cargo\u2015 contrat\u00f3 a una empresa para acercarse y reforzar el contacto con representantes de la administraci\u00f3n del presidente de Estados Unidos, Donald Trump.<\/p>\n<p>El Ministerio de Relaciones Exteriores del pa\u00eds sudamericano, golpeado por una grave crisis de violencia criminal, inform\u00f3 este jueves en un comunicado que contrat\u00f3 una firma de \u201casesor\u00eda y cabildeo\u201d con el fin de \u201cfomentar una relaci\u00f3n constructiva y de colaboraci\u00f3n con la administraci\u00f3n del presidente Trump\u201d.<\/p>\n<p>El Gobierno asegura que escogi\u00f3 a la empresa Mercury Public Affairs LLC, que se presenta en su p\u00e1gina web como una \u201cfirma p\u00fablica de alto riesgo\u201d y de car\u00e1cter bipartidista, as\u00ed como que tiene experiencia en relaciones gubernamentales y capacidades para extender contactos con instituciones estadounidenses oficiales.<\/p>\n<p>\u201cEmpleamos estrategias t\u00e1cticas neutrales que abarcan comunicaciones estrat\u00e9gicas, movilizaci\u00f3n de base, encuestas y cabildeo estatal, disponibles en nuestras 13 oficinas\u201d, agrega la firma en su sitio oficial.<\/p>\n<p>CNN solicit\u00f3 este jueves a la empresa m\u00e1s informaci\u00f3n sobre los alcances del contrato y est\u00e1 a la espera de respuesta.<\/p>\n<p>La Canciller\u00eda sostiene que contrat\u00f3 a la empresa mediante un \u201cproceso de licitaci\u00f3n competitivo\u201d, lo cual se\u00f1al\u00f3 como una \u201cpr\u00e1ctica corriente de gobiernos pasados\u201d. Considera que la firma result\u00f3 ser \u201cla mejor, m\u00e1s rentable y beneficiosa para el Estado\u201d.<\/p>\n<p>\u201cConstituye una herramienta adicional al servicio de las embajadas para avanzar sus intereses ante el Congreso, el Ejecutivo, los medios de prensa y los centros de estudios (de EE.UU.)\u201d, precis\u00f3.<\/p>\n<p>CNN consult\u00f3 a la Contralor\u00eda General de Ecuador si analizar\u00e1 los t\u00e9rminos y alcances de este contrato, que \u2015seg\u00fan la Canciller\u00eda\u2015 recoge recomendaciones que la Contralor\u00eda realiz\u00f3 en el pasado para este tipo de operaciones. La Contralor\u00eda respondi\u00f3 a CNN que realizar\u00e1 las consultas respectivas.<\/p>\n<p>CNN solicit\u00f3 a la Embajada de Ecuador en Estados Unidos m\u00e1s informaci\u00f3n sobre el contrato y cu\u00e1les son los objetivos formales encomendados a la firma estadounidense para lograr acercamientos con la administraci\u00f3n Trump.<\/p>\n<p>El presidente Daniel Noboa ha solicitado p\u00fablicamente desde hace varios meses mayor apoyo de la comunidad internacional para combatir al crimen organizado transnacional que ha sembrado ra\u00edces en varias zonas del pa\u00eds.<\/p>\n<p>Noboa se quej\u00f3 en junio \u2014en una entrevista con la revista estadounidense The New Yorker\u2015 de que Estados Unidos no apoye con m\u00e1s recursos a esta lucha; mientras, el Departamento de Estado de EE.UU. dijo entonces a CNN que desde 2018 aportan a Ecuador US$ 278 millones para contribuir financieramente en seguridad y defensa, as\u00ed como asesoramiento de expertos, intercambios y capacitaciones para el desarrollo de capacidades, donaciones de suministros e intercambio de informaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un mes antes de la segunda vuelta electoral en Ecuador y a pocos d\u00edas del debate presidencial obligatorio, el Gobierno del presidente Daniel Noboa \u2015quien compite para permanecer en el cargo\u2015 contrat\u00f3 a una empresa para acercarse y reforzar el contacto con representantes de la administraci\u00f3n del presidente de Estados Unidos, Donald Trump. El Ministerio [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459887","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un mes antes de la segunda vuelta electoral en Ecuador y a pocos d\u00edas del debate presidencial obligatorio, el Gobierno del presidente Daniel Noboa \u2015quien compite para permanecer en el cargo\u2015 contrat\u00f3 a una empresa para acercarse y reforzar el contacto con representantes de la administraci\u00f3n del presidente de Estados Unidos, Donald Trump. El Ministerio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-13T20:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump\",\"datePublished\":\"2025-03-13T20:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/\"},\"wordCount\":516,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/\",\"name\":\"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-13T20:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump - Noticias","og_description":"Un mes antes de la segunda vuelta electoral en Ecuador y a pocos d\u00edas del debate presidencial obligatorio, el Gobierno del presidente Daniel Noboa \u2015quien compite para permanecer en el cargo\u2015 contrat\u00f3 a una empresa para acercarse y reforzar el contacto con representantes de la administraci\u00f3n del presidente de Estados Unidos, Donald Trump. El Ministerio [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-13T20:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/"},"author":{"name":"","@id":""},"headline":"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump","datePublished":"2025-03-13T20:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/"},"wordCount":516,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/","name":"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-13T20:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\u00eda para acercarse a la administraci\u00f3n Trump","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/13\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-13T20:03:44Z","datePublished":"2025-03-13T20:03:44Z","dateModified":"2025-03-13T20:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Gobierno de Ecuador contrata empresa de cabildeo y asesor\\u00eda para acercarse a la administraci\\u00f3n Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/13\\\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/13\\\/ecuador-empresa-de-cabilde-asesoria-acercarse-trump-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-13T20:03:44Z\",\"datePublished\":\"2025-03-13T20:03:44Z\",\"dateModified\":\"2025-03-13T20:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460553,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/28\/daniel-noboa-reunira-donald-trump-orix\/","url_meta":{"origin":1459887,"position":0},"title":"El presidente de Ecuador, Daniel Noboa, se reunir\u00e1 con Donald Trump este s\u00e1bado en Florida","author":"","date":"marzo 28, 2025","format":false,"excerpt":"El presidente Donald Trump se reunir\u00e1 con su par de Ecuador, Daniel Noboa, este fin de semana en Florida, seg\u00fan inform\u00f3 la Casa Blanca a CNN.Se espera que ambos l\u00edderes se re\u00fanan el s\u00e1bado en Mar-a-Lago.Seg\u00fan un funcionario de la Casa Blanca, el presidente latinoamericano tambi\u00e9n podr\u00eda jugar golf con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460599,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/29\/ecuador-noboa-trump-encuentro-amistoso-orix\/","url_meta":{"origin":1459887,"position":1},"title":"Noboa y Trump sostienen encuentro &#171;amistoso y privado&#187;, dice el Gobierno de Ecuador","author":"","date":"marzo 29, 2025","format":false,"excerpt":"Los presidentes de Ecuador, Daniel Noboa, y de Estados Unidos, Donald Trump, se reunieron este s\u00e1bado en Florida en un encuentro \u201camistoso y privado\u201d, dijo el Gobierno de Ecuador en un breve comunicado.El Gobierno de Ecuador agreg\u00f3 que durante la pr\u00f3xima semana dar\u00e1 m\u00e1s informaci\u00f3n sobre la reuni\u00f3n, de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470653,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/01\/30\/noboa-trump-aliado-relacion-petro-colombia-eeuu-orix\/","url_meta":{"origin":1459887,"position":2},"title":"Daniel Noboa es uno de los mayores aliados de Trump en la regi\u00f3n, pero esa relaci\u00f3n es cada vez m\u00e1s un arma de doble filo","author":"","date":"enero 30, 2026","format":false,"excerpt":"Pocos d\u00edas antes de la reuni\u00f3n prevista en Washington entre el presidente de Colombia, Gustavo Petro, y el mandatario estadounidense, Donald Trump, un tercer actor pol\u00edtico entr\u00f3 en escena de manera sorpresiva para arremeter con dureza en contra de Petro y su Gobierno. Se trata del presidente de Ecuador, Daniel\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472387,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/20\/noboa-reafirma-alianza-ee-uu-defiende-vinculo-china-orix\/","url_meta":{"origin":1459887,"position":3},"title":"Noboa reafirma su alianza con EE.UU. pero defiende el v\u00ednculo con China: &#171;No puedo pelearme con mi segundo socio comercial&#187;","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Ecuador busca mantener el equilibrio entre seguridad y comercio, y oscila entre sus dos socios principales en esos temas: Estados Unidos y China.El presidente de Ecuador, Daniel Noboa, asegur\u00f3 este viernes que est\u00e1 alineado al Gobierno del presidente Donald Trump para combatir la criminalidad en su pa\u00eds, pero descarta que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459797,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/11\/campo-sacha-petroleo-ecuador-orix\/","url_meta":{"origin":1459887,"position":4},"title":"Campo Sacha, la &#171;joya de la corona&#187; del petr\u00f3leo de Ecuador. \u00bfPor qu\u00e9 es tan importante?","author":"","date":"marzo 11, 2025","format":false,"excerpt":"El petr\u00f3leo de la m\u00e1s alta calidad en Ecuador se encuentra en el Campo Sacha, ubicado en la provincia de Orellana, en el coraz\u00f3n de la Amazon\u00eda de este pa\u00eds sudamericano. Sacha o Bloque 60 cuenta tambi\u00e9n con las reservas nacionales m\u00e1s importantes y es operado por la empresa estatal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458366,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/06\/abogados-contrato-canal-panama-empresa-hong-kong-orix\/","url_meta":{"origin":1459887,"position":5},"title":"Abogados solicitan revocar contrato en el canal de Panam\u00e1 otorgado a empresa vinculada a conglomerado de Hong Kong","author":"","date":"febrero 6, 2025","format":false,"excerpt":"Dos abogados paname\u00f1os solicitaron a la Corte Suprema de Justicia revocar un contrato a una empresa vinculada a un conglomerado con sede en Hong Kong que opera dos terminales portuarias en ambos lados del canal de Panam\u00e1. La petici\u00f3n surge justo cuando Estados Unidos afirma que hay control chino en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459887"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459887\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}