{"id":1459921,"date":"2025-03-14T06:03:37","date_gmt":"2025-03-14T13:03:37","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/"},"modified":"2025-03-14T06:03:37","modified_gmt":"2025-03-14T13:03:37","slug":"enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/","title":{"rendered":"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente"},"content":{"rendered":"<p>Estados Unidos present\u00f3 una nueva propuesta que garantizar\u00eda la liberaci\u00f3n de un pu\u00f1ado de rehenes vivos en manos de Hamas a cambio de una pr\u00f3rroga de un mes del alto el fuego entre Israel y Hamas, inform\u00f3 una fuente familiarizada con las negociaciones.<\/p>\n<p>El n\u00famero exacto de rehenes vivos y muertos que deber\u00e1 liberar Hamas durante la pr\u00f3rroga del alto el fuego, as\u00ed como el n\u00famero de prisioneros palestinos que deber\u00e1 excarcelar Israel, siguen siendo objeto de negociaci\u00f3n, dijo la fuente.<\/p>\n<p>Seg\u00fan la propuesta de EE.UU., presentada esta semana en Qatar por el enviado especial estadounidense para Medio Oriente, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/13\/mundo\/rusia-duda-alto-fuego-eeuu-ucrania-trax\">Steve Witkoff<\/a>, Israel tambi\u00e9n levantar\u00eda el <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/06\/mundo\/atacando-comida-habitantes-gaza-nuevo-bloqueo-ayuda-israeli-trax\">bloqueo<\/a> de la ayuda humanitaria a Gaza, que lleva casi dos semanas en vigor, a\u00f1adi\u00f3 la fuente.<\/p>\n<p>La pr\u00f3rroga del alto el fuego se extender\u00eda hasta el final de la Pascua jud\u00eda, con lo que se prolongar\u00eda la pausa en los combates y se renovar\u00eda la entrada de ayuda humanitaria durante el mes sagrado musulm\u00e1n del Ramad\u00e1n y la festividad jud\u00eda.<\/p>\n<p>Preguntado por la propuesta, un portavoz del Departamento de Estado de EE.UU. dijo que no har\u00edan comentarios sobre las negociaciones en curso.<\/p>\n<p>Cuando se le pidi\u00f3 que comentara los informes sobre el progreso de las negociaciones, el portavoz de Hamas, Basem Naim, dijo: \u201cLas cosas est\u00e1n estancadas\u201d.<\/p>\n<p>La oficina del primer ministro de Israel no respondi\u00f3 a la petici\u00f3n de comentarios de CNN.<\/p>\n<p>La m\u00e1s reciente propuesta estadounidense supuso una reducci\u00f3n respecto a su propuesta anterior en el n\u00famero de rehenes que deb\u00eda liberar Hamas durante el mismo periodo, lo que provoc\u00f3 la r\u00e1pida preocupaci\u00f3n de las familias de los rehenes.<\/p>\n<p>\u201cLas publicaciones sobre el esbozo para la devoluci\u00f3n de solo unos pocos rehenes suscitan una gran preocupaci\u00f3n entre las familias de los rehenes, que temen que sus seres queridos permanezcan en cautiverio durante un periodo largo y desconocido\u201d, declar\u00f3 en un comunicado el Foro de Familias de Rehenes y Desaparecidos.<\/p>\n<p>\u201cExigimos un acuerdo exhaustivo e inmediato que devuelva a los 59 rehenes de una sola vez y no deje a nadie atr\u00e1s\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Se cree que menos de la mitad de los 59 rehenes que siguen retenidos en <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/12\/mundo\/israel-civiles-escudos-humanos-gaza-investigacion-trax\">Gaza<\/a> siguen con vida.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos present\u00f3 una nueva propuesta que garantizar\u00eda la liberaci\u00f3n de un pu\u00f1ado de rehenes vivos en manos de Hamas a cambio de una pr\u00f3rroga de un mes del alto el fuego entre Israel y Hamas, inform\u00f3 una fuente familiarizada con las negociaciones. El n\u00famero exacto de rehenes vivos y muertos que deber\u00e1 liberar Hamas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459921","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente - Noticias\" \/>\n<meta property=\"og:description\" content=\"Estados Unidos present\u00f3 una nueva propuesta que garantizar\u00eda la liberaci\u00f3n de un pu\u00f1ado de rehenes vivos en manos de Hamas a cambio de una pr\u00f3rroga de un mes del alto el fuego entre Israel y Hamas, inform\u00f3 una fuente familiarizada con las negociaciones. El n\u00famero exacto de rehenes vivos y muertos que deber\u00e1 liberar Hamas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T13:03:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente\",\"datePublished\":\"2025-03-14T13:03:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/\",\"name\":\"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-14T13:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente - Noticias","og_description":"Estados Unidos present\u00f3 una nueva propuesta que garantizar\u00eda la liberaci\u00f3n de un pu\u00f1ado de rehenes vivos en manos de Hamas a cambio de una pr\u00f3rroga de un mes del alto el fuego entre Israel y Hamas, inform\u00f3 una fuente familiarizada con las negociaciones. El n\u00famero exacto de rehenes vivos y muertos que deber\u00e1 liberar Hamas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-14T13:03:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/"},"author":{"name":"","@id":""},"headline":"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente","datePublished":"2025-03-14T13:03:37+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/","name":"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-14T13:03:37+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-14T13:03:37Z","datePublished":"2025-03-14T13:03:37Z","dateModified":"2025-03-14T13:03:37Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El enviado de EE.UU. presenta a Israel y Hamas una nueva propuesta para extender el alto el fuego en Gaza, dice una fuente\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/14\\\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/14\\\/enviado-israel-hamas-nueva-propuesta-extender-alto-fuego-gaza-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-14T13:03:37Z\",\"datePublished\":\"2025-03-14T13:03:37Z\",\"dateModified\":\"2025-03-14T13:03:37Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459375,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/01\/israel-prorroga-cese-ramadan-pascua-trax\/","url_meta":{"origin":1459921,"position":0},"title":"Israel dice que respalda la pr\u00f3rroga temporal del alto el fuego propuesta por EE.UU. durante el Ramad\u00e1n y la Pascua jud\u00eda","author":"","date":"marzo 1, 2025","format":false,"excerpt":"La oficina del primer ministro de Israel, Benjamin Netanyahu, anunci\u00f3 este domingo, hora local, que Israel respalda una propuesta estadounidense para prorrogar temporalmente el actual alto el fuego durante el mes sagrado isl\u00e1mico del Ramad\u00e1n y la festividad de la Pascua jud\u00eda.Seg\u00fan el proyecto, la pr\u00f3rroga del alto el fuego\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460585,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/29\/hamas-acepta-propuesta-alto-el-fuego-egipto-israel-trax\/","url_meta":{"origin":1459921,"position":1},"title":"Hamas acepta la propuesta de alto el fuego de Egipto, pero Israel responde con una contrapropuesta","author":"","date":"marzo 29, 2025","format":false,"excerpt":"Hamas acept\u00f3 una nueva propuesta de Egipto para liberar a cinco rehenes, incluido el estadounidense israel\u00ed Edan Alexander, a cambio de un alto el fuego renovado, seg\u00fan una fuente de Hamas que habl\u00f3 con CNN.La propuesta es similar a la presentada hace varias semanas por el enviado especial de EE.UU.,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459386,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/02\/israel-detiene-ayuda-humanitaria-gaza-acuerdo-trax\/","url_meta":{"origin":1459921,"position":2},"title":"Israel detiene el ingreso de ayuda humanitaria a Gaza","author":"","date":"marzo 2, 2025","format":false,"excerpt":"Israel inform\u00f3 que detuvo la entrada de toda ayuda humanitaria en Gaza tras el fin de la primera fase del acuerdo de alto el fuego y la negativa de Hamas a una pr\u00f3rroga respaldada por Estados Unidos.\u201cCon la finalizaci\u00f3n de la fase A del acuerdo de rehenes, y ante la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460779,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/03\/hamas-contrapropuesta-alto-el-fuego-trax\/","url_meta":{"origin":1459921,"position":3},"title":"Hamas rechaza la contrapropuesta israel\u00ed de alto el fuego","author":"","date":"abril 3, 2025","format":false,"excerpt":"Hamas rechaz\u00f3 la \u00faltima propuesta de Israel de un alto el fuego temporal en Gaza, que habr\u00eda supuesto una tregua de 40 d\u00edas a cambio de la liberaci\u00f3n de 11 rehenes.Una fuente de alto rango de Hamas, que habl\u00f3 con CNN bajo condici\u00f3n de anonimato, confirm\u00f3 a CNN que el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464231,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/07\/04\/hamas-respuesta-positiva-propuesta-alto-el-fuego-gaza-trax\/","url_meta":{"origin":1459921,"position":4},"title":"Hamas da una &#171;respuesta positiva&#187; a la propuesta de alto el fuego en un paso clave hacia un acuerdo","author":"","date":"julio 4, 2025","format":false,"excerpt":"Hamas anunci\u00f3 este viernes que ha \u201cpresentado una respuesta positiva\u201d a una propuesta para un alto el fuego de 60 d\u00edas en Gaza, abriendo el camino hacia un acuerdo para detener el conflicto tras meses de esfuerzos fallidos.\u201cHamas ha presentado una respuesta positiva a los mediadores, y el movimiento est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462815,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/26\/enviado-ee-uu-acuerdo-alto-el-fuego-hamas-acepte-trax\/","url_meta":{"origin":1459921,"position":5},"title":"Enviado de EE.UU. dice que hay un acuerdo de alto el fuego sobre la mesa y pide a Hamas que lo acepte","author":"","date":"mayo 26, 2025","format":false,"excerpt":"El enviado especial de EE.UU., Steve Witkoff, dijo a CNN que actualmente hay sobre la mesa un acuerdo de alto el fuego e intercambio de rehenes para Gaza, con una v\u00eda para poner fin a la guerra, e inst\u00f3 a Hamas a aceptarlo.La propuesta prev\u00e9 la liberaci\u00f3n de la mitad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459921"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459921\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}