{"id":1459930,"date":"2025-03-14T09:03:47","date_gmt":"2025-03-14T16:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/"},"modified":"2025-03-14T09:03:47","modified_gmt":"2025-03-14T16:03:47","slug":"jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/","title":{"rendered":"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: &#171;Los polic\u00edas son seres humanos y en un punto les duele&#187;"},"content":{"rendered":"<p><strong>J\u00e9sica Ponce, docente de la Escuela Social Cura Brochero de Villa 21\/24 Zavaleta<\/strong>, habl\u00f3 este viernes en CNN Radio luego de pariticpar de la marcha los jubilados que termin\u00f3 con represi\u00f3n policial y tras convertirse en protagonista de un viral que circul\u00f3 en las redes sociales.<\/p>\n<p>\u201cEst\u00e1bamos sobre Rivadavia y habia solo una linea de policias, por detr\u00e1s estaban reprimiendo muy fuerte. En un momento, avanzaron y la gente tuvo que retroceder para llegar a la bocacalle de Rivadavia y en ese momento avanza el cami\u00f3n desalojando sin nig\u00fan sentido\u201d, relat\u00f3 la docente en di\u00e1logo con <strong>Nacho Gir\u00f3n en La Ma\u00f1ana de CNN.<\/strong><\/p>\n<p>Y expres\u00f3: \u201cNadie estaba prendiendo fuego nada. Hubo algunos que tiraban cosas, pero tampoco es negativo porque con algo hab\u00eda que defenderse. Pero en ese momento que avanzaron nadie estaba ni siquiera empujando o escupiendo. Solo se cantaba\u201d.<\/p>\n<p>Por eso, Ponce reiter\u00f3 que \u201cla polic\u00eda avanz\u00f3 antes de que alguien hiciera algo\u201d, en tanto que remarc\u00f3 que \u201cHoy la polic\u00eda es parte de la vulneraci\u00f3n social\u201d.<\/p>\n<p>\u201cTrat\u00e1bamos de acompa\u00f1ar a los adultos mayores, pero los que son primera linea todos los mi\u00e9rcoles son los jubilados que est\u00e1 todos los mi\u00e9rcoles grit\u00e1ndole a un gobierno y a un Congreso que no los escucha\u201d, opin\u00f3, y aclar\u00f3: \u201cFui a la marcha por decisi\u00f3n propia: la lucha de los jubilados es legitima\u201d.<\/p>\n<p>Finalmente, sobre sobre la Escuela Social Cura Brochero, indic\u00f3: \u201cEstamos haciendo una colecta de libros y \u00fatiles para los chicos\u201d. \u201cNuestro alias es escuela.brochero y el Instagram es @escuelaprimariacurabrochero\u201d, cerr\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e9sica Ponce, docente de la Escuela Social Cura Brochero de Villa 21\/24 Zavaleta, habl\u00f3 este viernes en CNN Radio luego de pariticpar de la marcha los jubilados que termin\u00f3 con represi\u00f3n policial y tras convertirse en protagonista de un viral que circul\u00f3 en las redes sociales. \u201cEst\u00e1bamos sobre Rivadavia y habia solo una linea de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459930","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: &quot;Los polic\u00edas son seres humanos y en un punto les duele&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: &quot;Los polic\u00edas son seres humanos y en un punto les duele&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"J\u00e9sica Ponce, docente de la Escuela Social Cura Brochero de Villa 21\/24 Zavaleta, habl\u00f3 este viernes en CNN Radio luego de pariticpar de la marcha los jubilados que termin\u00f3 con represi\u00f3n policial y tras convertirse en protagonista de un viral que circul\u00f3 en las redes sociales. \u201cEst\u00e1bamos sobre Rivadavia y habia solo una linea de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T16:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: &#171;Los polic\u00edas son seres humanos y en un punto les duele&#187;\",\"datePublished\":\"2025-03-14T16:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/\",\"name\":\"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: \\\"Los polic\u00edas son seres humanos y en un punto les duele\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-14T16:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: &#171;Los polic\u00edas son seres humanos y en un punto les duele&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: \"Los polic\u00edas son seres humanos y en un punto les duele\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/","og_locale":"es_ES","og_type":"article","og_title":"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: \"Los polic\u00edas son seres humanos y en un punto les duele\" - Noticias","og_description":"J\u00e9sica Ponce, docente de la Escuela Social Cura Brochero de Villa 21\/24 Zavaleta, habl\u00f3 este viernes en CNN Radio luego de pariticpar de la marcha los jubilados que termin\u00f3 con represi\u00f3n policial y tras convertirse en protagonista de un viral que circul\u00f3 en las redes sociales. \u201cEst\u00e1bamos sobre Rivadavia y habia solo una linea de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/","og_site_name":"Noticias","article_published_time":"2025-03-14T16:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/"},"author":{"name":"","@id":""},"headline":"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: &#171;Los polic\u00edas son seres humanos y en un punto les duele&#187;","datePublished":"2025-03-14T16:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/","url":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/","name":"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: \"Los polic\u00edas son seres humanos y en un punto les duele\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-14T16:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: &#171;Los polic\u00edas son seres humanos y en un punto les duele&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"J\u00e9sica Ponce, la docente que se volvi\u00f3 viral en la marcha: &#171;Los polic\u00edas son seres humanos y en un punto les duele&#187;","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-14T16:03:47Z","datePublished":"2025-03-14T16:03:47Z","dateModified":"2025-03-14T16:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"J\\u00e9sica Ponce, la docente que se volvi\\u00f3 viral en la marcha: &#171;Los polic\\u00edas son seres humanos y en un punto les duele&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/14\\\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/14\\\/jesica-ponce-la-docente-que-se-volvio-viral-en-la-marcha-los-policias-son-seres-humanos-y-en-un-punto-les-duele\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-14T16:03:47Z\",\"datePublished\":\"2025-03-14T16:03:47Z\",\"dateModified\":\"2025-03-14T16:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458925,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/19\/piccirillo-el-marido-de-jesica-cirio-cada-vez-mas-complicado-lo-senalan-por-armar-una-causa-falsa-para-evitar-una-deuda\/","url_meta":{"origin":1459930,"position":0},"title":"Piccirillo, el marido de J\u00e9sica Cirio, cada vez m\u00e1s complicado: lo se\u00f1alan por armar una causa falsa para evitar una deuda","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Carlos Pousa, abogado de Francisco Hauque, habl\u00f3 este mi\u00e9rcoles en CNN Radio sobre el caso que tiene como principal acusado a El\u00edas Piccirillo, el marido de J\u00e9sica Cirio, por haber inventado presuntamente una causa para evitar pagar una deuda millonaria: \u201cA mi cliente le plantaron droga y un arma y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460331,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/24\/el-abogado-del-exmarido-de-jesica-cirio-afirmo-que-no-hay-pruebas-directas-contra-elias-piccirillo\/","url_meta":{"origin":1459930,"position":1},"title":"El abogado del exmarido de Jesica Cirio afirm\u00f3 que &#171;no hay pruebas directas contra El\u00edas Piccirillo&#187;","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Fernando Sicilia, abogado de El\u00edas Piccirillo, exmarido de Jesica Cirio, detall\u00f3 la causa por la que se encuentra detenido su defendido.En CNN Primera Ma\u00f1ana, explic\u00f3 que \u201cest\u00e1 detenidos, presentamos la excarcelaci\u00f3n, que fue rechazada, apelamos y estamos a la espera de que la c\u00e1mara nos de una buena noticia. El\u00edas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461230,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/15\/cada-vez-la-situacion-de-cirio-es-mas-comprometida-avanza-la-causa-contra-piccirillo\/","url_meta":{"origin":1459930,"position":2},"title":"&#171;Cada vez la situaci\u00f3n de Cirio es m\u00e1s comprometida&#187;: avanza la causa contra Piccirillo","author":"","date":"abril 15, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Carlos Pousa, abogado de Francisco Hauque, v\u00edctima de El\u00edas Piccirillo, habl\u00f3 este martes en Los Primeros de la Tarde con P\u00eda Shaw y Nacho Juliano sobre la causa que investiga al esposo de J\u00e9sica Cirio por presuntamente haber inventado una denuncia para evitar pagar una deuda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463209,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/04\/detienen-miguel-pantoja-alias-pajarraco-vinculado-43-ayotzinapa-orix\/","url_meta":{"origin":1459930,"position":3},"title":"Detienen a Juan Miguel Pantoja, alias &#171;Pajarraco&#187;, presuntamente vinculado con desaparici\u00f3n de los estudiantes de Ayotzinapa","author":"","date":"junio 4, 2025","format":false,"excerpt":"El gabinete de Seguridad de M\u00e9xico inform\u00f3 el arresto de Juan Miguel Pantoja Miranda, alias \u201cPajarraco\u201d, por delitos de delincuencia organizada y desaparici\u00f3n forzada en relaci\u00f3n con las investigaciones de la desaparici\u00f3n de los 43 estudiantes de Ayotzinapa, Guerrero, en 2014.En un comunicado difundido este mi\u00e9rcoles, se detall\u00f3 que se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452004,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/20\/enjuiciaran-natanael-cano-mexico-soborno-orix\/","url_meta":{"origin":1459930,"position":4},"title":"Enjuiciar\u00e1n al cantante Natanael Cano en M\u00e9xico por cargos de soborno","author":"","date":"agosto 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El cantante mexicano Natanael Cano deber\u00e1 enfrentar un juicio tras haber sido acusado de cohecho por el presunto intento de sobornar a varios polic\u00edas que lo hab\u00edan detenido por conducir con exceso de velocidad, dijo la Fiscal\u00eda de Sonora citando la decisi\u00f3n de un juez este lunes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460317,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/23\/gustavo-montanini-nos-parecio-que-teniamos-que-tener-un-primer-proyecto-interesante-vinculado-con-esas-nuevas-tecnologias\/","url_meta":{"origin":1459930,"position":5},"title":"Gustavo Montanini: &#171;Nos pareci\u00f3 que ten\u00edamos que tener un primer proyecto interesante vinculado con esas nuevas tecnolog\u00edas&#187;","author":"","date":"marzo 23, 2025","format":false,"excerpt":"Gustavo Montanini, secretario acad\u00e9mico de la Facultad de Ciencias Econ\u00f3micas, habl\u00f3 este domingo con CNN Radio sobre los nuevos chatbots para brindar apoyo a los estudiantes.En Mundo UBA con Ricardo Braginski indic\u00f3: \u201cEl proyecto surgi\u00f3 fundamentalmente porque muchos profesores se acercaron a la Secretar\u00eda, a la subsecretar\u00eda, hablando del tema\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459930"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459930\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}