{"id":1459951,"date":"2025-03-14T18:03:53","date_gmt":"2025-03-15T01:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/"},"modified":"2025-03-14T18:03:53","modified_gmt":"2025-03-15T01:03:53","slug":"opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/","title":{"rendered":"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba"},"content":{"rendered":"<p>Silvio Rodr\u00edguez, gran cantor y poeta, acaba de publicar en su blog <a href=\"https:\/\/segundacita.blogspot.com\/2025\/03\/otro-ojala.html\">Segunda Cita<\/a> una nota sobre la cr\u00edtica situaci\u00f3n en Cuba. No es la primera. Esta vez, en 243 palabras, se refiri\u00f3 a la \u201cdignidad nacional\u201d de la isla.<\/p>\n<p>\u201cDistintas se\u00f1ales sugieren que est\u00e1 ocurriendo una especie de desaparici\u00f3n paulatina del sentido de dignidad nacional\u201d, escribe Silvio. \u201cLo siento en hechos ciudadanos del d\u00eda a d\u00eda\u201d. El cantautor cubano se\u00f1ala que el rumbo tomado en Washington y los cambios en su pol\u00edtica exterior \u201char\u00e1n m\u00e1s da\u00f1o\u201d a Cuba. Es una \u201cnueva revuelta mundial\u201d, que se suma \u201ca la involuci\u00f3n que (\u2026) venimos experimentando por nuestra propia cuenta\u201d, completa.<\/p>\n<p>No es la primera vez que Rodr\u00edguez se refiere a las duras situaciones por las que atraviesa su pa\u00eds. Usualmente es aplaudido o criticado ferozmente por quienes no le perdonan haber sido sincero al apoyar a la Revoluci\u00f3n Cubana, como es ahora al expresar sus cr\u00edticas. Pero esta vez ha tenido una <a href=\"https:\/\/www.cibercuba.com\/noticias\/2025-03-11-u207888-e207888-s27061-nid298639-jefa-prensa-diaz-canel-responde-silvio-defiende\">respuesta<\/a> \u2014al parecer oficiosa\u2014 del Gobierno cubano, que ha provocado tambi\u00e9n cierto revuelo. La firma Leticia Mart\u00ednez, jefe del equipo de prensa de comunicaci\u00f3n de la Presidencia, publicada en<a href=\"https:\/\/warnermedia-my.sharepoint.com\/personal\/alfredo_meza_cnn_com\/Documents\/Attachments\/Davila%20marzo%202025.docx#_msocom_1\">%5BDR1%5D<\/a> <a href=\"https:\/\/warnermedia-my.sharepoint.com\/personal\/alfredo_meza_cnn_com\/Documents\/Attachments\/Davila%20marzo%202025.docx#_msocom_2\">%5BMA2%5D<\/a> su p\u00e1gina personal de Facebook.<\/p>\n<p>No hay que asustarse por las pol\u00e9micas.  Mart\u00ednez debi\u00f3 haberla publicado en Cubadebate y haber mencionado directamente a Silvio. Menos susto, m\u00e1s alegr\u00eda. \u00bfNo decimos que la libertad de opiniones es fundamental? No hay problema, adelante la pol\u00e9mica.<\/p>\n<p>La cr\u00edtica de Rodr\u00edguez obedeci\u00f3 a la lujosa cena celebrada en el Sal\u00f3n de los Pasos Perdidos del Capitolio Nacional, con motivo del Festival del Habano 2025. Fue una selecta reuni\u00f3n de gente del comercio y millonarios donde, de acuerdo con los reportes de las publicaciones especializadas, <a href=\"https:\/\/www.cigaraficionado.com\/article\/behike-breaks-record-humidor-sells-for-nearly-5-million-in-cuba\">un humidificador Behike se vendi\u00f3 en US$ 4,8 millones<\/a>, repleto de habanos. La venta total de estos artefactos (que conservan la humedad perfecta), <a href=\"https:\/\/es.halfwheel.com\/festival-del-habano-xxv-the-humidor-auction\/447802\/\">alcanz\u00f3 casi US$ 17 millones<\/a>. Pero la joya de la velada fue la presentaci\u00f3n, por primera vez, del Cohiba Behike BHK 58.<\/p>\n<p>Seg\u00fan la revista Cigar Aficionado, que cubri\u00f3 la gala, cuando los 1.400 invitados entraron al espectacular sal\u00f3n recibieron su primer habano, un Cohiba Medio Siglo, el \u00fanico que no ser\u00eda un Behike. Al finalizar cada plato de la cena, elegantes camareros recorrieron la sala con bandejas llenas de habanos. As\u00ed distribuyeron toda la l\u00ednea Cohiba Behike BHK. Primero el Behike BHK 52. Luego el 54, despu\u00e9s el BHK 56 y finalmente lleg\u00f3 la estrella de la noche: el Cohiba Behike BHK 58, para encenderlo y degustarlo. Mil bocanadas de placer al mismo tiempo llenaron el l\u00edmpido espacio del Capitolio Nacional. Toda una noche de placer y de lujo.<\/p>\n<p>Eso fue lo que provoc\u00f3 la cr\u00edtica del cantautor. Las calles de La Habana, las mesas de los hogares, las bocanadas de humo nunca son tan espl\u00e9ndidas en el resto del pa\u00eds. Habl\u00f3 de la involuci\u00f3n de la dignidad nacional, de \u201cla carnavalizaci\u00f3n de la estatua de la naci\u00f3n y la tumba del mamb\u00ed desconocido\u201d muy cerca de la gran gala.<\/p>\n<p>La \u201cdignidad nacional\u201d fue uno de los flam\u00edgeros estandartes de la Revoluci\u00f3n Cubana, cuando la gritaba a los cuatro vientos. Ahora el trovador se pregunta qu\u00e9 pas\u00f3. Silvio, admirado amigo, sencillamente es el tiempo que pas\u00f3. Eres el gran referente moral de esta Cuba que padece grandes penurias, impensables cuando desde La Habana se hablaba del futuro. Ahora, Cuba apenas puede hablar de lo que pasar\u00e1 pasado ma\u00f1ana.<\/p>\n<p>Pero \u00bfqu\u00e9 puede hacer el gobierno cubano, preso de un lado por \u201cesta nueva revuelta mundial\u201d como dices, (vieja, adem\u00e1s, agrego yo); y del otro, por la esencial inseguridad de no saber c\u00f3mo llevar al pa\u00eds hacia el ma\u00f1ana.<\/p>\n<p>Eso es lo que se hace en el mundo: reunirse con compradores, millonarios, modelos, m\u00fasicos y sicofantes, en un sitio lo m\u00e1s espectacular que puedas, para dar publicidad a una marca. De vender, que es necesario. En aquellos tiempos de la dignidad, los uniformes y las armas nos forzaban a ella. Ahora son los camareros elegantes y los habanos de categor\u00eda los que incitan la venta, apoyados por la presencia del presidente de la naci\u00f3n. Y hasta su presencia puede entenderse: un humano y pasajero placer entre los insolubles problemas que enfrenta d\u00eda a d\u00eda.<\/p>\n<p>Las calles, las mesas, y las bocanadas de humo de los cubanos de a pie son como un problema aparte. Eso pasa en todos los pa\u00edses pobres, como lo es el nuestro hoy en d\u00eda. Silvio, eres una voz honesta, valiente y \u201cOjal\u00e1 que las cubanas y cubanos de verg\u00fcenza no permitamos la indignidad y la destrucci\u00f3n de esta Patria que ha costado tanto construir y defender\u201d, como dices en tu nota. Lo que no s\u00e9 muy bien es c\u00f3mo transitar ese camino.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Silvio Rodr\u00edguez, gran cantor y poeta, acaba de publicar en su blog Segunda Cita una nota sobre la cr\u00edtica situaci\u00f3n en Cuba. No es la primera. Esta vez, en 243 palabras, se refiri\u00f3 a la \u201cdignidad nacional\u201d de la isla. \u201cDistintas se\u00f1ales sugieren que est\u00e1 ocurriendo una especie de desaparici\u00f3n paulatina del sentido de dignidad [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459951","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba - Noticias\" \/>\n<meta property=\"og:description\" content=\"Silvio Rodr\u00edguez, gran cantor y poeta, acaba de publicar en su blog Segunda Cita una nota sobre la cr\u00edtica situaci\u00f3n en Cuba. No es la primera. Esta vez, en 243 palabras, se refiri\u00f3 a la \u201cdignidad nacional\u201d de la isla. \u201cDistintas se\u00f1ales sugieren que est\u00e1 ocurriendo una especie de desaparici\u00f3n paulatina del sentido de dignidad [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-15T01:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba\",\"datePublished\":\"2025-03-15T01:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/\"},\"wordCount\":860,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/\",\"name\":\"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-15T01:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/","og_locale":"es_ES","og_type":"article","og_title":"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba - Noticias","og_description":"Silvio Rodr\u00edguez, gran cantor y poeta, acaba de publicar en su blog Segunda Cita una nota sobre la cr\u00edtica situaci\u00f3n en Cuba. No es la primera. Esta vez, en 243 palabras, se refiri\u00f3 a la \u201cdignidad nacional\u201d de la isla. \u201cDistintas se\u00f1ales sugieren que est\u00e1 ocurriendo una especie de desaparici\u00f3n paulatina del sentido de dignidad [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-15T01:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/"},"author":{"name":"","@id":""},"headline":"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba","datePublished":"2025-03-15T01:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/"},"wordCount":860,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/","name":"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-15T01:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"OPINI\u00d3N | Silvio Rodr\u00edguez y la dignidad nacional de Cuba","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-15T01:03:53Z","datePublished":"2025-03-15T01:03:53Z","dateModified":"2025-03-15T01:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"OPINI\\u00d3N | Silvio Rodr\\u00edguez y la dignidad nacional de Cuba\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/14\\\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/14\\\/opinion-jorge-davila-miguel-silvio-rodriguez-cuba-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-15T01:03:53Z\",\"datePublished\":\"2025-03-15T01:03:53Z\",\"dateModified\":\"2025-03-15T01:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472402,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/20\/cuba-regala-fusil-combate-silvio-rodriguez-orix\/","url_meta":{"origin":1459951,"position":0},"title":"Cuba le regala un fusil AKM al cantautor Silvio Rodr\u00edguez por su &#171;patri\u00f3tica disposici\u00f3n&#187; a defender el pa\u00eds","author":"","date":"marzo 20, 2026","format":false,"excerpt":"El Gobierno del presidente de Cuba, Miguel D\u00edaz-Canel, le regal\u00f3 este viernes un fusil AKM y una r\u00e9plica de la misma arma al cantautor cubano Silvio Rodr\u00edguez por su \u201cpatri\u00f3tica disposici\u00f3n\u201d para defender al pa\u00eds, que atraviesa una grave crisis que se ha profundizado en las \u00faltimas semanas por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472209,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/14\/cuba-nieto-raul-castro-conversaciones-eeuu-quien-es-orix\/","url_meta":{"origin":1459951,"position":1},"title":"Mientras EE.UU. presiona a Cuba, un Castro conocido como &#171;el Cangrejo&#187; est\u00e1 haciendo apariciones p\u00fablicas. Por esto importa","author":"","date":"marzo 14, 2026","format":false,"excerpt":"Ra\u00fal Guillermo Rodr\u00edguez Castro, nieto del expresidente de Cuba Ra\u00fal Castro, apareci\u00f3 por primera vez este viernes en dos actos p\u00fablicos junto al presidente Miguel D\u00edaz-Canel, un hecho que, seg\u00fan analistas, plantea interrogantes sobre su cu\u00e1l es su papel en el liderazgo de Cuba, mientras la isla enfrenta llamados a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472428,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","url_meta":{"origin":1459951,"position":2},"title":"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU.","author":"","date":"marzo 21, 2026","format":false,"excerpt":"El presidente de Cuba, Miguel D\u00edaz-Canel, habl\u00f3 este viernes sobre la presi\u00f3n que ejerce Estados Unidos sobre la isla y, en medio de las tensiones con el Gobierno de Donald Trump, reconoci\u00f3 que puede haber una agresi\u00f3n contra la isla y dijo que el pueblo cubano se prepara para defender\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472475,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/23\/diaz-canel-dispuesto-vida-revolucion-cuba-presion-eeuu-orix\/","url_meta":{"origin":1459951,"position":3},"title":"D\u00edaz-Canel dice que en Cuba no quieren la guerra pero est\u00e1n dispuestos a &#171;dar la vida por la Revoluci\u00f3n&#187;","author":"","date":"marzo 23, 2026","format":false,"excerpt":"En medio de la creciente presi\u00f3n de Estados Unidos, el presidente de Cuba, Miguel D\u00edaz-Canel, asegur\u00f3 en una entrevista con el pol\u00edtico espa\u00f1ol Pablo Iglesias que su Gobierno apuesta por el di\u00e1logo, pero se prepara para \u201cel peor de los escenarios\u201d en defensa de la soberan\u00eda de la isla, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472438,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/22\/analisis-trump-fin-revolucion-cuba-acuerdo-trax\/","url_meta":{"origin":1459951,"position":4},"title":"Trump pretende poner fin a la revoluci\u00f3n que inici\u00f3 Fidel Castro. \u00bfPueden Estados Unidos y Cuba llegar a un acuerdo?","author":"","date":"marzo 22, 2026","format":false,"excerpt":"Donald Trump quiere que creamos que un acuerdo con Cuba est\u00e1 a la vuelta de la esquina. Despu\u00e9s de esta \u00faltima semana, no estoy tan seguro.\u201cNo tienen energ\u00eda. No tienen dinero. Est\u00e1n en serios problemas\u201d, ha dicho Trump, explicando por qu\u00e9 cree que el Gobierno cubano est\u00e1 desesperado por llegar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472808,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","url_meta":{"origin":1459951,"position":5},"title":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado","author":"","date":"abril 2, 2026","format":false,"excerpt":"Cuba parece estar al borde del colapso. Sin petr\u00f3leo desde la ca\u00edda de Nicol\u00e1s Maduro en Venezuela en enero, sin el apoyo pol\u00edtico de muchos de sus antiguos aliados y en medio de una perpetua crisis econ\u00f3mica, el pa\u00eds comunista atraviesa la que es posiblemente la crisis m\u00e1s importante desde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459951"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459951\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}