{"id":1459981,"date":"2025-03-15T23:03:47","date_gmt":"2025-03-16T06:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/"},"modified":"2025-03-15T23:03:47","modified_gmt":"2025-03-16T06:03:47","slug":"capitan-mar-del-norte-tribunal-homicidio-negligencia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/","title":{"rendered":"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia"},"content":{"rendered":"<p>El capit\u00e1n ruso del <a href=\"https:\/\/cnn.com\/2025\/03\/12\/uk\/solong-captain-russian-stena-north-sea-crash-intl-gbr\/index.html\">carguero Solong<\/a> que se estrell\u00f3 contra un petrolero con bandera estadounidense a principios de esta semana en el Mar del Norte compareci\u00f3 ante un tribunal ingl\u00e9s este s\u00e1bado acusado de homicidio por negligencia grave.<\/p>\n<p>El Solong, con bandera portuguesa, choc\u00f3 el lunes con el Stena Immaculate mientras estaba anclado frente a la costa noreste de Inglaterra y transportaba enormes cantidades de combustible para aviones para el ej\u00e9rcito estadounidense, provocando un incendio en ambos buques y esfuerzos de rescate de emergencia por parte de la guardia costera brit\u00e1nica.<\/p>\n<p>El capit\u00e1n del Solong, Vladimir Motin, de 59 a\u00f1os y natural de San Petersburgo, compareci\u00f3 este s\u00e1bado ante el Tribunal de Magistrados de Hull tras ser acusado por la muerte de Mark Angelo Pernia, un tripulante filipino de 38 a\u00f1os que no pudo ser localizado despu\u00e9s del accidente y se presume muerto.<\/p>\n<p>En una audiencia de 35 minutos, el tribunal escuch\u00f3 c\u00f3mo el Solong se estrell\u00f3 contra el Stena Immaculate, un incidente que los expertos mar\u00edtimos calificaron de \u201cmisterio\u201d.<\/p>\n<p>La fiscal Amelia Katz dijo que el Stena Immaculate hab\u00eda estado anclado durante m\u00e1s de 15 horas antes de que el Solong, que viajaba a una velocidad de m\u00e1s de 15 nudos, se estrellara contra \u00e9l, inform\u00f3 Reuters.<\/p>\n<p>\u201cDurante un per\u00edodo de m\u00e1s de 40 minutos antes de la colisi\u00f3n, el Solong estaba en ruta directa para impactar con el Stena Immaculate, que estaba anclado y estacionario\u201d, dijo Katz.<\/p>\n<p>\u201cNo hubo ning\u00fan intento de comunicaci\u00f3n del Solong para advertir de la inminente colisi\u00f3n y el Solong no ajust\u00f3 su rumbo ni su velocidad en ning\u00fan momento\u201d, a\u00f1adi\u00f3.<\/p>\n<p>La tripulaci\u00f3n completa del Stena Immaculate, compuesta por 23 personas, fue rescatada, mientras que solo 13 de las 14 personas a bordo del Solong fueron puestas a salvo. El ministro mar\u00edtimo brit\u00e1nico, Mike Kane, declar\u00f3 que la operaci\u00f3n de b\u00fasqueda y rescate del tripulante desaparecido, posteriormente identificado como Pernia, se hab\u00eda cancelado a \u00faltima hora del lunes.<\/p>\n<p>El Stena Immaculate, que seg\u00fan Kane transportaba 220.000 barriles de combustible para aviones cuando el accidente, es parte de una flota de 10 buques cisterna que participan en un programa del gobierno estadounidense para suministrar combustible a sus fuerzas armadas.<\/p>\n<p>La empresa estadounidense de log\u00edstica Crowley, que gestiona el petrolero, dijo que el buque es parte del \u201cPrograma de Seguridad de Petroleros\u201d del Departamento de Defensa de Estados Unidos, que \u201cgarantiza que una flota comercial pueda transportar f\u00e1cilmente suministros de combustible l\u00edquido en momentos de necesidad\u201d.<\/p>\n<p>La guardia costera brit\u00e1nica dijo el mi\u00e9rcoles que no hab\u00eda ning\u00fan incendio visible en el Stena Immaculate, pero el viernes todav\u00eda hab\u00eda \u201cpeque\u00f1as bolsas peri\u00f3dicas de fuego\u201d en el Solong.<\/p>\n<p>Aunque el accidente inicialmente provoc\u00f3 temores de enormes da\u00f1os al medio ambiente, la guardia costera dijo el viernes que \u201csigue sin haber motivos de preocupaci\u00f3n por la contaminaci\u00f3n\u201d de ninguno de los barcos.<\/p>\n<p>Greenpeace afirm\u00f3 que parece que se ha evitado por poco un desastre medioambiental.<\/p>\n<p>\u201cCuando un buque portacontenedores del tama\u00f1o de un campo de f\u00fatbol choca contra un petrolero que transporta miles de toneladas de combustible para aviones a 16 nudos cerca de \u00e1reas naturales sensibles, el potencial de da\u00f1os graves es enorme\u201d, dijo el mi\u00e9rcoles el Dr. Paul Johnston, de los Laboratorios de Investigaci\u00f3n de Greenpeace.<\/p>\n<p>\u201cLa prioridad ahora debe ser garantizar, en la medida de lo posible, que ambos buques permanezcan a flote, que no haya m\u00e1s fugas de combustible para aviones del petrolero y que la carga del portacontenedores est\u00e9 completamente caracterizada y segura\u201d, a\u00f1adi\u00f3.<\/p>\n<p>La guardia costera brit\u00e1nica dijo que el Stena Immaculate permanece anclado mientras que el Solong se mantiene en una posici\u00f3n segura en alta mar mediante un remolcador.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El capit\u00e1n ruso del carguero Solong que se estrell\u00f3 contra un petrolero con bandera estadounidense a principios de esta semana en el Mar del Norte compareci\u00f3 ante un tribunal ingl\u00e9s este s\u00e1bado acusado de homicidio por negligencia grave. El Solong, con bandera portuguesa, choc\u00f3 el lunes con el Stena Immaculate mientras estaba anclado frente a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459981","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia - Noticias\" \/>\n<meta property=\"og:description\" content=\"El capit\u00e1n ruso del carguero Solong que se estrell\u00f3 contra un petrolero con bandera estadounidense a principios de esta semana en el Mar del Norte compareci\u00f3 ante un tribunal ingl\u00e9s este s\u00e1bado acusado de homicidio por negligencia grave. El Solong, con bandera portuguesa, choc\u00f3 el lunes con el Stena Immaculate mientras estaba anclado frente a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-16T06:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia\",\"datePublished\":\"2025-03-16T06:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/\"},\"wordCount\":685,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/\",\"name\":\"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-16T06:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia - Noticias","og_description":"El capit\u00e1n ruso del carguero Solong que se estrell\u00f3 contra un petrolero con bandera estadounidense a principios de esta semana en el Mar del Norte compareci\u00f3 ante un tribunal ingl\u00e9s este s\u00e1bado acusado de homicidio por negligencia grave. El Solong, con bandera portuguesa, choc\u00f3 el lunes con el Stena Immaculate mientras estaba anclado frente a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-16T06:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/"},"author":{"name":"","@id":""},"headline":"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia","datePublished":"2025-03-16T06:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/"},"wordCount":685,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/","name":"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-16T06:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El capit\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/15\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-16T06:03:47Z","datePublished":"2025-03-16T06:03:47Z","dateModified":"2025-03-16T06:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El capit\\u00e1n ruso del barco accidentado en el Mar del Norte comparece ante el tribunal acusado de homicidio por negligencia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/15\\\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/15\\\/capitan-mar-del-norte-tribunal-homicidio-negligencia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-16T06:03:47Z\",\"datePublished\":\"2025-03-16T06:03:47Z\",\"dateModified\":\"2025-03-16T06:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459808,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/12\/capitan-carguero-colision-mar-norte-nacionalidad-rusa-trax\/","url_meta":{"origin":1459981,"position":0},"title":"El capit\u00e1n de un carguero arrestado en una colisi\u00f3n en el Mar del Norte es de nacionalidad rusa, afirma su propietario","author":"","date":"marzo 12, 2025","format":false,"excerpt":"El capit\u00e1n del carguero Solong que fue arrestado tras estrellarse contra un petrolero frente a las costas de Inglaterra es un ciudadano ruso, dijo el mi\u00e9rcoles el propietario del barco, Ernst Russ, mientras los expertos mar\u00edtimos buscan respuestas.El Solong se estrell\u00f3 contra el Stena Immaculate, de bandera estadounidense, incendiando ambos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459728,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/incendio-colision-petrolero-y-buque-de-carga-costas-reino-unido-trax\/","url_meta":{"origin":1459981,"position":1},"title":"Se produce un incendio tras la colisi\u00f3n de un petrolero y un buque de carga frente a las costas del Reino Unido","author":"","date":"marzo 10, 2025","format":false,"excerpt":"Un petrolero y un carguero chocaron frente a la costa noreste de Inglaterra, causando un gran incendio, lo que desencaden\u00f3 una respuesta de emergencia de los guardacostas brit\u00e1nicos.La Guardia Costera dijo que envi\u00f3 un helic\u00f3ptero y botes salvavidas desde pueblos cercanos, as\u00ed como \u201cbarcos con capacidad de extinci\u00f3n de incendios\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468897,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/02\/sospechoso-tiroteo-washington-declara-inocente-trax\/","url_meta":{"origin":1459981,"position":2},"title":"El sospechoso del tiroteo en la ciudad de Washington se declara inocente en su primera comparecencia desde el hospital","author":"","date":"diciembre 2, 2025","format":false,"excerpt":"Un hombre afgano compareci\u00f3 ante la corte de manera virtual desde una cama de hospital este martes para declararse inocente de los cargos relacionados con el tiroteo en la ciudad de Washington.Rahmanullah Lakanwal est\u00e1 acusado de disparar a dos miembros de la Guardia Nacional cerca de la Casa Blanca la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463153,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/03\/arrestan-familia-sospechoso-soliman-ataque-colorado-trax\/","url_meta":{"origin":1459981,"position":3},"title":"ICE arresta a la familia del sospechoso del ataque antisemita en Colorado","author":"","date":"junio 3, 2025","format":false,"excerpt":"La familia del ciudadano egipcio acusado de intento de homicidio tras un ataque antisemita en Boulder, Colorado, ha sido puesta bajo custodia del ICE, confirm\u00f3 un funcionario del Departamento de Seguridad Nacional a CNN el martes.El presunto atacante, Mohamed Soliman, tiene esposa y cinco hijos, seg\u00fan documentos judiciales. Se desconoce\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469191,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/11\/tyler-robinson-caso-charlie-kirk-tribunal-trax\/","url_meta":{"origin":1459981,"position":4},"title":"El presunto asesino de Charlie Kirk, Tyler Robinson, comparece por primera vez en persona ante el tribunal","author":"","date":"diciembre 11, 2025","format":false,"excerpt":"Tyler Robinson, el hombre de 22 a\u00f1os acusado de matar de un disparo al activista pol\u00edtico conservador Charlie Kirk, compareci\u00f3 este jueves en un tribunal de Utah por primera vez en persona desde su arresto.Robinson llevaba una camisa azul clara, una corbata a rayas y pantalones caqui, y se le\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473608,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/28\/polymarket-maduro-soldado-apuestas-trax\/","url_meta":{"origin":1459981,"position":5},"title":"Soldado que apost\u00f3 en Polymarket sobre captura de Maduro y gan\u00f3 US$ 400.000 se declar\u00f3 inocente","author":"","date":"abril 28, 2026","format":false,"excerpt":"El militar de fuerzas especiales involucrado en la captura del presidente depuesto de Venezuela Nicol\u00e1s Maduro se declar\u00f3 inocente este martes de usar informaci\u00f3n clasificada sobre el operativo para obtener m\u00e1s de US$ 400.000 en ganancias ilegales.Gannon Ken Van Dyke, un militar activo de 38 a\u00f1os destinado en Fort Bragg,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459981"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459981\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}