{"id":1459986,"date":"2025-03-16T03:03:51","date_gmt":"2025-03-16T10:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/"},"modified":"2025-03-16T03:03:51","modified_gmt":"2025-03-16T10:03:51","slug":"padre-hombre-trans-trump-tratamiento-hijo-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/","title":{"rendered":"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo"},"content":{"rendered":"<p>Despu\u00e9s de someterse a una cirug\u00eda, Ashton Colby qued\u00f3 confinado a una cama y no pod\u00eda mover los brazos ni realizar tareas b\u00e1sicas.<\/p>\n<p>Pero su padre, Rick Colby, estuvo all\u00ed en cada paso del camino, ayud\u00e1ndolo a recuperarse de su cirug\u00eda superior: un apoyo que signific\u00f3 el mundo por parte de su padre republicano conservador despu\u00e9s de que Ashton se declarara transg\u00e9nero y se sometiera a la operaci\u00f3n.<\/p>\n<p>La cirug\u00eda es una opci\u00f3n que algunas personas trans, aunque no todas, eligen como parte de la atenci\u00f3n m\u00e1s amplia de afirmaci\u00f3n de g\u00e9nero que pueden recibir para facilitar su transici\u00f3n. Ashton ten\u00eda 19 a\u00f1os en ese momento.<\/p>\n<p>\u201cEstuvo en la habitaci\u00f3n del hotel ayud\u00e1ndome a recuperarme y a tomar batidos de prote\u00ednas cuando no pod\u00eda usar los brazos. Ha marcado, literalmente, una diferencia crucial en mi vida\u201d, declar\u00f3 a CNN Ashton, ahora de 32 a\u00f1os.<\/p>\n<p>Ashton hab\u00eda estado atormentado por el miedo a ser rechazado por su familia en las semanas previas a su salida del armario en 2012. Pero su padre lo apoy\u00f3 durante la terapia y las citas m\u00e9dicas, asegur\u00e1ndose de que recibiera la atenci\u00f3n especializada que necesitaba para afirmar su g\u00e9nero y prosperar, lo que Ashton dice: \u201cMe salv\u00f3 la vida\u201d.<\/p>\n<p>Rick vot\u00f3 por el presidente Donald Trump en 2024 y describe su papel como un \u201cliniero ofensivo\u201d en una misi\u00f3n m\u00e1s amplia para combatir los conceptos err\u00f3neos y la legislaci\u00f3n que ataca los derechos de las personas transg\u00e9nero y la atenci\u00f3n m\u00e9dica.<\/p>\n<p>Ahora, se enfrenta un nuevo desaf\u00edo: un decreto de Trump que niega fondos federales a proveedores de atenci\u00f3n m\u00e9dica que reafirme el g\u00e9nero para menores. La orden amenaza con afectar incluso la atenci\u00f3n m\u00e9dica para Ashton, quien es adulto, y para muchas otras personas.<\/p>\n<p>Si bien dicha medida aplica a la atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero para menores de 19 a\u00f1os y ha sido <a href=\"https:\/\/www.cnn.com\/2025\/03\/01\/politics\/trump-order-transgender-youth-care-seattle-judge\/index.html\">suspendida temporalmente<\/a> por dos jueces federales, a\u00fan afecta a pacientes de todas las edades. Muchas cl\u00ednicas y hospitales de todo el pa\u00eds suspendieron temporalmente la atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero antes de que los jueces bloquearan la orden. Si bien la atenci\u00f3n se ha reanudado en muchos centros, a los proveedores, temerosos por la posible p\u00e9rdida de fondos federales, les preocupa tener que suspender la atenci\u00f3n por completo en el futuro, seg\u00fan informaron expertos a CNN.<\/p>\n<p>Ashton ha recibido atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero en la misma cl\u00ednica de Ohio desde 2015, siendo adulto. El a\u00f1o pasado, Ohio prohibi\u00f3 algunos aspectos de la atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero para menores. Si bien la atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero para adultos sigue siendo legal en Ohio, su proveedor le advirti\u00f3 el mes pasado que, tras la orden de Trump, los pacientes podr\u00edan tener que cruzar la frontera estatal a Pensilvania para acceder a la atenci\u00f3n, seg\u00fan Ashton. Su centro m\u00e9dico depende de millones de d\u00f3lares en apoyo federal para atender a todos sus pacientes.<\/p>\n<p>La orden ejecutiva ha sumido en el caos a los proveedores de servicios m\u00e9dicos y a sus pacientes, incluso en estados dem\u00f3cratas donde anteriormente la atenci\u00f3n estaba protegida.<\/p>\n<p>Las interrupciones en la atenci\u00f3n de reafirmaci\u00f3n de g\u00e9nero tras la orden ya son palpables. Los pacientes que toman bloqueadores de la pubertad y necesitan cambiar a terapia hormonal ya han experimentado o temen interrupciones en su tratamiento y enfrentan riesgos m\u00e9dicos significativos, seg\u00fan una pediatra que habl\u00f3 con CNN de forma an\u00f3nima debido a amenazas a su seguridad.<\/p>\n<p>La orden es parte de una ola de medidas dirigidas a la atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero que se han impulsado en los \u00faltimos a\u00f1os (junto con un n\u00famero r\u00e9cord de <a href=\"https:\/\/www.cnn.com\/politics\/anti-lgbtq-plus-state-bill-rights-dg\/index.html\">proyectos de ley anti-LGBTQ<\/a> presentados en 2023) en todo Estados Unidos, principalmente por republicanos.<\/p>\n<p>Rick Colby dice que no puede apoyar las medidas de la administraci\u00f3n Trump dirigidas a la comunidad transg\u00e9nero.<\/p>\n<p>\u201cEstoy de acuerdo con casi todo lo que hace Trump, excepto con las personas transg\u00e9nero\u201d, dijo Rick a CNN.<\/p>\n<p>Para Ashton, recibir atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero le permiti\u00f3 estar en \u201cun gran lugar y ser la persona que siempre estuvo destinado a ser, es decir, un hombre\u201d, dijo su padre.<\/p>\n<p>\u201cNo importa cu\u00e1l sea su afiliaci\u00f3n pol\u00edtica, mi principal preocupaci\u00f3n es c\u00f3mo mantener vivo a mi hijo y ayudarlo a ser feliz, prosperar y ser un miembro productivo de la sociedad\u201d, dijo Rick.<\/p>\n<p>Ashton Colby toma testosterona como una inyecci\u00f3n semanal como parte de un plan de tratamiento continuo para controlar la disforia de g\u00e9nero que, seg\u00fan \u00e9l, \u201cahora, por suerte, no tengo\u201d.<\/p>\n<ul>\n<li><strong>La atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero<\/strong> es una atenci\u00f3n m\u00e9dicamente necesaria y basada en evidencia que utiliza un enfoque multidisciplinario para ayudar a una persona a realizar la transici\u00f3n de su g\u00e9nero asignado (el que se le asign\u00f3 al nacer) a su g\u00e9nero afirmado (el g\u00e9nero por el que desea ser conocido).<\/li>\n<li>Aunque algunos cr\u00edticos de las terapias sugieren que los menores de 19 a\u00f1os deber\u00edan esperar hasta la edad adulta para hacer la transici\u00f3n, la Academia Estadounidense de Pediatr\u00eda dice que ese es un enfoque obsoleto que asume que la identidad de g\u00e9nero est\u00e1 fijada a cierta edad.<\/li>\n<li>El tratamiento est\u00e1 avalado por <a href=\"https:\/\/www.ama-assn.org\/delivering-care\/population-care\/advocating-lgbtq-community\">la Asociaci\u00f3n M\u00e9dica Estadounidense<\/a> , la <a href=\"https:\/\/www.psychiatry.org\/getattachment\/8665a2f2-0b73-4477-8f60-79015ba9f815\/Position-Treatment-of-Transgender-Gender-Diverse-Youth.pdf\">Asociaci\u00f3n Estadounidense de Psiquiatr\u00eda<\/a> y <a href=\"https:\/\/publications.aap.org\/aapnews\/news\/25340\/AAP-reaffirms-gender-affirming-care-policy?autologincheck=redirected\">la Academia Estadounidense de Pediatr\u00eda<\/a> , entre otros <a href=\"https:\/\/transhealthproject.org\/resources\/medical-organization-statements\/\">grupos m\u00e9dicos importantes<\/a>, como cl\u00ednicamente apropiado para ni\u00f1os y adultos con <strong>disforia de g\u00e9nero<\/strong>, una angustia psicol\u00f3gica que puede resultar cuando la identidad de g\u00e9nero de una persona y el sexo asignado al nacer no coinciden.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.mayoclinic.org\/tests-procedures\/masculinizing-hormone-therapy\/about\/pac-20385099#:~:text=Some%20of%20the%20physical%20changes,facial%20hair%2C%20cannot%20be%20reversed.\">Pero le preocupa que su plan de tratamiento se vea alterado por primera vez desde su transici\u00f3n. Seg\u00fan la Cl\u00ednica Mayo,<\/a> cuando los pacientes que se someten a terapia hormonal dejan de tomar testosterona, algunos cambios f\u00edsicos pueden revertirse.<a href=\"https:\/\/www.mayoclinic.org\/tests-procedures\/masculinizing-hormone-therapy\/about\/pac-20385099#:~:text=Some%20of%20the%20physical%20changes,facial%20hair%2C%20cannot%20be%20reversed.\"><\/a><\/p>\n<p>\u201cHe estado realmente preocupado de que, incluso como adulto, me puedan quitar la atenci\u00f3n m\u00e9dica o hacer que sea mucho m\u00e1s dif\u00edcil acceder a ella\u201d, dijo Ashton.<strong><\/strong><\/p>\n<p>No est\u00e1 solo. Varios profesionales de la salud informaron a CNN que han recibido noticias de pacientes y padres de ni\u00f1os trans con ansiedad que ya han experimentado o prev\u00e9n interrupciones en la atenci\u00f3n m\u00e9dica de sus hijos.<\/p>\n<p>Los expertos dicen que el futuro de su tratamiento es incierto sin importar en qu\u00e9 estado vivan, ya que las cl\u00ednicas e instituciones m\u00e9dicas adoptan un enfoque \u201creacio al riesgo\u201d debido a la amenaza de perder fondos federales esenciales para tratar a todos los pacientes y realizar investigaciones.<\/p>\n<p>En la semana posterior a la firma de la orden por parte de Trump, <a href=\"https:\/\/www.whitehouse.gov\/articles\/2025\/02\/president-trump-is-delivering-on-his-commitment-to-protect-our-kids\/\">cl\u00ednicas y hospitales de todo el pa\u00eds<\/a> anunciaron p\u00fablicamente la suspensi\u00f3n de la atenci\u00f3n de reasignaci\u00f3n de g\u00e9nero para menores de 19 a\u00f1os. Sin embargo, en febrero, la reanudaron despu\u00e9s de que <a href=\"https:\/\/riag.ri.gov\/press-releases\/attorney-general-neronha-and-14-attorneys-general-issue-joint-statement-protecting\">los fiscales generales<\/a> estatales advirtieran que denegar el tratamiento podr\u00eda violar las leyes estatales contra la discriminaci\u00f3n. Entre estas instituciones m\u00e9dicas se encontraban <a href=\"https:\/\/www.denverpost.com\/2025\/02\/20\/denver-health-childrens-hopital-colorado-resume-gender-affirming-care\/\">Denver Health<\/a>, <a href=\"https:\/\/www.denverpost.com\/2025\/02\/20\/denver-health-childrens-hopital-colorado-resume-gender-affirming-care\/\">Children\u2019s Health Colorado<\/a>, <a href=\"https:\/\/lalgbtcenter.org\/vanguard\/press-releases\/statement-los-angeles-lgbt-center-th%5B%E2%80%A6%5Dg-gender-affirming-care-urges-more-hospitals-to-do-the-same\/\">Children\u2019s Hospital Los Angeles<\/a> y <a href=\"https:\/\/michiganadvance.com\/2025\/02\/12\/more-than-40-mi-organizations-call-on-corewell-health-to-resume-providing-gender-affirming-care\/\">Corewell Health<\/a> en Michigan.<\/p>\n<p>Dos jueces federales han <a href=\"https:\/\/amp.cnn.com\/cnn\/2025\/03\/01\/politics\/trump-order-transgender-youth-care-seattle-judge\">pausado la orden de Trump<\/a>, incluido el juez de distrito estadounidense Brendan Hurson en Baltimore, quien el 4 de marzo extendi\u00f3 una orden de restricci\u00f3n temporal que se hab\u00eda ingresado previamente en el caso, diciendo que las interrupciones en la atenci\u00f3n m\u00e9dica para los j\u00f3venes trans podr\u00edan ser \u201cpotencialmente catastr\u00f3ficas\u201d y se\u00f1alando los riesgos de una mayor disforia de g\u00e9nero e incertidumbre suicida.<\/p>\n<p>Un grupo de <a href=\"https:\/\/riag.ri.gov\/press-releases\/attorney-general-neronha-and-14-attorneys-general-issue-joint-statement-protecting\">15 fiscales generales<\/a> tambi\u00e9n emiti\u00f3 una declaraci\u00f3n conjunta en febrero para \u201creafirmar su apoyo\u201d a la atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero y dijeron que \u201ccontinuar\u00e1n haciendo cumplir las leyes estatales que brindan acceso a la atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero\u201d.<\/p>\n<p>Pero aun cuando algunos hospitales y cl\u00ednicas est\u00e1n cambiando de postura, la volatilidad del tratamiento m\u00e9dico mantiene alta la ansiedad mientras los proveedores y las familias lidian con las consecuencias de la orden y el caso legal pendiente.<\/p>\n<p>Muchas instituciones est\u00e1n pausando la atenci\u00f3n m\u00e9dica \u201cen secreto\u201d sin documentar formalmente los cambios, sino que les dicen a los proveedores que cancelen en silencio porque temen reacciones negativas, seg\u00fan Alex Sheldon, director ejecutivo de GLMA, uno de los m\u00faltiples grupos LGBTQ <a href=\"https:\/\/glma.org\/news_manager.php?page=29578\">que est\u00e1n demandando a la Administraci\u00f3n Trump<\/a> por la orden ejecutiva.<\/p>\n<p>\u201cSi la financiaci\u00f3n est\u00e1 condicionada a no brindar atenci\u00f3n a una poblaci\u00f3n muy peque\u00f1a de pacientes \u2014j\u00f3venes trans y no binarios\u2014, perder esa financiaci\u00f3n obligar\u00eda a muchos hospitales a cerrar por completo\u201d, dijo Sheldon.<\/p>\n<p>Muchas instituciones m\u00e9dicas han decidido \u201cpecar de miedo\u201d, dijo Sheldon.<s><\/s><\/p>\n<p>\u201cEs cruel porque hay que elegir qui\u00e9n va a sufrir. Sabemos que ser\u00e1n los pacientes transg\u00e9nero porque son menos\u201d, dijo el pediatra que habl\u00f3 an\u00f3nimamente. \u201c\u00bfDetienen esta atenci\u00f3n tan crucial que salva vidas para estos ni\u00f1os, o ponen en riesgo la atenci\u00f3n de todos estos pacientes que tambi\u00e9n la necesitan?\u201d<\/p>\n<p>Los proveedores ya est\u00e1n respondiendo a las \u201cllamadas fren\u00e9ticas\u201d de los padres de sus pacientes, dijo el m\u00e9dico.<\/p>\n<p>Nos preguntan: \u201c\u00bfQu\u00e9 va a pasar? \u00bfVan a cerrar? \u00bfPueden renovar sus recetas lo antes posible antes del cierre?\u201d. Hay pacientes programados para inhibidores de la pubertad dentro de un mes y les preocupa no poder cumplir con su cita.<\/p>\n<p>Algunas familias est\u00e1n haciendo planes para mudarse fuera del pa\u00eds, incluidas aquellas que no tienen muchos recursos, dijo el m\u00e9dico.<\/p>\n<p>Los proveedores de atenci\u00f3n m\u00e9dica en el campo dicen que enfrentan una elecci\u00f3n imposible entre mantener est\u00e1ndares \u00e9ticos de atenci\u00f3n y arriesgar sus medios de vida, ya que la legislaci\u00f3n podr\u00eda significar que perder\u00e1n sus trabajos o licencias m\u00e9dicas por seguir las pautas m\u00e9dicas establecidas respaldadas por todas las asociaciones m\u00e9dicas principales.<\/p>\n<p>Una de las principales preocupaciones es la de los ni\u00f1os que toman <a href=\"https:\/\/www.cnn.com\/2024\/03\/15\/health\/puberty-blockers-explained-nhs-wellness\/index.html\">bloqueadores de la pubertad<\/a> y que no podr\u00e1n acceder a la terapia hormonal si la atenci\u00f3n se interrumpe repentinamente, explic\u00f3 el m\u00e9dico.<\/p>\n<p>\u201cNo pueden llegar a la adolescencia tard\u00eda sin hormonas porque entonces hay riesgos m\u00e9dicos significativos\u201d, a\u00f1adi\u00f3 el m\u00e9dico.<\/p>\n<p>Los pacientes que toman bloqueadores de la pubertad tienen implantes debajo de la piel que s\u00f3lo pueden extraerse quir\u00fargicamente, seg\u00fan el m\u00e9dico.<\/p>\n<p>\u201cEntonces, ahora mismo nos enfrentamos a la cuesti\u00f3n \u00e9tica de: si lo mantenemos pero no reciben hormonas, tendr\u00e1n problemas con su densidad \u00f3sea, tal vez con el desarrollo cerebral\u201d, dijo el m\u00e9dico. \u201cPero si retiramos el implante, tendr\u00e1n un retroceso. Comenzar\u00e1 la pubertad end\u00f3gena y eso ser\u00e1 bastante traum\u00e1tico. \u00bfQu\u00e9 hacemos?\u201d<\/p>\n<p>No todos los proveedores suspender\u00e1n sus servicios si se aplica la orden de Trump.<\/p>\n<p>Un centro de salud sin fines de lucro que recibe fondos federales todav\u00eda brinda atenci\u00f3n de afirmaci\u00f3n de g\u00e9nero a los j\u00f3venes, pero buscar\u00e1 obtener fondos alternativos si se aplica la orden, seg\u00fan su equipo de liderazgo, que acept\u00f3 hablar con CNN de forma an\u00f3nima debido a preocupaciones de seguridad y privacidad.<\/p>\n<p>Los hospitales, especialmente los centros m\u00e9dicos acad\u00e9micos, suelen recibir financiaci\u00f3n para investigaci\u00f3n del gobierno federal. La situaci\u00f3n var\u00eda m\u00e1s en el caso de las cl\u00ednicas, pero suelen obtener fondos de fuentes que cobran a las aseguradoras, tienen una escala m\u00f3vil de tarifas y tambi\u00e9n pueden recibir subvenciones federales, seg\u00fan el director ejecutivo del centro de salud.<\/p>\n<p>Somos cientos de personas que brindamos terapia hormonal a pacientes. Todos entendemos que se trata de atenci\u00f3n primaria y rutinaria, y existe una s\u00f3lida evidencia al respecto. Para muchos, es fundamental seguir haci\u00e9ndolo porque simplemente lo consideramos atenci\u00f3n primaria, afirm\u00f3 el director ejecutivo.<\/p>\n<p>Para Ashton Colby, el apoyo de sus seres queridos lo ayuda a afrontar el miedo y la incertidumbre que rodean la atenci\u00f3n m\u00e9dica durante la administraci\u00f3n Trump.<\/p>\n<p>El padre de Ashton refuta con vehemencia las afirmaciones de los republicanos de que \u00abla gente se est\u00e1 volviendo transg\u00e9nero por capricho\u00bb. Cita su experiencia directa al presenciar a Ashton sufrir disforia de g\u00e9nero.<\/p>\n<p>Sufri\u00f3 much\u00edsimo durante sus a\u00f1os de formaci\u00f3n y como adolescente\u2026 la depresi\u00f3n, la ansiedad, el estr\u00e9s.<\/p>\n<p>Para Ashton y otras personas transg\u00e9nero y no binarias, ahora existe incertidumbre sobre sus futuras citas y el r\u00e9gimen de tratamiento continuo del que dependen.<\/p>\n<p>\u201cNo deber\u00eda tener un plan de salida con mi proveedor de esta manera. He estado nervioso\u201d, dijo Ashton.<\/p>\n<p>Rick cree que la \u201cextrema derecha\u201d de su partido \u201cno cree en absoluto que ser transg\u00e9nero sea algo real\u201d y dice que se involucran en esfuerzos para \u201cborrarlas y hacerles la vida dif\u00edcil, a pesar de que las personas transg\u00e9nero son ciudadanos estadounidenses y est\u00e1n tratando de participar en el sue\u00f1o americano y vivir sus vidas para que los dejen en paz como a todos los dem\u00e1s\u201d.<\/p>\n<p>El camino a seguir, dice, es que el Partido Republicano escuche a la comunidad transg\u00e9nero y a los m\u00e9dicos que los atienden.<\/p>\n<p>Rick dijo que cuando m\u00e1s odio recibe es cuando \u201cme identifico como un republicano conservador, padre de un hijo transg\u00e9nero a quien quiero y apoyo. Eso les molesta, porque no encaja con la narrativa, que es: \u2018todos los de izquierda hacen esto\u2019\u201d.<\/p>\n<p>Pero para \u00e9l, esto demuestra el punto: \u201cMuestra que este es realmente un asunto que trasciende una ideolog\u00eda pol\u00edtica y que realmente hay una verdad objetiva en ello\u201d.<\/p>\n<p>Aunque Ashton dice que no est\u00e1 de acuerdo con muchas de las creencias conservadoras de su padre y que no votaron por el mismo candidato, se han acercado m\u00e1s al \u201cresponder al llamado a la defensa\u201d.<\/p>\n<p>Sabe que est\u00e1 seguro en su casa y en su comunidad, por lo que decidi\u00f3 quedarse en Ohio despu\u00e9s de considerar mudarse a un estado m\u00e1s azul con m\u00e1s leyes que protejan sus derechos.<\/p>\n<p>Ashton dijo de su padre: \u00abComo ha tenido que repetirlo y declararlo p\u00fablicamente una y otra vez que me ama\u2026 lo siento m\u00e1s en el coraz\u00f3n. Estoy a salvo con \u00e9l aqu\u00ed\u00bb.<\/p>\n<p>Kristen Rogers y Jen Christensen de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de someterse a una cirug\u00eda, Ashton Colby qued\u00f3 confinado a una cama y no pod\u00eda mover los brazos ni realizar tareas b\u00e1sicas. Pero su padre, Rick Colby, estuvo all\u00ed en cada paso del camino, ayud\u00e1ndolo a recuperarse de su cirug\u00eda superior: un apoyo que signific\u00f3 el mundo por parte de su padre republicano conservador [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459986","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de someterse a una cirug\u00eda, Ashton Colby qued\u00f3 confinado a una cama y no pod\u00eda mover los brazos ni realizar tareas b\u00e1sicas. Pero su padre, Rick Colby, estuvo all\u00ed en cada paso del camino, ayud\u00e1ndolo a recuperarse de su cirug\u00eda superior: un apoyo que signific\u00f3 el mundo por parte de su padre republicano conservador [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-16T10:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo\",\"datePublished\":\"2025-03-16T10:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/\"},\"wordCount\":2561,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/\",\"name\":\"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-16T10:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo - Noticias","og_description":"Despu\u00e9s de someterse a una cirug\u00eda, Ashton Colby qued\u00f3 confinado a una cama y no pod\u00eda mover los brazos ni realizar tareas b\u00e1sicas. Pero su padre, Rick Colby, estuvo all\u00ed en cada paso del camino, ayud\u00e1ndolo a recuperarse de su cirug\u00eda superior: un apoyo que signific\u00f3 el mundo por parte de su padre republicano conservador [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-16T10:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/"},"author":{"name":"","@id":""},"headline":"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo","datePublished":"2025-03-16T10:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/"},"wordCount":2561,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/","name":"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-16T10:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El padre de un hombre transg\u00e9nero vot\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/16\/padre-hombre-trans-trump-tratamiento-hijo-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-16T10:03:51Z","datePublished":"2025-03-16T10:03:51Z","dateModified":"2025-03-16T10:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El padre de un hombre transg\\u00e9nero vot\\u00f3 por Trump. Ahora teme que una orden del presidente afecte el tratamiento de su hijo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/16\\\/padre-hombre-trans-trump-tratamiento-hijo-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/16\\\/padre-hombre-trans-trump-tratamiento-hijo-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-16T10:03:51Z\",\"datePublished\":\"2025-03-16T10:03:51Z\",\"dateModified\":\"2025-03-16T10:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447842,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/08\/cirugia-cambio-de-sexo-amenaza-dignidad-unica-de-una-persona-dice-el-vaticano-trax\/","url_meta":{"origin":1459986,"position":0},"title":"La cirug\u00eda de cambio de sexo amenaza la &#171;dignidad \u00fanica&#187; de una persona, dice el Vaticano","author":"","date":"abril 8, 2024","format":false,"excerpt":"(CNN) --\u00a0 El Vaticano emiti\u00f3 una fuerte advertencia contra la \"teor\u00eda de g\u00e9nero\" y dijo que cualquier cirug\u00eda de cambio de sexo corre el riesgo de amenazar \"la dignidad \u00fanica\" de una persona, en un nuevo documento firmado y aprobado por el papa Francisco.Titulada \u201cDignitas Inifinita\u201d (Dignidad Infinita), la declaraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448695,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/30\/activista-transexual-hong-kong-obtiene-nuevo-documento-identidad-masculino-tras-anos-batalla-legal-trax\/","url_meta":{"origin":1459986,"position":1},"title":"Un activista transexual de Hong Kong obtiene un nuevo documento de identidad masculino tras a\u00f1os de batalla legal","author":"","date":"abril 30, 2024","format":false,"excerpt":"(CNN) -- Para muchos de nosotros, un documento de identidad es un peque\u00f1o trozo de pl\u00e1stico metido en la cartera en el que rara vez pensamos mucho.Pero para el activista transexual de Hong Kong Henry Tse su documento de identidad fue algo que domin\u00f3 su mundo durante los \u00faltimos siete\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459278,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/27\/pentagono-expulsar-miembros-transgenero-trax\/","url_meta":{"origin":1459986,"position":2},"title":"El Pent\u00e1gono planea expulsar a los miembros transg\u00e9nero del servicio, bajo una nueva pol\u00edtica del Gobierno de Trump","author":"","date":"febrero 27, 2025","format":false,"excerpt":"El Pent\u00e1gono planea expulsar a los miembros transg\u00e9nero que actualmente est\u00e9n en servicio y que no cumplen con los requisitos espec\u00edficos bajo su nueva directiva pol\u00edtica, seg\u00fan la gu\u00eda oficial hecha p\u00fablica en una presentaci\u00f3n judicial del mi\u00e9rcoles.\u201cLos miembros del servicio que tengan un diagn\u00f3stico actual o antecedentes de disforia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456502,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/11\/lula-procedimiento-medico-cirugia-hemorragia-trax\/","url_meta":{"origin":1459986,"position":3},"title":"Lula se someter\u00e1 a un procedimiento m\u00e9dico adicional tras cirug\u00eda de emergencia por hemorragia cerebral","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Se espera que el presidente de Brasil, Luiz In\u00e1cio Lula da Silva, se someta a un procedimiento m\u00e9dico adicional el jueves como parte de su tratamiento luego de la cirug\u00eda de emergencia que tuvo el martes para drenar una hemorragia en su cerebro.Los m\u00e9dicos del Hospital S\u00edrio-Liban\u00e9s de Sao Paulo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456518,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/12\/lula-da-silva-recupera-cirugia-orix\/","url_meta":{"origin":1459986,"position":4},"title":"Lula se recupera de una segunda cirug\u00eda &#171;exitosa&#187;, informa m\u00e9dico","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, se recupera con \u00e9xito de un procedimiento m\u00e9dico adicional que le realizaron este jueves como parte de su tratamiento tras la cirug\u00eda de emergencia a la que se someti\u00f3 el martes para drenar una hemorragia cerebral, inform\u00f3 el doctor Roberto Kalil\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469562,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/25\/brasil-bolsonaro-supera-cirugia-hernia-efe\/","url_meta":{"origin":1459986,"position":5},"title":"Bolsonaro supera con \u00e9xito una cirug\u00eda por una hernia, dice su esposa","author":"","date":"diciembre 25, 2025","format":false,"excerpt":"El expresidente de Brasil Jair Bolsonaro, en prisi\u00f3n por intento de golpe de Estado, super\u00f3 \u201ccon \u00e9xito y sin complicaciones\u201d la operaci\u00f3n a la que se someti\u00f3 este jueves por una hernia inguinal bilateral, seg\u00fan inform\u00f3 su familia.\u201c\u00a1Cirug\u00eda finalizada con \u00e9xito! Sin complicaciones. Ahora, esperar la recuperaci\u00f3n de la anestesia\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1459986"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1459986\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1459986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1459986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1459986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}