{"id":1460004,"date":"2025-03-17T00:03:48","date_gmt":"2025-03-17T07:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/"},"modified":"2025-03-17T00:03:48","modified_gmt":"2025-03-17T07:03:48","slug":"casa-blanca-niega-deportaciones-venezolanos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/","title":{"rendered":"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos"},"content":{"rendered":"<p>La Casa Blanca niega haber violado <a href=\"https:\/\/www.cnn.com\/2025\/03\/16\/politics\/trump-administration-deportations-alien-enemies-act\/index.html\">la orden de un juez emitida este s\u00e1bado de detener<\/a> las deportaciones de presuntos pandilleros venezolanos a El Salvador, lo que, de ocurrir, acercar\u00eda al pa\u00eds al borde de una crisis constitucional en medio de los enfrentamientos legales de una administraci\u00f3n con pretensiones de amasar un vasto poder presidencial.<\/p>\n<p>El drama rodea a los migrantes venezolanos expulsados \u200b\u200bcon el uso poco com\u00fan de una ley del siglo XVIII, <a href=\"https:\/\/www.cnn.com\/2024\/11\/14\/politics\/alien-enemies-act-1798-trump-cec\/index.html\">la Ley de Enemigos Extranjero<\/a>s, otra decisi\u00f3n controvertida y que puede representar una extralimitaci\u00f3n del presidente Donald Trump.<\/p>\n<p>El juez federal de distrito James Boasberg <a href=\"https:\/\/www.cnn.com\/2025\/03\/15\/politics\/judge-blocks-trump-wartime-authorities-alien-enemies-act\/index.html\">bloque\u00f3 temporalmente las deportaciones<\/a> para considerar las implicaciones de la aplicaci\u00f3n de la ley y dictamin\u00f3 ante el tribunal que cualquier avi\u00f3n que ya estuviera en el aire transportando migrantes deb\u00eda regresar a Estados Unidos. Sin embargo, el gobierno anunci\u00f3 este domingo que 250 deportados, presuntamente afiliados a la pandilla Tren de Aragua, se encontraban bajo custodia salvadore\u00f1a.<\/p>\n<p>Una declaraci\u00f3n cuidadosamente redactada por la secretaria de prensa de la Casa Blanca, Karoline Leavitt solo profundiz\u00f3 la intriga sobre si los funcionarios desafiaron al juez.<\/p>\n<p>La Administraci\u00f3n no se neg\u00f3 a cumplir una orden judicial. Esta, que carec\u00eda de fundamento legal, se emiti\u00f3 despu\u00e9s de que extranjeros terroristas (del Tren de Aragua) ya hubieran sido expulsados \u200b\u200bdel territorio estadounidense, declar\u00f3 Leavitt.<\/p>\n<p>\u201cUn solo juez en una sola ciudad no puede dirigir los movimientos de un portaaviones lleno de terroristas extranjeros que fueron expulsados \u200b\u200bf\u00edsicamente de suelo estadounidense\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Una distinci\u00f3n que Leavitt hizo sobre la orden \u201cescrita\u201d del juez, y el hecho de que indicara que los migrantes hab\u00edan salido de territorio estadounidense, pero no especificara en qu\u00e9 momento del cronograma llegaron a El Salvador, parece significativa. Sin embargo, su uso de la frase \u201cportaaviones\u201d resulta confuso. Y la Casa Blanca no tiene la facultad de decretar la legalidad de las \u00f3rdenes judiciales.<\/p>\n<p>A\u00fan no se sabe con certeza cu\u00e1ndo se dictaron las \u00f3rdenes de Boasberg ni c\u00f3mo se relacionan con la operaci\u00f3n de deportaci\u00f3n. Pero si la administraci\u00f3n desafiara al juez, podr\u00eda crear el mayor atolladero legal de la administraci\u00f3n hasta la fecha y alimentar\u00eda el temor de que una presidencia autoritaria pudiera desafiar abiertamente el Estado de Derecho.<\/p>\n<p>El drama apunta a una tendencia.<\/p>\n<p>Trump ejerce ahora un poder inmenso. Esto deja a quienes podr\u00edan limitarlo \u2014incluidos los tribunales y sus oponentes pol\u00edticos\u2014 con la tarea de cuestionarlo m\u00e1s tarde, despu\u00e9s de que sus acciones hayan generado un cambio casi irrevocable.<\/p>\n<p>La invocaci\u00f3n de la <a href=\"https:\/\/www.cnn.com\/2025\/03\/16\/politics\/trump-administration-deportations-alien-enemies-act\/index.html\">Ley de Enemigos Extranjeros<\/a> para acelerar las deportaciones es un paso importante, ya que su uso est\u00e1 limitado a tiempos de guerra.<\/p>\n<p>Mientras tanto, la represi\u00f3n de las protestas estudiantiles, resaltada por <a href=\"https:\/\/www.cnn.com\/2025\/03\/11\/us\/mahmoud-khalil-columbia-ice-green-card-hnk\/index.html\">el arresto de un palestino titular de una tarjeta verde,<\/a> se justifica con el argumento de que sus opiniones antiisrael\u00edes da\u00f1an los intereses de la pol\u00edtica exterior estadounidense, pero los cr\u00edticos ven un intento de aplastar los derechos de la Primera Enmienda y el disenso en educaci\u00f3n por parte de una Casa Blanca no controlada por la Constituci\u00f3n.<\/p>\n<p><a href=\"https:\/\/www.cnn.com\/2025\/03\/15\/media\/voice-of-america-trump-cuts\/index.html\">Mientras tanto, el cierre repentino<\/a> por parte de Trump del servicio internacional de radio y televisi\u00f3n financiado por los contribuyentes, Voice of America, durante el fin de semana, renov\u00f3 el debate sobre si tiene el poder de ignorar unilateralmente el gasto autorizado en las leyes aprobadas por el Congreso y sigui\u00f3 a sus escalofriantes afirmaciones del viernes de que los medios de comunicaci\u00f3n que no promueven sus opiniones de MAGA son \u201ccorruptos e ilegales\u201d.<\/p>\n<p>Millones de votantes enviaron a Trump a Washington para destruir instituciones que, seg\u00fan ellos, no reflejan su cultura, valores e intereses materiales. Y las encuestas muestran que, entre sus partidarios, las acciones de Trump gozan de popularidad.<\/p>\n<p>Su mantra es actuar con rapidez, ya que los l\u00edmites al poder presidencial son mayormente retroactivos, lo que significa que Trump puede obtener los resultados deseados antes de que puedan detenerlo. Un departamento gubernamental, por ejemplo, puede ser desmantelado irreparablemente por el Departamento de Eficiencia Gubernamental de Elon Musk, incluso si un juez ordena posteriormente la restauraci\u00f3n de los programas, fondos y trabajadores despedidos.<\/p>\n<p>La Ley de Enemigos Extranjeros de 1798 ha dado lugar a abusos que mancharon la historia estadounidense. Manch\u00f3 la reputaci\u00f3n del segundo presidente, John Adams, y se utiliz\u00f3 para justificar el internamiento de estadounidenses de origen japon\u00e9s durante la Segunda Guerra Mundial.<\/p>\n<p>El texto de la ley dice que puede invocarse siempre que se declare una guerra entre Estados Unidos y \u201ccualquier naci\u00f3n o gobierno extranjero\u201d o cuando \u201cse perpetre, intente o amenace con una invasi\u00f3n o incursi\u00f3n depredadora contra el territorio de Estados Unidos por cualquier naci\u00f3n o gobierno extranjero\u201d y el presidente haga una proclamaci\u00f3n a tal efecto.<\/p>\n<p>Pero Estados Unidos no est\u00e1 en guerra con Venezuela, y aunque Trump repiti\u00f3 con frecuencia que el pa\u00eds sufre una \u201cinvasi\u00f3n\u201d de migrantes indocumentados, delincuentes y pandilleros, el Congreso, no el presidente, tiene la responsabilidad constitucional de declarar la guerra. Por lo tanto, la pregunta inmediata es si Trump se extralimit\u00f3 en el ejercicio de sus funciones y en el ejercicio de su cargo con las deportaciones.<\/p>\n<p>La orden de restricci\u00f3n temporal de Boasberg ten\u00eda como objetivo crear tiempo para permitir que se resolvieran estos argumentos legales cr\u00edticos.<\/p>\n<p>El senador republicano de Dakota del Sur, Mike Rounds, declar\u00f3 este domingo a Jake Tapper de CNN en el programa \u201cState of the Union\u201d que desconoc\u00eda si el gobierno hab\u00eda ignorado la orden del juez de bloquear las deportaciones. Sin embargo, a\u00f1adi\u00f3: \u201cEsperamos que el poder ejecutivo cumpla la ley. Hemos dicho en el pasado que cumpliremos la ley\u2026 somos una rep\u00fablica constitucional y cumpliremos esas leyes\u201d.<\/p>\n<p>El secretario de Estado, Marco Rubio, anunci\u00f3 el domingo en X que m\u00e1s de 250 \u201cmiembros enemigos extranjeros del Tren de Aragua\u201d hab\u00edan sido enviados a El Salvador para ser retenidos en sus excelentes c\u00e1rceles a un precio justo. Estados Unidos est\u00e1 pagando US$ 6 millones por su alojamiento.<\/p>\n<p>El momento en que se ejecutaron las distintas \u00f3rdenes judiciales y las deportaciones est\u00e1 ahora en tela de juicio.<\/p>\n<p>Boasberg inicialmente hab\u00eda impedido que la administraci\u00f3n deportara a cinco personas que presentaron una impugnaci\u00f3n legal. Tras una audiencia posterior, ampli\u00f3 su acci\u00f3n para incluir a todos los extranjeros bajo custodia estadounidense sujetos a la proclamaci\u00f3n de Trump. La secretaria de Justicia, Pam Bondi, y otros altos funcionarios del Departamento de Justicia argumentaron en una presentaci\u00f3n este domingo que \u201calgunos pandilleros\u201d fueron deportados entre las dos \u00f3rdenes de Boasberg del s\u00e1bado. Afirmaron que los cinco demandantes iniciales no fueron deportados. La administraci\u00f3n ya ha apelado las medidas de la jueza.<\/p>\n<p>El caso tiene trascendencia m\u00e1s all\u00e1 de las instrucciones del juez.<\/p>\n<p>El derecho internacional generalmente proh\u00edbe la deportaci\u00f3n de personas a lugares donde podr\u00edan enfrentar persecuci\u00f3n. Las brutales condiciones de hacinamiento que enfrentan los reclusos en El Salvador podr\u00edan alcanzar ese umbral. Y el gobierno del presidente Nayib Bukele \u2014a quien los funcionarios de Trump elogian con frecuencia\u2014 est\u00e1 acusado de abusos constitucionales y de derechos humanos que contradicen la mayor parte de la comprensi\u00f3n de los valores de la pol\u00edtica exterior estadounidense en las \u00faltimas d\u00e9cadas.<\/p>\n<p>Adem\u00e1s, existen preocupaciones sobre por qu\u00e9 Trump est\u00e1 utilizando la infame Ley de Enemigos Extranjeros, dado que existen otros mecanismos para expulsar a pandilleros. La falta de transparencia del gobierno sobre la identidad de las personas deportadas tambi\u00e9n podr\u00eda plantear la posibilidad de que migrantes indocumentados que no son pandilleros sean privados de sus derechos legales, incluidos en la purga y condenados a un destino sombr\u00edo bajo custodia de El Salvador.<\/p>\n<p>\u201cDarles esta amplia libertad para simplemente\u2026 afirmar que alguien es algo que est\u00e1 mal\u201d, dijo la representante dem\u00f3crata de Texas Jasmine Crockett a Tapper. \u201cTenemos tribunales, tenemos procesos, tenemos leyes, y deber\u00edamos seguir adelante y aplicarlas\u201d.<\/p>\n<p>Pero los beneficios pol\u00edticos que obtiene Trump al actuar con celo autoritario son obvios y le permiten dar a entender que cualquiera que cuestione sus acciones se est\u00e1 poniendo del lado de criminales crueles que nadie quiere en Estados Unidos.<\/p>\n<p>\u201cGracias a El Salvador y, en particular, al presidente Bukele, por comprender esta horrible situaci\u00f3n, que se permiti\u00f3 que ocurriera en Estados Unidos debido al liderazgo dem\u00f3crata incompetente\u201d, escribi\u00f3 el presidente en Truth Social este domingo.<\/p>\n<p>La administraci\u00f3n tambi\u00e9n enfrenta preguntas sobre el manejo de la detenci\u00f3n del exestudiante de la Universidad de Columbia Mahmoud Khalil, un refugiado palestino cuya tarjeta verde fue revocada por su participaci\u00f3n en las protestas del a\u00f1o pasado por la guerra entre Israel y Hamas.<\/p>\n<p>\u00bfFue arrestado Khalil por actividades que legalmente podr\u00edan catalogarse como apoyo material a una organizaci\u00f3n terrorista, o se encuentra detenido en violaci\u00f3n de sus derechos amparados por la Primera Enmienda como residente legal permanente de Estados Unidos? Sus partidarios afirman que fue atacado \u00fanicamente por denunciar la ofensiva israel\u00ed contra Gaza tras los ataques del 7 de octubre de 2023.<\/p>\n<p>Pero Rubio argument\u00f3 este domingo en el programa \u201cFace the Nation\u201d de CBS que era \u201cmuy sencillo\u201d ver que Khalil hab\u00eda mentido al solicitar la residencia permanente sobre sus futuras actividades pol\u00edticas, que inclu\u00edan participar en eventos a favor de Hamas. \u201cPara empezar, nunca debimos haberlo dejado entrar. Si nos hubiera dicho: \u2018Voy para all\u00e1 y me convertir\u00e9 en el portavoz y uno de los l\u00edderes de un movimiento que va a revolucionar una de sus supuestas universidades de \u00e9lite\u2019 \u2014la gente ni siquiera puede ir a la escuela, las bibliotecas est\u00e1n siendo vandalizadas\u2014, nunca lo habr\u00edamos dejado entrar\u201d, dijo Rubio. El secretario de Estado reiter\u00f3 su argumento de que la actividad de Khalil iba \u201cen contra de los intereses de la pol\u00edtica exterior de Estados Unidos\u201d.<\/p>\n<p>La ley estadounidense establece que cualquier persona que \u201capoye o apoye actividades terroristas o convenza a otros a hacerlo\u201d no puede obtener una visa para ingresar al pa\u00eds. Sin embargo, es probable que el pr\u00f3ximo caso se centre parcialmente en si dichas prohibiciones se aplican a un residente permanente legal que ya se encuentra en Estados Unidos.<strong><\/strong><\/p>\n<p>Rubio no present\u00f3 pruebas en la entrevista de que Khalil hubiera cometido un delito, apoyado materialmente a un grupo terrorista o promovido el terrorismo. Si Khalil simplemente expresaba su apoyo a Hamas en general \u2014por muy vil que esto pueda parecerles a muchos estadounidenses\u2014, podr\u00eda considerarse que estaba ejerciendo su derecho a la libertad de expresi\u00f3n, protegido por la Constituci\u00f3n y que el gobierno no puede restringir.<\/p>\n<p>Este caso ha causado profunda preocupaci\u00f3n porque plantea la posibilidad de que cualquier inmigrante que no sea ciudadano pueda ser arrestado y deportado si dice cosas que el presidente o su gobierno decidan unilateralmente que son contrarias a los intereses de la pol\u00edtica exterior estadounidense.<\/p>\n<p>El caso de Khalil tambi\u00e9n se est\u00e1 litigando en los tribunales. Un juez federal bloque\u00f3 su deportaci\u00f3n y permanece bajo custodia del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE). Al igual que el caso de los presuntos pandilleros venezolanos, el caso parece destinado a llegar a la Corte Suprema, que se enfrentar\u00e1 a una oleada de casos sin precedentes que definir\u00e1n tanto a esta administraci\u00f3n como a la presidencia en el futuro.<\/p>\n<p>Todos los casos contienen esta pregunta de una forma u otra: \u00bfTiene Trump la enorme autoridad que se ha asignado a s\u00ed mismo en el intento m\u00e1s agresivo de ejercer el poder en la historia de la presidencia moderna?<\/p>\n<p>El presidente no espera los resultados. Est\u00e1 empe\u00f1ado en forjar cambios profundos en el gobierno, los valores y la cultura estadounidenses que ser\u00e1n dif\u00edciles de revertir para cualquier futuro presidente o Congreso.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Casa Blanca niega haber violado la orden de un juez emitida este s\u00e1bado de detener las deportaciones de presuntos pandilleros venezolanos a El Salvador, lo que, de ocurrir, acercar\u00eda al pa\u00eds al borde de una crisis constitucional en medio de los enfrentamientos legales de una administraci\u00f3n con pretensiones de amasar un vasto poder presidencial. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460004","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Casa Blanca niega haber violado la orden de un juez emitida este s\u00e1bado de detener las deportaciones de presuntos pandilleros venezolanos a El Salvador, lo que, de ocurrir, acercar\u00eda al pa\u00eds al borde de una crisis constitucional en medio de los enfrentamientos legales de una administraci\u00f3n con pretensiones de amasar un vasto poder presidencial. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T07:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos\",\"datePublished\":\"2025-03-17T07:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/\"},\"wordCount\":2053,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/\",\"name\":\"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-17T07:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos - Noticias","og_description":"La Casa Blanca niega haber violado la orden de un juez emitida este s\u00e1bado de detener las deportaciones de presuntos pandilleros venezolanos a El Salvador, lo que, de ocurrir, acercar\u00eda al pa\u00eds al borde de una crisis constitucional en medio de los enfrentamientos legales de una administraci\u00f3n con pretensiones de amasar un vasto poder presidencial. [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-17T07:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/"},"author":{"name":"","@id":""},"headline":"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos","datePublished":"2025-03-17T07:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/"},"wordCount":2053,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/","name":"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-17T07:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/casa-blanca-niega-deportaciones-venezolanos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-17T07:03:48Z","datePublished":"2025-03-17T07:03:48Z","dateModified":"2025-03-17T07:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Casa Blanca niega haber ignorado la orden judicial que detiene las deportaciones de venezolanos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/casa-blanca-niega-deportaciones-venezolanos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/casa-blanca-niega-deportaciones-venezolanos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-17T07:03:48Z\",\"datePublished\":\"2025-03-17T07:03:48Z\",\"dateModified\":\"2025-03-17T07:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461418,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/20\/juez-alito-critica-corte-suprema-orden-ley-enemigos-extranjeros-trax\/","url_meta":{"origin":1460004,"position":0},"title":"Juez Alito critica a la mayor\u00eda de la Corte Suprema por la orden &#171;sin precedentes&#187; de la Ley de Enemigos Extranjeros","author":"","date":"abril 20, 2025","format":false,"excerpt":"El juez de la Corte Suprema Samuel Alito dio una cr\u00edtica contundente durante el fin de semana reprochando a sus colegas por una orden temporal emitida horas antes que detuvo al presidente Donald Trump de deportar a un grupo de venezolanos bajo la Ley de Enemigos Extranjeros.\u201cLiteralmente, en medio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460182,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/20\/james-boasberg-juez-trump-deportaciones-venezolanos-ley-enemigos-extranjeros-orix\/","url_meta":{"origin":1460004,"position":1},"title":"\u00bfQui\u00e9n es James Boasberg, el juez que ha intentado impedir las deportaciones de Trump bajo la Ley de Enemigos Extranjeros?","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Cuando el Gobierno de Donald Trump invoc\u00f3 el fin de semana la Ley de Enemigos Extranjeros para deportar a El Salvador a cientos de venezolanos a quienes se\u00f1alan como miembros del Tren de Aragua, un juez intent\u00f3 impedirlo. Los vuelos siguieron su rumbo, pero el magistrado fue objeto de fuertes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460031,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","url_meta":{"origin":1460004,"position":2},"title":"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &#171;celebrados&#187;","author":"","date":"marzo 17, 2025","format":false,"excerpt":"El \u201czar de la frontera\u201d de la Casa Blanca, Tom Homan, defendi\u00f3 este lunes la deportaci\u00f3n por parte del gobierno de cientos de presuntos pandilleros, en su mayor\u00eda venezolanos, a El Salvador, a pesar de la orden de un juez federal de revertir los vuelos.\u201cPara cuando lleg\u00f3 la otra orden,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460015,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/","url_meta":{"origin":1460004,"position":3},"title":"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario","author":"","date":"marzo 17, 2025","format":false,"excerpt":"M\u00e1s de la mitad de las 261 deportaciones de inmigrantes \u200b\u200ba El Salvador se hicieron bajo una amplia autoridad de tiempos de guerra, conocida como Ley de Enemigos Extranjeros, invocada por el Gobierno de Trump, seg\u00fan un alto funcionario de la Casa Blanca.De los 261 enviados a la naci\u00f3n centroamericana,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462269,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/13\/trump-corte-suprema-deportacion-200-migrantes-venezolanos-trax\/","url_meta":{"origin":1460004,"position":4},"title":"El gobierno de Trump solicita a la Corte Suprema de Justicia que reanude la deportaci\u00f3n de casi 200 migrantes venezolanos","author":"","date":"mayo 13, 2025","format":false,"excerpt":"El gobierno de Trump solicit\u00f3 este lunes a la Corte Suprema de Justicia que le permita reanudar las deportaciones de casi 200 migrantes venezolanos detenidos en Texas, e inst\u00f3 al alto tribunal levantar una orden del mes pasado que suspendi\u00f3 temporalmente la expulsi\u00f3n de migrantes sujetos a la Ley de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461481,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/22\/migrantes-venezolanos-trump-orden-corte-suprema-trax\/","url_meta":{"origin":1460004,"position":5},"title":"Migrantes venezolanos afirman que la administraci\u00f3n Trump no cumple con la orden de la Corte Suprema","author":"","date":"abril 22, 2025","format":false,"excerpt":"Un grupo de inmigrantes venezolanos que la administraci\u00f3n Trump ten\u00eda en la mira para su deportaci\u00f3n bajo una amplia autoridad en tiempos de guerra dijo a la Corte Suprema que el aviso que les dieron los funcionarios de inmigraci\u00f3n sobre su inminente deportaci\u00f3n no cumple con una orden anterior del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1460004"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460004\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1460004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1460004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1460004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}