{"id":1460015,"date":"2025-03-17T08:03:43","date_gmt":"2025-03-17T15:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/"},"modified":"2025-03-17T08:03:43","modified_gmt":"2025-03-17T15:03:43","slug":"deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/","title":{"rendered":"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario"},"content":{"rendered":"<p>M\u00e1s de la mitad de las<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/16\/eeuu\/trump-deporta-ley-enemigos-extranjeros-juez-trax\"> 261 deportaciones de inmigrantes \u200b\u200ba El Salvador<\/a> se hicieron bajo una amplia autoridad de tiempos de guerra, conocida como Ley de Enemigos Extranjeros, invocada por el Gobierno de Trump, seg\u00fan un alto funcionario de la Casa Blanca.<\/p>\n<p>De los 261 enviados a la naci\u00f3n centroamericana, 137 personas fueron deportadas bajo la proclamaci\u00f3n firmada el s\u00e1bado, mientras que el resto fueron deportados bajo otras leyes federales, incluidos inmigrantes de El Salvador con presuntos v\u00ednculos con la pandilla MS-13.<\/p>\n<p>Los funcionarios del Gobierno de Trump han descrito a algunos de los expulsados \u200b\u200bdurante el fin de semana como presuntos miembros de la pandilla venezolana Tren de Aragua, lo que sirvi\u00f3 de base para la proclamaci\u00f3n presidencial que invoca la Ley de Enemigos Extranjeros.<\/p>\n<p>Los presuntos <a href=\"https:\/\/www.cnn.com\/2025\/03\/16\/politics\/trump-administration-deportations-alien-enemies-act\/index.html\">pandilleros<\/a>, en su mayor\u00eda venezolanos, fueron deportados de Estados Unidos a una prisi\u00f3n en El Salvador el domingo, y el Gobierno Trump invoc\u00f3 la Ley de Enemigos Extranjeros para acelerar las deportaciones a pesar de un fallo judicial que detuvo la medida.<\/p>\n<p>En el \u00faltimo enfrentamiento dram\u00e1tico entre la Casa Blanca y el poder judicial, un juez federal bloque\u00f3 temporalmente la capacidad de la administraci\u00f3n de usar la centenaria ley el s\u00e1bado por la noche, y orden\u00f3 verbalmente a todos los aviones en el aire que transportaran a algunos de esos migrantes que regresaran a Estados Unidos.<\/p>\n<p>El juez de distrito estadounidense James Boasberg dijo que la orden de restricci\u00f3n temporal permanecer\u00e1 vigente durante 14 d\u00edas \u201co hasta nueva orden del tribunal\u201d. Una persona familiarizada con el asunto dijo que los aviones ya estaban en el aire en el momento del fallo del juez.<\/p>\n<p>\u201cEn particular, dada la informaci\u00f3n de los demandantes, no refutada por el gobierno, de que los vuelos est\u00e1n saliendo activamente y planeando partir, no creo poder esperar m\u00e1s\u201d, dijo el juez federal de distrito James Boasberg durante la audiencia. \u201cCualquier avi\u00f3n que contenga a estas personas, que vaya a despegar o est\u00e9 en el aire debe ser devuelto a Estados Unidos\u201d.<\/p>\n<p>Pero el domingo por la noche, el presidente Donald Trump defendi\u00f3 su uso de la Ley, diciendo a los periodistas a bordo del Air Force One: \u201cLes puedo decir esto, estas eran malas personas. Ese era un mal grupo de, como digo, hombres\u201d.<\/p>\n<p>El uso anterior de la Ley de Enemigos Extranjeros tuvo lugar en tiempos de guerra, pero Trump argument\u00f3 que \u201cesto era una \u00e9poca de guerra\u201d y una \u201cinvasi\u00f3n\u201d de migrantes y criminales, repitiendo sus afirmaciones pasadas sobre el manejo de la inmigraci\u00f3n por parte de la administraci\u00f3n Biden.<\/p>\n<p>Cuando se le pregunt\u00f3 si su gobierno hab\u00eda violado la orden del juez, Trump respondi\u00f3: \u201cTendr\u00eda que hablar con los abogados sobre eso\u201d.<\/p>\n<p>La secretaria de Prensa de la Casa Blanca, Karoline Leavitt, tambi\u00e9n dijo el domingo que el Gobierno no viol\u00f3 la orden del juez porque fue emitida despu\u00e9s de que los migrantes en cuesti\u00f3n hab\u00edan abandonado Estados Unidos.<\/p>\n<p>\u201cEl Gobierno no se \u2018neg\u00f3 a cumplir\u2019 una orden judicial. La orden, que no ten\u00eda base legal, fue emitida despu\u00e9s de que los extranjeros terroristas (del Tren de Aragua) ya hab\u00edan sido expulsados \u200b\u200bdel territorio estadounidense\u201d, dijo Leavitt en un comunicado, insistiendo en que no hab\u00eda conflicto entre las acciones de la administraci\u00f3n y la orden escrita.<\/p>\n<p>\u201cUn solo juez en una sola ciudad no puede dirigir los movimientos de un portaaviones lleno de terroristas extranjeros que fueron expulsados \u200b\u200bf\u00edsicamente de suelo estadounidense\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Este lunes los abogados de ACLU\/Democracy Forward pidieron a Boasberg que solicite inmediatamente respuestas al Gobierno de Trump sobre las deportaciones que ocurrieron el s\u00e1bado.<\/p>\n<p>En una presentaci\u00f3n presentada durante la noche, dijeron que los informes de los medios, los datos p\u00fablicos y la propia presentaci\u00f3n del Departamento de Justicia el domingo sugieren \u201cque los acusados \u200b\u200bpueden haber violado las \u00f3rdenes del tribunal\u201d.<\/p>\n<p>Piden al juez Boasberg que ordene \u201cinmediatamente\u201d al Departamento de Justicia que \u201cpresente una o m\u00e1s declaraciones juradas de personas con conocimiento directo de los hechos\u201d.<\/p>\n<p>Leavitt dijo m\u00e1s temprano el domingo que, por orden del presidente, el Departamento de Seguridad Nacional hab\u00eda arrestado a casi 300 miembros de la pandilla venezolana Tren de Aragua durante el fin de semana. El secretario de Estado, Marco Rubio, tambi\u00e9n dijo que \u201ccientos de criminales violentos fueron enviados fuera de nuestro pa\u00eds\u201d y agradeci\u00f3 al presidente de El Salvador, Nayib Bukele, por ofrecer encarcelar a los deportados.<\/p>\n<p>Agreg\u00f3 que Bukele hab\u00eda solicitado que dos l\u00edderes de la pandilla MS-13, as\u00ed como otros 21 salvadore\u00f1os detenidos en Estados Unidos, fueran devueltos para \u201cenfrentar la justicia en su patria\u201d.<\/p>\n<p>Bukele anunci\u00f3 la ma\u00f1ana del domingo que los presuntos integrantes del Tren de Aragua llegaron a El Salvador y fueron trasladados al Centro de Confinamiento del Terrorismo, o CECOT, \u201cpor el plazo de un a\u00f1o\u201d. Su publicaci\u00f3n incluy\u00f3 un video de hombres siendo sacados de autobuses esposados \u200b\u200by con la cabeza rapada.<\/p>\n<p>Trump, en Truth Social, <a href=\"https:\/\/truthsocial.com\/@realDonaldTrump\/posts\/114173862724361939\">agradeci\u00f3 <\/a>al l\u00edder salvadore\u00f1o por aceptar a los deportados horas despu\u00e9s.<\/p>\n<p>La cooperaci\u00f3n entre ambos l\u00edderes ha sido una posibilidad desde hace alg\u00fan tiempo. CNN <a href=\"https:\/\/www.cnn.com\/2025\/03\/13\/politics\/erik-prince-return-maneuvered-inside-trump-orbit\/index.html\">inform\u00f3 <\/a>anteriormente que Erik Prince, un aliado de Trump, ha estado en contacto con Bukele desde el a\u00f1o pasado sobre la posibilidad de aceptar inmigrantes indocumentados de Estados Unidos si Trump era elegido.<\/p>\n<p>EE.UU. pagar\u00e1 US$ 6 millones a El Salvador para albergar a los deportados. El dinero, seg\u00fan Bukele, ayudar\u00e1 a sostener el sistema penitenciario, que actualmente cuesta US$ 200 millones anuales. Agreg\u00f3 que la acci\u00f3n ayudar\u00e1 a las fuerzas del orden a recopilar inteligencia y detener a m\u00e1s miembros de la MS-13.<\/p>\n<p>Bukele tambi\u00e9n pareci\u00f3 restarle importancia al incidente la madrugada del domingo. Al compartir una captura de pantalla de un art\u00edculo sobre el fallo del s\u00e1bado, <a href=\"https:\/\/x.com\/nayibbukele\/status\/1901238762614517965\">escribi\u00f3 <\/a>en X: \u201cUps\u2026 demasiado tarde\u201d. Posteriormente Rubio comparti\u00f3 la publicaci\u00f3n de Bukele en su propia p\u00e1gina.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de la mitad de las 261 deportaciones de inmigrantes \u200b\u200ba El Salvador se hicieron bajo una amplia autoridad de tiempos de guerra, conocida como Ley de Enemigos Extranjeros, invocada por el Gobierno de Trump, seg\u00fan un alto funcionario de la Casa Blanca. De los 261 enviados a la naci\u00f3n centroamericana, 137 personas fueron deportadas [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460015","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario - Noticias\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de la mitad de las 261 deportaciones de inmigrantes \u200b\u200ba El Salvador se hicieron bajo una amplia autoridad de tiempos de guerra, conocida como Ley de Enemigos Extranjeros, invocada por el Gobierno de Trump, seg\u00fan un alto funcionario de la Casa Blanca. De los 261 enviados a la naci\u00f3n centroamericana, 137 personas fueron deportadas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T15:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario\",\"datePublished\":\"2025-03-17T15:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/\"},\"wordCount\":1058,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/\",\"name\":\"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-17T15:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario - Noticias","og_description":"M\u00e1s de la mitad de las 261 deportaciones de inmigrantes \u200b\u200ba El Salvador se hicieron bajo una amplia autoridad de tiempos de guerra, conocida como Ley de Enemigos Extranjeros, invocada por el Gobierno de Trump, seg\u00fan un alto funcionario de la Casa Blanca. De los 261 enviados a la naci\u00f3n centroamericana, 137 personas fueron deportadas [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-17T15:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/"},"author":{"name":"","@id":""},"headline":"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario","datePublished":"2025-03-17T15:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/"},"wordCount":1058,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/","name":"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-17T15:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"M\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-17T15:03:43Z","datePublished":"2025-03-17T15:03:43Z","dateModified":"2025-03-17T15:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"M\\u00e1s de la mitad de las deportaciones a El Salvador se hicieron bajo la Ley de Enemigos Extranjeros, dice funcionario\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/deportaciones-el-salvador-ley-de-enemigos-extranjeros-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-17T15:03:43Z\",\"datePublished\":\"2025-03-17T15:03:43Z\",\"dateModified\":\"2025-03-17T15:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460031,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","url_meta":{"origin":1460015,"position":0},"title":"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &#171;celebrados&#187;","author":"","date":"marzo 17, 2025","format":false,"excerpt":"El \u201czar de la frontera\u201d de la Casa Blanca, Tom Homan, defendi\u00f3 este lunes la deportaci\u00f3n por parte del gobierno de cientos de presuntos pandilleros, en su mayor\u00eda venezolanos, a El Salvador, a pesar de la orden de un juez federal de revertir los vuelos.\u201cPara cuando lleg\u00f3 la otra orden,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460638,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/31\/deportaciones-presuntos-pandilleros-el-salvador-trax\/","url_meta":{"origin":1460015,"position":1},"title":"Rubio dice que EE.UU. deport\u00f3 a 17 presuntos pandilleros del Tren de Aragua y la MS-13 el domingo","author":"","date":"marzo 31, 2025","format":false,"excerpt":"El secretario de Estado de Estados Unidos, Marco Rubio, dijo que 17 presuntos miembros del Tren de Aragua y de la MS-13 fueron deportados por el ej\u00e9rcito estadounidense el domingo por la noche.Rubio describi\u00f3 la deportaci\u00f3n como \u201cuna exitosa operaci\u00f3n antiterrorista con nuestros aliados en El Salvador\u201d.\u201cUna vez m\u00e1s, extendemos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461723,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/28\/trump-el-salvador-negociaciones-deportados-cecot-trax\/","url_meta":{"origin":1460015,"position":2},"title":"Gobierno de Trump propuso en negociaciones enviar hasta 500 presuntos miembros de pandillas a megaprisi\u00f3n de El Salvador","author":"","date":"abril 28, 2025","format":false,"excerpt":"Estados Unidos propuso enviar hasta 500 inmigrantes venezolanos con presuntos v\u00ednculos con la pandilla Tren de Aragua a El Salvador mientras los dos gobiernos buscan llegar a un acuerdo sobre el uso de la megaprisi\u00f3n de la naci\u00f3n centroamericana, seg\u00fan correos electr\u00f3nicos vistos por CNN.Los detalles del acuerdo, que no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459989,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/16\/trump-deporta-ley-enemigos-extranjeros-juez-trax\/","url_meta":{"origin":1460015,"position":3},"title":"Gobierno de Trump deporta a cientos de personas bajo la Ley de Enemigos Extranjeros a pesar de prohibici\u00f3n de juez","author":"","date":"marzo 16, 2025","format":false,"excerpt":"El Gobierno de Trump anunci\u00f3 este domingo que cientos de personas fueron deportadas del pa\u00eds despu\u00e9s de que el presidente Donald Trump invocara la Ley de Enemigos Extranjeros, una amplia facultad para tiempos de guerra que solo se ha utilizado en tres ocasiones anteriores, para acelerar las deportaciones de migrantes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460203,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/20\/que-ganan-el-salvador-bukele-deportados-ee-uu-orix\/","url_meta":{"origin":1460015,"position":4},"title":"\u00bfQu\u00e9 ganan El Salvador y Bukele recibiendo deportados de EE.UU.?","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Con las cabezas rapadas, encorvados y esposados de pies y manos. As\u00ed ingresaron al Centro de Confinamiento de Terrorismo (Cecot) de El Salvador los 261 inmigrantes deportados por Estados Unidos bajo \u00f3rdenes del presidente Donald Trump.Funcionarios estadounidenses describieron a algunos de los expulsados como presuntos miembros de la organizaci\u00f3n criminal\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460161,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/19\/gobierno-trump-inmigrantes-deportados-miembros-pandillas-evidencia-trax\/","url_meta":{"origin":1460015,"position":5},"title":"El Gobierno de Trump dice que los inmigrantes deportados son miembros de pandillas, pero no los nombra ni revela evidencia","author":"","date":"marzo 19, 2025","format":false,"excerpt":"El Gobierno de Trump ha deportado a cientos de inmigrantes mientras se niega a revelar sus identidades o la evidencia en su contra, lo que ha generado quejas por parte de las familias de los migrantes y de cr\u00edticos que dicen que la administraci\u00f3n est\u00e1 pisoteando las libertades civiles.El Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1460015"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460015\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1460015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1460015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1460015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}