{"id":1460031,"date":"2025-03-17T12:03:38","date_gmt":"2025-03-17T19:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/"},"modified":"2025-03-17T12:03:38","modified_gmt":"2025-03-17T19:03:38","slug":"zar-frontera-trump-defiende-deportacion-celebracion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","title":{"rendered":"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &#171;celebrados&#187;"},"content":{"rendered":"<p>El \u201czar de la frontera\u201d de la Casa Blanca, Tom Homan, defendi\u00f3 este lunes la deportaci\u00f3n por parte del gobierno de cientos de presuntos pandilleros, en su mayor\u00eda venezolanos, a El Salvador, a pesar de la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/15\/eeuu\/juez-federal-prohibe-trump-expulsar-inmigrantes-ley-enemigos-extranjeros-trax\">orden de un juez federal<\/a> de revertir los vuelos.<\/p>\n<p>\u201cPara cuando lleg\u00f3 la otra orden, el avi\u00f3n ya estaba sobre aguas internacionales lleno de terroristas y representando importantes amenazas para la seguridad p\u00fablica\u201d, declar\u00f3 Homan a la prensa a las afueras de la Casa Blanca. \u201cEl presidente hizo exactamente lo correcto\u201d.<\/p>\n<p>Y a\u00f1adi\u00f3: \u201cExpulsamos a terroristas. Eso deber\u00eda ser una celebraci\u00f3n en este pa\u00eds\u201d.<\/p>\n<p>Cuando Alayna Treene, de CNN, le pidi\u00f3 que explicara el momento de la orden del juez, Homan evadi\u00f3 el tema y dijo: \u201cEl presidente, mediante proclamaci\u00f3n, se apoder\u00f3 de su autoridad bajo la Ley de Enemigos Extranjeros y la impuso, lo cual tiene derecho a hacer\u201d.<\/p>\n<p>M\u00e1s de la mitad de las<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/16\/eeuu\/trump-deporta-ley-enemigos-extranjeros-juez-trax\"> 261 deportaciones de inmigrantes \u200b\u200ba El Salvador<\/a> realizadas el domingo se hicieron bajo una amplia autoridad de tiempos de guerra, conocida como Ley de Enemigos Extranjeros, invocada por el Gobierno de Trump, seg\u00fan un alto funcionario de la Casa Blanca.<\/p>\n<p>De los 261 enviados a la naci\u00f3n centroamericana, 137 personas fueron deportadas bajo la proclamaci\u00f3n firmada el s\u00e1bado, mientras que el resto fueron deportados bajo otras leyes federales, incluidos inmigrantes de El Salvador con presuntos v\u00ednculos con la pandilla MS-13.<\/p>\n<p>Los funcionarios del Gobierno de Trump han descrito a algunos de los expulsados \u200b\u200bdurante el fin de semana como presuntos miembros de la pandilla venezolana Tren de Aragua, lo que sirvi\u00f3 de base para la proclamaci\u00f3n presidencial que invoca la Ley de Enemigos Extranjeros.<\/p>\n<p>Los presuntos <a href=\"https:\/\/www.cnn.com\/2025\/03\/16\/politics\/trump-administration-deportations-alien-enemies-act\/index.html\">pandilleros<\/a>, en su mayor\u00eda venezolanos, fueron deportados de Estados Unidos a una prisi\u00f3n en El Salvador el domingo, y el Gobierno Trump invoc\u00f3 la Ley de Enemigos Extranjeros para acelerar las deportaciones a pesar de un fallo judicial que detuvo la medida.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u201czar de la frontera\u201d de la Casa Blanca, Tom Homan, defendi\u00f3 este lunes la deportaci\u00f3n por parte del gobierno de cientos de presuntos pandilleros, en su mayor\u00eda venezolanos, a El Salvador, a pesar de la orden de un juez federal de revertir los vuelos. \u201cPara cuando lleg\u00f3 la otra orden, el avi\u00f3n ya estaba [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460031","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El &quot;zar de la frontera&quot; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &quot;celebrados&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El &quot;zar de la frontera&quot; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &quot;celebrados&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"El \u201czar de la frontera\u201d de la Casa Blanca, Tom Homan, defendi\u00f3 este lunes la deportaci\u00f3n por parte del gobierno de cientos de presuntos pandilleros, en su mayor\u00eda venezolanos, a El Salvador, a pesar de la orden de un juez federal de revertir los vuelos. \u201cPara cuando lleg\u00f3 la otra orden, el avi\u00f3n ya estaba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T19:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &#171;celebrados&#187;\",\"datePublished\":\"2025-03-17T19:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/\"},\"wordCount\":371,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/\",\"name\":\"El \\\"zar de la frontera\\\" de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser \\\"celebrados\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-17T19:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &#171;celebrados&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El \"zar de la frontera\" de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser \"celebrados\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El \"zar de la frontera\" de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser \"celebrados\" - Noticias","og_description":"El \u201czar de la frontera\u201d de la Casa Blanca, Tom Homan, defendi\u00f3 este lunes la deportaci\u00f3n por parte del gobierno de cientos de presuntos pandilleros, en su mayor\u00eda venezolanos, a El Salvador, a pesar de la orden de un juez federal de revertir los vuelos. \u201cPara cuando lleg\u00f3 la otra orden, el avi\u00f3n ya estaba [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-17T19:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/"},"author":{"name":"","@id":""},"headline":"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &#171;celebrados&#187;","datePublished":"2025-03-17T19:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/"},"wordCount":371,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","name":"El \"zar de la frontera\" de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser \"celebrados\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-17T19:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &#171;celebrados&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\u00f3n y dice que deber\u00edan ser &#171;celebrados&#187;","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/zar-frontera-trump-defiende-deportacion-celebracion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-17T19:03:38Z","datePublished":"2025-03-17T19:03:38Z","dateModified":"2025-03-17T19:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El &#171;zar de la frontera&#187; de Trump defiende los vuelos de deportaci\\u00f3n y dice que deber\\u00edan ser &#171;celebrados&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/zar-frontera-trump-defiende-deportacion-celebracion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/zar-frontera-trump-defiende-deportacion-celebracion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-17T19:03:38Z\",\"datePublished\":\"2025-03-17T19:03:38Z\",\"dateModified\":\"2025-03-17T19:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460156,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/19\/zar-frontera-trump-fallo-vuelos-deportacion-trax\/","url_meta":{"origin":1460031,"position":0},"title":"El &#171;zar de la frontera&#187; de Trump dice que el fallo que detiene temporalmente vuelos de deportaci\u00f3n no ha frenado la operaci\u00f3n","author":"","date":"marzo 19, 2025","format":false,"excerpt":"El \u201czar de la frontera\u201d del presidente Donald Trump, Tom Homan, dijo este mi\u00e9rcoles que el fallo de un juez federal que detiene temporalmente las deportaciones bajo la Ley de Enemigos Extranjeros no ha ralentizado los esfuerzos del Gobierno para deportar a migrantes de Estados Unidos.\u201cNo, estamos ah\u00ed arrestando personas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461333,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/17\/zar-frontera-deportacion-abrego-garcia-carece-sentido-trax\/","url_meta":{"origin":1460031,"position":1},"title":"El &#171;zar de la frontera&#187; de Trump dice que la orden de 2019 que bloquea la deportaci\u00f3n de \u00c1brego Garc\u00eda &#171;carece de sentido&#187;","author":"","date":"abril 17, 2025","format":false,"excerpt":"El \u201czar de la frontera\u201d del presidente Donald Trump, Tom Homan, argument\u00f3 este jueves que la orden judicial que proh\u00edbe expl\u00edcitamente la deportaci\u00f3n de un hombre de Maryland a su pa\u00eds de origen, El Salvador, \u201ccarece de sentido\u201d porque el Gobierno de Trump design\u00f3 a la pandilla MS-13 como una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456743,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/12\/18\/zar-frontera-trump-plan-deportaciones-financiamiento-trax\/","url_meta":{"origin":1460031,"position":2},"title":"El &#171;zar de la frontera&#187; de Trump dice que necesitar\u00e1 financiamiento y 100.000 camas para realizar sus planes de deportaci\u00f3n","author":"","date":"diciembre 18, 2024","format":false,"excerpt":"Tom Homan, a quien Donald Trump ha designado como el \u201czar de la frontera\u201d de su pr\u00f3xima administraci\u00f3n, dijo este mi\u00e9rcoles por la noche que se est\u00e1n planeando deportaciones de inmigrantes indocumentados a gran escala y que necesitar\u00e1 financiamiento del Congreso para hacerlo.En una entrevista con Kaitlan Collins de CNN,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460313,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/23\/zar-frontera-trump-criticas-debido-proceso-inmigrantes-deportados-trax\/","url_meta":{"origin":1460031,"position":3},"title":"El &#171;zar de la frontera&#187; de Trump desestima las cr\u00edticas sobre el debido proceso para inmigrantes deportados","author":"","date":"marzo 23, 2025","format":false,"excerpt":"El \u201czar de la frontera\u201d del presidente Donald Trump, Tom Homan, rechaz\u00f3 este domingo las cr\u00edticas de quienes han expresado preocupaciones sobre los derechos legales de los inmigrantes despu\u00e9s de que el presidente invocara una ley de tiempos de guerra del siglo XVIII para otorgarle amplia autoridad sobre las deportaciones.\u201c\u00bfDebido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461720,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/28\/gobierno-trump-deportacion-ninos-decision-padres-trax\/","url_meta":{"origin":1460031,"position":4},"title":"Gobierno de Trump dice que la deportaci\u00f3n de ni\u00f1os estadounidenses se debi\u00f3 a una &#171;decisi\u00f3n de los padres&#187;","author":"","date":"abril 28, 2025","format":false,"excerpt":"El Gobierno de Trump defendi\u00f3 su decisi\u00f3n de deportar a tres ni\u00f1os que de nacionalidad estadounidense durante el fin de semana, argumentando el lunes que la decisi\u00f3n fue tomada por los padres, quienes estaban siendo deportados como inmigrantes indocumentados.\u201cSi te quedas en este pa\u00eds ilegalmente y haces caso omiso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461259,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/16\/trump-vance-defienden-politicas-deportacion-caso-abrego-garcia-trax\/","url_meta":{"origin":1460031,"position":5},"title":"Trump y Vance defienden las pol\u00edticas de deportaci\u00f3n de EE.UU. en medio del caso de \u00c1brego Garc\u00eda","author":"","date":"abril 16, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, dijo que su trabajo es sacar a los \u201casesinos y matones\u201d de EE.UU., en una aparente defensa de las t\u00e1cticas de su gobierno para deportar a quienes seg\u00fan ellos son terroristas y criminales extranjeros indocumentados.\u201cEl somnoliento Joe Biden, EL PEOR PRESIDENTE DE LA\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1460031"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460031\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1460031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1460031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1460031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}