{"id":1460033,"date":"2025-03-17T14:03:39","date_gmt":"2025-03-17T21:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/"},"modified":"2025-03-17T14:03:39","modified_gmt":"2025-03-17T21:03:39","slug":"carteles-droga-redes-sociales-reclutar-jovenes-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/","title":{"rendered":"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes"},"content":{"rendered":"<p>La Secretar\u00eda de Seguridad de M\u00e9xico alert\u00f3 que los carteles del narcotr\u00e1fico est\u00e1n utilizando redes sociales para atraer, y en algunos casos forzar, a j\u00f3venes a unirse a sus filas.<\/p>\n<p>Seg\u00fan la Unidad de Inteligencia de la Polic\u00eda Federal, se han identificado varias cuentas en plataformas digitales que operan con este prop\u00f3sito.<\/p>\n<p>El secretario de Seguridad P\u00fablica, Omar Garc\u00eda Harfuch, explic\u00f3 que constantemente detectan y eliminan perfiles de este tipo, aunque algunas de estas cuentas resultan ser falsas. \u201cLas investigaciones contin\u00faan cuando se trata de casos reales\u201d, afirm\u00f3.<\/p>\n<p>Las declaraciones del secretario de Seguridad se dan en el contexto del <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/03\/10\/mexico\/video\/campo-exterminio-teuchitlan-jalisco-madres-buscadoras-perspectivas-mexico-tv\">hallazgo de un terreno en Teuchitl\u00e1n<\/a>, Jalisco, que colectivos y organizaciones de derechos humanos identificaron como un presunto centro de reclutamiento forzado y explotaci\u00f3n laboral.<\/p>\n<p>La representante del colectivo Guerreros Buscadores de Jalisco, Indira Navarro, se\u00f1al\u00f3 que personas reportadas como desaparecidas eran llevadas a este sitio. Seg\u00fan su testimonio, algunas v\u00edctimas eran enga\u00f1adas con ofertas de trabajo prometiendo pagos de hasta 6.000 pesos- equivalente a US$ 300- semanales. \u201cLos citaban en la central de autobuses, les quitaban el celular, quemaban sus pertenencias. Esto coincide con lo que nos han contado j\u00f3venes con los que he hablado\u201d, detall\u00f3.<\/p>\n<p>A pesar de que el colectivo denunci\u00f3 estos hechos ante las autoridades locales, Navarro afirm\u00f3 que no recibieron respuesta. La Fiscal\u00eda de Jalisco dijo a CNN que est\u00e1n investigando lo sucedido en el lugar.<\/p>\n<p>Los grupos delictivos tambi\u00e9n han puesto su mirada en estudiantes universitarios.<\/p>\n<p>El coordinador de Seguridad de la Universidad de Guadalajara, Montalberti Serrano, afirm\u00f3 que han detectado casos de alumnos que fueron contactados a trav\u00e9s de redes sociales con falsas ofertas de empleo.<\/p>\n<p>\u201cUn amigo invita al otro y la informaci\u00f3n se comparte, algunos creen que se trata de una oportunidad real y acuden sin saber en lo que se est\u00e1n metiendo\u201d, explic\u00f3.<\/p>\n<p>La Fiscal\u00eda de Jalisco asegur\u00f3 a CNN que trabajan en conjunto con universidades p\u00fablicas y privadas para prevenir estos reclutamientos y que las denuncias est\u00e1n siendo atendidas.<\/p>\n<p>Un <a href=\"https:\/\/www.nytimes.com\/es\/2024\/12\/01\/espanol\/america-latina\/mexico-fentanilo-carteles-estudiantes-quimica.html\">reportaje publicado por The New York Times<\/a> en diciembre de 2024 revel\u00f3 que carteles del narcotr\u00e1fico estar\u00edan reclutando estudiantes de qu\u00edmica para la fabricaci\u00f3n de fentanilo. Sin embargo, la presidenta de M\u00e9xico, Claudia Sheinbaum, desestim\u00f3 la publicaci\u00f3n, asegurando que su Gobierno no tiene registro de algo similar.<\/p>\n<p>Un estudio publicado en 2023 por la revista Science revel\u00f3 que miles de personas son reclutadas cada a\u00f1o por grupos criminales en M\u00e9xico<\/p>\n<p>Seg\u00fan el modelo matem\u00e1tico utilizado en la investigaci\u00f3n, basado en datos p\u00fablicos sobre detenciones, homicidios y desapariciones, los carteles mexicanos contar\u00edan con alrededor de 175.000 miembros, lo que los convertir\u00eda en el quinto mayor empleador del pa\u00eds.<\/p>\n<p>El investigador y expolic\u00eda de la Ciudad de M\u00e9xico, Rafael Prieto Curiel, explic\u00f3 que estos grupos recurren al reclutamiento como una estrategia para reponer las p\u00e9rdidas que sufren debido a operativos de la polic\u00eda, el ej\u00e9rcito y la Guardia Nacional.<\/p>\n<p>La Administraci\u00f3n para el Control de Drogas de Estados Unidos (DEA por sus silgas en ingl\u00e9s) inform\u00f3 en julio de 2023 que los carteles de Sinaloa y Jalisco Nueva Generaci\u00f3n sumaban m\u00e1s de 44.800 miembros con operaciones en aproximadamente 100 pa\u00edses.<\/p>\n<p>Sin embargo, en su momento, el entonces presidente Andr\u00e9s Manuel L\u00f3pez Obrador rechaz\u00f3 estas cifras y pidi\u00f3 pruebas a la agencia estadounidense.<\/p>\n<p>Actualmente, no existen cifras oficiales sobre la cantidad de personas que integran los carteles en M\u00e9xico, a pesar de ello, s\u00ed hay datos sobre el n\u00famero de desaparecidos en el pa\u00eds.<\/p>\n<p>Seg\u00fan la Comisi\u00f3n Nacional de B\u00fasqueda del Gobierno Federal, hasta el 12 de marzo de 2025, m\u00e1s de 124.000 personas est\u00e1n registradas como desaparecidas en M\u00e9xico.<\/p>\n<p>El estado de Jalisco encabeza la lista con 15.000 desapariciones, aunque los registros no especifican las circunstancias en las que ocurri\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar\u00eda de Seguridad de M\u00e9xico alert\u00f3 que los carteles del narcotr\u00e1fico est\u00e1n utilizando redes sociales para atraer, y en algunos casos forzar, a j\u00f3venes a unirse a sus filas. Seg\u00fan la Unidad de Inteligencia de la Polic\u00eda Federal, se han identificado varias cuentas en plataformas digitales que operan con este prop\u00f3sito. El secretario de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460033","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Secretar\u00eda de Seguridad de M\u00e9xico alert\u00f3 que los carteles del narcotr\u00e1fico est\u00e1n utilizando redes sociales para atraer, y en algunos casos forzar, a j\u00f3venes a unirse a sus filas. Seg\u00fan la Unidad de Inteligencia de la Polic\u00eda Federal, se han identificado varias cuentas en plataformas digitales que operan con este prop\u00f3sito. El secretario de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T21:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes\",\"datePublished\":\"2025-03-17T21:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/\"},\"wordCount\":701,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/\",\"name\":\"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-17T21:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes - Noticias","og_description":"La Secretar\u00eda de Seguridad de M\u00e9xico alert\u00f3 que los carteles del narcotr\u00e1fico est\u00e1n utilizando redes sociales para atraer, y en algunos casos forzar, a j\u00f3venes a unirse a sus filas. Seg\u00fan la Unidad de Inteligencia de la Polic\u00eda Federal, se han identificado varias cuentas en plataformas digitales que operan con este prop\u00f3sito. El secretario de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-17T21:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/"},"author":{"name":"","@id":""},"headline":"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes","datePublished":"2025-03-17T21:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/"},"wordCount":701,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/","name":"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-17T21:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Carteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/carteles-droga-redes-sociales-reclutar-jovenes-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-17T21:03:39Z","datePublished":"2025-03-17T21:03:39Z","dateModified":"2025-03-17T21:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Carteles de la droga en M\\u00e9xico usan redes sociales para reclutar j\\u00f3venes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/carteles-droga-redes-sociales-reclutar-jovenes-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/carteles-droga-redes-sociales-reclutar-jovenes-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-17T21:03:39Z\",\"datePublished\":\"2025-03-17T21:03:39Z\",\"dateModified\":\"2025-03-17T21:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1460059,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/18\/5-cosas-18-marzo-deportaciones-lider-ms-13-reclutamiento-carteles-mexico-orix\/","url_meta":{"origin":1460033,"position":0},"title":"Las 5 cosas que debes saber este 18 de marzo: Deportaciones, Israel ataca Gaza y reclutamiento en c\u00e1rteles de M\u00e9xico","author":"","date":"marzo 18, 2025","format":false,"excerpt":"Israel ataca a Hamas y se rompe el cese del fuego en Gaza. C\u00e1rteles de la droga en M\u00e9xico usan redes sociales para reclutar j\u00f3venes. El testimonio de una madre que cree que su hijo est\u00e1 entre los deportados de EE.UU. al Cecot. Trump despidi\u00f3 a los cient\u00edficos que monitorean\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466949,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/29\/carteles-reclutamiento-jovenes-redes-trax\/","url_meta":{"origin":1460033,"position":1},"title":"As\u00ed operan los c\u00e1rteles que reclutan a j\u00f3venes estadounidenses a trav\u00e9s de las redes sociales","author":"","date":"septiembre 29, 2025","format":false,"excerpt":"A los 20 a\u00f1os, la joven estaba en apuros. Acababa de dar a luz y ten\u00eda que pagar la matr\u00edcula, el alquiler y la leche de f\u00f3rmula. Madre soltera en Phoenix, intentaba llegar a fin de mes y construir un futuro estudiando psicolog\u00eda.\u201cLlega un punto en que es tanto que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465472,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/13\/como-operativo-mexico-eeuu-miembros-carteles-orix\/","url_meta":{"origin":1460033,"position":2},"title":"\u00bfC\u00f3mo fue el operativo en el que M\u00e9xico envi\u00f3 a EE.UU. a 26 miembros de c\u00e1rteles que estaban en prisi\u00f3n?","author":"","date":"agosto 13, 2025","format":false,"excerpt":"El Gobierno de M\u00e9xico envi\u00f3 el martes a Estados Unidos a 26 miembros de c\u00e1rteles del narcotr\u00e1fico que se encontraban en prisiones federales y estatales del pa\u00eds.Entre estos integrantes, que fueron enviados en avi\u00f3n, destacan Abigael Gonz\u00e1lez Valencia, l\u00edder de \u201cLos Cuinis\u201d, grupo vinculado al C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG);\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472572,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/26\/criticos-grandes-tecnologicas-celebran-veredicto-redes-sociales-trax\/","url_meta":{"origin":1460033,"position":3},"title":"Cr\u00edticos de las grandes tecnol\u00f3gicas celebran veredicto sin precedentes sobre las redes sociales","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Para los cr\u00edticos de empresas tecnol\u00f3gicas como Meta y Google, el veredicto del mi\u00e9rcoles en el juicio por adicci\u00f3n a las redes sociales ha sido, literalmente, el resultado de a\u00f1os de trabajo.Padres, expertos en seguridad infantil y algunos legisladores afirmaron que la determinaci\u00f3n de la responsabilidad era un momento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471345,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/17\/juicio-mark-zuckerberg-adiccion-redes-sociales-menores-trax\/","url_meta":{"origin":1460033,"position":4},"title":"Familias en duelo y preguntas dif\u00edciles le esperan a Mark Zuckerberg en el juicio por la adicci\u00f3n a las redes sociales","author":"","date":"febrero 17, 2026","format":false,"excerpt":"Hace dos a\u00f1os, Joann Bogard estuvo presente en una sala de audiencias del Capitolio y vio a Mark Zuckerberg disculparse con padres afligidos que rastreaban la muerte de sus hijos hasta el mundo en internet que \u00e9l ayud\u00f3 a crear.La sala estaba llena de padres con fotos de los hijos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472546,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/25\/jurado-responsables-meta-youtube-adiccion-trax\/","url_meta":{"origin":1460033,"position":5},"title":"Un jurado declara responsables a Meta y YouTube en un juicio por adicci\u00f3n en redes sociales","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Un jurado en California declar\u00f3 a Meta y YouTube responsables en todos los cargos en un caso hist\u00f3rico que acus\u00f3 a los gigantes tecnol\u00f3gicos de volver intencionalmente adicta a una joven y perjudicar su salud mental.Meta y YouTube actuaron con negligencia en el dise\u00f1o de sus plataformas, sab\u00edan que ese\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1460033"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460033\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1460033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1460033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1460033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}