{"id":1460037,"date":"2025-03-17T16:03:40","date_gmt":"2025-03-17T23:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/"},"modified":"2025-03-17T16:03:40","modified_gmt":"2025-03-17T23:03:40","slug":"incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/","title":{"rendered":"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado&#187;"},"content":{"rendered":"<p><strong>(CNN Radio Argentina) \u2013 Alejandro Bianchi,<\/strong> fundador de Asesor de Inversiones y director de la Maestr\u00eda en Finanzas de la UADE, analiz\u00f3 el contexto econ\u00f3mico actual en una entrevista con <strong>CNN Radio. <\/strong>Durante su di\u00e1logo, abord\u00f3 la incertidumbre que generan las pol\u00edticas de Donald Trump, la situaci\u00f3n del d\u00f3lar en Argentina y el panorama pol\u00edtico de cara a las elecciones.<\/p>\n<p>En <em>CNN Econom\u00eda y Actualidad de Julieta Tarr\u00e9s, <\/em>Bianchi se\u00f1al\u00f3 que el a\u00f1o en los mercados internacionales comenz\u00f3 con alta volatilidad debido a la imprevisibilidad de la pol\u00edtica de Trump. <strong>\u201cEso genera nerviosismo en el mundo inversor, sobre todo en las bolsas, que siempre tienen m\u00e1s volatilidad que la econom\u00eda real\u201d,<\/strong> explic\u00f3. Adem\u00e1s, mencion\u00f3 un c\u00e1lculo que estima que por cada punto promedio que Estados Unidos aumenta en tarifas, el PBI global puede resentirse en un 0,10%.<\/p>\n<p><strong>Venta de reservas del Banco Central y suba del d\u00f3lar paralelo<\/strong><\/p>\n<p>En cuanto a la situaci\u00f3n cambiaria de Argentina, Bianchi se refiri\u00f3 a la cotizaci\u00f3n del d\u00f3lar y la relaci\u00f3n con las reservas. \u201cSi todos los argentinos quisi\u00e9ramos cambiar nuestros pesos por d\u00f3lares de las reservas brutas, ese d\u00f3lar estar\u00eda entre 1100 y 1450 seg\u00fan el c\u00e1lculo\u201d, afirm\u00f3. A partir de esa estimaci\u00f3n, sostuvo que <strong>\u201ces l\u00f3gico que el d\u00f3lar se ubique en un punto intermedio, alrededor de 1250 o 1300\u201d.<\/strong><\/p>\n<p>Asimismo, Bianchi se\u00f1al\u00f3 que una vez que se concrete el acuerdo con el FMI, ingresar\u00e1n d\u00f3lares al pa\u00eds y la relaci\u00f3n entre oferta y demanda de divisas mejorar\u00e1. <strong>\u201cEso permitir\u00e1 que el Banco Central pueda abrir el cepo y salir de esta situaci\u00f3n de cerrojo financiero sin que el d\u00f3lar se desestabilice demasiado\u201d, <\/strong>explic\u00f3.<\/p>\n<p><strong>El escenario pol\u00edtico y las variables econ\u00f3micas<\/strong><\/p>\n<p>De cara a las elecciones, Bianchi analiz\u00f3 el impacto de la econom\u00eda en el gobierno y la oposici\u00f3n. <strong>\u201cEl a\u00f1o comenz\u00f3 con un error no forzado por parte del gobierno con el tema Libra, que debilit\u00f3 su posici\u00f3n\u201d,<\/strong> indic\u00f3. Sin embargo, consider\u00f3 que esta situaci\u00f3n podr\u00eda derivar en un beneficio indirecto para los argentinos. \u201cEl gobierno baj\u00f3 un poco sus pretensiones y ya se vio una foto de un principio de acuerdo con el PRO, entre La Libertad Avanza y el PRO\u201d, se\u00f1al\u00f3.<\/p>\n<p>Para Bianchi, esta alianza podr\u00eda fortalecer la estructura del oficialismo a nivel nacional. <strong>\u201cLa Libertad Avanza gan\u00f3 en todo el pa\u00eds, pero no tiene estructura en las provincias y eso es lo que le falta\u201d,<\/strong> concluy\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Radio Argentina) \u2013 Alejandro Bianchi, fundador de Asesor de Inversiones y director de la Maestr\u00eda en Finanzas de la UADE, analiz\u00f3 el contexto econ\u00f3mico actual en una entrevista con CNN Radio. Durante su di\u00e1logo, abord\u00f3 la incertidumbre que generan las pol\u00edticas de Donald Trump, la situaci\u00f3n del d\u00f3lar en Argentina y el panorama pol\u00edtico [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460037","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Radio Argentina) \u2013 Alejandro Bianchi, fundador de Asesor de Inversiones y director de la Maestr\u00eda en Finanzas de la UADE, analiz\u00f3 el contexto econ\u00f3mico actual en una entrevista con CNN Radio. Durante su di\u00e1logo, abord\u00f3 la incertidumbre que generan las pol\u00edticas de Donald Trump, la situaci\u00f3n del d\u00f3lar en Argentina y el panorama pol\u00edtico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T23:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado&#187;\",\"datePublished\":\"2025-03-17T23:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/\"},\"wordCount\":477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/\",\"name\":\"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-17T23:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/","og_locale":"es_ES","og_type":"article","og_title":"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado\" - Noticias","og_description":"(CNN Radio Argentina) \u2013 Alejandro Bianchi, fundador de Asesor de Inversiones y director de la Maestr\u00eda en Finanzas de la UADE, analiz\u00f3 el contexto econ\u00f3mico actual en una entrevista con CNN Radio. Durante su di\u00e1logo, abord\u00f3 la incertidumbre que generan las pol\u00edticas de Donald Trump, la situaci\u00f3n del d\u00f3lar en Argentina y el panorama pol\u00edtico [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/","og_site_name":"Noticias","article_published_time":"2025-03-17T23:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/"},"author":{"name":"","@id":""},"headline":"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado&#187;","datePublished":"2025-03-17T23:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/","url":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/","name":"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-17T23:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Incertidumbre econ\u00f3mica y acuerdo con el FMI: la visi\u00f3n de Alejandro Bianchi sobre el d\u00f3lar y el mercado&#187;","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-17T23:03:40Z","datePublished":"2025-03-17T23:03:40Z","dateModified":"2025-03-17T23:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Incertidumbre econ\\u00f3mica y acuerdo con el FMI: la visi\\u00f3n de Alejandro Bianchi sobre el d\\u00f3lar y el mercado&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/incertidumbre-economica-y-acuerdo-con-el-fmi-la-vision-de-alejandro-bianchi-sobre-el-dolar-y-el-mercado\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-17T23:03:40Z\",\"datePublished\":\"2025-03-17T23:03:40Z\",\"dateModified\":\"2025-03-17T23:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458714,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/13\/volatilidad-en-el-mercado-soledad-lopez-analizo-el-impacto-del-fmi-el-cepo-y-los-aranceles-de-trump\/","url_meta":{"origin":1460037,"position":0},"title":"Volatilidad en el mercado: Soledad L\u00f3pez analiz\u00f3 el impacto del FMI, el cepo y los aranceles de Trump","author":"","date":"febrero 13, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Soledad L\u00f3pez, gerente de Desarrollo de Rava Burs\u00e1til, habl\u00f3 este jueves con CNN Radio y sostuvo que en el mercado \u201ctenemos una volatilidad impresionante\u201d.En CNN Econom\u00eda y Actualidad con Julieta Tarr\u00e9s, la especialista se\u00f1al\u00f3 que \u201cfebrero siempre es un mes bajista despu\u00e9s de un enero alcista.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458090,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/01\/31\/paula-bujia-este-ano-sera-volatil-y-estados-unidos-marcara-el-camino-con-un-presidente-que-genera-incertidumbre\/","url_meta":{"origin":1460037,"position":1},"title":"Paula Buj\u00eda: &#171;Este a\u00f1o ser\u00e1 vol\u00e1til y Estados Unidos marcar\u00e1 el camino con un presidente que genera incertidumbre&#187;","author":"","date":"enero 31, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Paula Buj\u00eda, economista, asesora en inversiones y cofundadora de Buda Partners, habl\u00f3 este viernes con CNN Radio sobre los factores que marcar\u00e1n la econom\u00eda global en 2025 y su impacto en los mercados emergentes.En CNN Econom\u00eda y Actualidad con Julieta Tarr\u00e9s, la especialista se\u00f1al\u00f3 que \u201ceste\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459747,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/10\/carrino-economista-trump-genera-incertidumbre-sobre-las-reglas-de-juego-y-afecta-la-economia\/","url_meta":{"origin":1460037,"position":2},"title":"Carrino, economista: &#171;Trump genera incertidumbre sobre las reglas de juego y eso afecta la econom\u00eda&#187;","author":"","date":"marzo 10, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Iv\u00e1n Carrino, profesor de econom\u00eda y consultor, dialog\u00f3 este lunes con CNN Econom\u00eda y Actualidad, conducido por Julieta Tarr\u00e9s, sobre la situaci\u00f3n de los mercados internacionales y su impacto en Argentina.\u201cLo m\u00e1s urgente o preocupante es lo que est\u00e1 pasando en los mercados. Luego de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461548,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/23\/camilo-tiscornia-si-argentina-sigue-por-este-camino-las-expectativas-a-mediano-plazo-son-buenas\/","url_meta":{"origin":1460037,"position":3},"title":"Camilo Tiscornia: &#171;Si Argentina sigue por este camino, las expectativas a mediano plazo son buenas&#187;","author":"","date":"abril 23, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Camilo Tiscornia, economista, analiz\u00f3 este mi\u00e9rcoles en CNN Econom\u00eda y Actualidad la situaci\u00f3n del pa\u00eds frente al contexto internacional y los \u00faltimos indicadores de la actividad local.\u201cFue un d\u00eda positivo en el mundo, a partir de cierta calma en la negociaci\u00f3n que lleva adelante Estados Unidos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461329,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/17\/caamano-economista-con-el-cambio-de-esquema-uno-de-los-costos-a-pagar-es-la-inflacion\/","url_meta":{"origin":1460037,"position":4},"title":"Caama\u00f1o, economista: &#171;Con el cambio de esquema, uno de los costos a pagar es la inflaci\u00f3n&#187;","author":"","date":"abril 17, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Gabriel Caama\u00f1o, economista de Outlier, dialog\u00f3 este jueves con CNN Econom\u00eda y Actualidad sobre la salida del cepo por parte del gobierno de Javier Milei y sus implicancias para la econom\u00eda.\u201cSe vio y es algo positivo que hubo muy poca volatilidad en los primeros d\u00edas, aunque\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460807,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/03\/trump-obliga-a-todos-a-negociar-el-analisis-de-david-miazzo-sobre-el-nuevo-escenario-comercial\/","url_meta":{"origin":1460037,"position":5},"title":"&#171;Trump obliga a todos a negociar&#187;: el an\u00e1lisis de David Miazzo sobre el nuevo escenario comercial","author":"","date":"abril 3, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 David Miazzo, economista y director de la consultora DATA Miazzo, dialog\u00f3 este jueves con CNN Econom\u00eda y Actualidad de Julieta Tarr\u00e9s sobre los efectos de los aranceles anunciados por Donald Trump y su impacto en el comercio internacional y los precios de los commodities.\u201cTrump obliga a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1460037"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460037\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1460037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1460037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1460037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}