{"id":1460038,"date":"2025-03-17T16:03:40","date_gmt":"2025-03-17T23:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/"},"modified":"2025-03-17T16:03:40","modified_gmt":"2025-03-17T23:03:40","slug":"modulo-blue-ghost-finaliza-mision-luna-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/","title":{"rendered":"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos"},"content":{"rendered":"<p>Firefly Aerospace, la compa\u00f1\u00eda con sede en Texas que realiz\u00f3 un alunizaje impecable con su nave espacial Blue Ghost a principios de este mes, declar\u00f3 finalizada la hist\u00f3rica misi\u00f3n tras alcanzar el 100% de sus objetivos. Esta haza\u00f1a marca la primera operaci\u00f3n comercial completamente exitosa en la Luna, seg\u00fan inform\u00f3 la compa\u00f1\u00eda el lunes.<\/p>\n<p>Blue Ghost, un m\u00f3dulo de aterrizaje rob\u00f3tico de cuatro patas, aproximadamente del tama\u00f1o de un veh\u00edculo peque\u00f1o, pas\u00f3 dos semanas operando en la cara visible de la Luna. El lugar de aterrizaje se encontraba cerca de una antigua formaci\u00f3n volc\u00e1nica llamada Mons Latreille, justo al norte del ecuador.<\/p>\n<p>El Blue Ghost disfrut\u00f3 de la luz solar durante la mayor parte de la misi\u00f3n hasta que el anochecer lunar trajo oscuridad al lugar de aterrizaje el domingo. Sin embargo, el veh\u00edculo logr\u00f3 cumplir un objetivo clave de la misi\u00f3n y continu\u00f3 operando durante unas cinco horas despu\u00e9s del anochecer, gracias a la energ\u00eda suministrada por las bater\u00edas.<\/p>\n<p>Durante sus operaciones, el m\u00f3dulo de alunizaje transmiti\u00f3 a la Tierra un total de aproximadamente 120 gigabytes de datos, equivalentes a m\u00e1s de 24.000 canciones. Las tareas de Blue Ghost incluyeron la adquisici\u00f3n de la se\u00f1al GPS m\u00e1s lejana jam\u00e1s recibida, el uso de una aspiradora especial para recolectar y clasificar el polvo lunar y el despliegue de un taladro para medir la temperatura del suelo.<\/p>\n<p>El control de la misi\u00f3n Firefly recibi\u00f3 la se\u00f1al final de Blue Ghost alrededor de las 7:15 p.m. hora de Miami (6:15 p.m. CT) del domingo, seg\u00fan la compa\u00f1\u00eda.<\/p>\n<p>\u201cEste logro marca la operaci\u00f3n comercial m\u00e1s larga en la Luna hasta la fecha\u201d, dijo Firefly en un <a href=\"https:\/\/fireflyspace.com\/news\/firefly-aerospace-successfully-completes-14-days-of-surface-operations-on-the-moon\/\">comunicado<\/a>.<\/p>\n<p>El m\u00f3dulo de aterrizaje Blue Ghost tambi\u00e9n envi\u00f3 un mensaje de despedida antes de pasar al \u201cmodo monumento\u201d, una referencia al hecho de que se espera que el m\u00f3dulo de aterrizaje permanezca inactivo en la superficie de la Luna en el futuro previsible.<\/p>\n<p>\u201cCambio de modo de misi\u00f3n detectado, ahora en Modo Monumento. Buenas noches amigos\u201d, <a href=\"https:\/\/x.com\/Firefly_Space\/status\/1901414669677449256\">dec\u00eda el mensaje de la nave espacial<\/a>, seg\u00fan una publicaci\u00f3n compartida por Firefly en la plataforma de redes sociales X.<\/p>\n<p>\u201cVelar\u00e9 en este punto del Mare Crisium para observar el continuo viaje de la humanidad hacia las estrellas. Aqu\u00ed, sobrevivir\u00e9 a sus r\u00edos m\u00e1s caudalosos, a sus monta\u00f1as m\u00e1s altas, y quiz\u00e1s incluso a su especie tal como la conocemos\u201d, continuaba la nota. \u201cPero es notable que una especie pueda sobrevivir gracias a su propio ingenio. Aqu\u00ed yace Blue Ghost, un testimonio del equipo que, con el cari\u00f1oso apoyo de sus familias y amigos, construy\u00f3 y oper\u00f3 esta m\u00e1quina y sus cargas \u00fatiles\u201d.<\/p>\n<p>Operar durante la noche lunar es una tarea dif\u00edcil, debido a que las temperaturas de la superficie lunar pueden variar dr\u00e1sticamente desde <a href=\"https:\/\/science.nasa.gov\/moon\/weather-on-the-moon\/#:~:text=Temperatures%20near%20the%20Moon's%20equator,F%20(%2D246%C2%B0C).\">121\u00b0C<\/a> hasta -173\u00b0C.<\/p>\n<p>Al caer la noche lunar, se esperaba que Blue Ghost capturara un video en 4K del resplandor del horizonte lunar. Durante este fen\u00f3meno, ya presenciado por los astronautas del Apolo, las part\u00edculas de polvo lunar parecen levitar alrededor del ocaso lunar.<\/p>\n<p>La NASA y Firefly planean compartir esas observaciones durante una conferencia de prensa programada para el martes a las 2 p.m. (hora de Miami).<\/p>\n<p>Por otra parte, Blue Ghost presenci\u00f3 un eclipse lunar la semana pasada. El evento proyect\u00f3 la sombra de la Tierra sobre la Luna, sumiendo brevemente al m\u00f3dulo de aterrizaje en la oscuridad. Sin embargo, el explorador rob\u00f3tico observ\u00f3 posteriormente el impresionante \u201cefecto de anillo de diamante\u201d cuando el Sol se asom\u00f3 m\u00e1s all\u00e1 de nuestro planeta.<\/p>\n<p>Desde la Tierra, ese eclipse fue visible como una \u201c<a href=\"https:\/\/www.cnn.com\/2025\/03\/14\/science\/gallery\/march-2025-blood-moon\/index.html\">luna de sangre<\/a>\u201d que pareci\u00f3 te\u00f1ir a nuestro vecino celestial m\u00e1s cercano de un tono naranja rojizo.<\/p>\n<p>Firefly ha calificado su misi\u00f3n como \u201cel primer alunizaje comercial completamente exitoso\u201d de la historia. El t\u00edtulo hace referencia a Intuitive Machines, otra empresa con sede en Texas, cuyo m\u00f3dulo de aterrizaje Odysseus se convirti\u00f3 el a\u00f1o pasado en la primera nave espacial comercial en aterrizar suavemente en la Luna. Sin embargo, el veh\u00edculo aterriz\u00f3 en una orientaci\u00f3n lateral que present\u00f3 importantes dificultades de comunicaci\u00f3n y caus\u00f3 la finalizaci\u00f3n anticipada de la misi\u00f3n.<\/p>\n<p>El segundo m\u00f3dulo de Intuitive Machines, Athena, aterriz\u00f3 en la Luna pocos d\u00edas despu\u00e9s de Blue Ghost, pero corri\u00f3 una suerte similar, quedando de lado cerca del polo sur lunar. Ambos sitios de aterrizaje de Intuitive Machines se encontraban en la compleja regi\u00f3n m\u00e1s meridional de la Luna, plagada de cr\u00e1teres de impacto y otros peligros.<\/p>\n<p>Varias empresas comerciales, entre ellas Astrobotic Technology, con sede en EE.UU., Ispace, con sede en Jap\u00f3n, y la compa\u00f1\u00eda israel\u00ed SpaceIL, intentaron anteriormente, sin \u00e9xito, realizar un aterrizaje suave de veh\u00edculos en la Luna.<\/p>\n<p>Durante d\u00e9cadas, estas misiones se consideraron demasiado rigurosas tecnol\u00f3gicamente y costosas para el sector privado.<\/p>\n<p>Tanto Intuitive Machines como Firefly volaron sus m\u00f3dulos de aterrizaje lunares bajo el programa de Servicios de Carga Lunar Comercial (CLPS) de la NASA, que tiene como objetivo estimular al sector empresarial a dedicarse a la exploraci\u00f3n lunar.<\/p>\n<p>Firefly recibi\u00f3 un contrato a precio fijo de US$ 101,5 millones para esta misi\u00f3n.<\/p>\n<p>En el marco del programa de Servicios de Carga Lunar Comercial, la NASA espera establecer una flota de naves espaciales desarrolladas por el sector privado que puedan explorar rob\u00f3ticamente la superficie lunar (de manera relativamente r\u00e1pida y econ\u00f3mica) antes de que la agencia env\u00ede astronautas de regreso a la Luna a finales de esta d\u00e9cada.<\/p>\n<p>\u201cNuestro equipo puede parecer m\u00e1s joven y menos experimentado que los de muchas naciones y empresas que intentaron alunizajes antes que nosotros, pero el apoyo que nos tenemos unos a otros es lo que impulsa el arduo trabajo y la dedicaci\u00f3n para encontrar cada soluci\u00f3n que hizo de esta misi\u00f3n un \u00e9xito\u201d, dijo Will Coogan, ingeniero jefe de Blue Ghost, en un comunicado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Firefly Aerospace, la compa\u00f1\u00eda con sede en Texas que realiz\u00f3 un alunizaje impecable con su nave espacial Blue Ghost a principios de este mes, declar\u00f3 finalizada la hist\u00f3rica misi\u00f3n tras alcanzar el 100% de sus objetivos. Esta haza\u00f1a marca la primera operaci\u00f3n comercial completamente exitosa en la Luna, seg\u00fan inform\u00f3 la compa\u00f1\u00eda el lunes. Blue [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460038","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Firefly Aerospace, la compa\u00f1\u00eda con sede en Texas que realiz\u00f3 un alunizaje impecable con su nave espacial Blue Ghost a principios de este mes, declar\u00f3 finalizada la hist\u00f3rica misi\u00f3n tras alcanzar el 100% de sus objetivos. Esta haza\u00f1a marca la primera operaci\u00f3n comercial completamente exitosa en la Luna, seg\u00fan inform\u00f3 la compa\u00f1\u00eda el lunes. Blue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-17T23:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos\",\"datePublished\":\"2025-03-17T23:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/\"},\"wordCount\":1075,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/\",\"name\":\"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-17T23:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos - Noticias","og_description":"Firefly Aerospace, la compa\u00f1\u00eda con sede en Texas que realiz\u00f3 un alunizaje impecable con su nave espacial Blue Ghost a principios de este mes, declar\u00f3 finalizada la hist\u00f3rica misi\u00f3n tras alcanzar el 100% de sus objetivos. Esta haza\u00f1a marca la primera operaci\u00f3n comercial completamente exitosa en la Luna, seg\u00fan inform\u00f3 la compa\u00f1\u00eda el lunes. Blue [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-17T23:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/"},"author":{"name":"","@id":""},"headline":"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos","datePublished":"2025-03-17T23:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/"},"wordCount":1075,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/","name":"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-17T23:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El m\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\u00f3n hist\u00f3rica y cumple el 100% de sus objetivos","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/modulo-blue-ghost-finaliza-mision-luna-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-17T23:03:40Z","datePublished":"2025-03-17T23:03:40Z","dateModified":"2025-03-17T23:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El m\\u00f3dulo de alunizaje Blue Ghost de Firefly finaliza una misi\\u00f3n hist\\u00f3rica y cumple el 100% de sus objetivos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/modulo-blue-ghost-finaliza-mision-luna-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/modulo-blue-ghost-finaliza-mision-luna-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-17T23:03:40Z\",\"datePublished\":\"2025-03-17T23:03:40Z\",\"dateModified\":\"2025-03-17T23:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459387,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/02\/blue-ghost-robot-luna-trax\/","url_meta":{"origin":1460038,"position":0},"title":"El m\u00f3dulo Blue Ghost aluniza con \u00e9xito","author":"","date":"marzo 2, 2025","format":false,"excerpt":"El m\u00f3dulo de alunizaje rob\u00f3tico Blue Ghost, construido por la empresa Firefly, descendi\u00f3 con \u00e9xito en la Luna.Firefly pudo afirmar r\u00e1pidamente que el veh\u00edculo hab\u00eda llegado a la superficie porque sus cuatro patas de aterrizaje est\u00e1n equipadas con sensores dise\u00f1ados para confirmar inmediatamente el alunizaje.El Blue Ghost fue puesto en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457522,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/01\/14\/spacex-lanzara-misiones-luna-firefly-ispace-spacex-trax\/","url_meta":{"origin":1460038,"position":1},"title":"SpaceX lanzar\u00e1 dos misiones a la Luna en un solo cohete","author":"","date":"enero 14, 2025","format":false,"excerpt":"Un cohete Falcon 9 de SpaceX est\u00e1 listo para lanzar un par de m\u00f3dulos de alunizaje en un viaje a nuestro vecino celestial m\u00e1s cercano, dando inicio a lo que se espera que sea un a\u00f1o agitado de misiones lunares en medio de una renovada carrera para establecer una presencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459597,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/06\/modulo-athena-intuitive-machines-superficie-lunar-trax\/","url_meta":{"origin":1460038,"position":2},"title":"El m\u00f3dulo de aterrizaje Athena de Intuitive Machines se encuentra en la superficie lunar, pero su estado no es claro","author":"","date":"marzo 6, 2025","format":false,"excerpt":"Un m\u00f3dulo de aterrizaje rob\u00f3tico llamado Athena descendi\u00f3 finalmente a la superficie de la Luna, lo que supone el segundo alunizaje de una empresa estadounidense esta semana. Sin embargo, por el momento se desconoce la orientaci\u00f3n del m\u00f3dulo de aterrizaje.Intuitive Machines, con sede en Houston, que el a\u00f1o pasado se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459153,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/24\/nave-espacial-blue-ghost-fotos-luna-trax\/","url_meta":{"origin":1460038,"position":3},"title":"La nave espacial Blue Ghost comparte primeros planos impresionantes a d\u00edas de intentar alunizar","author":"","date":"febrero 24, 2025","format":false,"excerpt":"El m\u00f3dulo de alunizaje Blue Ghost comparti\u00f3 im\u00e1genes deslumbrantes de nuestro sat\u00e9lite natural desde que entr\u00f3 con \u00e9xito en su \u00f3rbita el 13 de febrero.Las nuevas im\u00e1genes muestran un primer plano del lado lejano de la Luna, un \u00e1rea que no es visible desde la Tierra, tomada despu\u00e9s de que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459644,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/07\/modulo-aterrizaje-athena-muerto-luna-trax\/","url_meta":{"origin":1460038,"position":4},"title":"Declaran que el m\u00f3dulo de aterrizaje Athena est\u00e1 &#171;muerto&#187; y yace de lado en la Luna","author":"","date":"marzo 7, 2025","format":false,"excerpt":"Intuitive Machines, la empresa con sede en Houston que iba a llevar a cabo una hist\u00f3rica misi\u00f3n de b\u00fasqueda de agua en el polo sur de la Luna, anunci\u00f3 el viernes que su m\u00f3dulo de aterrizaje Athena se apag\u00f3 solo un d\u00eda despu\u00e9s de llegar a la superficie lunar.Se esperaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444074,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/18\/la-agencia-de-exploracion-aeroespacial-de-japon-se-prepara-para-20-minutos-de-terror-por-intento-de-alunizaje-de-su-nave-slim\/","url_meta":{"origin":1460038,"position":5},"title":"La Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n se prepara para &#171;20 minutos de terror&#187; por intento de alunizaje de su nave SLIM","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN) -- Mientras la primera misi\u00f3n estadounidense de alunizaje en d\u00e9cadas finaliza sin alcanzar su objetivo, una nave espacial lanzada por Jap\u00f3n se acerca a la Luna y se prepara para un intento hist\u00f3rico de alunizaje.Se espera que el Smart Lander for Investigating Moon (SLIM) de la Agencia de Exploraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1460038"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460038\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1460038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1460038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1460038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}