{"id":1460043,"date":"2025-03-17T18:03:44","date_gmt":"2025-03-18T01:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/"},"modified":"2025-03-17T18:03:44","modified_gmt":"2025-03-18T01:03:44","slug":"israel-ataques-extensos-en-gaza-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/","title":{"rendered":"Israel informa que ejecuta varios ataques en Gaza"},"content":{"rendered":"<p>Israel inform\u00f3 que ejecuta \u201cataques extensos\u201d contra Hamas en Gaza, poniendo en duda el fr\u00e1gil cese del fuego.<\/p>\n<p>En un comunicado, las Fuerzas de Defensa de Israel (FDI) y la Agencia de Seguridad de Israel dijeron el martes temprano, hora local, que estaban \u201cllevando a cabo ataques extensos contra objetivos terroristas pertenecientes a la organizaci\u00f3n terrorista Hamas en Gaza\u201d.<\/p>\n<p>La Defensa Civil en Gaza dijo que varias personas estaban \u201catrapadas bajo los escombros de casas que fueron bombardeadas en varias \u00e1reas\u201d del enclave. Corresponsales de CNN en Gaza informaron sobre los sonidos de ataques en m\u00faltiples ubicaciones.<\/p>\n<p>El primer ministro de Israel, Benjamin Netanyahu, y el ministro de Defensa, Israel Katz, ordenaron la operaci\u00f3n, acusando a Hamas de \u201cnegarse repetidamente\u201d a liberar rehenes y rechazar ofertas de mediaci\u00f3n.<\/p>\n<p>\u201cLas FDI est\u00e1n atacando actualmente objetivos de la organizaci\u00f3n terrorista Hamas en toda Gaza, con el objetivo de lograr los objetivos de guerra determinados por el escal\u00f3n pol\u00edtico, incluyendo la liberaci\u00f3n de todos nuestros rehenes, vivos y muertos\u201d, dijo un comunicado de la Oficina del Primer Ministro.<\/p>\n<p>\u201cA partir de ahora, Israel actuar\u00e1 contra Hamas con una fuerza militar creciente\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Israel inform\u00f3 que ejecuta \u201cataques extensos\u201d contra Hamas en Gaza, poniendo en duda el fr\u00e1gil cese del fuego. En un comunicado, las Fuerzas de Defensa de Israel (FDI) y la Agencia de Seguridad de Israel dijeron el martes temprano, hora local, que estaban \u201cllevando a cabo ataques extensos contra objetivos terroristas pertenecientes a la organizaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460043","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Israel informa que ejecuta varios ataques en Gaza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel informa que ejecuta varios ataques en Gaza - Noticias\" \/>\n<meta property=\"og:description\" content=\"Israel inform\u00f3 que ejecuta \u201cataques extensos\u201d contra Hamas en Gaza, poniendo en duda el fr\u00e1gil cese del fuego. En un comunicado, las Fuerzas de Defensa de Israel (FDI) y la Agencia de Seguridad de Israel dijeron el martes temprano, hora local, que estaban \u201cllevando a cabo ataques extensos contra objetivos terroristas pertenecientes a la organizaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-18T01:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Israel informa que ejecuta varios ataques en Gaza\",\"datePublished\":\"2025-03-18T01:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/\"},\"wordCount\":222,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/\",\"name\":\"Israel informa que ejecuta varios ataques en Gaza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-18T01:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel informa que ejecuta varios ataques en Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel informa que ejecuta varios ataques en Gaza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Israel informa que ejecuta varios ataques en Gaza - Noticias","og_description":"Israel inform\u00f3 que ejecuta \u201cataques extensos\u201d contra Hamas en Gaza, poniendo en duda el fr\u00e1gil cese del fuego. En un comunicado, las Fuerzas de Defensa de Israel (FDI) y la Agencia de Seguridad de Israel dijeron el martes temprano, hora local, que estaban \u201cllevando a cabo ataques extensos contra objetivos terroristas pertenecientes a la organizaci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-18T01:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/"},"author":{"name":"","@id":""},"headline":"Israel informa que ejecuta varios ataques en Gaza","datePublished":"2025-03-18T01:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/"},"wordCount":222,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/","name":"Israel informa que ejecuta varios ataques en Gaza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-18T01:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Israel informa que ejecuta varios ataques en Gaza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Israel informa que ejecuta varios ataques en Gaza","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/17\/israel-ataques-extensos-en-gaza-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-18T01:03:44Z","datePublished":"2025-03-18T01:03:44Z","dateModified":"2025-03-18T01:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Israel informa que ejecuta varios ataques en Gaza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/israel-ataques-extensos-en-gaza-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/17\\\/israel-ataques-extensos-en-gaza-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-18T01:03:44Z\",\"datePublished\":\"2025-03-18T01:03:44Z\",\"dateModified\":\"2025-03-18T01:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1468532,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/11\/20\/israel-mata-28-palestinos-gaza-hamas-trax\/","url_meta":{"origin":1460043,"position":0},"title":"Ataques israel\u00edes en Gaza dejan al menos 32 palestinos muertos, mientras Hamas advierte de una &#171;peligrosa escalada&#187;","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"Los ataques israel\u00edes en Gaza han causado la muerte de al menos 32 palestinos en la \u00faltima escalada de violencia desde que entr\u00f3 en vigor el alto el fuego entre Israel y Hamas.El Ministerio de Salud palestino inform\u00f3 que entre los muertos en los ataques, que continuaron desde el mi\u00e9rcoles\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460197,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/20\/fuerzas-defensa-israel-operacion-terrestre-en-rafah-trax\/","url_meta":{"origin":1460043,"position":1},"title":"Las Fuerzas de Defensa de Israel dicen que comenz\u00f3 una operaci\u00f3n terrestre en Rafah","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Las Fuerzas de Defensa de Israel (FDI) aseguran que comenz\u00f3 una operaci\u00f3n terrestre en la ciudad de Rafah, en el sur de Gaza.La operaci\u00f3n en el campo de refugiados de Al-Shaboura ya ha desmantelado varios sitios de infraestructura \u201cterrorista\u201d, dijeron las FDI en un comunicado este jueves.Afirmaron que sus militares\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451713,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/08\/10\/israeli-school-strike-gaza-trax\/","url_meta":{"origin":1460043,"position":2},"title":"Al menos 90 palestinos muertos en un ataque israel\u00ed contra una escuela de Gaza, seg\u00fan portavoz de la Defensa Civil","author":"","date":"agosto 10, 2024","format":false,"excerpt":"(CNN) -- Al menos 90 palestinos murieron en un ataque israel\u00ed contra la escuela de Al-Tabi'in, en la ciudad de Gaza, seg\u00fan declar\u00f3 o a CNN el portavoz de la Defensa Civil de Gaza, Mahmoud Basal.\"Hemos recuperado al menos 90\" personas muertas, ha dicho Basal, a\u00f1adiendo que \"muchas de ellas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460195,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/20\/ataques-israelies-gaza-591-muertos-trax\/","url_meta":{"origin":1460043,"position":3},"title":"Ataques israel\u00edes en Gaza causaron la muerte de 591 personas desde el martes, dice la Oficina de Prensa del gobierno de Hamas","author":"","date":"marzo 20, 2025","format":false,"excerpt":"Los ataques israel\u00edes en Gaza han causado la muerte de al menos a 591 personas y herido a m\u00e1s de 1.042 desde que reanud\u00f3 su ofensiva el martes, seg\u00fan inform\u00f3 este jueves en un comunicado la Oficina de Prensa del gobierno de Hamas en el enclave.\u201cUn n\u00famero desconocido de v\u00edctimas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466438,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/09\/14\/ataques-israelies-gaza-70-muertos-trax\/","url_meta":{"origin":1460043,"position":4},"title":"Ataques israel\u00edes en Gaza dejan m\u00e1s de 70 muertos en un d\u00eda","author":"","date":"septiembre 14, 2025","format":false,"excerpt":"Al menos 74 palestinos murieron el s\u00e1bado en ataques israel\u00edes sobre Gaza, informaron funcionarios hospitalarios, con m\u00e1s de 50 de las v\u00edctimas en Ciudad de Gaza.Varias personas \u2013entre ellas mujeres, ni\u00f1os y ancianos\u2013 llegaron sin vida o heridas al Hospital Al Quds, seg\u00fan fuentes m\u00e9dicas. Decenas m\u00e1s fueron trasladadas a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450609,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/22\/muertos-desaparecidos-dos-ataques-centro-gaza-trax\/","url_meta":{"origin":1460043,"position":5},"title":"M\u00e1s de 40 personas murieron o est\u00e1n desaparecidas tras ataques en el centro de Gaza","author":"","date":"junio 22, 2024","format":false,"excerpt":"(CNN) -- 42 personas han muerto o est\u00e1n desaparecidas tras dos ataques en el centro de Gaza este s\u00e1bado, seg\u00fan report\u00f3 la Oficina de Medios de Comunicaci\u00f3n del Gobierno, controlada por Hamas.El director de la Oficina de Medios de Comunicaci\u00f3n, Ismail Al-Thawabtah, dijo a CNN que los ataques se hab\u00edan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1460043"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460043\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1460043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1460043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1460043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}