{"id":1460060,"date":"2025-03-18T06:03:45","date_gmt":"2025-03-18T13:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/"},"modified":"2025-03-18T06:03:45","modified_gmt":"2025-03-18T13:03:45","slug":"angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/","title":{"rendered":"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n"},"content":{"rendered":"<p>Angela Gentile, infect\u00f3loga pediatra y jefa del Departamento de Epidemiolog\u00eda del Hospital de Ni\u00f1os Ricardo Guti\u00e9rrez, se refiri\u00f3 al aumento de los casos de sarampi\u00f3n, de los cuales ya son 11 los confirmados en todo el pa\u00eds.<\/p>\n<p>En CNN Primera Ma\u00f1ana, asegur\u00f3 que \u201cel sarampi\u00f3n es una enfermedad viral exantem\u00e1tica, que quiere decir que cursa con fiebre y erupci\u00f3n. <strong>Es una enfermedad sumamente complicada que puede traer neumon\u00eda, encefalitis, trastornos del sistema nervioso, ceguera. Trae complicaciones muy graves, sobre todo en los menores de cinco a\u00f1os<\/strong>\u201d.<\/p>\n<p>Adem\u00e1s, remarc\u00f3 que \u201ces altamente contagiosa. <strong>Por cada caso de sarampi\u00f3n, se contagian 16 a 18<\/strong>. Mientras que con covid, por ejemplo, era 5 a 6 personas. Eso marca la gran contagiosidad de esta enfermedad viral\u201d.<\/p>\n<p>En este sentido, asegur\u00f3 que \u201ccuando estallan los brotes, empiezan por goteo algunos casos, pero hasta que uno lo detecta, ha contagiado, porque la enfermedad contagia cuatro d\u00edas antes de que aparezca la erupci\u00f3n y cuatro d\u00edas despu\u00e9s. Entonces, <strong>se detecta cuando tiene fiebre y erupci\u00f3n, pero ya vino contagiando cuatro d\u00edas antes, sin saber que ten\u00eda sarampi\u00f3n<\/strong>. Eso hace que se disemine muy r\u00e1pido. En los brotes, uno va un poco atr\u00e1s de los casos. Por eso es que es fundamental la vacunaci\u00f3n\u201d.<\/p>\n<p>La infect\u00f3loga pediatra destac\u00f3 que <strong>\u201clas Am\u00e9ricas est\u00e1n en este momento libres de sarampi\u00f3n, despu\u00e9s de haber pasado dos brotes importantes Brasil y Venezuela. Hoy tenemos 11 casos. Tenemos 7 en la ciudad de Buenos Aires, en la zona de Palermo, vinculadas a la importaci\u00f3n, y tenemos 4 en Florencio Varela. Si bien pertenecen a la misma cadena de transmisi\u00f3n, ya se asume que hay circulaci\u00f3n comunitaria, porque hay dos de los casos que no se contagiaron de nadie que uno puede identificar\u201d<\/strong>.<\/p>\n<p>Destac\u00f3 que <strong>\u201cla \u00fanica conducta para poder resolver es hacer una campa\u00f1a. Nos reunimos la Comisi\u00f3n Nacional de Inmunizaciones y se plante\u00f3 una campa\u00f1a con vacuna doble viral sarampi\u00f3n-rubiola para todo lo que es la ciudad de Buenos Aires y el conurbano, sobre todo Florencio Varela, que es donde est\u00e1n los casos\u201d<\/strong>.<\/p>\n<p>Explic\u00f3 que \u201c<strong>esa es una vacuna que se va a dar como extra, adicional, extraordinaria, no para contabilizarla en el calendario, pero s\u00ed es una vacuna para poder cortar brote<\/strong>. A futuro no podemos vivir haciendo campa\u00f1as, sino <strong>que necesitamos coberturas de vacunaci\u00f3n muy altas de calendario nacional que lleguen al 95%<\/strong>, que nos asegura poder cortar transmisi\u00f3n si entra un caso importado\u201d.<\/p>\n<p>Angela Gentile explic\u00f3 que \u201cnuestras coberturas est\u00e1n alrededor del 80% o menos incluso para la segunda dosis\u201d.<\/p>\n<p>Sobre la vacunaci\u00f3n en adultos, detall\u00f3 que \u201ctenemos que estar absolutamente seguros de tener dos dosis despu\u00e9s del a\u00f1o. Si uno tiene dudas hay que acercarse al vacunatorio y darse una dosis de triple viral porque hace falta dos dosis despu\u00e9s del a\u00f1o. Los nacidos antes de 1965, no, porque se asume que son tantos los brotes que seguramente han tenido sarampi\u00f3n\u201d.<\/p>\n<p>La jefa del Departamento de Epidemiolog\u00eda del Hospital de Ni\u00f1os Ricardo Guti\u00e9rrez cont\u00f3 que \u201cesta campa\u00f1a todav\u00eda se est\u00e1 delineando, pero la idea es de 6 a 11 meses una dosis que no le vale para calendario, es una dosis extra, y los chicos hasta los 4 a\u00f1os de edad, porque a los 5 a\u00f1os ya tiene la vacuna de calendario que es la triple viral, entonces hay que tomar esa franja intermedia\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Angela Gentile, infect\u00f3loga pediatra y jefa del Departamento de Epidemiolog\u00eda del Hospital de Ni\u00f1os Ricardo Guti\u00e9rrez, se refiri\u00f3 al aumento de los casos de sarampi\u00f3n, de los cuales ya son 11 los confirmados en todo el pa\u00eds. En CNN Primera Ma\u00f1ana, asegur\u00f3 que \u201cel sarampi\u00f3n es una enfermedad viral exantem\u00e1tica, que quiere decir que cursa [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1460060","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"Angela Gentile, infect\u00f3loga pediatra y jefa del Departamento de Epidemiolog\u00eda del Hospital de Ni\u00f1os Ricardo Guti\u00e9rrez, se refiri\u00f3 al aumento de los casos de sarampi\u00f3n, de los cuales ya son 11 los confirmados en todo el pa\u00eds. En CNN Primera Ma\u00f1ana, asegur\u00f3 que \u201cel sarampi\u00f3n es una enfermedad viral exantem\u00e1tica, que quiere decir que cursa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-18T13:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n\",\"datePublished\":\"2025-03-18T13:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/\"},\"wordCount\":633,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/\",\"name\":\"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-18T13:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/","og_locale":"es_ES","og_type":"article","og_title":"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n - Noticias","og_description":"Angela Gentile, infect\u00f3loga pediatra y jefa del Departamento de Epidemiolog\u00eda del Hospital de Ni\u00f1os Ricardo Guti\u00e9rrez, se refiri\u00f3 al aumento de los casos de sarampi\u00f3n, de los cuales ya son 11 los confirmados en todo el pa\u00eds. En CNN Primera Ma\u00f1ana, asegur\u00f3 que \u201cel sarampi\u00f3n es una enfermedad viral exantem\u00e1tica, que quiere decir que cursa [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/","og_site_name":"Noticias","article_published_time":"2025-03-18T13:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/"},"author":{"name":"","@id":""},"headline":"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n","datePublished":"2025-03-18T13:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/"},"wordCount":633,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/","url":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/","name":"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-18T13:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Angela Gentile, infect\u00f3loga pediatra, confirm\u00f3 que habr\u00e1 una campa\u00f1a de vacunaci\u00f3n para cortar el brote de sarampi\u00f3n","url":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/03\/18\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-18T13:03:45Z","datePublished":"2025-03-18T13:03:45Z","dateModified":"2025-03-18T13:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Angela Gentile, infect\\u00f3loga pediatra, confirm\\u00f3 que habr\\u00e1 una campa\\u00f1a de vacunaci\\u00f3n para cortar el brote de sarampi\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/18\\\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/03\\\/18\\\/angela-gentile-infectologa-pediatra-confirmo-que-habra-una-campana-de-vacunacion-para-cortar-el-brote-de-sarampion\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-18T13:03:45Z\",\"datePublished\":\"2025-03-18T13:03:45Z\",\"dateModified\":\"2025-03-18T13:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473043,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/04\/10\/aumentan-casos-sarampion-mexico-orix\/","url_meta":{"origin":1460060,"position":0},"title":"Aumentan los casos de sarampi\u00f3n en M\u00e9xico y ya se registraron un 39 % m\u00e1s que en 2025, seg\u00fan la Secretar\u00eda de Salud","author":"","date":"abril 10, 2026","format":false,"excerpt":"M\u00e9xico sigue posicionado como uno de los pa\u00edses con mayor cantidad de casos de sarampi\u00f3n en Am\u00e9rica. En lo que va del 2026, la Secretar\u00eda de Salud del pa\u00eds registr\u00f3 9.015 casos hasta el 9 de abril, un aumento considerable si se tiene en cuenta que durante 2025 se report\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460142,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/19\/pediatras-consejos-pacientes-dudan-vacunacion-trax\/","url_meta":{"origin":1460060,"position":1},"title":"Los pediatras recurren a estos consejos cuando hablan con pacientes que dudan sobre la vacunaci\u00f3n","author":"","date":"marzo 19, 2025","format":false,"excerpt":"A principios de la d\u00e9cada de 2000, cuando la Dra. Alexandra Cvijanovich terminaba su formaci\u00f3n m\u00e9dica en Utah, su equipo atendi\u00f3 a un ni\u00f1o de 13 a\u00f1os con panencefalitis esclerosante subaguda, una enfermedad neurol\u00f3gica degenerativa que puede ser mortal. Es una complicaci\u00f3n inusual del virus del sarampi\u00f3n que aparece a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459275,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/27\/nino-texas-primera-muerte-sarampion-decada-trax\/","url_meta":{"origin":1460060,"position":2},"title":"Un ni\u00f1o del oeste de Texas muere por sarampi\u00f3n. Es el primero en EE.UU. en una d\u00e9cada","author":"","date":"febrero 27, 2025","format":false,"excerpt":"La primera muerte por sarampi\u00f3n en el creciente brote registrado en el oeste de Texas fue la de un ni\u00f1o en edad escolar.El ni\u00f1o no estaba vacunado y hab\u00eda sido hospitalizado en Lubbock, Texas, dijo Lauren Adams, portavoz de la ciudad de Lubbock. Las autoridades no respondieron a preguntas sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459939,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/03\/14\/casos-sarampion-estados-unidos-superan-total-2024-trax\/","url_meta":{"origin":1460060,"position":3},"title":"Los casos de sarampi\u00f3n en Estados Unidos superan el total de 2024 en tan solo 3 meses de 2025","author":"","date":"marzo 14, 2025","format":false,"excerpt":"Con tan solo tres meses transcurridos de 2025, Estados Unidos ha superado el n\u00famero total de casos de sarampi\u00f3n en el pa\u00eds de todo el a\u00f1o pasado.En lo que va de 2025, se han notificado al menos 308 casos de sarampi\u00f3n en Estados Unidos, seg\u00fan datos de los Centros para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459289,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/02\/27\/casos-sarampion-estados-unidos-trax\/","url_meta":{"origin":1460060,"position":4},"title":"Seguimiento de los casos de sarampi\u00f3n en Estados Unidos","author":"","date":"febrero 27, 2025","format":false,"excerpt":"Varios brotes recientes de sarampi\u00f3n en Estados Unidos han aumentado el n\u00famero de casos y generado preocupaci\u00f3n entre los expertos en salud p\u00fablica, especialmente porque las tasas de vacunaci\u00f3n en ni\u00f1os siguen siendo bajas.La preocupaci\u00f3n este a\u00f1o surge tras la primera muerte reportada en EE.UU. desde 2015 y despu\u00e9s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463947,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/06\/25\/primer-caso-sarampion-bolivia-comunidad-menonita-orix\/","url_meta":{"origin":1460060,"position":5},"title":"El primer caso de sarampi\u00f3n del a\u00f1o en Bolivia se detect\u00f3 en una comunidad menonita, dicen las autoridades","author":"","date":"junio 25, 2025","format":false,"excerpt":"El primer caso de sarampi\u00f3n en 2025 en Bolivia se detect\u00f3 \u201cen una persona proveniente de Rusia\u201d que lleg\u00f3 a Santa Cruz e inici\u00f3 la primera cadena de transmisi\u00f3n en una colonia menonita, dijo el domingo el Ministerio de Salud de Bolivia. Las autoridades calculan que m\u00e1s de 200 colonias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1460060"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1460060\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1460060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1460060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1460060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}