{"id":1469067,"date":"2025-12-08T05:03:40","date_gmt":"2025-12-08T13:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/"},"modified":"2025-12-08T05:03:40","modified_gmt":"2025-12-08T13:03:40","slug":"pompeya-perdida-encuentran-escalera-romana-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/","title":{"rendered":"Investigadores encuentran una antigua escalera romana que revela la &#171;Pompeya perdida&#187;"},"content":{"rendered":"<p>Casi 2.000 a\u00f1os despu\u00e9s de que una devastadora erupci\u00f3n volc\u00e1nica destruyera y sepultara una pr\u00f3spera ciudad romana, los investigadores est\u00e1n recurriendo a la novedosa t\u00e9cnica de la arqueolog\u00eda digital para revelar la \u201cPompeya perdida\u201d.<\/p>\n<p>El monte Vesubio entr\u00f3 en erupci\u00f3n en el a\u00f1o 79 d.C., cubriendo Pompeya con una gruesa capa de roca fundida, ceniza y escombros. Algunos residentes huyeron, mientras que otros murieron, atrapados por el material volc\u00e1nico. Las ruinas fantasmales, congeladas en el tiempo, se convirtieron en un escenario que los arque\u00f3logos han investigado desde 1748.<\/p>\n<p>Las excavaciones han revelado los edificios y artefactos ocultos bajo la ceniza, restos coloridos de frescos decorativos y los inquietantes restos de los habitantes de la ciudad.<\/p>\n<p>Pero no todas las estructuras arquitect\u00f3nicas se conservaron en Pompeya, lo que deja a los investigadores con preguntas persistentes sobre la vida cotidiana en la antigua ciudad del sur de Italia.<\/p>\n<p>Ahora, una sofisticada combinaci\u00f3n de tecnolog\u00eda de teledetecci\u00f3n, fotograf\u00eda de corto alcance y t\u00e9cnicas arqueol\u00f3gicas tradicionales est\u00e1 ayudando a los investigadores a descubrir pistas que antes estaban ocultas, revelando aspectos de Pompeya que se hab\u00edan perdido con el tiempo como torres, s\u00edmbolos de riqueza y poder que quiz\u00e1s alguna vez dieron forma al paisaje urbano.<\/p>\n<p>\u201cAl reconstruir la arquitectura perdida, obtenemos una comprensi\u00f3n m\u00e1s matizada e hist\u00f3ricamente precisa de la antigua ciudad y de la vida en ella\u201d, dijo la doctora Susanne Muth, coautora principal del estudio y profesora en el Instituto de Arqueolog\u00eda de la Universidad Humboldt de Berl\u00edn.<\/p>\n<p>Los hallazgos y recreaciones digitales, realizados por el proyecto <a href=\"https:\/\/www.archaeologie.hu-berlin.de\/de\/klarcho\/winckelmann\/forschung\/forschungsprojekte\/aktuelle-forschungsprojekte\/pompeji-reset-digitale-dokumentation-und-rekonstruktion-der-verlorenen-stadt-prof-dr-susanne-muth\">Pompeii Reset<\/a> y publicados recientemente en el <a href=\"https:\/\/pompeiisites.org\/e-journal-degli-scavi-di-pompei\/la-torre-della-casa-del-tiaso-un-nuovo-progetto-di-ricerca-per-la-documentazione-e-la-ricostruzione-digitale-della-pompei-perduta\/\">E-Journal of the Excavations of Pompeii<\/a>, incluso podr\u00edan cambiar la forma en que imaginamos el horizonte de la antigua Pompeya.<\/p>\n<p>Durante una visita a Pompeya con estudiantes en 2022, Muth se inspir\u00f3 en los esfuerzos del Parque Arqueol\u00f3gico de Pompeya para preservar la ciudad. Consciente de los desaf\u00edos de estudiar ruinas fr\u00e1giles en medio de un clima cambiante y condiciones meteorol\u00f3gicas variables, propuso una idea para preservar el patrimonio cultural de Pompeya mediante la reconstrucci\u00f3n digital no invasiva, al tiempo que se obten\u00eda conocimiento sobre la antigua ciudad.<\/p>\n<p>El Parque Arqueol\u00f3gico de Pompeya se interes\u00f3 y se asoci\u00f3 con la Universidad Humboldt, que cuenta con un departamento de arqueolog\u00eda con un fuerte enfoque digital, incluyendo proyectos previos como la reconstrucci\u00f3n digital del <a href=\"https:\/\/www.projekte.hu-berlin.de\/de\/digitales-forum-romanum\">antiguo Foro Romano<\/a>.<\/p>\n<p>Como parte del trabajo en curso, el equipo del proyecto emplea t\u00e9cnicas como escaneos LiDAR (detecci\u00f3n y medici\u00f3n de luz) y fotograf\u00eda para documentar lo que queda de los edificios de Pompeya y crear modelos 3D. Luego, los investigadores utilizan pistas reveladas por los escaneos \u2014como agujeros que muestran evidencia de estructuras faltantes\u2014 para hacer reconstrucciones digitales de c\u00f3mo pudieron haber sido las estructuras antes de la erupci\u00f3n.<\/p>\n<p>Otras exploraciones recientes sobre la gente y la arquitectura de Pompeya tambi\u00e9n revelaron que <a href=\"https:\/\/www.cnn.com\/2025\/08\/14\/science\/pompeii-reoccupation-after-eruption\">los habitantes regresaron a las ruinas<\/a> unas d\u00e9cadas despu\u00e9s del desastre en el a\u00f1o 79 d.C.<\/p>\n<p>\u201cLa capa de escombros volc\u00e1nicos y ceniza que cubri\u00f3 Pompeya tras la erupci\u00f3n alcanz\u00f3 aproximadamente cinco metros de altura\u201d, dijo Gabriel Zuchtriegel, coautor principal del estudio y director del parque arqueol\u00f3gico, por correo electr\u00f3nico, y agreg\u00f3 que \u201ctodav\u00eda se pod\u00edan ver los pisos superiores emergiendo de la ceniza, en una especie de desierto gris\u201d.<\/p>\n<p>Los antiguos pisos bajos se convirtieron en s\u00f3tanos donde los habitantes construyeron hornos, molinos y chimeneas, que fueron descubiertos a principios de este a\u00f1o. Sin embargo, esos habitantes posteriores de Pompeya finalmente abandonaron el lugar tras otra devastadora erupci\u00f3n en el siglo V, se\u00f1al\u00f3 Zuchtriegel.<\/p>\n<p>Cuando comenzaron las excavaciones a mediados del siglo XVIII, todo lo que estaba bajo la capa de ceniza segu\u00eda preservado, pero los pisos superiores se hab\u00edan deteriorado y desaparecido.<\/p>\n<p>Hab\u00eda una falta de inter\u00e9s en esos pisos superiores perdidos, ya que se pensaba que eran simples viviendas para los esclavos y ciudadanos m\u00e1s pobres de Pompeya, explic\u00f3 Muth. \u201cDurante muchos siglos, las excavaciones en Pompeya se centraron m\u00e1s en encontrar estatuas valiosas y pinturas murales\u201d, se\u00f1al\u00f3.<\/p>\n<p>Pero el renovado inter\u00e9s surgi\u00f3 del deseo de comprender la vida cotidiana de los ciudadanos comunes, a\u00f1adi\u00f3. \u201cEn ese proceso, se ha descubierto que los ciudadanos m\u00e1s acomodados de Pompeya tambi\u00e9n utilizaban habitaciones en los pisos superiores, ya que all\u00ed se han encontrado rastros de mobiliario m\u00e1s lujoso\u201d.<\/p>\n<p>Al centrar su b\u00fasqueda en los pisos superiores, los investigadores se sintieron atra\u00eddos por una residencia reci\u00e9n excavada: la Casa del Tiaso, o Casa del Thiasos.<\/p>\n<p>En una habitaci\u00f3n de la planta baja se encontraba una monumental escalera de piedra que conduc\u00eda a un segundo piso. Las hendiduras en las paredes cerca de la parte superior de la escalera apuntaban a posibles evidencias de que una segunda escalera de madera hab\u00eda existido en el piso superior desaparecido y conduc\u00eda a\u00fan m\u00e1s arriba, a un tercer piso.<\/p>\n<p>\u201cCuando comenzamos a reconstruir esta habitaci\u00f3n en t\u00e9rminos de su arquitectura perdida, nos qued\u00f3 claro que solo pod\u00eda ser una torre\u201d, dijo Muth.<\/p>\n<p>La Casa del Tiaso fue una de las residencias m\u00e1s lujosas de Pompeya y probablemente pertenec\u00eda a una familia influyente, dijo Zuchtriegel.<\/p>\n<p>Conten\u00eda grandes salones decorativos para banquetes, uno de los cuales daba a un patio ajardinado y otro conduc\u00eda a un complejo de ba\u00f1os termales privados, se\u00f1al\u00f3 Muth.<\/p>\n<p>En esa \u00e9poca, las grandes villas campestres fuera de las murallas de la ciudad inclu\u00edan torres que se usaban para celebrar banquetes y disfrutar de vistas panor\u00e1micas.<\/p>\n<p>El escritor romano <a href=\"http:\/\/www.britannica.com\/biography\/Pliny-the-Younger\">Plinio el Joven<\/a> describi\u00f3 una torre as\u00ed en su villa campestre, donde pod\u00eda disfrutar del amanecer y el atardecer, dijo Muth. La leyenda cuenta que el emperador romano Ner\u00f3n observ\u00f3 el incendio de Roma desde una torre en los Jardines de Mecenas. Textos antiguos del siglo II a.C. y pinturas del siglo I a.C. al siglo I d.C. tambi\u00e9n incluyen torres anexas a villas lujosas.<\/p>\n<p>Pero los arque\u00f3logos no han buscado evidencia de torres dentro de ciudades romanas como Pompeya por una buena raz\u00f3n: estas casas a menudo se constru\u00edan como estructuras extensas, en lugar de viviendas de varios pisos agrupadas, explic\u00f3 Muth.<\/p>\n<p>\u201cLos hallazgos \u00fanicos en la Casa del Tiaso ahora nos llevan a creer que tales torres tambi\u00e9n exist\u00edan en las ciudades como un elemento de la arquitectura residencial de lujo que buscaba imitar la magn\u00edfica arquitectura de las villas y con la que el propietario quer\u00eda representar su estatus social desde lejos\u201d, dijo Muth.<\/p>\n<p>El due\u00f1o de la Casa del Tiaso pudo haber celebrado banquetes con invitados en el piso superior de la torre, disfrutando de la vista de la ciudad y el golfo de N\u00e1poles, a\u00f1adi\u00f3.<\/p>\n<p>La torre tambi\u00e9n pudo haberse utilizado para observar las estrellas en el cielo nocturno. La astrolog\u00eda era popular en la sociedad romana, aunque varios emperadores intentaron prohibirla, se\u00f1al\u00f3 Zuchtriegel.<\/p>\n<p>Las regulaciones religiosas pueden explicar por qu\u00e9 las torres no eran comunes en la ciudad, dijo el Dr. Marcello Mogetta, director del departamento de cl\u00e1sicos, arqueolog\u00eda y religi\u00f3n de la Universidad de Missouri. Mogetta no particip\u00f3 en la nueva investigaci\u00f3n.<\/p>\n<p>En la antigua Roma, los templos y santuarios necesitaban l\u00edneas de visi\u00f3n despejadas para la toma de auspicios \u2014interpretar presagios a partir del comportamiento de las aves\u2014 y otros rituales. Los edificios privados m\u00e1s altos estaban restringidos, lo que llev\u00f3 a que las mansiones urbanas se expandieran hacia abajo para crear pisos hundidos, explic\u00f3 Mogetta.<\/p>\n<p>Si bien hay evidencia clara de apartamentos en los pisos superiores en Pompeya, una torre de gran altura en una casa prestigiosa como la Casa del Tiaso es algo sin precedentes, pero no descabellado, dijo.<\/p>\n<p>Las torres tambi\u00e9n reflejan la innovaci\u00f3n creativa empleada por los habitantes de Pompeya para afirmar su prestigio, a\u00f1adi\u00f3 Mogetta.<\/p>\n<p>\u201cEstructuras similares a torres aparecen en pinturas murales pompeyanas que representan paisajes urbanos, aunque tradicionalmente se han descartado como fantas\u00eda art\u00edstica impulsada por el gusto por el ilusionismo\u201d, dijo Mogetta. \u201cLa reconstrucci\u00f3n propuesta desaf\u00eda esa suposici\u00f3n. Si es precisa, significa que esas escenas pintadas podr\u00edan haber reflejado el paisaje urbano real m\u00e1s de lo que pens\u00e1bamos\u201d.<\/p>\n<p>La reconstrucci\u00f3n digital de los edificios de Pompeya es como un trabajo de detective, dijo Muth. Toda la evidencia se recopila meticulosamente y no se deja ning\u00fan detalle sin documentar.<\/p>\n<p>Ahora los investigadores utilizan drones para capturar escaneos de edificios completos, tecnolog\u00eda l\u00e1ser para medir superficies y fotograf\u00eda de corto alcance para determinar detalles de textura. Las im\u00e1genes superpuestas ayudan a crear modelos 3D en un proceso llamado fotogrametr\u00eda.<\/p>\n<p>A partir de los escaneos y fotos se crea un gemelo digital de un edificio, que los investigadores usan para reconstruir la arquitectura perdida, reinsertando virtualmente vigas de madera en los agujeros de las paredes y siguiendo patrones para determinar d\u00f3nde existieron pisos superiores o escaleras.<\/p>\n<p>\u201cProcedemos con mucha cautela, discutimos mucho, probamos una propuesta, la rechazamos, la corregimos, descubrimos nuevas pistas, comparamos esas pistas con otros edificios de Pompeya para encontrar analog\u00edas\u201d, dijo Muth. \u201cPaso a paso, surge un modelo 3D sobre el que podemos desarrollar nuestros argumentos y propuestas de manera transparente y luego presentarlos para que puedan ser revisados y discutidos por la comunidad cient\u00edfica\u201d.<\/p>\n<p>Los arque\u00f3logos han utilizado durante mucho tiempo dibujos o modelos 3D a escala para reconstruir arquitectura perdida. La arqueolog\u00eda digital lleva el proceso algunos pasos m\u00e1s all\u00e1, se\u00f1al\u00f3 Muth.<\/p>\n<p>Es f\u00e1cil que los dibujos bidimensionales contengan errores porque solo pueden revisarse desde un \u00e1ngulo. Pero los modelos 3D deben ser 100 % precisos desde todos los \u00e1ngulos.<\/p>\n<p>\u201cSolo cuando el dise\u00f1o estructural del edificio se recrea digitalmente con precisi\u00f3n en un modelo 3D se puede comprender la arquitectura y desarrollar una reconstrucci\u00f3n plausible\u201d, dijo Muth.<\/p>\n<p>La tecnolog\u00eda de los videojuegos tambi\u00e9n est\u00e1 haciendo que los modelos 3D sean m\u00e1s accesibles, permitiendo examinar m\u00e1s de cerca los espacios habitables antiguos mediante recorridos virtuales.<\/p>\n<p>\u201cPodemos visualizar de manera m\u00e1s concreta un banquete a la luz de las velas, o una celebraci\u00f3n en la cima de la torre de la Casa del Tiaso, pero tambi\u00e9n las opresivas condiciones de trabajo en la llamada panader\u00eda de esclavos de al lado\u201d, explic\u00f3 Muth. \u201cTodo esto nos ayudar\u00e1 a plantear y obtener nuevas preguntas y respuestas sobre la vida en Pompeya\u201d.<\/p>\n<p>Aun as\u00ed, persisten las dudas sobre si hubo m\u00e1s casas en Pompeya que alguna vez incluyeron torres, y el equipo sigue buscando rastros de pisos superiores perdidos.<\/p>\n<p>\u201cPara quienes no pod\u00edan aprovechar las vistas naturales, una estructura tipo torre era una soluci\u00f3n ingeniosa: combinaba espect\u00e1culo, visibilidad y se\u00f1alizaci\u00f3n social en un solo gesto arquitect\u00f3nico\u201d, dijo Mogetta. \u201cSe necesita m\u00e1s trabajo del proyecto Pompeii Reset en otros sectores de la ciudad para revelar cu\u00e1n extendido estaba realmente el fen\u00f3meno\u201d.<\/p>\n<p>Las casas antiguas rara vez sobreviven al paso del tiempo, especialmente milenios, y si lo hacen, solo quedan fragmentos como cimientos s\u00f3lidos para marcar d\u00f3nde estuvo una residencia. Pero algunos sitios, como Pompeya, son excepcionales y podr\u00edan usarse para reconstruir antiguos horizontes urbanos y mostrar c\u00f3mo crecieron las ciudades con el tiempo. Por ejemplo, los investigadores saben que la Italia medieval estaba llena de <a href=\"https:\/\/www.cnn.com\/2025\/11\/25\/travel\/torre-dei-conti-collapse-rome-future\">torres<\/a> porque algunas de ellas a\u00fan se mantienen en pie hoy en d\u00eda.<\/p>\n<p>En el yacimiento arqueol\u00f3gico de <a href=\"http:\/\/whc.unesco.org\/en\/list\/1405\/\">\u00c7atalh\u00f6y\u00fck<\/a>, hay evidencia de una red de viviendas construidas tan juntas que las personas del Neol\u00edtico que viv\u00edan all\u00ed entre 7400 a.C. y 5200 a.C. ten\u00edan que usar los techos para acceder a sus interiores. Con el tiempo, se construyeron nuevas viviendas sobre las casas originales.<\/p>\n<p>\u201cSabemos que las ciudades y asentamientos del pasado debieron tener, a menudo, un horizonte m\u00e1s alto del que ahora podemos observar directamente, desde el \u00c7atalh\u00f6y\u00fck neol\u00edtico hasta las ciudades de la Italia medieval, y el mundo romano no es la excepci\u00f3n\u201d, dijo Daniel Diffendale, investigador posdoctoral en la Scuola Normale Superiore de Pisa, Italia, quien no particip\u00f3 en el nuevo trabajo. \u201cHay evidencia de edificios m\u00e1s altos si se busca\u201d.<\/p>\n<p>El objetivo de Muth es que la reconstrucci\u00f3n digital de la Casa del Tiaso incluya eventualmente todas las habitaciones. Pero el proyecto m\u00e1s amplio no tiene fecha de finalizaci\u00f3n; el equipo quiere ver cu\u00e1ntos edificios puede reconstruir virtualmente para preservar el patrimonio de Pompeya.<\/p>\n<p>Las herramientas digitales se han convertido en una forma fundamental de monitorear el estado de conservaci\u00f3n de Pompeya y determinar d\u00f3nde se necesita intervenci\u00f3n.<\/p>\n<p>Tambi\u00e9n pueden crear modelos de partes de la ciudad que no se conservaron en absoluto, dijo Zuchtriegel.<\/p>\n<p>\u201cLa arqueolog\u00eda digital es mucho m\u00e1s que simplemente crear reconstrucciones fantasiosas de edificios antiguos\u201d, dijo. \u201cEs una forma de reflexionar sobre estas estructuras y c\u00f3mo realmente funcionaban y se utilizaban\u201d.<\/p>\n<p>M\u00e1s de 13.000 habitaciones han sido excavadas en la ciudad perdida desde 1748, y un tercio de la antigua Pompeya sigue enterrado bajo ceniza volc\u00e1nica.<\/p>\n<p>Los hallazgos de excavaciones recientes podr\u00edan ayudar a los investigadores a comprender casas que se investigaron por primera vez hace d\u00e9cadas o siglos, pero excavar toda Pompeya no es el objetivo, dijo Zuchtriegel. El parque arqueol\u00f3gico quiere dejar algo para las futuras generaciones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Casi 2.000 a\u00f1os despu\u00e9s de que una devastadora erupci\u00f3n volc\u00e1nica destruyera y sepultara una pr\u00f3spera ciudad romana, los investigadores est\u00e1n recurriendo a la novedosa t\u00e9cnica de la arqueolog\u00eda digital para revelar la \u201cPompeya perdida\u201d. El monte Vesubio entr\u00f3 en erupci\u00f3n en el a\u00f1o 79 d.C., cubriendo Pompeya con una gruesa capa de roca fundida, ceniza [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469067","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Investigadores encuentran una antigua escalera romana que revela la &quot;Pompeya perdida&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investigadores encuentran una antigua escalera romana que revela la &quot;Pompeya perdida&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Casi 2.000 a\u00f1os despu\u00e9s de que una devastadora erupci\u00f3n volc\u00e1nica destruyera y sepultara una pr\u00f3spera ciudad romana, los investigadores est\u00e1n recurriendo a la novedosa t\u00e9cnica de la arqueolog\u00eda digital para revelar la \u201cPompeya perdida\u201d. El monte Vesubio entr\u00f3 en erupci\u00f3n en el a\u00f1o 79 d.C., cubriendo Pompeya con una gruesa capa de roca fundida, ceniza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-08T13:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Investigadores encuentran una antigua escalera romana que revela la &#171;Pompeya perdida&#187;\",\"datePublished\":\"2025-12-08T13:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/\"},\"wordCount\":2347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/\",\"name\":\"Investigadores encuentran una antigua escalera romana que revela la \\\"Pompeya perdida\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-08T13:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investigadores encuentran una antigua escalera romana que revela la &#171;Pompeya perdida&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investigadores encuentran una antigua escalera romana que revela la \"Pompeya perdida\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Investigadores encuentran una antigua escalera romana que revela la \"Pompeya perdida\" - Noticias","og_description":"Casi 2.000 a\u00f1os despu\u00e9s de que una devastadora erupci\u00f3n volc\u00e1nica destruyera y sepultara una pr\u00f3spera ciudad romana, los investigadores est\u00e1n recurriendo a la novedosa t\u00e9cnica de la arqueolog\u00eda digital para revelar la \u201cPompeya perdida\u201d. El monte Vesubio entr\u00f3 en erupci\u00f3n en el a\u00f1o 79 d.C., cubriendo Pompeya con una gruesa capa de roca fundida, ceniza [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-08T13:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/"},"author":{"name":"","@id":""},"headline":"Investigadores encuentran una antigua escalera romana que revela la &#171;Pompeya perdida&#187;","datePublished":"2025-12-08T13:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/"},"wordCount":2347,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/","name":"Investigadores encuentran una antigua escalera romana que revela la \"Pompeya perdida\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-08T13:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Investigadores encuentran una antigua escalera romana que revela la &#171;Pompeya perdida&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Investigadores encuentran una antigua escalera romana que revela la &#171;Pompeya perdida&#187;","url":"http:\/\/noticiasya.com\/el-valle\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/12\/08\/pompeya-perdida-encuentran-escalera-romana-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-08T13:03:40Z","datePublished":"2025-12-08T13:03:40Z","dateModified":"2025-12-08T13:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Investigadores encuentran una antigua escalera romana que revela la &#171;Pompeya perdida&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/12\\\/08\\\/pompeya-perdida-encuentran-escalera-romana-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/12\\\/08\\\/pompeya-perdida-encuentran-escalera-romana-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-08T13:03:40Z\",\"datePublished\":\"2025-12-08T13:03:40Z\",\"dateModified\":\"2025-12-08T13:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455744,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/11\/11\/pompeya-limita-visitantes-diarios-trax\/","url_meta":{"origin":1469067,"position":0},"title":"Pompeya limita su n\u00famero de visitantes diarios","author":"","date":"noviembre 11, 2024","format":false,"excerpt":"(CNN) -- Las autoridades de Pompeya, en el sur de Italia, establecer\u00e1n un l\u00edmite diario de 20.000 visitantes como parte de los esfuerzos para proteger el antiguo sitio arqueol\u00f3gico.La medida, que entrar\u00e1 en vigor a partir del 15 de noviembre, supondr\u00e1 la introducci\u00f3n de entradas personalizadas con el nombre de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469437,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/19\/yacimiento-pompeya-revela-receta-hormigon-romano-trax\/","url_meta":{"origin":1469067,"position":1},"title":"Un yacimiento de Pompeya revela la receta del hormig\u00f3n romano y contradice lo escrito por un famoso arquitecto","author":"","date":"diciembre 19, 2025","format":false,"excerpt":"Junto con muchas otras innovaciones, el Imperio romano revolucion\u00f3 la arquitectura con caracter\u00edsticas nunca antes vistas, como arcos de gran escala y techos abovedados. Y muchas de estas estructuras todav\u00eda se mantienen en pie hoy, a pesar de tener m\u00e1s de 2.000 a\u00f1os de antig\u00fcedad.Nada de esto habr\u00eda sido posible\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460753,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/02\/pompeya-descubren-dos-raras-estatuas-tumba-trax\/","url_meta":{"origin":1469067,"position":2},"title":"Descubren dos raras estatuas en una tumba de Pompeya","author":"","date":"abril 2, 2025","format":false,"excerpt":"Dos estatuas raras fueron descubiertas durante la excavaci\u00f3n de una enorme tumba en Pompeya. Los arque\u00f3logos afirman que las estatuas funerarias de m\u00e1rmol de un hombre y una mujer vestidos con toga arrojan nueva luz sobre el poder que ejerc\u00edan las sacerdotisas en la antigua ciudad, destruida por la erupci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447999,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/04\/11\/descubren-frescos-personajes-mitologicos-pompeya-trax\/","url_meta":{"origin":1469067,"position":3},"title":"Descubren impactantes frescos de personajes mitol\u00f3gicos en Pompeya","author":"","date":"abril 11, 2024","format":false,"excerpt":"(CNN) -- Los antiguos romanos disfrutaban de algo m\u00e1s que la comida durante sus fiestas, o eso parece demostrar un nuevo descubrimiento en el sitio arqueol\u00f3gico de Pompeya.Los arque\u00f3logos que trabajan en este sitio mundialmente conocido descubrieron una sala de banquetes con paredes pintadas de negro y cubiertas con frescos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450061,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/06\/05\/santuario-azul-es-el-ultimo-descubrimiento-pompeya-trax\/","url_meta":{"origin":1469067,"position":4},"title":"Un santuario pintado de azul es el \u00faltimo descubrimiento del &#171;cofre del tesoro&#187; de Pompeya","author":"","date":"junio 5, 2024","format":false,"excerpt":"Mil\u00e1n, Italia (CNN) -- Los arque\u00f3logos descubrieron una habitaci\u00f3n azul decorada a detalle, interpretada como un antiguo santuario romano conocido como sacrarium, durante las recientes excavaciones en el centro de Pompeya, Italia.El ministro de Cultura de Italia, Gennaro Sangiuliano, visit\u00f3 el sitio arqueol\u00f3gico el martes y describi\u00f3 la antigua ciudad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469525,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/23\/misterios-ciencia-resueltos-2025-trax\/","url_meta":{"origin":1469067,"position":5},"title":"Estos son los misterios hist\u00f3ricos que fueron resueltos por la ciencia en 2025","author":"","date":"diciembre 23, 2025","format":false,"excerpt":"Investigadores de todo el mundo pusieron manos a la obra este a\u00f1o para dar respuesta a algunas preguntas que han persistido durante d\u00e9cadas e incluso siglos. Los hallazgos, que invitan a la reflexi\u00f3n, ofrecen nuevas formas de comprender el pasado.La exploraci\u00f3n arqueol\u00f3gica de yacimientos hist\u00f3ricos arroj\u00f3 nuevas perspectivas. El an\u00e1lisis\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1469067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1469067"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1469067\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1469067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1469067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1469067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}