{"id":1469121,"date":"2025-12-09T14:03:42","date_gmt":"2025-12-09T22:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/"},"modified":"2025-12-09T14:03:42","modified_gmt":"2025-12-09T22:03:42","slug":"policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/","title":{"rendered":"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida"},"content":{"rendered":"<p>Una persona muri\u00f3 y otra result\u00f3 herida tras un tiroteo en la Universidad Estatal de Kentucky que interrumpi\u00f3 los ex\u00e1menes finales del semestre de los estudiantes antes de que salieran de vacaciones de invierno, seg\u00fan la polic\u00eda.<\/p>\n<p>El sospechoso est\u00e1 bajo custodia, dijo la polic\u00eda.<\/p>\n<p>El gobernador Andy Beshear dijo que est\u00e1 \u201cal tanto de algunas lesiones\u201d, mientras que el subjefe de polic\u00eda de Frankfort, Scott Tracy, dijo a la afiliada WDRB que dos personas resultaron heridas en el tiroteo, que ocurri\u00f3 en Young Hall, una residencia universitaria, en el campus.<\/p>\n<p>CNN se ha puesto en contacto con el Departamento de Polic\u00eda de Frankfort para obtener m\u00e1s informaci\u00f3n.<\/p>\n<p>Las agencias de seguridad siguen en el lugar y han asegurado el campus, ya que la escuela permanece cerrada.<\/p>\n<p>El tiroteo ocurri\u00f3 en el campus de la escuela alrededor de las 3:35 p.m., cuando el Departamento de Polic\u00eda de Frankfort respondi\u00f3 a un \u201cagresor activo\u201d, seg\u00fan la agencia.<\/p>\n<p>Funcionarios de la universidad dijeron que \u201ca\u00fan est\u00e1n en el proceso de recopilar informaci\u00f3n precisa y completa\u201d antes de emitir una declaraci\u00f3n oficial.<\/p>\n<p>La Universidad Estatal de Kentucky, que fue fundada en 1886, tiene m\u00e1s de 2.200 estudiantes y 450 miembros de la facultad y el personal, seg\u00fan su sitio web.<\/p>\n<p>El incidente del martes ocurre despu\u00e9s de que otras dos universidades hist\u00f3ricamente afroamericanas fueran atacadas en tiroteos separados durante los fines de semana de regreso a casa en octubre. Cinco personas resultaron heridas en un tiroteo cerca del campus de la Universidad Howard en Washington, dijo la polic\u00eda, pero ninguna de las v\u00edctimas era estudiante.<\/p>\n<p>Solo un d\u00eda despu\u00e9s, al menos una persona muri\u00f3 y otras seis resultaron heridas durante el fin de semana de regreso a casa en la Universidad Lincoln de Pensilvania, seg\u00fan la polic\u00eda.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una persona muri\u00f3 y otra result\u00f3 herida tras un tiroteo en la Universidad Estatal de Kentucky que interrumpi\u00f3 los ex\u00e1menes finales del semestre de los estudiantes antes de que salieran de vacaciones de invierno, seg\u00fan la polic\u00eda. El sospechoso est\u00e1 bajo custodia, dijo la polic\u00eda. El gobernador Andy Beshear dijo que est\u00e1 \u201cal tanto de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469121","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una persona muri\u00f3 y otra result\u00f3 herida tras un tiroteo en la Universidad Estatal de Kentucky que interrumpi\u00f3 los ex\u00e1menes finales del semestre de los estudiantes antes de que salieran de vacaciones de invierno, seg\u00fan la polic\u00eda. El sospechoso est\u00e1 bajo custodia, dijo la polic\u00eda. El gobernador Andy Beshear dijo que est\u00e1 \u201cal tanto de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-09T22:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida\",\"datePublished\":\"2025-12-09T22:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/\",\"name\":\"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-09T22:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida - Noticias","og_description":"Una persona muri\u00f3 y otra result\u00f3 herida tras un tiroteo en la Universidad Estatal de Kentucky que interrumpi\u00f3 los ex\u00e1menes finales del semestre de los estudiantes antes de que salieran de vacaciones de invierno, seg\u00fan la polic\u00eda. El sospechoso est\u00e1 bajo custodia, dijo la polic\u00eda. El gobernador Andy Beshear dijo que est\u00e1 \u201cal tanto de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-09T22:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/"},"author":{"name":"","@id":""},"headline":"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida","datePublished":"2025-12-09T22:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/","name":"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-09T22:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida","url":"http:\/\/noticiasya.com\/el-valle\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/12\/09\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-09T22:03:42Z","datePublished":"2025-12-09T22:03:42Z","dateModified":"2025-12-09T22:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Tiroteo en la Universidad Estatal de Kentucky deja una persona muerta y otra herida\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/12\\\/09\\\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/12\\\/09\\\/policia-investiga-tiroteo-universidad-estatal-de-kentucky-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-09T22:03:42Z\",\"datePublished\":\"2025-12-09T22:03:42Z\",\"dateModified\":\"2025-12-09T22:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461401,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/04\/19\/estudiantes-experimentaron-segundo-tiroteo-escolar-fsu-trax\/","url_meta":{"origin":1469121,"position":0},"title":"Estos estudiantes de Parkland experimentaron su segundo tiroteo mortal en la Universidad Estatal de Florida","author":"","date":"abril 19, 2025","format":false,"excerpt":"Mientras Ilana Badiner se refugiaba en el centro de estudiantes durante el tiroteo en la Universidad Estatal de Florida el jueves, recuerda haber pensado: \u201cYa sab\u00eda c\u00f3mo era la situaci\u00f3n\u201d.Hace siete a\u00f1os, Badiner estaba en octavo grado en la escuela secundaria adyacente a la escuela secundaria Marjory Stoneman Douglas (MSD)\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467515,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/10\/19\/heridos-tiroteo-universidad-oklahoma-trax\/","url_meta":{"origin":1469121,"position":1},"title":"Al menos tres heridos por tiroteo en una residencia estudiantil de la Universidad Estatal de Oklahoma","author":"","date":"octubre 19, 2025","format":false,"excerpt":"Un tiroteo en una residencia universitaria de la Universidad Estatal de Oklahoma dej\u00f3 al menos tres heridos la madrugada de este domingo, seg\u00fan un portavoz de la universidad.La Polic\u00eda dijo que \u201cno hay una amenaza continua para el campus\u201d.Los informes iniciales indican que el tiroteo ocurri\u00f3 cuando personas llegaron a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464487,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/07\/13\/kentucky-tiroteo-muertos-iglesia-trax\/","url_meta":{"origin":1469121,"position":2},"title":"Dos muertos en iglesia de Kentucky tras tiroteo en el que un atacante dispar\u00f3 a un agente estatal; el sospechoso muri\u00f3","author":"","date":"julio 13, 2025","format":false,"excerpt":"Una mujer de 72 a\u00f1os y otra de 32 murieron en un tiroteo este domingo en la iglesia bautista Richmond Road, en Lexington, Kentucky, informaron las autoridades.El atacante, quien tambi\u00e9n muri\u00f3, ya fue identificado, pero la polic\u00eda no revel\u00f3 su nombre porque su familia a\u00fan no ha sido notificada, indicaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442564,"url":"https:\/\/noticiasya.com\/el-valle\/2023\/12\/23\/tiroteo-en-centro-comercial-de-florida-deja-una-persona-muerta-y-una-herida-asegura-la-policia\/","url_meta":{"origin":1469121,"position":3},"title":"Tiroteo en centro comercial de Florida deja una persona muerta y una herida, asegura la polic\u00eda","author":"","date":"diciembre 23, 2023","format":false,"excerpt":"(CNN) --Un hombre muri\u00f3 y una mujer result\u00f3 herida despu\u00e9s de un tiroteo dentro de un centro comercial de Ocala, Florida, el s\u00e1bado por la tarde, seg\u00fan el jefe de polic\u00eda de Ocala, Mike Balken.Balken dijo que la polic\u00eda recibi\u00f3 llamadas al 911 sobre m\u00faltiples disparos dentro del Paddock Mall.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467749,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/10\/25\/heridos-tiroteo-universidad-lincoln-pensilvania-bienvenida-trax\/","url_meta":{"origin":1469121,"position":4},"title":"Al menos cuatro heridos de bala en una fiesta de bienvenida en la Universidad Lincoln en Pensilvania","author":"","date":"octubre 25, 2025","format":false,"excerpt":"La Polic\u00eda est\u00e1 respondiendo a un tiroteo que dej\u00f3 a varias personas heridas en la Universidad Lincoln de Pensilvania el s\u00e1bado por la noche, durante el fin de semana de regreso a casa de la universidad hist\u00f3ricamente negra.Tres personas con heridas de bala fueron trasladadas al Hospital Christiana en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462820,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/05\/26\/tiroteo-carolina-del-sur-barco-trax\/","url_meta":{"origin":1469121,"position":5},"title":"Altercado en un barco en Carolina del Sur termina con diez personas baleadas, seg\u00fan la Polic\u00eda","author":"","date":"mayo 26, 2025","format":false,"excerpt":"Diez personas resultaron heridas de bala y al menos otra result\u00f3 herida cuando una reuni\u00f3n en un barco de alquiler en una comunidad costera de Carolina del Sur se torn\u00f3 violenta, seg\u00fan la polic\u00eda.Algunos de los heridos en el tiroteo ocurrido el domingo en Little River se encontraban en estado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1469121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1469121"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1469121\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1469121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1469121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1469121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}