{"id":1469165,"date":"2025-12-10T19:03:44","date_gmt":"2025-12-11T03:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/"},"modified":"2025-12-10T19:03:44","modified_gmt":"2025-12-11T03:03:44","slug":"john-cena-wwe-icono-entretenimiento-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/","title":{"rendered":"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento"},"content":{"rendered":"<p>Cuando John Cena debut\u00f3 en la WWE, el panorama del \u201cdeporte entretenimiento\u201d era muy diferente al de ahora.<\/p>\n<p>Cena entraba en un terreno donde a\u00fan sonaban otros titanes de la industria, como Undertaker, The Rock, HHH o Stone Cold Steve Austin, pero su irrupci\u00f3n, violenta, marc\u00f3 el inicio de una era donde revolucion\u00f3 todo a su paso.<\/p>\n<p>El oriundo de West Newbury, cerca de Boston, Massachusetts, entr\u00f3 al ring con la cara apretada y un gesto de piedra, para retar al entonces campe\u00f3n de la compa\u00f1\u00eda, el exmedallista de oro ol\u00edmpico en lucha grecorromana, Kurt Angle, aduciendo que \u00e9l era todo \u201cagresi\u00f3n sin reglas\u201d.<\/p>\n<p>Pas\u00f3 por un par de transformaciones en su personaje, desde el rapero, que en efecto lleg\u00f3 a grabar una producci\u00f3n discogr\u00e1fica mientras su carrera ascend\u00eda como la espuma a mediados de los 2000 en WWE, hasta convertirse en lo que Vince McMahon jam\u00e1s pens\u00f3 que tendr\u00eda: un nuevo <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/24\/deportes\/muere-hulk-hogan-lucha-libre-trax\">Hulk Hogan.<\/a><\/p>\n<p>Amado por los ni\u00f1os, las mujeres ca\u00edan rendidas ante su estampa de exf\u00edsicoculturista, y no tan querido entre los adolescentes que se cansaban de verlo ganar siempre, Cena se volvi\u00f3 la imagen ic\u00f3nica de la compa\u00f1\u00eda, hasta entrada la segunda d\u00e9cada de los 2000.<\/p>\n<p>Cena es actualmente el luchador que ha ganado m\u00e1s veces en la historia de la WWE el t\u00edtulo al campe\u00f3n mundial, con un total de 17 veces. 14 veces como campe\u00f3n de la WWE, tres m\u00e1s como campe\u00f3n del peso pesado. Adem\u00e1s, es uno de los 25 campeones de Grand Slam, es decir, que gan\u00f3 todas las coronas de la compa\u00f1\u00eda.<\/p>\n<p>Logr\u00f3, adem\u00e1s de los campeonatos mundiales, cinco veces el t\u00edtulo de Estados Unidos, una vez el Intercontinental (ahora, en su tour de despedida) y cuatro veces campe\u00f3n mundial en parejas.<\/p>\n<p>Su preponderancia en la compa\u00f1\u00eda fue tal que, en su periodo como campe\u00f3n, termin\u00f3 encabezando cinco veces el evento m\u00e1s importante del a\u00f1o para WWE, Wrestlemania.<\/p>\n<p>No obstante, la carrera de Cena comenz\u00f3 a mermar en el ring al combinarse con una prol\u00edfica trayectoria en el cine y la televisi\u00f3n, recorriendo el mismo camino que alguna vez tambi\u00e9n transit\u00f3 su predecesor como estandarte de la empresa de lucha, Dwayne \u201cThe Rock\u201d Johnson.<\/p>\n<p>Al punto que termin\u00f3 siendo presentador del Premio Oscar en 2024, con una pol\u00e9mica aparici\u00f3n donde termin\u00f3 saliendo al escenario cubierto por apenas una diminuta toalla.<\/p>\n<p>Adem\u00e1s, esa fama fue aprovechada por el artista para realizar labores de filantrop\u00eda, convirti\u00e9ndose tambi\u00e9n en la imagen de la fundaci\u00f3n Make A Wish, que consiste en cumplir los deseos de ni\u00f1os en condiciones cr\u00edticas de salud.<\/p>\n<p>Cena anunci\u00f3 a finales de 2024 que este ser\u00eda su \u00faltimo a\u00f1o en la WWE. El cuerpo, a sus 48 a\u00f1os, ya no le responde de la misma forma, y \u00e9l confes\u00f3 en esa conferencia de prensa que quisiera dedicarle m\u00e1s tiempo a su nueva esposa y a sus proyectos en el cine.<\/p>\n<p>Realiz\u00f3 un tour de despedida que lo llev\u00f3 a darle la vuelta al mundo con la WWE en 2025, combatiendo en distintas ciudades en Estados Unidos, Europa y hasta en Jap\u00f3n y Australia.<\/p>\n<p>Pero, sin dudas, despu\u00e9s de que se toque la campana y se d\u00e9 la cuenta de tres en su \u00faltimo combate el s\u00e1bado 13 de diciembre en Washington, gane o pierda, su enorme legado lo deja como uno de los m\u00e1s grandes luchadores de todos los tiempos, y un personaje que con sus m\u00edmicas y gestos carg\u00f3 con la WWE en sus hombros hasta trascender al ensogado para volverse parte de la cultura pop.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando John Cena debut\u00f3 en la WWE, el panorama del \u201cdeporte entretenimiento\u201d era muy diferente al de ahora. Cena entraba en un terreno donde a\u00fan sonaban otros titanes de la industria, como Undertaker, The Rock, HHH o Stone Cold Steve Austin, pero su irrupci\u00f3n, violenta, marc\u00f3 el inicio de una era donde revolucion\u00f3 todo a [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469165","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando John Cena debut\u00f3 en la WWE, el panorama del \u201cdeporte entretenimiento\u201d era muy diferente al de ahora. Cena entraba en un terreno donde a\u00fan sonaban otros titanes de la industria, como Undertaker, The Rock, HHH o Stone Cold Steve Austin, pero su irrupci\u00f3n, violenta, marc\u00f3 el inicio de una era donde revolucion\u00f3 todo a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-11T03:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento\",\"datePublished\":\"2025-12-11T03:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/\"},\"wordCount\":657,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/\",\"name\":\"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-11T03:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/","og_locale":"es_ES","og_type":"article","og_title":"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento - Noticias","og_description":"Cuando John Cena debut\u00f3 en la WWE, el panorama del \u201cdeporte entretenimiento\u201d era muy diferente al de ahora. Cena entraba en un terreno donde a\u00fan sonaban otros titanes de la industria, como Undertaker, The Rock, HHH o Stone Cold Steve Austin, pero su irrupci\u00f3n, violenta, marc\u00f3 el inicio de una era donde revolucion\u00f3 todo a [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/","og_site_name":"Noticias","article_published_time":"2025-12-11T03:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/"},"author":{"name":"","@id":""},"headline":"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento","datePublished":"2025-12-11T03:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/"},"wordCount":657,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/","url":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/","name":"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-11T03:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"John Cena: de cargar a la WWE en sus hombros a \u00edcono del entretenimiento","url":"http:\/\/noticiasya.com\/el-valle\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/12\/10\/john-cena-wwe-icono-entretenimiento-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-11T03:03:44Z","datePublished":"2025-12-11T03:03:44Z","dateModified":"2025-12-11T03:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"John Cena: de cargar a la WWE en sus hombros a \\u00edcono del entretenimiento\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/12\\\/10\\\/john-cena-wwe-icono-entretenimiento-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/12\\\/10\\\/john-cena-wwe-icono-entretenimiento-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-11T03:03:44Z\",\"datePublished\":\"2025-12-11T03:03:44Z\",\"dateModified\":\"2025-12-11T03:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465345,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/08\/09\/john-cena-trasplante-cabello-cambio-vida-trax\/","url_meta":{"origin":1469165,"position":0},"title":"John Cena dice que hacerse un trasplante de cabello &#171;cambi\u00f3 por completo el rumbo&#187; de su vida","author":"","date":"agosto 9, 2025","format":false,"excerpt":"John Cena tiene un nuevo aspecto gracias a un trasplante de cabello al que se someti\u00f3 el a\u00f1o pasado, y lo est\u00e1 adoptando por completo.El actor y leyenda de la lucha libre habl\u00f3 abiertamente sobre su decisi\u00f3n de hacerse un trasplante de cabello en una nueva entrevista con la revista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464866,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/07\/25\/hulk-hogan-documental-netflix-muerte-trax\/","url_meta":{"origin":1469165,"position":1},"title":"Hulk Hogan estaba filmando un documental para Netflix al momento de su muerte","author":"","date":"julio 25, 2025","format":false,"excerpt":"Hulk Hogan se encontraba en pleno rodaje de un documental para Netflix cuando falleci\u00f3, seg\u00fan pudo saber CNN.La leyenda de la lucha libre profesional muri\u00f3 a principios de esta semana, a los 71 a\u00f1os.El proyecto, que no hab\u00eda sido anunciado previamente y que se realiza en asociaci\u00f3n con la World\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469261,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/14\/john-cena-retiro-lucha-libre-wwe-orix\/","url_meta":{"origin":1469165,"position":2},"title":"El retiro de una leyenda: John Cena se despidi\u00f3 de la lucha libre con un final que nadie imagin\u00f3","author":"","date":"diciembre 14, 2025","format":false,"excerpt":"Los finales no siempre son felices. Eso es lo que qued\u00f3 demostrado en la noche del s\u00e1bado o madrugada del domingo en el Capital One Arena de Washington, durante el Saturday Night\u2019s Main Event.Ante una multitud que se apil\u00f3 para verlo de cerca, el legendario John Cena se subi\u00f3 por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444493,"url":"https:\/\/noticiasya.com\/el-valle\/2024\/01\/27\/vince-mcmahon-fundador-de-wwe-renuncia-en-medio-de-acusaciones-de-trafico-sexual\/","url_meta":{"origin":1469165,"position":3},"title":"Vince McMahon, fundador de WWE, renuncia en medio de acusaciones de tr\u00e1fico sexual","author":"","date":"enero 27, 2024","format":false,"excerpt":"(CNN) -- Vince McMahon renunci\u00f3 a su cargo de presidente ejecutivo de TKO, la empresa matriz de WWE, luego de inquietantes acusaciones de agresi\u00f3n sexual, trata y abuso f\u00edsico.Las acusaciones salieron a la luz en una demanda presentada por una exmiembro del personal de la WWE, Janel Grant, que trabajaba\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465014,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/07\/31\/revelan-causa-muerte-hulk-hogan-trax\/","url_meta":{"origin":1469165,"position":4},"title":"Revelan la causa de muerte de Hulk Hogan","author":"","date":"julio 31, 2025","format":false,"excerpt":"El luchador profesional Hulk Hogan muri\u00f3 de un ataque al coraz\u00f3n, seg\u00fan las autoridades.La causa oficial de muerte de Hogan se cita como \u201cinfarto agudo de miocardio\u201d, que en t\u00e9rminos sencillos significa un ataque al coraz\u00f3n, de acuerdo con un informe de aprobaci\u00f3n de cremaci\u00f3n de la oficina del m\u00e9dico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469266,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/15\/5-cosas-15-diciembre-orix\/","url_meta":{"origin":1469165,"position":5},"title":"Las 5 cosas que debes saber este 15 de diciembre: Triunfo de Kast, tiroteo en Sydney, avi\u00f3n de JetBlue y m\u00e1s","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Al menos 15 muertos tras el ataque en una playa de Sydney durante una celebraci\u00f3n de Januc\u00e1. Incidente entre un avi\u00f3n de JetBlue y una aeronave militar de EE.UU. Muere el director de Hollywood Rob Reiner. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1469165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1469165"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1469165\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1469165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1469165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1469165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}