{"id":1469279,"date":"2025-12-15T09:03:42","date_gmt":"2025-12-15T17:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/"},"modified":"2025-12-15T09:03:42","modified_gmt":"2025-12-15T17:03:42","slug":"detienen-nick-hijo-rob-reiner-muerte-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/","title":{"rendered":"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa"},"content":{"rendered":"<p>Nick Reiner, hijo de Rob y Michele Singer Reiner, fue ingresado en una c\u00e1rcel de Los \u00c1ngeles el lunes, despu\u00e9s de que sus padres fueran encontrados muertos en su casa de Brentwood, seg\u00fan consta en los registros penitenciarios.<\/p>\n<p>Sin embargo, los registros no especifican el cargo que enfrenta Nick Reiner. El hombre, de 32 a\u00f1os, enfrenta un cargo por un delito grave y su fianza se fij\u00f3 en US$ 4 millones, seg\u00fan indican los registros.<\/p>\n<p>Las autoridades est\u00e1n investigando las muertes como aparentes homicidios.<\/p>\n<p>Los investigadores entrevistaron a un familiar el domingo por la noche en relaci\u00f3n con las muertes, seg\u00fan inform\u00f3 a CNN una fuente policial familiarizada con la investigaci\u00f3n.<\/p>\n<p><em>Noticia en desarrollo.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nick Reiner, hijo de Rob y Michele Singer Reiner, fue ingresado en una c\u00e1rcel de Los \u00c1ngeles el lunes, despu\u00e9s de que sus padres fueran encontrados muertos en su casa de Brentwood, seg\u00fan consta en los registros penitenciarios. Sin embargo, los registros no especifican el cargo que enfrenta Nick Reiner. El hombre, de 32 a\u00f1os, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1469279","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nick Reiner, hijo de Rob y Michele Singer Reiner, fue ingresado en una c\u00e1rcel de Los \u00c1ngeles el lunes, despu\u00e9s de que sus padres fueran encontrados muertos en su casa de Brentwood, seg\u00fan consta en los registros penitenciarios. Sin embargo, los registros no especifican el cargo que enfrenta Nick Reiner. El hombre, de 32 a\u00f1os, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-15T17:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa\",\"datePublished\":\"2025-12-15T17:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/\"},\"wordCount\":151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/\",\"name\":\"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-15T17:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa - Noticias","og_description":"Nick Reiner, hijo de Rob y Michele Singer Reiner, fue ingresado en una c\u00e1rcel de Los \u00c1ngeles el lunes, despu\u00e9s de que sus padres fueran encontrados muertos en su casa de Brentwood, seg\u00fan consta en los registros penitenciarios. Sin embargo, los registros no especifican el cargo que enfrenta Nick Reiner. El hombre, de 32 a\u00f1os, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-15T17:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/"},"author":{"name":"","@id":""},"headline":"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa","datePublished":"2025-12-15T17:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/"},"wordCount":151,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/","name":"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-15T17:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa","url":"http:\/\/noticiasya.com\/el-valle\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2025\/12\/15\/detienen-nick-hijo-rob-reiner-muerte-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-15T17:03:42Z","datePublished":"2025-12-15T17:03:42Z","dateModified":"2025-12-15T17:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Detienen al hijo de Rob Reiner tras la muerte del cineasta y su esposa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/12\\\/15\\\/detienen-nick-hijo-rob-reiner-muerte-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2025\\\/12\\\/15\\\/detienen-nick-hijo-rob-reiner-muerte-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-15T17:03:42Z\",\"datePublished\":\"2025-12-15T17:03:42Z\",\"dateModified\":\"2025-12-15T17:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1469307,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/16\/que-paso-muertes-rob-reiner-michele-claves-orix\/","url_meta":{"origin":1469279,"position":0},"title":"\u00bfQu\u00e9 pas\u00f3 en la muerte de Rob Reiner y su esposa, de qu\u00e9 acusan al hijo y c\u00f3mo habr\u00edan sido los homicidios?","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Nick Reiner, de 32 a\u00f1os, est\u00e1 detenido sin derecho a fianza despu\u00e9s de que sus padres \u2014el actor y director de Hollywood Rob Reiner, de 78 a\u00f1os, y su esposa, Michele Singer Reiner, de 67\u2014 fueran encontrados muertos en la casa familiar de Brentwood, en Los \u00c1ngeles, un d\u00eda despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469409,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/18\/que-ocurrio-antes-y-despues-muerte-rob-michele-reiner-trax\/","url_meta":{"origin":1469279,"position":1},"title":"Qu\u00e9 ocurri\u00f3 en las horas previas y posteriores a la muerte de Rob y Michele Reiner","author":"","date":"diciembre 18, 2025","format":false,"excerpt":"En las horas posteriores a que la polic\u00eda encontrara los cuerpos de Rob Reiner y Michele Singer Reiner dentro de su casa en Brentwood, California, se intensific\u00f3 la especulaci\u00f3n sobre qu\u00e9 pudo haber llevado a alguien a asesinar al querido director de Hollywood y de su esposa, una carism\u00e1tica fot\u00f3grafa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469368,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/17\/rob-michele-reiner-amor-hijo-homicidio-trax\/","url_meta":{"origin":1469279,"position":2},"title":"Lo que Rob y Michele Reiner dec\u00edan del amor que le ten\u00edan a su hijo Nick, acusado de homicidio premeditado tras su muerte","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Durante un tiempo, en los a\u00f1os 90, el cineasta Rob Reiner apart\u00f3 su atenci\u00f3n de las pel\u00edculas que lo hab\u00edan hecho famoso para enfocarse en un proyecto que lo apasionaba.La teor\u00eda del apego estaba en pleno auge: la idea de que un ni\u00f1o necesita formar lazos seguros con un cuidador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469276,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/15\/quien-es-nick-reiner-hijo-rob-y-michele-trax\/","url_meta":{"origin":1469279,"position":3},"title":"\u00bfQui\u00e9n es Nick Reiner, el hijo de Rob y Michele Reiner?","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"Nick Reiner, quien actualmente se encuentra encarcelado en Los \u00c1ngeles por un delito grave no especificado tras la muerte de sus padres en su domicilio, hablaba con frecuencia sobre su lucha contra la adicci\u00f3n a las drogas.Reiner, de 32 a\u00f1os, coescribi\u00f3 la pel\u00edcula de 2015 \u201cBeing Charlie\u201d, inspirada en sus\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471564,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/23\/nick-reiner-se-declara-inocente-homicidio-rob-michele-reiner-trax\/","url_meta":{"origin":1469279,"position":4},"title":"Nick Reiner se declara inocente de los cargos de homicidio por la muerte de sus padres, Rob y Michele Reiner","author":"","date":"febrero 23, 2026","format":false,"excerpt":"Nick Reiner, el hombre de 32 a\u00f1os acusado de dos cargos de homicidio premeditado en relaci\u00f3n con el mortal apu\u00f1alamiento de sus padres, el famoso director Rob Reiner y la fot\u00f3grafa Michele Singer Reiner, se declar\u00f3 inocente en un tribunal de Los \u00c1ngeles el lunes.Reiner renunci\u00f3 a su derecho a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469264,"url":"https:\/\/noticiasya.com\/el-valle\/2025\/12\/14\/muertos-casa-rob-reiner-hollywood-trax\/","url_meta":{"origin":1469279,"position":5},"title":"Muere el director de cine Rob Reiner y su esposa Michele, inform\u00f3 su familia, y la Polic\u00eda investiga un aparente homicidio","author":"","date":"diciembre 14, 2025","format":false,"excerpt":"Un portavoz de la familia Reiner dijo el domingo por la noche que Michele y Rob Reiner han fallecido, describiendo la p\u00e9rdida como \u201ctr\u00e1gica\u201d y pidiendo privacidad mientras los familiares est\u00e1n de luto.\u201cCon profundo dolor anunciamos el tr\u00e1gico fallecimiento de Michele y Rob Reiner.Estamos desconsolados por esta p\u00e9rdida repentina y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1469279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1469279"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1469279\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1469279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1469279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1469279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}