{"id":1472016,"date":"2026-03-09T09:03:48","date_gmt":"2026-03-09T16:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/"},"modified":"2026-03-09T09:03:48","modified_gmt":"2026-03-09T16:03:48","slug":"anthropic-demanda-gobierno-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/","title":{"rendered":"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro"},"content":{"rendered":"<p>Anthropic demand\u00f3 el lunes al Departamento de Defensa y a otras agencias federales por la decisi\u00f3n de la administraci\u00f3n Trump de etiquetar a la empresa de IA como un \u201criesgo para la cadena de suministro\u201d.<\/p>\n<p>La demanda es el \u00faltimo avance en el conflicto entre el Pent\u00e1gono y una de las empresas de IA m\u00e1s importantes del mundo, mientras la Casa Blanca intenta impulsar la adopci\u00f3n de la IA por parte del Gobierno.<\/p>\n<p>La designaci\u00f3n de riesgo para la cadena de suministro se hace generalmente a empresas asociadas con adversarios extranjeros e influye en la forma en que Anthropic puede hacer negocios con empresas que trabajan con el Departamento de Defensa. Anthropic ahora alega que esa categorizaci\u00f3n es legalmente err\u00f3nea.<\/p>\n<p>\u201cSolicitar una revisi\u00f3n judicial no altera nuestro compromiso de larga data de aprovechar la IA para proteger nuestra seguridad nacional, pero es un paso necesario para proteger nuestro negocio, nuestros clientes y nuestros socios\u201d, declar\u00f3 un portavoz de Anthropic en un comunicado. \u201cSeguiremos buscando todas las v\u00edas para una resoluci\u00f3n, incluyendo el di\u00e1logo con el Gobierno\u201d.<\/p>\n<p>CNN se ha puesto en contacto con el Departamento de Defensa y la Casa Blanca para obtener comentarios.<\/p>\n<p>El Pent\u00e1gono emiti\u00f3 la designaci\u00f3n de riesgo para la cadena de suministro tras el fracaso de las negociaciones para actualizar su contrato con Anthropic debido a dos puntos d\u00e9biles que Anthropic exige al Departamento de Defensa: que su herramienta de IA no se utilice para la vigilancia masiva de ciudadanos estadounidenses y que no se utilice para armas aut\u00f3nomas. Sin embargo, el Pent\u00e1gono quiere utilizar la IA de Anthropic para \u201ctodos los fines legales\u201d, argumentando que no puede permitir que una empresa privada dicte c\u00f3mo pueden usar sus herramientas en una emergencia de seguridad nacional. El Pent\u00e1gono afirm\u00f3 previamente que no est\u00e1 interesado en utilizar la IA para la vigilancia masiva de ciudadanos estadounidenses ni para armas aut\u00f3nomas.<\/p>\n<p>El 27 de febrero, la administraci\u00f3n Trump orden\u00f3 a las agencias federales y contratistas militares que suspendieran sus negocios con Anthropic despu\u00e9s de que la compa\u00f1\u00eda se negara a permitir que el Pent\u00e1gono utilizara su tecnolog\u00eda sin restricciones. Ese mismo d\u00eda, el secretario de Defensa, Pete Hegseth, declar\u00f3 que Anthropic ser\u00eda etiquetada como un riesgo para la cadena de suministro y a\u00f1adi\u00f3 que \u201cning\u00fan contratista, proveedor o socio que haga negocios con las fuerzas armadas de Estados Unidos podr\u00e1 realizar ninguna actividad comercial con Anthropic\u201d. Sin embargo, el director ejecutivo de Anthropic, Dario Amodei, afirm\u00f3 que la carta formal que recibi\u00f3, design\u00e1ndola como un riesgo para la cadena de suministro, indica que sus clientes solo tendr\u00e1n restricciones para usar Claude en trabajos directamente relacionados con sus contratos con el Pent\u00e1gono.<\/p>\n<p>Anthropic hab\u00eda declarado previamente que planeaba impugnar la designaci\u00f3n en los tribunales, a\u00f1adiendo que \u201csentaba un precedente peligroso para cualquier empresa estadounidense que negociara con el Gobierno\u201d.<\/p>\n<p>El director ejecutivo de Anthropic, Dario Amodei, se reuni\u00f3 con Hegseth el 24 de febrero, pero no llegaron a un acuerdo. En una entrada de blog que explicaba la decisi\u00f3n de la empresa de rechazar la oferta del Pent\u00e1gono, Amodei afirm\u00f3 que la IA no se puede utilizar actualmente de forma fiable y segura en casos como la vigilancia masiva y las armas aut\u00f3nomas. Tambi\u00e9n afirm\u00f3 que la empresa ha estado manteniendo conversaciones productivas con el Pent\u00e1gono sobre c\u00f3mo colaborar, respetando sus l\u00edmites, y c\u00f3mo garantizar una transici\u00f3n fluida si no se llega a un acuerdo.<\/p>\n<p>Trump declar\u00f3 en una publicaci\u00f3n en Truth Social del 27 de febrero que Anthropic hab\u00eda cometido un \u201cerror catastr\u00f3fico\u201d y acus\u00f3 a la empresa de intentar dictar el funcionamiento de las fuerzas armadas. OpenAI lleg\u00f3 a un acuerdo con el Pent\u00e1gono pocas horas despu\u00e9s de la orden de la administraci\u00f3n Trump.<\/p>\n<p>Anthropic no ha hecho m\u00e1s que crecer en medio del conflicto. Su aplicaci\u00f3n Claude AI super\u00f3 a ChatGPT de OpenAI en la App Store de iPhone por primera vez al d\u00eda siguiente de que el Pent\u00e1gono anunciara la rescisi\u00f3n de su contrato con Anthropic. La compa\u00f1\u00eda tambi\u00e9n anunci\u00f3 el 5 de marzo que m\u00e1s de un mill\u00f3n de personas se registran en Claude cada d\u00eda.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anthropic demand\u00f3 el lunes al Departamento de Defensa y a otras agencias federales por la decisi\u00f3n de la administraci\u00f3n Trump de etiquetar a la empresa de IA como un \u201criesgo para la cadena de suministro\u201d. La demanda es el \u00faltimo avance en el conflicto entre el Pent\u00e1gono y una de las empresas de IA m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472016","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro - Noticias\" \/>\n<meta property=\"og:description\" content=\"Anthropic demand\u00f3 el lunes al Departamento de Defensa y a otras agencias federales por la decisi\u00f3n de la administraci\u00f3n Trump de etiquetar a la empresa de IA como un \u201criesgo para la cadena de suministro\u201d. La demanda es el \u00faltimo avance en el conflicto entre el Pent\u00e1gono y una de las empresas de IA m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-09T16:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro\",\"datePublished\":\"2026-03-09T16:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/\"},\"wordCount\":769,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/\",\"name\":\"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-09T16:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro - Noticias","og_description":"Anthropic demand\u00f3 el lunes al Departamento de Defensa y a otras agencias federales por la decisi\u00f3n de la administraci\u00f3n Trump de etiquetar a la empresa de IA como un \u201criesgo para la cadena de suministro\u201d. La demanda es el \u00faltimo avance en el conflicto entre el Pent\u00e1gono y una de las empresas de IA m\u00e1s [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-09T16:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro","datePublished":"2026-03-09T16:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/"},"wordCount":769,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/","name":"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-09T16:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro","url":"http:\/\/noticiasya.com\/el-valle\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/el-valle\/2026\/03\/09\/anthropic-demanda-gobierno-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-09T16:03:48Z","datePublished":"2026-03-09T16:03:48Z","dateModified":"2026-03-09T16:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Anthropic demanda al Gobierno de Trump tras ser designada como riesgo para la cadena de suministro\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/03\\\/09\\\/anthropic-demanda-gobierno-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/el-valle\\\/2026\\\/03\\\/09\\\/anthropic-demanda-gobierno-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-09T16:03:48Z\",\"datePublished\":\"2026-03-09T16:03:48Z\",\"dateModified\":\"2026-03-09T16:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472297,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/17\/exjueces-apoyan-anthropic-pentagono-riesgo-trax\/","url_meta":{"origin":1472016,"position":0},"title":"Exjueces apoyan a Anthropic y expresan recelos por el uso del Pent\u00e1gono de la etiqueta de riesgo en la cadena de suministro","author":"","date":"marzo 17, 2026","format":false,"excerpt":"Casi 150 jueces federales y estatales jubilados presentaron el martes un escrito amicus curiae en apoyo a la empresa de IA, Anthropic, en su demanda contra el Gobierno de Trump por designarla como un \u201criesgo en la cadena de suministro\u201d, seg\u00fan ha sabido CNN.Los exjueces, nombrados tanto por republicanos como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472596,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/03\/26\/jueza-bloquea-pentagono-castigar-anthropic-trax\/","url_meta":{"origin":1472016,"position":1},"title":"Jueza bloquea el esfuerzo del Pent\u00e1gono por &#171;castigar&#187; a Anthropic al catalogarla como un riesgo para la cadena de suministro","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Una jueza federal en California bloque\u00f3 indefinidamente el esfuerzo del Pent\u00e1gono por \u201ccastigar\u201d a Anthropic al etiquetarla como un riesgo para la cadena de suministro e intentar cortar los v\u00ednculos del Gobierno con la empresa de Inteligencia Artificial (IA), al dictaminar que esas medidas atropellaban sus derechos constitucionales.\u201cNada en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471738,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/27\/gobierno-ordena-militares-agencias-federales-no-trabajar-anthropic-trax\/","url_meta":{"origin":1472016,"position":2},"title":"El Gobierno de Trump ordena a contratistas militares y agencias federales cesar negocios con Anthropic","author":"","date":"febrero 27, 2026","format":false,"excerpt":"El Gobierno de Trump orden\u00f3 a las agencias federales y a los contratistas que trabajan con las Fuerzas Armadas que dejen de hacer negocios con Anthropic, despu\u00e9s de que la empresa se negara a permitir que el Pent\u00e1gono utilizara su tecnolog\u00eda de inteligencia artificial sin restricciones.Las agencias gubernamentales, incluido el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471752,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/28\/openai-pentagono-trump-prohibe-anthropic-trax\/","url_meta":{"origin":1472016,"position":3},"title":"OpenAI llega a un acuerdo con el Pent\u00e1gono horas despu\u00e9s de que el Gobierno de Trump prohibiera a Anthropic","author":"","date":"febrero 28, 2026","format":false,"excerpt":"El CEO de OpenAI, Sam Altman, anunci\u00f3 el viernes por la noche que la compa\u00f1\u00eda hab\u00eda firmado un acuerdo con el Pent\u00e1gono para que sus herramientas de IA se utilizaran en los sistemas clasificados militares, pero con restricciones aparentemente similares a las que su rival Anthropic tambi\u00e9n hab\u00eda solicitado.El acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471716,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/27\/anthropic-rechaza-pentagono-trax\/","url_meta":{"origin":1472016,"position":4},"title":"Anthropic rechaza la \u00faltima oferta del Pent\u00e1gono: &#171;No podemos, con conciencia, acceder a su solicitud&#187;","author":"","date":"febrero 27, 2026","format":false,"excerpt":"Anthropic rechaz\u00f3 la \u00faltima oferta del Pent\u00e1gono para modificar su contrato, alegando que los cambios no cumplen con las preocupaciones de la compa\u00f1\u00eda sobre el uso de la IA para la vigilancia masiva o para armas totalmente aut\u00f3nomas.El Pent\u00e1gono y Anthropic discrepan sobre las restricciones que la compa\u00f1\u00eda impone al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471637,"url":"https:\/\/noticiasya.com\/el-valle\/2026\/02\/25\/anthropic-abandona-seguridad-ia-pentagono-trax\/","url_meta":{"origin":1472016,"position":5},"title":"Anthropic abandona su principal promesa de seguridad en medio de una pelea por los l\u00edmites de su IA con el Pent\u00e1gono","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Anthropic, una empresa fundada por exiliados de OpenAI preocupados por los peligros de la inteligencia artificial (IA), est\u00e1 relajando su principio b\u00e1sico de seguridad en respuesta a la competencia.En lugar de restricciones autoimpuestas que limiten el desarrollo de sus modelos de IA, Anthropic est\u00e1 adoptando un marco de seguridad no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/el-valle\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1472016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/comments?post=1472016"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/posts\/1472016\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/media?parent=1472016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/categories?post=1472016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/el-valle\/wp-json\/wp\/v2\/tags?post=1472016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}